{"id":11594,"date":"2019-07-28T21:27:03","date_gmt":"2019-07-28T21:27:03","guid":{"rendered":"https:\/\/larevistadigital.com.ar\/blog\/?p=11594"},"modified":"2019-07-28T21:27:03","modified_gmt":"2019-07-28T21:27:03","slug":"dolores-pierde-el-control-choca-un-auto-estacionado-y-se-incrusta-contra-un-poste","status":"publish","type":"post","link":"https:\/\/larevistadigital.com.ar\/blog\/dolores-pierde-el-control-choca-un-auto-estacionado-y-se-incrusta-contra-un-poste\/","title":{"rendered":"DOLORES: PIERDE EL CONTROL, CHOCA UN AUTO ESTACIONADO Y SE INCRUSTA CONTRA UN POSTE"},"content":{"rendered":"<p>El hecho ocurri\u00f3 en horas de la ma\u00f1ana del domingo 28 de julio en calle Bassi, entre M\u00e1rquez y Rivadavia, donde la conductora de un veh\u00edculo Citroen Ds3 que circulaba por Bassi sufri\u00f3 una descompensaci\u00f3n, perdi\u00f3 el control del veh\u00edculo y tras chocar con un Ford Ka que estaba estacionado sin ocupantes, lo arrastr\u00f3 unos metros y termin\u00f3 incrustado contra un poste.<\/p>\n<p>La mujer fue trasladada al hospital local con algunos golpes que no revestir\u00edan gravedad.<\/p>\n<p>Se produjeron importantes da\u00f1os materiales en ambos veh\u00edculos.<\/p>\n<p>PUBLICADO EN DIARIO COL<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>El hecho ocurri\u00f3 en horas de la ma\u00f1ana del domingo 28 de julio en calle Bassi, entre M\u00e1rquez y Rivadavia, donde la conductora de un veh\u00edculo Citroen Ds3 que circulaba por Bassi sufri\u00f3 una descompensaci\u00f3n, <a class=\"mh-excerpt-more\" href=\"https:\/\/larevistadigital.com.ar\/blog\/dolores-pierde-el-control-choca-un-auto-estacionado-y-se-incrusta-contra-un-poste\/\" title=\"DOLORES: PIERDE EL CONTROL, CHOCA UN AUTO ESTACIONADO Y SE INCRUSTA CONTRA UN POSTE\">[Leer M\u00e1s]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":11595,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[43,51],"tags":[],"class_list":{"0":"post-11594","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-dolores","8":"category-regionales"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Screenshot_4-7.jpg?fit=864%2C482&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8qtrQ-310","jetpack-related-posts":[{"id":13005,"url":"https:\/\/larevistadigital.com.ar\/blog\/choco-un-auto-estacionado-y-se-dio-a-la-fuga\/","url_meta":{"origin":11594,"position":0},"title":"CHOC\u00d3 UN AUTO ESTACIONADO Y SE DIO A LA FUGA","author":"Alejandro Sosa Ruda","date":"3 noviembre, 2019","format":false,"excerpt":"DOLORES - Un autom\u00f3vil marca Peugeot color gris, que se Hallaba estacionado en\u00a0 la calle Buenos Aires al 1150, sufri\u00f3 da\u00f1os cuando un sujeto que manejaba otro veh\u00edculo lo choc\u00f3 y se dio a la fuga. El rodado, que ser\u00eda una camioneta perdi\u00f3 el control e impact\u00f3 la parte trasera\u2026","rel":"","context":"En \u00abDOLORES\u00bb","block_context":{"text":"DOLORES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/dolores\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Screenshot_2-56.jpg?fit=858%2C513&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Screenshot_2-56.jpg?fit=858%2C513&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Screenshot_2-56.jpg?fit=858%2C513&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Screenshot_2-56.jpg?fit=858%2C513&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":9615,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-un-individuo-en-estado-de-ebriedad-choca-auto-estacionado-y-habria-bromeado-al-respecto\/","url_meta":{"origin":11594,"position":1},"title":"CHASCOM\u00daS: UN INDIVIDUO EN ESTADO DE EBRIEDAD, CHOCA AUTO ESTACIONADO Y HABR\u00cdA BROMEADO AL RESPECTO","author":"Alejandro Sosa Ruda","date":"8 abril, 2019","format":false,"excerpt":"Anoche antes de las 20, se produjo un accidente de tr\u00e1nsito en Avenida Presidente Alfons\u00edn entre Grito de Dolores y Obligado, en inmediaciones al Club Atl\u00e9tico. All\u00ed, un autom\u00f3vil Ford K\u00e1, impact\u00f3 contra un Renault Clio que se encontraba estacionado. Ante la llegada de personal policial, inspector\u00eda y la ambulancia\u2026","rel":"","context":"En \u00abPOLICIALES\u00bb","block_context":{"text":"POLICIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/policiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2019\/04\/CONDUCTORES-ALCOHOLIZADOS.jpg?fit=720%2C635&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2019\/04\/CONDUCTORES-ALCOHOLIZADOS.jpg?fit=720%2C635&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2019\/04\/CONDUCTORES-ALCOHOLIZADOS.jpg?fit=720%2C635&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2019\/04\/CONDUCTORES-ALCOHOLIZADOS.jpg?fit=720%2C635&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":10638,"url":"https:\/\/larevistadigital.com.ar\/blog\/maipu-auto-choca-con-camion-estacionado-un-muerto-y-un-herido\/","url_meta":{"origin":11594,"position":2},"title":"MAIP\u00da: AUTO CHOCA CON CAMI\u00d3N ESTACIONADO. UN MUERTO Y UN HERIDO.","author":"Alejandro Sosa Ruda","date":"15 junio, 2019","format":false,"excerpt":"Un joven vecino de Maipu falleci\u00f3 esta madrugada como consecuencia de un siniestro vial ocurrido en la calle Lavalle de tal ciudad, frente al predio del club Atl\u00e9tico. Por causas que se tratan de establecer, el veh\u00edculo en el que se trasladaba el maipuense, colision\u00f3 contra un cami\u00f3n que estaba\u2026","rel":"","context":"En \u00abPOLICIALES\u00bb","block_context":{"text":"POLICIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/policiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/64445929_2294786880612685_2261391686837993472_n.jpg?fit=960%2C540&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/64445929_2294786880612685_2261391686837993472_n.jpg?fit=960%2C540&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/64445929_2294786880612685_2261391686837993472_n.jpg?fit=960%2C540&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/64445929_2294786880612685_2261391686837993472_n.jpg?fit=960%2C540&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":18098,"url":"https:\/\/larevistadigital.com.ar\/blog\/video-mar-del-plata-joven-choca-contra-un-poste-y-pierde-la-vida\/","url_meta":{"origin":11594,"position":3},"title":"[VIDEO] MAR DEL PLATA: JOVEN CHOCA CONTRA UN POSTE Y PIERDE LA VIDA","author":"Alejandro Sosa Ruda","date":"12 diciembre, 2020","format":false,"excerpt":"Un joven de 30 a\u00f1os perdi\u00f3 la vida en Mar del Plata despu\u00e9s de protagonizar un violento choque contra un poste cuando circulaba por la Avenida 39 y Monse\u00f1or Enrique Rau. El siniestro se constat\u00f3 alrededor de la 1.15 de este viernes y, seg\u00fan lo que pudo confirmar\u00a00223\u00a0de fuentes oficiales\u2026","rel":"","context":"En \u00abPOLICIALES\u00bb","block_context":{"text":"POLICIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/policiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Screenshot_1-175.jpg?fit=1003%2C562&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Screenshot_1-175.jpg?fit=1003%2C562&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Screenshot_1-175.jpg?fit=1003%2C562&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Screenshot_1-175.jpg?fit=1003%2C562&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":4421,"url":"https:\/\/larevistadigital.com.ar\/blog\/dolores-dos-jovenes-graves-luego-chocar-moto-auto\/","url_meta":{"origin":11594,"position":4},"title":"DOLORES: DOS JOVENES GRAVES LUEGO DE CHOCAR CON SU MOTO CONTRA UN AUTO","author":"Alejandro Sosa Ruda","date":"8 enero, 2018","format":false,"excerpt":"El hecho ocurri\u00f3 durante la madrugada en el kil\u00f3metro en el kil\u00f3metro 205 de la ruta 2, cuando dos j\u00f3venes que viajaban a bordo de su motocicleta Gilera 110, impactaron contra un autom\u00f3vil marca Torino que hab\u00eda sufrido un desperfecto y estaba estacionado sobre el puente del canal 9. Extra\u00f1amente,\u2026","rel":"","context":"En \u00abDOLORES\u00bb","block_context":{"text":"DOLORES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/dolores\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/01\/Screenshot_1-1.jpg?fit=1004%2C674&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/01\/Screenshot_1-1.jpg?fit=1004%2C674&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/01\/Screenshot_1-1.jpg?fit=1004%2C674&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/01\/Screenshot_1-1.jpg?fit=1004%2C674&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":46685,"url":"https:\/\/larevistadigital.com.ar\/blog\/un-auto-se-subio-a-la-vereda-y-choco-contra-un-poste-en-la-plata\/","url_meta":{"origin":11594,"position":5},"title":"Un auto se subi\u00f3 a la vereda y choc\u00f3 contra un poste en La Plata","author":"Alejandro Sosa Ruda","date":"26 julio, 2026","format":false,"excerpt":"El accidente ocurri\u00f3 en pleno casco urbano de la capital bonaerense. El conductor perdi\u00f3 el control del veh\u00edculo y termin\u00f3 impactando contra una columna de alumbrado p\u00fablico. A pesar de la violencia del choque, no se registraron heridos de gravedad. 26 de julio de 2026 LA PLATA -\u00a0 \u00a0Un nuevo\u2026","rel":"","context":"En \u00abPOLICIALES\u00bb","block_context":{"text":"POLICIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/policiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-07-26-161120.jpg?fit=781%2C412&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-07-26-161120.jpg?fit=781%2C412&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-07-26-161120.jpg?fit=781%2C412&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-07-26-161120.jpg?fit=781%2C412&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/11594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=11594"}],"version-history":[{"count":1,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/11594\/revisions"}],"predecessor-version":[{"id":11596,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/11594\/revisions\/11596"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media\/11595"}],"wp:attachment":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=11594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=11594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=11594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}