{"id":19877,"date":"2021-04-27T17:23:08","date_gmt":"2021-04-27T17:23:08","guid":{"rendered":"https:\/\/larevistadigital.com.ar\/blog\/?p=19877"},"modified":"2021-04-27T17:25:47","modified_gmt":"2021-04-27T17:25:47","slug":"19877-2","status":"publish","type":"post","link":"https:\/\/larevistadigital.com.ar\/blog\/19877-2\/","title":{"rendered":"CHASCOM\u00daS: LA ANTOJADIZA FORMA DE MANEJARSE DEL MUNICIPIO CON LA VACUNACI\u00d3N"},"content":{"rendered":"<p>D\u00edas pasados En una publicaci\u00f3n de la Municipalidad en facebook, \u00a0se informa que la Sec. De Salud P\u00fablica junto al intendente recorrieron el Centro de Vacunaci\u00f3n.<\/p>\n<p>All\u00ed mismo los funcionarios afirman que el vacunatorio est\u00e1 funcionando de forma eficiente y el trato con cada vecino es de una amabilidad absoluta.<\/p>\n<blockquote>\n<h3>Pero entre los comentarios que realizan los vecinos se confirma aquello que varios lectores de <strong>LRD<\/strong> nos manifestaron.\u00a0 Esto es que se encontraban citados para la aplicaci\u00f3n de la 1er dosis los d\u00edas viernes 16, s\u00e1bado 17 y domingo 18 y que fuera suspendida por falta de vacunas.<\/h3>\n<\/blockquote>\n<p>En esa oportunidad hubieron vecinos que fueron llamados, y se le informo que no hab\u00eda vacunas y que al momento de llegar m\u00e1s dosis se los volver\u00eda a convocar.\u00a0 Otros se enteraron al ir a presentarse.<\/p>\n<blockquote>\n<h3>Pero resulta que llego el fin de semana siguiente y por lo visto llegaron vacunas pero no fueron nuevamente convocados\u2026 Algunos\u00a0 se presentaros espont\u00e1neamente, se quejaron y\u2026fueron vacunados\u2026<\/h3>\n<\/blockquote>\n<p>Y entonces vemos que otra vez resulta m\u00e1s que sospechoso el sistema de turnos y prioridades, y todos nos preguntamos\u2026\u00bf\u00bfC\u00f3mo se dan los turnos?<\/p>\n<blockquote>\n<h3>Porque \u201cdicen\u201d <strong>los turnos los da la provincia,<\/strong> pero ha sucedido que algunos <strong>por ser parientes<\/strong> aunque no tengan domicilio en nuestra ciudad fueron vacunados, otros porque <strong>prepearon o se quejaron <\/strong>fueron vacunados\u2026ni que hablar de los considerados como <strong>personal estrat\u00e9gico<\/strong>\u00a0 por\u00a0 el Municipio, algunos no llegan a los 25 a\u00f1os de edad\u2026<\/h3>\n<\/blockquote>\n<p>Desde la oposici\u00f3n en el Concejo Deliberante se hicieron las preguntas y requerimientos del caso, pero el oficialismo se limit\u00f3 a responder que el sistema que se usa es excelente, y que no van a dar las listas de vacunador por cuidar la \u00abintimidad\u00bb (cuando parad\u00f3jicamente publicaron listas con las n\u00f3minas en un principio)<\/p>\n<blockquote>\n<h3>\u00bfCu\u00e1les son las prioridades? \u00bfCu\u00e1l es el sistema? Hay gente de edad y con problemas de salud que est\u00e1 muy atemorizada y no se merecen el destrato que vemos ocurre cuando se lo convoca, se le suspende el turno y despu\u00e9s ve que se est\u00e1n aplicando vacunas, pero ellos \u00a0no son nuevamente citados.<\/h3>\n<\/blockquote>\n<p>\u00bfQu\u00e9 le dir\u00e1n a las familias de las personas que fallecen por covid?&#8230; Seguramente nada.<\/p>\n<p>Otro claro caso de falta total de transparencia. Y van&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>D\u00edas pasados En una publicaci\u00f3n de la Municipalidad en facebook, \u00a0se informa que la Sec. De Salud P\u00fablica junto al intendente recorrieron el Centro de Vacunaci\u00f3n. All\u00ed mismo los funcionarios afirman que el vacunatorio est\u00e1 <a class=\"mh-excerpt-more\" href=\"https:\/\/larevistadigital.com.ar\/blog\/19877-2\/\" title=\"CHASCOM\u00daS: LA ANTOJADIZA FORMA DE MANEJARSE DEL MUNICIPIO CON LA VACUNACI\u00d3N\">[Leer M\u00e1s]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":19878,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[6],"tags":[],"class_list":{"0":"post-19877","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-chascomus"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/f608x342-645589_675312_174.jpg?fit=608%2C342&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8qtrQ-5aB","jetpack-related-posts":[{"id":15184,"url":"https:\/\/larevistadigital.com.ar\/blog\/bloques-de-oposicion-hacen-un-pedido-de-informes-al-ejecutivo-por-la-falta-de-vacunas-contra-la-gripe\/","url_meta":{"origin":19877,"position":0},"title":"BLOQUES DE OPOSICI\u00d3N HACEN UN PEDIDO DE INFORMES AL EJECUTIVO POR LA FALTA DE VACUNAS CONTRA LA GRIPE","author":"Alejandro Sosa Ruda","date":"12 mayo, 2020","format":false,"excerpt":"La cl\u00e1sica \"vacuna antigripal\" que se aplica cada a\u00f1o por estas \u00e9pocas, hoy pasa por una situaci\u00f3n que realmente es muy preocupante. Hay un calendario que est\u00e1 siendo dif\u00edcil de cumplir, con la premura que es necesaria para los distintos grupos de riesgo, sobre todo hoy, que el mundo se\u2026","rel":"","context":"En \u00abINTERES GENERAL\u00bb","block_context":{"text":"INTERES GENERAL","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/interes-general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/unnamed-4.jpg?fit=512%2C295&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":45023,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-se-ve-afectado-por-la-falta-de-envio-de-vacunas-antigripales-por-parte-del-gobierno-nacional\/","url_meta":{"origin":19877,"position":1},"title":"Chascom\u00fas se ve afectado por la falta de env\u00edo de vacunas antigripales por parte del Gobierno Nacional","author":"Alejandro Sosa Ruda","date":"8 abril, 2026","format":false,"excerpt":"La demora en la entrega de vacunas afecta a municipios de todo el pa\u00eds. En Chascom\u00fas, esta situaci\u00f3n genera dificultades para avanzar con normalidad en la campa\u00f1a de vacunaci\u00f3n antigripal y otros esquemas del calendario obligatorio. 08 de abril de 2026 CHASCOM\u00daS -\u00a0 \u00a0Desde el Gobierno de la Provincia de\u2026","rel":"","context":"En \u00abINTERES GENERAL\u00bb","block_context":{"text":"INTERES GENERAL","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/interes-general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/69d6998872fd9.png?fit=668%2C445&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/69d6998872fd9.png?fit=668%2C445&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/69d6998872fd9.png?fit=668%2C445&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":20342,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-farmacias-con-vacunas-antigripales-para-afiliados-a-pami-con-turnos-asignados\/","url_meta":{"origin":19877,"position":2},"title":"CHASCOM\u00daS: FARMACIAS CON VACUNAS ANTIGRIPALES PARA AFILIADOS A PAMI CON TURNOS ASIGNADOS","author":"Alejandro Sosa Ruda","date":"18 mayo, 2021","format":false,"excerpt":"CHASCOM\u00daS - El Colegio de Farmac\u00e9uticos de Chascom\u00fas informa que las farmacias Batastini, Chascom\u00fas, Belgrano, Puyssegur, Malena, Del Norte y Farmasur ya tienen vacunas antigripales para afiliados de PAMI con turno asignado. Vale recordar que los turnos de vacunaci\u00f3n no se solicitan m\u00e1s en las farmacias, debiendo hacerlo en el\u2026","rel":"","context":"En \u00abDESTACADAS\u00bb","block_context":{"text":"DESTACADAS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/destacadas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2021-05-18-at-11.35.03.jpeg?fit=800%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2021-05-18-at-11.35.03.jpeg?fit=800%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2021-05-18-at-11.35.03.jpeg?fit=800%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2021-05-18-at-11.35.03.jpeg?fit=800%2C800&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":18963,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-se-piden-informes-y-presiciones-acerca-de-la-vacunacion\/","url_meta":{"origin":19877,"position":3},"title":"CHASCOM\u00daS: SE PIDEN INFORMES Y PRESICIONES ACERCA DE LA VACUNACI\u00d3N","author":"Alejandro Sosa Ruda","date":"22 febrero, 2021","format":false,"excerpt":"Luego del may\u00fasculo esc\u00e1ndalo protagonizado por el renunciado Ministro de Salud, Gin\u00e9s Gonzalez Garc\u00eda, y las situaciones denunciadas en distintos lugares, donde las autoridades de turno han privilegiado de manera insensata, ilegal e irresponsable a amigos y distintos personajes pol\u00edticos, los distritos han puesto en la mira el desarrollo de\u2026","rel":"","context":"En \u00abINTERES GENERAL\u00bb","block_context":{"text":"INTERES GENERAL","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/interes-general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/3180.jpg?fit=1004%2C566&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/3180.jpg?fit=1004%2C566&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/3180.jpg?fit=1004%2C566&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/3180.jpg?fit=1004%2C566&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":25404,"url":"https:\/\/larevistadigital.com.ar\/blog\/comienzan-a-aplicar-dosis-de-resfuerzo-en-chicos-de-5-a-11-a\/","url_meta":{"origin":19877,"position":4},"title":"COMIENZAN A APLICAR D\u00d3SIS DE RESFUERZO EN CHICOS DE 5 A 11 A","author":"Alejandro Sosa Ruda","date":"26 mayo, 2022","format":false,"excerpt":"A partir de hoy se aplicar\u00e1n, de forma libre y federal, 120 d\u00edas despu\u00e9s de completado el esquema de vacunaci\u00f3n inicial. Lo acordaron ministros y ministras de Salud de todo el pa\u00eds en el COFESA. Tras el consenso establecido en el Consejo Federal de Salud, el Gobierno de la Provincia\u2026","rel":"","context":"En \u00abINTERES GENERAL\u00bb","block_context":{"text":"INTERES GENERAL","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/interes-general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20220525140006_vacunacion-refuerzo.jpg?fit=880%2C512&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20220525140006_vacunacion-refuerzo.jpg?fit=880%2C512&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20220525140006_vacunacion-refuerzo.jpg?fit=880%2C512&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20220525140006_vacunacion-refuerzo.jpg?fit=880%2C512&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":41374,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-te-informamos-en-detalle-sobre-la-campana-de-vacunacion-en-los-barrios\/","url_meta":{"origin":19877,"position":5},"title":"Chascom\u00fas: Te informamos en detalle sobre la campa\u00f1a de vacunaci\u00f3n en los barrios","author":"Alejandro Sosa Ruda","date":"10 septiembre, 2025","format":false,"excerpt":"Una nueva oportunidad para completar el calendario obligatorio para ni\u00f1os, adolescentes y adultos. 10 de Septiembre de 20254 CHASCOM\u00daS\u00a0 -\u00a0 \u00a0La campa\u00f1a de vacunaci\u00f3n masiva contin\u00faa en distintos Centros de Atenci\u00f3n Primaria, con el prop\u00f3sito de facilitar el acceso para que vecinos y vecinas completen el esquema obligatorio, fundamentalmente, ni\u00f1os\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/68c1a96eb024c.png?fit=668%2C445&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/68c1a96eb024c.png?fit=668%2C445&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/68c1a96eb024c.png?fit=668%2C445&ssl=1&resize=525%2C300 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/19877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=19877"}],"version-history":[{"count":4,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/19877\/revisions"}],"predecessor-version":[{"id":19882,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/19877\/revisions\/19882"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media\/19878"}],"wp:attachment":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=19877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=19877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=19877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}