{"id":20550,"date":"2021-05-31T13:10:11","date_gmt":"2021-05-31T13:10:11","guid":{"rendered":"https:\/\/larevistadigital.com.ar\/blog\/?p=20550"},"modified":"2021-05-31T13:10:11","modified_gmt":"2021-05-31T13:10:11","slug":"conmocion-fallece-en-rauch-un-joven-de-31-anos-por-covid","status":"publish","type":"post","link":"https:\/\/larevistadigital.com.ar\/blog\/conmocion-fallece-en-rauch-un-joven-de-31-anos-por-covid\/","title":{"rendered":"CONMOCI\u00d3N: FALLECE EN RAUCH UN JOVEN DE 31 A\u00d1OS POR COVID"},"content":{"rendered":"<p>Un joven de 31 a\u00f1os se convirti\u00f3 en la 23\u00aa v\u00edctima de Covid en Rauch. El muchacho estaba internado desde hace un tiempo en la Unidad de Terapia Intensiva del Hospital de dicha ciudad.<\/p>\n<p>En la ma\u00f1ana de hoy lunes, de acuerdo a lo que informa el portal colega ABCHoy.com.ar, \u00abse reunir\u00e1 la Mesa de Emergencia local para evaluar la situaci\u00f3n de la enfermedad en nuestra localidad y se evaluar\u00e1 si se contin\u00faa con las restricciones como hasta el momento o se toman nuevas medidas\u00bb.<\/p>\n<div id=\"bottom-cerrar\" class=\"ayacu-despues-del-contenido\">(FUENTE: ayacuchoald\u00eda)<\/div>\n<div class=\"mh-social-bottom\">\n<div class=\"mh-share-buttons clearfix\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Un joven de 31 a\u00f1os se convirti\u00f3 en la 23\u00aa v\u00edctima de Covid en Rauch. El muchacho estaba internado desde hace un tiempo en la Unidad de Terapia Intensiva del Hospital de dicha ciudad. En <a class=\"mh-excerpt-more\" href=\"https:\/\/larevistadigital.com.ar\/blog\/conmocion-fallece-en-rauch-un-joven-de-31-anos-por-covid\/\" title=\"CONMOCI\u00d3N: FALLECE EN RAUCH UN JOVEN DE 31 A\u00d1OS POR COVID\">[Leer M\u00e1s]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":20551,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[51],"tags":[],"class_list":{"0":"post-20550","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-regionales"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/hospital-rauch.jpg?fit=800%2C600&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8qtrQ-5ls","jetpack-related-posts":[{"id":18174,"url":"https:\/\/larevistadigital.com.ar\/blog\/lamentablemente-rauch-tuvo-su-primera-victima-por-covid-19\/","url_meta":{"origin":20550,"position":0},"title":"LAMENTABLEMENTE, RAUCH TUVO SU PRIMERA V\u00cdCTIMA POR COVID-19","author":"Alejandro Sosa Ruda","date":"16 diciembre, 2020","format":false,"excerpt":"Rauch tuvo su primera v\u00edctima por Coronavirus. Se trata de una mujer de 79 a\u00f1os que hab\u00eda sido internada ayer. As\u00ed lo confirm\u00f3 el Sistema Municipal de Salud de Rauch. La Dra. Rosana V\u00e9lez se\u00f1al\u00f3 que\u00a0\u00a0\u00abHab\u00eda sido internada en el d\u00eda de ayer (martes) una abuela de 79 a\u00f1os que\u2026","rel":"","context":"En \u00abREGIONALES\u00bb","block_context":{"text":"REGIONALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/regionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/achaga-anuncio-rauch-covid.jpeg?fit=1070%2C605&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/achaga-anuncio-rauch-covid.jpeg?fit=1070%2C605&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/achaga-anuncio-rauch-covid.jpeg?fit=1070%2C605&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/achaga-anuncio-rauch-covid.jpeg?fit=1070%2C605&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/achaga-anuncio-rauch-covid.jpeg?fit=1070%2C605&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":20313,"url":"https:\/\/larevistadigital.com.ar\/blog\/rauch-volco-un-auto-en-la-ruta-30-y-el-conductor-tenia-covid\/","url_meta":{"origin":20550,"position":1},"title":"RAUCH: VOLC\u00d3 UN AUTO EN LA RUTA 30 Y EL CONDUCTOR TEN\u00cdA COVID","author":"Alejandro Sosa Ruda","date":"17 mayo, 2021","format":false,"excerpt":"D\u00edas pasados un autom\u00f3vil Chevrolet Corsa dominio JQC 063 que viajaba por la Ruta 30, en direcci\u00f3n Rauch \u2013 Las Flores. Los dos ocupantes fueron trasladados al Hospital Municipal. Uno de ellos era COVID positivo. Tras ser asistidos por una unidad de Bomberos Voluntarios, la pareja que ocupaba el veh\u00edculo\u2026","rel":"","context":"En \u00abPOLICIALES\u00bb","block_context":{"text":"POLICIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/policiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/vuelco-corsa-10-5-2021.jpg?fit=800%2C443&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/vuelco-corsa-10-5-2021.jpg?fit=800%2C443&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/vuelco-corsa-10-5-2021.jpg?fit=800%2C443&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/vuelco-corsa-10-5-2021.jpg?fit=800%2C443&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":23734,"url":"https:\/\/larevistadigital.com.ar\/blog\/rauch-adolescente-denuncia-que-fue-abusada\/","url_meta":{"origin":20550,"position":2},"title":"RAUCH: ADOLESCENTE DENUNCIA QUE FUE ABUSADA","author":"Alejandro Sosa Ruda","date":"1 febrero, 2022","format":false,"excerpt":"RAUCH -\u00a0 La denuncia radicada por una adolescente por un caso de abuso sexual del que fue v\u00edctima durante este fin de semana provoc\u00f3 que se movilizara el mecanismo judicial. El hecho, registrado en una vivienda de nuestra ciudad, fue denunciado por la adolescente ante la Comisar\u00eda de la Mujer\u2026","rel":"","context":"En \u00abPOLICIALES\u00bb","block_context":{"text":"POLICIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/policiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/policia-rauch-enero-2022.jpg?fit=660%2C400&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/policia-rauch-enero-2022.jpg?fit=660%2C400&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/policia-rauch-enero-2022.jpg?fit=660%2C400&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":22244,"url":"https:\/\/larevistadigital.com.ar\/blog\/fallecio-el-ex-intendente-de-rauch-jorge-ugarte-a-los-92-anos-de-edad\/","url_meta":{"origin":20550,"position":3},"title":"FALLECI\u00d3 EL EX INTENDENTE DE RAUCH, JORGE UGARTE A LOS 92 A\u00d1OS DE EDAD","author":"Alejandro Sosa Ruda","date":"6 octubre, 2021","format":false,"excerpt":"Este martes 5 de Octubre a los 92 a\u00f1os de edad falleci\u00f3 en Rauch el ex intendente Jorge Mario Ram\u00f3n Ugarte. Fue Jefe Comunal de la vecina localidad durante 3 per\u00edodos, desde el 2003 al 2015. Nacido el 4 de febrero de 1929, el doctor Ugarte se convirti\u00f3 en una\u2026","rel":"","context":"En \u00abPOLITICA PROVINCIAL\u00bb","block_context":{"text":"POLITICA PROVINCIAL","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/politica\/politica-provincial\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2021-10-06-082802.jpg?fit=842%2C527&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2021-10-06-082802.jpg?fit=842%2C527&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2021-10-06-082802.jpg?fit=842%2C527&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2021-10-06-082802.jpg?fit=842%2C527&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":24056,"url":"https:\/\/larevistadigital.com.ar\/blog\/rauch-vuelco-en-la-ruta-30\/","url_meta":{"origin":20550,"position":4},"title":"RAUCH: VUELCO EN LA RUTA 30","author":"Alejandro Sosa Ruda","date":"17 febrero, 2022","format":false,"excerpt":"Un autom\u00f3vil que se dirig\u00eda hacia Tandil volc\u00f3 en la Ruta 30, a cercan\u00edas a la rotonda que une con la Ruta 50. La conductora, domiciliada en CABA, result\u00f3 ilesa. En la ma\u00f1ana del mi\u00e9rcoles, aproximadamente a las\u00a09 horas, los Bomberos Voluntarios de Rauch acudieron por un llamado telef\u00f3nico a\u2026","rel":"","context":"En \u00abREGIONALES\u00bb","block_context":{"text":"REGIONALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/regionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/vuelco-sandero-rauch-16-2-2022.jpg?fit=800%2C600&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/vuelco-sandero-rauch-16-2-2022.jpg?fit=800%2C600&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/vuelco-sandero-rauch-16-2-2022.jpg?fit=800%2C600&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/vuelco-sandero-rauch-16-2-2022.jpg?fit=800%2C600&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":21914,"url":"https:\/\/larevistadigital.com.ar\/blog\/alerta-del-servicio-meteorologico-por-temporal-y-lluvias-intensas-en-ayacucho-rauch-tandil-y-balcarce\/","url_meta":{"origin":20550,"position":5},"title":"ALERTA DEL SERVICIO METEOROL\u00d3GICO POR TEMPORAL Y LLUVIAS INTENSAS EN AYACUCHO, RAUCH, TANDIL Y BALCARCE","author":"Alejandro Sosa Ruda","date":"8 septiembre, 2021","format":false,"excerpt":"El Servicio Meteorol\u00f3gico Nacional emiti\u00f3 un alerta por tormentas y lluvias muy fuertes que afectar\u00edan a Ayacucho, Rauch, Tandil y Balcarce. Se recomienda tomar las precauciones del caso. \u00a0","rel":"","context":"En \u00abREGIONALES\u00bb","block_context":{"text":"REGIONALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/regionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/ALERTA-METEOROLOGICO.jpg?fit=1140%2C758&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/ALERTA-METEOROLOGICO.jpg?fit=1140%2C758&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/ALERTA-METEOROLOGICO.jpg?fit=1140%2C758&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/ALERTA-METEOROLOGICO.jpg?fit=1140%2C758&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/ALERTA-METEOROLOGICO.jpg?fit=1140%2C758&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/20550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=20550"}],"version-history":[{"count":1,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/20550\/revisions"}],"predecessor-version":[{"id":20552,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/20550\/revisions\/20552"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media\/20551"}],"wp:attachment":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=20550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=20550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=20550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}