{"id":20866,"date":"2021-06-23T16:42:23","date_gmt":"2021-06-23T16:42:23","guid":{"rendered":"https:\/\/larevistadigital.com.ar\/blog\/?p=20866"},"modified":"2021-06-23T16:42:23","modified_gmt":"2021-06-23T16:42:23","slug":"piden-revocar-la-prision-domiciliaria-de-alberto-samid","status":"publish","type":"post","link":"https:\/\/larevistadigital.com.ar\/blog\/piden-revocar-la-prision-domiciliaria-de-alberto-samid\/","title":{"rendered":"PIDEN REVOCAR LA PRISI\u00d3N DOMICILIARIA DE ALBERTO SAMID"},"content":{"rendered":"<p><strong><em>A trav\u00e9s de una presentaci\u00f3n formulada hace minutos, el diputado bonaerense de Juntos por el Cambio, Luciano Bugallo, solicit\u00f3 ante la Unidad Fiscal de Ejecuci\u00f3n Penal que se le revoque el beneficio de la presi\u00f3n domiciliaria a Alberto Samid, luego del esc\u00e1ndalo protagonizado esta tarde en Ramos Mejia donde comensales de un restaurante repudiaron la presencia del empresario de la carne y lograron echarlo.<\/em><\/strong><\/p>\n<p>Este hecho de incumplimiento no es el primero en la trayectoria judicial de <strong>Samid<\/strong>, en abril de 2019 se hab\u00eda fugado a Belice buscando entorpecer la investigaci\u00f3n que reca\u00eda sobre \u00e9l. Ahora, en un nuevo acto de desobediencia, el medi\u00e1tico empresario fue detectado por personas que se encontraban comiendo en un restaurante y lo grabaron violando sin disimulo la prisi\u00f3n domiciliaria junto a 2 acompa\u00f1antes.<\/p>\n<p>A ra\u00edz de esta situaci\u00f3n, un legislador que responde a\u00a0<strong>Elisa\u00a0<\/strong>Carri\u00f3 en la Legislatura Provincial, el diputado de la\u00a0<strong>Coalici\u00f3n Civica<\/strong>,\u00a0<strong>Luciano Bugall<\/strong>o realiz\u00f3 una denuncia penal requiriendo que se le revoque el beneficio:<strong>\u00a0\u201dPresentamos ante la Unidad Fiscal de Ejecuci\u00f3n Penal, un pedido de revocaci\u00f3n del beneficio de prisi\u00f3n domiciliaria contra Alberto Samid. Es inaceptable que mientras los trabajadores est\u00e1n encerrados sin poder trabajar, los delincuentes est\u00e9n libres y con total impunidad\u201d,<\/strong> anunciaba por las redes sociales.<\/p>\n<p>Seg\u00fan consta en la denuncia formulada hoy por el legislador \u201clilito\u201d\u00a0<strong>\u201dJos\u00e9 Alberto Samid se hallaba junto a otros dos hombres en una mesa del restaurante \u201cPaja Rota\u201d, en la Avenida de mayo 836. Ante las protestas de los clientes los tres abandonaron el lugar, tal como acreditan diferentes medios period\u00edsticos, mediante videofilmado almorzando fuera de su domicilio, como un ciudadano libre, que no lo es\u201d.<\/strong><\/p>\n<p>Por \u00faltimo, el diputado<strong> Bugallo<\/strong> expone que\u00a0<strong>\u201dpor haber violado el beneficio otorgado, los suscriptos sugieren la revocaci\u00f3n del mismo y solicitan la prisi\u00f3n efectiva del condenado\u201d<\/strong>, concluy\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>A trav\u00e9s de una presentaci\u00f3n formulada hace minutos, el diputado bonaerense de Juntos por el Cambio, Luciano Bugallo, solicit\u00f3 ante la Unidad Fiscal de Ejecuci\u00f3n Penal que se le revoque el beneficio de la presi\u00f3n <a class=\"mh-excerpt-more\" href=\"https:\/\/larevistadigital.com.ar\/blog\/piden-revocar-la-prision-domiciliaria-de-alberto-samid\/\" title=\"PIDEN REVOCAR LA PRISI\u00d3N DOMICILIARIA DE ALBERTO SAMID\">[Leer M\u00e1s]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":20867,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[50],"tags":[],"class_list":{"0":"post-20866","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-interes-general"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/ARCHI_852001.jpg?fit=760%2C424&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8qtrQ-5qy","jetpack-related-posts":[{"id":35300,"url":"https:\/\/larevistadigital.com.ar\/blog\/abuso-sexualmente-de-una-nina-y-pide-la-domiciliaria\/","url_meta":{"origin":20866,"position":0},"title":"ABUS\u00d3 SEXUALMENTE DE UNA NI\u00d1A, Y PIDE LA DOMICILIARIA","author":"Alejandro Sosa Ruda","date":"21 febrero, 2024","format":false,"excerpt":"El acusado se encuentra con prisi\u00f3n preventiva en una Unidad Penitenciaria provincial. 21 de febrero de 2023 MAR DEL TUY\u00da -\u00a0\u00a0 La Justicia imput\u00f3 a R.C M . por abuso sexual, perpetrado a una ni\u00f1a menor de 10 a\u00f1os, y en las \u00faltimas horas, la defensa del abusador present\u00f3 un\u2026","rel":"","context":"En \u00abPOLICIALES\u00bb","block_context":{"text":"POLICIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/policiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/menores-abuso.png?fit=1001%2C565&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/menores-abuso.png?fit=1001%2C565&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/menores-abuso.png?fit=1001%2C565&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/menores-abuso.png?fit=1001%2C565&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":474,"url":"https:\/\/larevistadigital.com.ar\/blog\/franco-macri-vido-mira-voy-prision-domiciliaria-vos-no\/","url_meta":{"origin":20866,"position":1},"title":"Franco Macri a De Vido: \u201cMir\u00e1 que yo voy a prisi\u00f3n domiciliaria, y vos no\u201d","author":"Alejandro Sosa Ruda","date":"1 marzo, 2017","format":false,"excerpt":"Mientras desde el Frente Renovador pretenden citar a Franco Macri al congreso por el tema del Correo, en el kirchnerismo est\u00e1n preocupados porque creen que la declaraci\u00f3n del empresario los puede perjudicar m\u00e1s a ellos que al presidente. Seg\u00fan pudo saberse, el padre del presidente, Franco Macri se puso en\u2026","rel":"","context":"En \u00abPOLITICA\u00bb","block_context":{"text":"POLITICA","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/principalmm010317pn.jpg?fit=1200%2C674&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/principalmm010317pn.jpg?fit=1200%2C674&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/principalmm010317pn.jpg?fit=1200%2C674&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/principalmm010317pn.jpg?fit=1200%2C674&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/principalmm010317pn.jpg?fit=1200%2C674&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":15239,"url":"https:\/\/larevistadigital.com.ar\/blog\/revocan-la-prision-domiciliaria-de-un-delincuente-que-al-salir-cometio-otro-robo\/","url_meta":{"origin":20866,"position":2},"title":"REVOCAN LA PRISI\u00d3N DOMICILIARIA DE UN DELINCUENTE QUE AL SALIR COMETI\u00d3 OTRO ROBO","author":"Alejandro Sosa Ruda","date":"18 mayo, 2020","format":false,"excerpt":"La Sala 1 de la C\u00e1mara de Apelaci\u00f3n y Garant\u00edas dio lugar al recurso de apelaci\u00f3n del fiscal Guillermo Nicora. En la resoluci\u00f3n remarcan que no se le dio aviso a la v\u00edctima de la medida. MAR DEL PLATA - Una pena \u00fanica a 16 a\u00f1os y medio de prisi\u00f3n\u2026","rel":"","context":"En \u00abPOLICIALES\u00bb","block_context":{"text":"POLICIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/policiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/6462594433258920_1.jpg?fit=1200%2C951&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/6462594433258920_1.jpg?fit=1200%2C951&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/6462594433258920_1.jpg?fit=1200%2C951&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/6462594433258920_1.jpg?fit=1200%2C951&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/6462594433258920_1.jpg?fit=1200%2C951&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":40093,"url":"https:\/\/larevistadigital.com.ar\/blog\/cristina-kirchner-se-presentara-en-comodoro-py-el-miercoles-y-solicita-prision-domiciliaria\/","url_meta":{"origin":20866,"position":3},"title":"Cristina Kirchner se presentar\u00e1 en Comodoro Py el mi\u00e9rcoles y solicita prisi\u00f3n domiciliaria","author":"Alejandro Sosa Ruda","date":"13 junio, 2025","format":false,"excerpt":"La expresidenta confirm\u00f3 que acatar\u00e1 el fallo judicial y reforz\u00f3 su pedido de prisi\u00f3n domiciliaria, invocando razones de seguridad. 13 de Junio de 2025 BUENOS AIRES -\u00a0 A trav\u00e9s de una carta difundida en sus redes sociales, Cristina Fern\u00e1ndez de Kirchner anunci\u00f3 que el pr\u00f3ximo mi\u00e9rcoles 18 de junio se\u2026","rel":"","context":"En \u00abINTERES GENERAL\u00bb","block_context":{"text":"INTERES GENERAL","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/interes-general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Cristina-Kirchner.jpg?fit=712%2C441&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Cristina-Kirchner.jpg?fit=712%2C441&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Cristina-Kirchner.jpg?fit=712%2C441&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Cristina-Kirchner.jpg?fit=712%2C441&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":23947,"url":"https:\/\/larevistadigital.com.ar\/blog\/revocan-la-prision-domiciliaria-del-hombre-detenido-por-abusar-de-su-bisnieta-de-3-meses\/","url_meta":{"origin":20866,"position":4},"title":"REVOCAN LA PRISI\u00d3N DOMICILIARIA DEL HOMBRE DETENIDO POR ABUSAR DE SU BISNIETA DE 3 MESES","author":"Alejandro Sosa Ruda","date":"12 febrero, 2022","format":false,"excerpt":"El jueves pasado cuando la Polic\u00eda Bonaerense detuvo a un hombre de 63 a\u00f1os acusado de haber abusado sexualmente de su bisnieta de tres meses, uno de los datos que emergi\u00f3 r\u00e1pidamente entre los investigadores era que en esa casa el imputado cumpl\u00eda prisi\u00f3n domiciliaria por una causa previa, tambi\u00e9n\u2026","rel":"","context":"En \u00abINTERES GENERAL\u00bb","block_context":{"text":"INTERES GENERAL","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/interes-general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20220211154836_tribunal-oral-federal-mar-del-plata.jpg?fit=880%2C512&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20220211154836_tribunal-oral-federal-mar-del-plata.jpg?fit=880%2C512&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20220211154836_tribunal-oral-federal-mar-del-plata.jpg?fit=880%2C512&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20220211154836_tribunal-oral-federal-mar-del-plata.jpg?fit=880%2C512&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":15394,"url":"https:\/\/larevistadigital.com.ar\/blog\/durante-la-pandemia-casi-100-presos-salieron-de-batan\/","url_meta":{"origin":20866,"position":5},"title":"DURANTE LA PANDEMIA, CASI 100 PRESOS SALIERON DE BAT\u00c1N","author":"Alejandro Sosa Ruda","date":"28 mayo, 2020","format":false,"excerpt":"La cifra surgi\u00f3 a trav\u00e9s de un relevamiento realizado por LA CAPITAL en los distintos juzgados marplatenses: 48 reclusos obtuvieron la libertad asistida o condicional, y 47 el beneficio de prisi\u00f3n domiciliaria. En tanto, se rechazaron 150 pedidos del mismo tipo y restan ser respondidos m\u00e1s de 300. Desde marzo\u2026","rel":"","context":"En \u00abREGIONALES\u00bb","block_context":{"text":"REGIONALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/regionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Screenshot_1-112.jpg?fit=1006%2C696&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Screenshot_1-112.jpg?fit=1006%2C696&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Screenshot_1-112.jpg?fit=1006%2C696&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Screenshot_1-112.jpg?fit=1006%2C696&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/20866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=20866"}],"version-history":[{"count":1,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/20866\/revisions"}],"predecessor-version":[{"id":20868,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/20866\/revisions\/20868"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media\/20867"}],"wp:attachment":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=20866"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=20866"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=20866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}