{"id":2132,"date":"2017-04-26T11:46:57","date_gmt":"2017-04-26T11:46:57","guid":{"rendered":"https:\/\/larevistadigital.com.ar\/blog\/?p=2132"},"modified":"2017-04-26T11:46:57","modified_gmt":"2017-04-26T11:46:57","slug":"comunicado-ucr-chascomus","status":"publish","type":"post","link":"https:\/\/larevistadigital.com.ar\/blog\/comunicado-ucr-chascomus\/","title":{"rendered":"COMUNICADO UCR CHASCOMUS"},"content":{"rendered":"<h2>Desde el Boloque de concejales de UCR-Cambiemos de Chascom\u00fas nos hicieron llegar el siguiente comunicado.<\/h2>\n<p>&nbsp;<\/p>\n<p><strong>INS\u00d3LITO: LOS CONCEJALES DEL \u201cCHAPA\u201d GAST\u00d3N IMPIDEN EL TRATAMIENTO DEL PRESUPUESTO<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Nunca en la historia de los 135 distritos de la Provincia de Buenos Aires, los concejales oficialistas se opusieron al tratamiento de una herramienta tan importante para el Departamento Ejecutivo. Sus propios concejales ponen palos en la rueda.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>El bloque de Concejales de la Uni\u00f3n C\u00edvica Radical manifiesta su asombro y preocupaci\u00f3n por las actitudes obstruccionistas de los concejales que responden al intendente desde el inicio de las sesiones ordinarias, que han impedido de distintas formas el tratamiento del presupuesto, herramientas que el propio intendente y sus funcionarios han exigido en reiteradas oportunidades.<\/p>\n<p>En tal sentido, en la reuni\u00f3n de Comisi\u00f3n de Presupuesto de este lunes, el bloque de concejales de la Uni\u00f3n C\u00edvica Radical en el Frente Cambiemos, acompa\u00f1ado por el Frente para la Victoria, present\u00f3 un nuevo despacho de Presupuesto para el a\u00f1o 2017, que contempla distintos aspectos superadores, incluyendo la realizaci\u00f3n de distintas obras para nuestra ciudad (como la bicisenda para el barrio El Porte\u00f1o y el pavimento de calle Las Heras), as\u00ed como las correcciones que surgieron durante las reuniones que mantuvo el cuerpo con funcionarios del Departamento Ejecutivo, reforzando partidas para la salud, la seguridad, producci\u00f3n, empleo y pol\u00edticas sociales.<\/p>\n<blockquote>\n<h3>Llamativamente, los concejales de Unidad por Chascom\u00fas y el Frente Renovador, no solo no suscribieron este despacho, sino que tampoco firmaron despacho aprobando el proyecto del propio Departamento Ejecutivo.<\/h3>\n<h3>A ello se le suma el hecho de que, en la anterior reuni\u00f3n de la Comisi\u00f3n de Presupuesto del 17 de abril, fueron los mismos concejales oficialistas los que se ausentaron no dando el qu\u00f3rum necesario para el tratamiento del proyecto.<\/h3>\n<\/blockquote>\n<p>Se\u00f1or Intendente, ahora entendemos a qui\u00e9nes estaban dirigidas sus palabras del discurso inaugural del per\u00edodo ordinario del Concejo Deliberante, cuando afirm\u00f3 la necesidad de contar con un instrumento tan importante como lo es el presupuesto.<\/p>\n<p>Intendente <strong>Gast\u00f3n<\/strong>, tome entonces el toro por las astas, y ponga a sus concejales a trabajar.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Desde el Boloque de concejales de UCR-Cambiemos de Chascom\u00fas nos hicieron llegar el siguiente comunicado. &nbsp; INS\u00d3LITO: LOS CONCEJALES DEL \u201cCHAPA\u201d GAST\u00d3N IMPIDEN EL TRATAMIENTO DEL PRESUPUESTO \u00a0 Nunca en la historia de los 135 <a class=\"mh-excerpt-more\" href=\"https:\/\/larevistadigital.com.ar\/blog\/comunicado-ucr-chascomus\/\" title=\"COMUNICADO UCR CHASCOMUS\">[Leer M\u00e1s]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":2134,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[6,41,12],"tags":[],"class_list":{"0":"post-2132","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-chascomus","8":"category-destacadas","9":"category-politica"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/04\/11028007_733884126732360_7999233073238367143_n.jpg?fit=650%2C488&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8qtrQ-yo","jetpack-related-posts":[{"id":13598,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-asumieron-los-nuevos-concejales-con-la-presencia-del-intendente-y-su-gabinete\/","url_meta":{"origin":2132,"position":0},"title":"CHASCOM\u00daS: ASUMIERON LOS NUEVOS CONCEJALES CON LA PRESENCIA DEL INTENDENTE Y SU GABINETE","author":"Alejandro Sosa Ruda","date":"10 diciembre, 2019","format":false,"excerpt":"Esta ma\u00f1ana, en el marco de celebrarse 36 a\u00f1os de la Restauraci\u00f3n de la Democracia, el Intendente Municipal se hizo presente en el Honorable Concejo Deliberante para compartir la sesi\u00f3n de despedida de los concejales salientes y de asunci\u00f3n de los entrantes. Como lo adelant\u00f3 La Revista Digital, fue elegido\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/80365766_2855415971145936_5407380846619394048_o.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/80365766_2855415971145936_5407380846619394048_o.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/80365766_2855415971145936_5407380846619394048_o.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/80365766_2855415971145936_5407380846619394048_o.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/80365766_2855415971145936_5407380846619394048_o.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":29730,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-familias-convocan-a-una-marcha-al-concejo-deliberante-el-proximo-jueves-contra-el-veto-de-una-ordenanza-por-parte-del-intendente-gaston\/","url_meta":{"origin":2132,"position":1},"title":"CHASCOM\u00daS: FAMILIAS CONVOCAN A UNA MARCHA AL CONCEJO DELIBERANTE EL PR\u00d3XIMO JUEVES CONTRA EL VETO DE UNA ORDENANZA POR PARTE DEL INTENDENTE GAST\u00d3N","author":"Alejandro Sosa Ruda","date":"10 enero, 2023","format":false,"excerpt":"Son 370 familias que se ven impedidas de construir su vivienda, por un capricho del Gobierno Local, que pese a ser \"Cooperativistas\" los trata como si fueran un \"Barrio Privado\" y no solo no colabora con las familias, sino que adem\u00e1s pone todo tipo de trabas que impiden que accedan\u2026","rel":"","context":"En \u00abDESTACADAS\u00bb","block_context":{"text":"DESTACADAS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/destacadas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2023-01-10-200118.jpg?fit=727%2C411&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2023-01-10-200118.jpg?fit=727%2C411&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2023-01-10-200118.jpg?fit=727%2C411&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2023-01-10-200118.jpg?fit=727%2C411&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":29509,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-el-gobierno-local-participo-de-una-reunion-con-los-concejales-y-prometio-ambiciosas-obras\/","url_meta":{"origin":2132,"position":2},"title":"CHASCOM\u00daS: EL GOBIERNO LOCAL PARTICIP\u00d3 DE UNA REUNI\u00d3N CON LOS CONCEJALES Y PROMETI\u00d3 AMBICIOSAS OBRAS","author":"Alejandro Sosa Ruda","date":"16 diciembre, 2022","format":false,"excerpt":"La reuni\u00f3n se hizo en el marco de una reuni\u00f3n plenaria del Deliberativo local. CHASCOM\u00daS -\u00a0\u00a0El Secretario de Gobierno, Cipriano P\u00e9rez del Cerro, junto al de Hacienda, Juan Fecundo Alfons\u00edn y a la Directora de Presupuesto, Natalia Vanni fueron de la partida en una reuni\u00f3n plenaria del Concejo Deliberante, donde\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/PRESUPUESTO-1.jpg?fit=900%2C557&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/PRESUPUESTO-1.jpg?fit=900%2C557&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/PRESUPUESTO-1.jpg?fit=900%2C557&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/PRESUPUESTO-1.jpg?fit=900%2C557&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":6125,"url":"https:\/\/larevistadigital.com.ar\/blog\/destacable-gesto-del-intendente-de-chascomus-javier-gaston-y-su-bloque-de-concejales\/","url_meta":{"origin":2132,"position":3},"title":"DESTACABLE GESTO DEL INTENDENTE DE CHASCOM\u00daS, JAVIER GAST\u00d3N Y SU BLOQUE DE CONCEJALES","author":"Alejandro Sosa Ruda","date":"3 agosto, 2018","format":false,"excerpt":"El intendente de Chascom\u00fas, Javier Gast\u00f3n y el bloque de concejales de Unidad por Chascom\u00fas, se hicieron presentes en el Congreso Nacional a efectos de apoyar a los Bomberos Voluntarios de la ciudad y el pa\u00eds en su reclamo para que no se quiten los subsidios para el equipamiento y\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/08\/Screenshot_1.jpg?fit=670%2C556&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/08\/Screenshot_1.jpg?fit=670%2C556&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/08\/Screenshot_1.jpg?fit=670%2C556&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":10209,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-urgente-pedido-de-informes-el-intendente-debera-responder-en-cinco-dias-por-la-defraudacion-de-uno-de-los-directores-del-hospital-municipal\/","url_meta":{"origin":2132,"position":4},"title":"CHASCOM\u00daS: URGENTE PEDIDO DE INFORMES. EL INTENDENTE DEBER\u00c1 RESPONDER EN CINCO D\u00cdAS POR LA DEFRAUDACI\u00d3N DE UNO DE LOS DIRECTORES DEL HOSPITAL MUNICIPAL","author":"Alejandro Sosa Ruda","date":"15 mayo, 2019","format":false,"excerpt":"Los concejales presentaron un pedido de informes para que se expliqu\u00e9 desde cu\u00e1ndo se conoce esta situaci\u00f3n, y qu\u00e9 medidas se han tomado. Luego de la nota que fue primicia de La Revista Digital el d\u00eda de ayer, y repercuti\u00f3 hoy en todos los medios locales, e inclusive en medios\u2026","rel":"","context":"En \u00abDESTACADAS\u00bb","block_context":{"text":"DESTACADAS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/destacadas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2019\/05\/WhatsApp-Image-2019-05-12-at-14.44.jpg?fit=675%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2019\/05\/WhatsApp-Image-2019-05-12-at-14.44.jpg?fit=675%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2019\/05\/WhatsApp-Image-2019-05-12-at-14.44.jpg?fit=675%2C1200&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":3040,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-comunicado-del-bloque-de-ucr-cambiemos\/","url_meta":{"origin":2132,"position":5},"title":"CHASCOM\u00daS: COMUNICADO DEL BLOQUE DE UCR-CAMBIEMOS","author":"Alejandro Sosa Ruda","date":"10 agosto, 2017","format":false,"excerpt":"La actitud de los funcionarios municipales no contribuye a un di\u00e1logo constructivo En horas de la ma\u00f1ana del d\u00eda mi\u00e9rcoles, luego de que el Concejo Deliberante hubiera aprobado tres comunicaciones sin que existiera alg\u00fan tipo de respuesta por parte del Departamento Ejecutivo, lo que motiv\u00f3 una convocatoria por decreto ante\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/08\/ucr_14dediciembrede2016_elfuerte.jpg?fit=709%2C426&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/08\/ucr_14dediciembrede2016_elfuerte.jpg?fit=709%2C426&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/08\/ucr_14dediciembrede2016_elfuerte.jpg?fit=709%2C426&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/08\/ucr_14dediciembrede2016_elfuerte.jpg?fit=709%2C426&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/2132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=2132"}],"version-history":[{"count":2,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/2132\/revisions"}],"predecessor-version":[{"id":2136,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/2132\/revisions\/2136"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media\/2134"}],"wp:attachment":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=2132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=2132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=2132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}