{"id":21970,"date":"2021-09-14T19:25:12","date_gmt":"2021-09-14T19:25:12","guid":{"rendered":"https:\/\/larevistadigital.com.ar\/blog\/?p=21970"},"modified":"2021-09-14T19:25:12","modified_gmt":"2021-09-14T19:25:12","slug":"flavio-ponce-ahora-todos-quieren-salir-en-la-foto-pero-el-radicalismo-fue-la-columna-vertebral-del-triunfo-en-las-paso","status":"publish","type":"post","link":"https:\/\/larevistadigital.com.ar\/blog\/flavio-ponce-ahora-todos-quieren-salir-en-la-foto-pero-el-radicalismo-fue-la-columna-vertebral-del-triunfo-en-las-paso\/","title":{"rendered":"FLAVIO PONCE: \u00abAHORA TODOS QUIEREN SALIR EN LA FOTO, PERO EL RADICALISMO FUE LA COLUMNA VERTEBRAL DEL TRI\u00daNFO EN LAS PASO\u00bb"},"content":{"rendered":"<h2>Luego de la victoria en las PASO, apareci\u00f3 la primera pol\u00e9mica, pero en el espacio que menos se pensaba: JUNTOS.<\/h2>\n<p><strong>CHASCOM\u00daS &#8211;<\/strong> \u00a0Sucedi\u00f3 que el Presidente del Comit\u00e9 de la UCR de Chascom\u00fas, <strong>Flavio Danilo Ponce<\/strong>, hizo una publicaci\u00f3n en su cuenta personal de facebook, donde efect\u00faa un an\u00e1lisis de los resultados y titula: <strong>\u00abEN CHASCOMUS SE IMPUSO MANES Y LA UCR TRIUNFO SOBRE EL PRO Y EL KIRCHNERISMO SIENDO EL PARTIDO MAS VOTADO EN EL PUEBLO\u00bb.<\/strong><\/p>\n<p>En la publicaci\u00f3n, Ponce hace referencia al triunfo de la UCR, sin mencionar al GEN de <strong>Margarita Solbizer<\/strong>, ni al Partido del Di\u00e1logo de <strong>Emilio Monz\u00f3<\/strong> que tambi\u00e9n fueron de la partida.<\/p>\n<blockquote>\n<h3>Esto, puso de muy mal humor a distintos actores de los partidos referenciados, como tambi\u00e9n a propios, que recriminan la acci\u00f3n \u00abinconsulta\u00bb de Ponce, ya que aunque haya publicado en su cuenta personal, al ejercer el cargo de Presidente del Partido, deja involucrados a todos los radicales. (Hasta el mismo Javier Gast\u00f3n en una nota habr\u00eda manifestado que \u00ablos radicales se est\u00e1n adjudicando el triunfo\u00bb)<\/h3>\n<\/blockquote>\n<p>Consultado por <strong>Alejandro \u00abEl Tano\u00bb Sosa y Carlos Lasserre<\/strong> en el programa <strong>\u00abAtaque de Radio\u00bb que se emite de lunes a viernes por FM ACTIVA (93,1 mhtz), Ponce<\/strong> no solo redobl\u00f3 la apuesta, sino que dijo no arrepentirse de lo que hab\u00eda escrito, agregando que <strong><em>\u00abAhora algunos quieren salir en la foto, pero el radicalismo fue el art\u00edfice y la columna vertebral del triunfo\u00bb.\u00a0<\/em><\/strong><\/p>\n<blockquote>\n<h3><strong>Ponce<\/strong>, continu\u00f3 diciendo que <em><strong>\u00abPrimero hay que decir que en el \u00fanico caso que hubo internas fue entre el radicalismo y el PRO, y esa pulseada la gan\u00f3 en Chascom\u00fas Manes con much\u00edsima claridad, y que queda muy claro que fuimos los que mayor cantidad de votos le aportamos al triunfo de Ferrante. Adem\u00e1s en la elecci\u00f3n, no solo le ganamos al PRO, sino que adem\u00e1s la UCR sac\u00f3 m\u00e1s votos que el Frente de Todos\u00bb.<\/strong><\/em><\/h3>\n<\/blockquote>\n<p>Mencion\u00f3 que <em><strong>\u00abPor ah\u00ed hay gente que este triunfo del radicalismo le molesta, o quieren verlo en otro lugar, mientras nosotros queremos verlo en el lugar que obtuvo\u00bb, y agreg\u00f3 \u00abAc\u00e1 hubo una lista que encabez\u00f3 Facundo Manes, y no se niega que estuvo Monz\u00f3 y Stolbizer, pero convengamos que quien puso la estructura fue la UCR, que compiti\u00f3 con el PRO\u00bb.<\/strong><\/em><\/p>\n<blockquote>\n<h3>A su vez se pregunt\u00f3 <em><strong>\u00ab\u00bfPorqu\u00e9 no puedo festejar que el radicalismo le gan\u00f3 las paso al PRO en Chascom\u00fas? no veo que eso tenga que molestar a nadie ni provoque rupturas. Es el resultado que sali\u00f3\u00bb<\/strong><\/em>. Y dispar\u00f3<strong><em> \u00abA muchos les conviene negar a la Uni\u00f3n C\u00edvica Radical, porque no les conviene que el partido crezca, mientras que nosotros trabajamos para que s\u00ed lo haga\u00bb<\/em><\/strong><\/h3>\n<\/blockquote>\n<p><em><strong>\u00abCada uno tiene libertad de opinar lo que quiere. Yo hice un an\u00e1lisis personal en mi red social, y cualquiera puede estar de acuerdo o no. Yo no saqu\u00e9 un comunicado\u00bb<\/strong><\/em>, agreg\u00f3.<\/p>\n<p>Termin\u00f3 diciendo que <strong><em>\u00abNo me arrepiento de lo que escrib\u00ed, porque a veces esos son los n\u00fameros que se quieren esconder. Somos la columna vertebral del armado local, y hemos aportado la mayor\u00eda de votos en el triunfo de Ramiro. Y eso est\u00e1 comprobado por las listas de diputados donde la UCR le gan\u00f3 la interna al PRO, y sac\u00f3 m\u00e1s votos que el Frente de Todos\u00bb.<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Luego de la victoria en las PASO, apareci\u00f3 la primera pol\u00e9mica, pero en el espacio que menos se pensaba: JUNTOS. CHASCOM\u00daS &#8211; \u00a0Sucedi\u00f3 que el Presidente del Comit\u00e9 de la UCR de Chascom\u00fas, Flavio Danilo <a class=\"mh-excerpt-more\" href=\"https:\/\/larevistadigital.com.ar\/blog\/flavio-ponce-ahora-todos-quieren-salir-en-la-foto-pero-el-radicalismo-fue-la-columna-vertebral-del-triunfo-en-las-paso\/\" title=\"FLAVIO PONCE: \u00abAHORA TODOS QUIEREN SALIR EN LA FOTO, PERO EL RADICALISMO FUE LA COLUMNA VERTEBRAL DEL TRI\u00daNFO EN LAS PASO\u00bb\">[Leer M\u00e1s]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":17712,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[50,12,23],"tags":[],"class_list":{"0":"post-21970","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-interes-general","8":"category-politica","9":"category-politica-local"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/FLAVIO-PONCE-1.jpg?fit=1000%2C1195&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8qtrQ-5Im","jetpack-related-posts":[{"id":44049,"url":"https:\/\/larevistadigital.com.ar\/blog\/fuerte-embestida-interna-en-la-ucr-chascomus-flavio-ponce-hablo-de-entregadores-y-cuestiono-el-respaldo-a-milei\/","url_meta":{"origin":21970,"position":0},"title":"Fuerte embestida interna en la UCR Chascom\u00fas: Flavio Ponce habl\u00f3 de \u201centregadores\u201d y cuestion\u00f3 el respaldo a Milei","author":"Alejandro Sosa Ruda","date":"20 febrero, 2026","format":false,"excerpt":"El dirigente radical Flavio Ponce expres\u00f3 su malestar con sectores de su propio partido a nivel local y nacional. Apunt\u00f3 contra la conducci\u00f3n, cuestion\u00f3 el acompa\u00f1amiento a la reforma laboral y denunci\u00f3 pr\u00e1cticas que, seg\u00fan afirm\u00f3, vac\u00edan de contenido al radicalismo. 20 de febrero de 2026 CHASCOM\u00daS\u00a0 -\u00a0 \u00a0El vocal\u2026","rel":"","context":"En \u00abDESTACADAS\u00bb","block_context":{"text":"DESTACADAS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/destacadas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-02-20-005443.jpg?fit=845%2C476&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-02-20-005443.jpg?fit=845%2C476&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-02-20-005443.jpg?fit=845%2C476&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-02-20-005443.jpg?fit=845%2C476&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":4209,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-secretario-general-la-ucr-aseguro-la-anomalia-cometida-casalins-morena-puede-llevada-al-comite-provincia\/","url_meta":{"origin":21970,"position":1},"title":"CHASCOM\u00daS: EL SECRETARIO GENERAL DE LA UCR ASEGUR\u00d3 QUE LA ANOMAL\u00cdA COMETIDA POR CASALINS Y EL MORENA, PUEDE SER LLEVADA AL COMIT\u00c9 PROVINCIA","author":"Alejandro Sosa Ruda","date":"13 diciembre, 2017","format":false,"excerpt":"En di\u00e1logo con el programa AM Show que se emite por la FM 101,5 el Secretario General de la UCR, Flavio Ponce se refiri\u00f3 a la publicaci\u00f3n que hizo en su perfil personal de Facebook, criticando con dureza a Osvaldo Casalins, y el espacio que representa por su comportamiento durante\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/12\/18278317_10212938092109948_2099445239619507510_o.jpg?fit=1012%2C601&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/12\/18278317_10212938092109948_2099445239619507510_o.jpg?fit=1012%2C601&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/12\/18278317_10212938092109948_2099445239619507510_o.jpg?fit=1012%2C601&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/12\/18278317_10212938092109948_2099445239619507510_o.jpg?fit=1012%2C601&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":16666,"url":"https:\/\/larevistadigital.com.ar\/blog\/video-las-diez-preguntas-de-la-revista-digital-hoy-flavio-ponce-proximo-presidente-de-la-ucr-de-chascomus\/","url_meta":{"origin":21970,"position":2},"title":"[VIDEO] LAS DIEZ PREGUNTAS DE LA REVISTA DIGITAL: HOY FLAVIO PONCE, PROXIMO PRESIDENTE DE LA UCR DE CHASCOM\u00daS","author":"Alejandro Sosa Ruda","date":"2 octubre, 2020","format":false,"excerpt":"Extrenamos una nueva secci\u00f3n semanal, que se trata de una especie de ping pong de 10 preguntas en video, a distintos personajes de actualidad. Hoy empezamos con quien presidir\u00e1 la UCR de Chascom\u00fas, Flavio Ponce, que se prest\u00f3 a la requisitoria. Aqu\u00ed el video, que adem\u00e1s subimos a nuestro canal\u2026","rel":"","context":"En \u00abDESTACADAS\u00bb","block_context":{"text":"DESTACADAS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/destacadas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/FLAVIO-PONCE-REPORTAJE.jpg?fit=1000%2C1007&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/FLAVIO-PONCE-REPORTAJE.jpg?fit=1000%2C1007&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/FLAVIO-PONCE-REPORTAJE.jpg?fit=1000%2C1007&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/FLAVIO-PONCE-REPORTAJE.jpg?fit=1000%2C1007&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":4194,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-implosiono-la-ucr-lapidaria-carta-del-secretario-general-la-ucr-alfonsinismo\/","url_meta":{"origin":21970,"position":3},"title":"CHASCOM\u00daS: \u00bfIMPLOSION\u00d3 LA UCR?&#8230; LAPIDARIA CARTA DEL SECRETARIO GENERAL DE LA UCR CONTRA EL ALFONSINISMO","author":"Alejandro Sosa Ruda","date":"12 diciembre, 2017","format":false,"excerpt":"Luego de la puja por la presidencia del Concejo Deliberante, el Secretario General de la Uni\u00f3n C\u00edvica Radical, Flavio Ponce escribi\u00f3 un comunicado que a continuaci\u00f3n reproducimos, en el que muestra su indignaci\u00f3n para con sus \"correligionarios\" del MORENA, sector que responde a la diputada Liliana Denot, y al dirigente\u2026","rel":"","context":"En \u00abDESTACADAS\u00bb","block_context":{"text":"DESTACADAS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/destacadas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/12\/15540655_10211551417163941_5225436794095271720_o.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/12\/15540655_10211551417163941_5225436794095271720_o.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/12\/15540655_10211551417163941_5225436794095271720_o.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/12\/15540655_10211551417163941_5225436794095271720_o.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/12\/15540655_10211551417163941_5225436794095271720_o.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":39160,"url":"https:\/\/larevistadigital.com.ar\/blog\/si-se-arma-otro-partido-deberia-renunciar-a-su-banca-flavio-ponce-critico-la-jugada-de-redruello-y-ferrante\/","url_meta":{"origin":21970,"position":4},"title":"\u00abSi se arma otro partido, deber\u00eda renunciar a su banca\u00bb:  Flavio Ponce critic\u00f3 la jugada de Redruello y Ferrante","author":"Alejandro Sosa Ruda","date":"27 marzo, 2025","format":false,"excerpt":"Flavio Ponce, fue muy duro con respecto a la decisi\u00f3n de Valentino Redruello y Ramiro Ferrante de armar un vecinalismo, afirmando que la banca le pertenece al partido. 27 de Marzo de 2023 CHASCOM\u00daS -\u00a0 \u00a0El dirigente radical y aspirante a concejal Flavio \u201cEl Bocha\u201d Ponce se sum\u00f3 al debate\u2026","rel":"","context":"En \u00abINTERES GENERAL\u00bb","block_context":{"text":"INTERES GENERAL","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/interes-general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2025-03-27-201407.jpg?fit=840%2C478&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2025-03-27-201407.jpg?fit=840%2C478&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2025-03-27-201407.jpg?fit=840%2C478&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2025-03-27-201407.jpg?fit=840%2C478&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":40212,"url":"https:\/\/larevistadigital.com.ar\/blog\/flavio-ponce-marco-la-cancha-el-radicalismo-no-va-a-negociar-con-milei-ni-con-el-kirchnerismo\/","url_meta":{"origin":21970,"position":5},"title":"Flavio Ponce marc\u00f3 la cancha: \u201cEl radicalismo no va a negociar con Milei ni con el kirchnerismo\u201d","author":"Alejandro Sosa Ruda","date":"29 junio, 2025","format":false,"excerpt":"El referente de la UCR en Chascom\u00fas fue categ\u00f3rico al rechazar acuerdos con La Libertad Avanza. Reivindic\u00f3 la identidad partidaria, defendi\u00f3 a las autoridades del Comit\u00e9 local y adelant\u00f3 nombres de cara a las elecciones. 29 de Junio de 2025 CHASCOM\u00daS\u00a0 -\u00a0 \u00a0 El dirigente radical Flavio Ponce dej\u00f3 en\u2026","rel":"","context":"En \u00abINTERES GENERAL\u00bb","block_context":{"text":"INTERES GENERAL","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/interes-general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2025-06-29-221503.jpg?fit=801%2C486&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2025-06-29-221503.jpg?fit=801%2C486&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2025-06-29-221503.jpg?fit=801%2C486&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2025-06-29-221503.jpg?fit=801%2C486&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/21970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=21970"}],"version-history":[{"count":1,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/21970\/revisions"}],"predecessor-version":[{"id":21971,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/21970\/revisions\/21971"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media\/17712"}],"wp:attachment":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=21970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=21970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=21970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}