{"id":22056,"date":"2021-09-20T03:24:26","date_gmt":"2021-09-20T03:24:26","guid":{"rendered":"https:\/\/larevistadigital.com.ar\/blog\/?p=22056"},"modified":"2021-09-20T03:24:26","modified_gmt":"2021-09-20T03:24:26","slug":"115-millones-para-tres-ganadores-del-quini-6","status":"publish","type":"post","link":"https:\/\/larevistadigital.com.ar\/blog\/115-millones-para-tres-ganadores-del-quini-6\/","title":{"rendered":"115 MILLONES PARA TRES GANADORES DEL QUINI 6"},"content":{"rendered":"<h2>Dos apostadores registraron seis aciertos en la modalidad Tradicional y otro meti\u00f3 los seis en el Siempre Sale.<\/h2>\n<p>Tres apostadores que registraron seis aciertos en distintas modalidades del sorteo del\u00a0<strong>Quini 6<\/strong>\u00a0realizado este domingo se repartir\u00e1n un pozo de casi 115 millones de pesos.<\/p>\n<p>En la jugada Tradicional dos apostadores metieron las seis coincidencias con los n\u00fameros 02, 11, 12, 19, 23 y 35.<\/p>\n<p>Cada uno de ellos se hizo acreedor a un premio de $ 55.476.502, a los que habr\u00e1 que descontarle los impuestos al momento del cobro.<\/p>\n<p>Adem\u00e1s, en la modalidad Siempre Sale, otro apostador registr\u00f3 seis aciertos con las bolillas 00, 17, 20, 29, 36 y 38 y percibir\u00e1 un premio de $ 13.429.791.<\/p>\n<p><strong>Tradicional<\/strong><\/p>\n<p>02 11 12 19 23 35<\/p>\n<p>6 aciertos: 2 ganadores ($ 55.476.502)<br \/>\n5 aciertos: 96 ganadores ($ 21.837)<br \/>\n4 aciertos: 3817 ganadores ($ 164)<\/p>\n<p><strong>Segunda vuelta<\/strong><\/p>\n<p>01 08 18 25 36 41<\/p>\n<p>6 aciertos: Vacante ($ 35.000.000)<br \/>\n5 aciertos: 66 ganadores ($ 31.763)<br \/>\n4 aciertos: 2414 ganadores ($ 260)<\/p>\n<p><strong>Revancha<\/strong><\/p>\n<p>00 01 05 18 35 41<\/p>\n<p>6 aciertos: Vacante ($ 83.512.996)<\/p>\n<p><strong>Siempre Sale<\/strong><\/p>\n<p>00 17 20 29 36 38<\/p>\n<p>6 aciertos: 1 ganador ($ 13.429.791)<\/p>\n<p><strong>Pozo extra<\/strong><\/p>\n<p>872 ganadores ($ 8.601)<\/p>\n<p>&nbsp;<\/p>\n<p>Pozo estimado para el pr\u00f3ximo sorteo: $ 201.000.000.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Dos apostadores registraron seis aciertos en la modalidad Tradicional y otro meti\u00f3 los seis en el Siempre Sale. Tres apostadores que registraron seis aciertos en distintas modalidades del sorteo del\u00a0Quini 6\u00a0realizado este domingo se repartir\u00e1n <a class=\"mh-excerpt-more\" href=\"https:\/\/larevistadigital.com.ar\/blog\/115-millones-para-tres-ganadores-del-quini-6\/\" title=\"115 MILLONES PARA TRES GANADORES DEL QUINI 6\">[Leer M\u00e1s]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":22057,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[50],"tags":[],"class_list":{"0":"post-22056","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-interes-general"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/QUINI.jpg?fit=957%2C536&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8qtrQ-5JK","jetpack-related-posts":[{"id":22175,"url":"https:\/\/larevistadigital.com.ar\/blog\/mas-de-58-millones-para-un-ganador-del-quini-6\/","url_meta":{"origin":22056,"position":0},"title":"MAS DE 58 MILLONES PARA UN GANADOR DEL QUINI 6","author":"Alejandro Sosa Ruda","date":"30 septiembre, 2021","format":false,"excerpt":"Un apostador que registr\u00f3 seis aciertos en la modalidad Segunda Vuelta se qued\u00f3 con un pozo millonario. Un apostador que registr\u00f3 seis aciertos en la\u00a0Segunda Vuelta del Quini Seis\u00a0se hizo acreedor a un pozo de m\u00e1s de\u00a058 millones de pesos\u00a0en el sorteo realizado este mi\u00e9rcoles 29 de septiembre. El afortunado\u2026","rel":"","context":"En \u00abINTERES GENERAL\u00bb","block_context":{"text":"INTERES GENERAL","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/interes-general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/el-joven-que-asegura-haber-descifrado-como-viralizar-un-video-en-youtube-y-gana-millones.jpg?fit=1201%2C740&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/el-joven-que-asegura-haber-descifrado-como-viralizar-un-video-en-youtube-y-gana-millones.jpg?fit=1201%2C740&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/el-joven-que-asegura-haber-descifrado-como-viralizar-un-video-en-youtube-y-gana-millones.jpg?fit=1201%2C740&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/el-joven-que-asegura-haber-descifrado-como-viralizar-un-video-en-youtube-y-gana-millones.jpg?fit=1201%2C740&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/el-joven-que-asegura-haber-descifrado-como-viralizar-un-video-en-youtube-y-gana-millones.jpg?fit=1201%2C740&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":27332,"url":"https:\/\/larevistadigital.com.ar\/blog\/gano-333-000-000-con-los-seis-numeros-del-sorteo-tradicional-del-quini-6\/","url_meta":{"origin":22056,"position":1},"title":"GAN\u00d3 $333.000.000.- CON LOS SEIS N\u00daMEROS DEL SORTEO TRADICIONAL DEL QUINI 6","author":"Alejandro Sosa Ruda","date":"29 agosto, 2022","format":false,"excerpt":"El nuevo millonario compr\u00f3 su ticket en una agencia de Gobernador Crespo, provincia de Santa Fe y se qued\u00f3 con los $ 333.483.042 en juego. Fue el \u00fanico ganador. 29 de agosto de 2022 No se llev\u00f3 el pozo r\u00e9cord de casi 787 millones de pesos al que se hizo\u2026","rel":"","context":"En \u00abINTERES GENERAL\u00bb","block_context":{"text":"INTERES GENERAL","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/interes-general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/5FPM66DVXNGZLEE32AY3B52OXU.jpg?fit=1023%2C682&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/5FPM66DVXNGZLEE32AY3B52OXU.jpg?fit=1023%2C682&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/5FPM66DVXNGZLEE32AY3B52OXU.jpg?fit=1023%2C682&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/5FPM66DVXNGZLEE32AY3B52OXU.jpg?fit=1023%2C682&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":16564,"url":"https:\/\/larevistadigital.com.ar\/blog\/teleafortunado-gano-mas-de-16-millones-en-el-telekino\/","url_meta":{"origin":22056,"position":2},"title":"TELEAFORTUNADO!!!!!! GAN\u00d3 M\u00c1S DE 16 MILLONES EN EL TELEKINO","author":"Alejandro Sosa Ruda","date":"27 septiembre, 2020","format":false,"excerpt":"El sorteo se realiz\u00f3 este domingo y el afortunado, que registr\u00f3 las quince coincidencias necesarias, se hizo acreedor a un pozo de $ 16.308.946. Un apostador que registr\u00f3 quince aciertos se qued\u00f3 con el pozo principal del\u00a0Telekino\u00a0sorteado este domingo. En efecto, el afortunado meti\u00f3 coincidencia plena con los n\u00fameros sorteados:\u2026","rel":"","context":"En \u00abINTERES GENERAL\u00bb","block_context":{"text":"INTERES GENERAL","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/interes-general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Screenshot_2-103.jpg?fit=747%2C434&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Screenshot_2-103.jpg?fit=747%2C434&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Screenshot_2-103.jpg?fit=747%2C434&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Screenshot_2-103.jpg?fit=747%2C434&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":17745,"url":"https:\/\/larevistadigital.com.ar\/blog\/una-persona-de-mar-del-plata-gano-el-quini-6-y-obtuvo-17-millones-de-pesos\/","url_meta":{"origin":22056,"position":3},"title":"UNA PERSONA DE MAR DEL PLATA GAN\u00d3 EL QUINI 6 Y OBTUVO 17 MILLONES DE PESOS","author":"Alejandro Sosa Ruda","date":"19 noviembre, 2020","format":false,"excerpt":"MAR DEL PLATA - Un hombre de Mar del Plata se hizo millonario de la noche a la ma\u00f1ana con el Quini 6. Apost\u00f3 a 6 n\u00fameros de este tradicional sorteo y gan\u00f3 17 millones de pesos. El ganador de la modalidad Revancha del Quini 6 escogi\u00f3 los siguientes n\u00fameros:\u2026","rel":"","context":"En \u00abREGIONALES\u00bb","block_context":{"text":"REGIONALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/regionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/quini-6-bolillero.jpg?fit=696%2C464&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/quini-6-bolillero.jpg?fit=696%2C464&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/quini-6-bolillero.jpg?fit=696%2C464&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":40290,"url":"https:\/\/larevistadigital.com.ar\/blog\/mar-del-plata-gano-800-millones-en-el-quini-6-y-no-estaba-enterado\/","url_meta":{"origin":22056,"position":4},"title":"Mar del Plata: Gan\u00f3 800 millones en el \u201cQuini 6\u201d, y no estaba enterado","author":"Alejandro Sosa Ruda","date":"2 julio, 2025","format":false,"excerpt":"Luego de varios d\u00edas de incertidumbre, finalmente se conoci\u00f3 la identidad del afortunado ganador del Quini 6: se trata de un alba\u00f1il de alrededor de 50 a\u00f1os, oriundo de Mar del Plata. Sin saber que hab\u00eda acertado los seis n\u00fameros, el hombre se present\u00f3 este lunes en la agencia donde\u2026","rel":"","context":"En \u00abREGIONALES\u00bb","block_context":{"text":"REGIONALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/regionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20250702171620_albanil-marplatense-ganador-quini-6.jpg?fit=880%2C512&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20250702171620_albanil-marplatense-ganador-quini-6.jpg?fit=880%2C512&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20250702171620_albanil-marplatense-ganador-quini-6.jpg?fit=880%2C512&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20250702171620_albanil-marplatense-ganador-quini-6.jpg?fit=880%2C512&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":30980,"url":"https:\/\/larevistadigital.com.ar\/blog\/crisis-roja-doman-renuncio-a-la-presidencia-de-independiente\/","url_meta":{"origin":22056,"position":5},"title":"CRISIS ROJA: DOMAN RENUNCI\u00d3 A LA PRESIDENCIA DE INDEPENDIENTE","author":"Alejandro Sosa Ruda","date":"11 abril, 2023","format":false,"excerpt":"Fabi\u00e1n Doman duro apenas unos seis meses en el cargo. \"No se encontraron las herramientas para ayudar a Independiente\", expres\u00f3 en un comunicado. 11 de abril de 2023 El periodista\u00a0Fabi\u00e1n Doman, que asumi\u00f3 como presidente del Club Atl\u00e9tico Independiente el 6 de octubre del 2022, renunci\u00f3 esta tarde a su\u2026","rel":"","context":"En \u00abDEPORTES\u00bb","block_context":{"text":"DEPORTES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/deportes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/DOMAN-1.jpg?fit=700%2C383&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/DOMAN-1.jpg?fit=700%2C383&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/DOMAN-1.jpg?fit=700%2C383&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/DOMAN-1.jpg?fit=700%2C383&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/22056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=22056"}],"version-history":[{"count":1,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/22056\/revisions"}],"predecessor-version":[{"id":22058,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/22056\/revisions\/22058"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media\/22057"}],"wp:attachment":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=22056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=22056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=22056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}