{"id":22614,"date":"2021-11-09T03:15:43","date_gmt":"2021-11-09T03:15:43","guid":{"rendered":"https:\/\/larevistadigital.com.ar\/blog\/?p=22614"},"modified":"2021-11-09T03:15:43","modified_gmt":"2021-11-09T03:15:43","slug":"rescate-aparecio-un-pequeno-lobo-marino-en-las-costas-de-berisso","status":"publish","type":"post","link":"https:\/\/larevistadigital.com.ar\/blog\/rescate-aparecio-un-pequeno-lobo-marino-en-las-costas-de-berisso\/","title":{"rendered":"RESCATE: APARECI\u00d3 UN PEQUE\u00d1O LOBO MARINO EN LAS COSTAS DE BERISSO"},"content":{"rendered":"<h2 class=\"fparrafo ctext fz18 lh25\">Este domingo por la tarde, vecinos de la ciudad de Berisso que disfrutaban de una jornada espl\u00e9ndida en la rivera del r\u00edo, avistaron a un peque\u00f1o lobo marino, que con dificultad intentaba acercarse a la playa. Fue rescatado por personal de Defensa Civil del municipio.<\/h2>\n<p><strong>BERISSO\u00a0 &#8211;\u00a0<\/strong><strong>Un peque\u00f1o lobo marino de dos pelos, fue avistado por vecinos de Berisso que disfrutaban del d\u00eda en la zona de <\/strong>Palo Blanco<strong>, cuando con dificultad el animalito intentaba acercarse a la playa.<\/strong><\/p>\n<p class=\"selectionShareable\">Seg\u00fan da cuenta el portal local InfoBerisso, inmediatamente los vecinos llamaron a los servicios de emergencia y fue el personal municipal de Defensa Civil el que arrib\u00f3 raudamente para darle rescate al peque\u00f1o animal.<\/p>\n<p class=\"selectionShareable\">Con alguna dificultad, dicho personal logr\u00f3 retirar al asustado lobito de las aguas del r\u00edo de la Plata, notando que ten\u00eda un collar numerado en su cuello lo que indica que no es el primer contacto con humanos que tiene el animal.<\/p>\n<p class=\"selectionShareable\">Este lunes, el peque\u00f1o mam\u00edfero era custodiado por los agentes locales a la espera de la intervenci\u00f3n de la Direcci\u00f3n de Fauna Provincial o del Organismo Provincial para el Desarrollo Sostenible (OPDS) para efectuar su traslado, a un lugar adecuado para su rehabilitaci\u00f3n.<\/p>\n<p class=\"selectionShareable\">Una fuente del municipio explic\u00f3 que este tipo de animales, \u00abno es poco habitual verlos en aguas de esta zona, porque cuando se presentan eventos clim\u00e1ticos como tormentas, viento sur o crecidas del R\u00edo de La Plata, \u201csi estos animales se encuentran en buenas condiciones regresan sin inconvenientes al cauce del r\u00edo, pero que en caso de hallarse perdidos o enfermos, se quedan en la costa\u00bb. (<b>InfoGEI<\/b>)Jd<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Este domingo por la tarde, vecinos de la ciudad de Berisso que disfrutaban de una jornada espl\u00e9ndida en la rivera del r\u00edo, avistaron a un peque\u00f1o lobo marino, que con dificultad intentaba acercarse a la <a class=\"mh-excerpt-more\" href=\"https:\/\/larevistadigital.com.ar\/blog\/rescate-aparecio-un-pequeno-lobo-marino-en-las-costas-de-berisso\/\" title=\"RESCATE: APARECI\u00d3 UN PEQUE\u00d1O LOBO MARINO EN LAS COSTAS DE BERISSO\">[Leer M\u00e1s]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":22615,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[51],"tags":[],"class_list":{"0":"post-22614","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-regionales"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2021-11-09-001421.jpg?fit=988%2C502&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8qtrQ-5SK","jetpack-related-posts":[{"id":17260,"url":"https:\/\/larevistadigital.com.ar\/blog\/sorpresivo-hallazgo-de-un-lobo-marino-en-la-costa-de-berazategui\/","url_meta":{"origin":22614,"position":0},"title":"SORPRESIVO HALLAZGO DE UN LOBO MARINO EN LA COSTA DE BERAZATEGUI","author":"Alejandro Sosa Ruda","date":"27 octubre, 2020","format":false,"excerpt":"El animal qued\u00f3 al resguardo en una pileta municipal a la espera de ser trasladado a Mundo Marino. Un peque\u00f1o lobo marino apareci\u00f3 en la costa de la localidad bonaerense de Berazategui,\u00a0por lo que tuvo que quedar a resguardo en las piletas de un completo recreativo municipal a la espera\u2026","rel":"","context":"En \u00abREGIONALES\u00bb","block_context":{"text":"REGIONALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/regionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/0038190487.jpg?fit=1140%2C640&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/0038190487.jpg?fit=1140%2C640&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/0038190487.jpg?fit=1140%2C640&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/0038190487.jpg?fit=1140%2C640&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/0038190487.jpg?fit=1140%2C640&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":24247,"url":"https:\/\/larevistadigital.com.ar\/blog\/rescatan-a-pinguino-que-aparecio-en-la-costa-de-berisso\/","url_meta":{"origin":22614,"position":1},"title":"RESCATAN A PING\u00dcINO QUE APARECI\u00d3 EN LA COSTA DE BERISSO","author":"Alejandro Sosa Ruda","date":"27 febrero, 2022","format":false,"excerpt":"Seg\u00fan las primeras informaciones,\u00a0el ping\u00fcino estaba herido, y se desplazaba con dificultad, justo a metros del puesto de vigilancia en el que estaban los agentes Ismael Borean y Cesar Pagano, en la costa de Berisso. Los guardavidas decidieron intervenir:\u00a0hidrataron al animal, le atendieron las heridas y contactaron al personal de\u2026","rel":"","context":"En \u00abREGIONALES\u00bb","block_context":{"text":"REGIONALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/regionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/este-si.jpg?fit=700%2C438&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/este-si.jpg?fit=700%2C438&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/este-si.jpg?fit=700%2C438&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/este-si.jpg?fit=700%2C438&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":26423,"url":"https:\/\/larevistadigital.com.ar\/blog\/prefectura-rescato-un-lobo-marino-en-la-plata\/","url_meta":{"origin":22614,"position":2},"title":"PREFECTURA RESCAT\u00d3 UN LOBO MARINO EN LA PLATA","author":"Alejandro Sosa Ruda","date":"7 julio, 2022","format":false,"excerpt":"Efectivos de la Prefectura Naval Argentina rescataron a un lobo marino peque\u00f1o que apareci\u00f3, desorientado, sobre la escollera del canal de acceso al puerto de La Plata. LA PLATA -\u00a0 La Autoridad Mar\u00edtima fue advertida de la presencia del animal e inmediatamente destac\u00f3 al lugar personal de la Prefectura Isla\u2026","rel":"","context":"En \u00abINTERES GENERAL\u00bb","block_context":{"text":"INTERES GENERAL","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/interes-general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20220706165834_prefectura-naval-rescato-un-lobo-marino-en-la-plata.jpg?fit=880%2C512&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20220706165834_prefectura-naval-rescato-un-lobo-marino-en-la-plata.jpg?fit=880%2C512&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20220706165834_prefectura-naval-rescato-un-lobo-marino-en-la-plata.jpg?fit=880%2C512&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20220706165834_prefectura-naval-rescato-un-lobo-marino-en-la-plata.jpg?fit=880%2C512&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":44511,"url":"https:\/\/larevistadigital.com.ar\/blog\/impactante-hallazgo-en-berisso-encontraron-un-craneo-humano-en-la-playa-de-isla-paulino\/","url_meta":{"origin":22614,"position":3},"title":"Impactante hallazgo en Berisso: encontraron un cr\u00e1neo humano en la playa de Isla Paulino","author":"Alejandro Sosa Ruda","date":"15 marzo, 2026","format":false,"excerpt":"El descubrimiento ocurri\u00f3 en la costa de la Isla Paulino, en Berisso. Vecinos alertaron a la Polic\u00eda tras detectar restos \u00f3seos en la arena. 15 de marzo de 2026 Un hallazgo de\u00a0restos \u00f3seos\u00a0gener\u00f3 un operativo policial durante la tarde del jueves en la\u00a0Isla Paulino, en\u00a0Berisso. Vecinos que recorr\u00edan la zona\u2026","rel":"","context":"En \u00abINTERES GENERAL\u00bb","block_context":{"text":"INTERES GENERAL","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/interes-general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-03-15-011901.jpg?fit=857%2C426&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-03-15-011901.jpg?fit=857%2C426&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-03-15-011901.jpg?fit=857%2C426&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-03-15-011901.jpg?fit=857%2C426&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":45692,"url":"https:\/\/larevistadigital.com.ar\/blog\/sorpresa-y-tension-en-ensenada-un-enorme-elefante-marino-aparecio-en-plena-calle-y-obligo-a-interrumpir-el-transito\/","url_meta":{"origin":22614,"position":4},"title":"[Video] Sorpresa y tensi\u00f3n en Ensenada: un enorme elefante marino apareci\u00f3 en plena calle y oblig\u00f3 a interrumpir el tr\u00e1nsito","author":"Alejandro Sosa Ruda","date":"19 mayo, 2026","format":false,"excerpt":"El animal fue visto en el camino hacia Isla Santiago y gener\u00f3 un amplio operativo de rescate. Vecinos registraron impactantes im\u00e1genes mientras personal de Fauna y Fundaci\u00f3n Temaik\u00e9n intentaba contenerlo. 19 de Mayo de 2026 Momentos de sorpresa y preocupaci\u00f3n se vivieron en la ciudad de Ensenada luego de que\u2026","rel":"","context":"En \u00abREGIONALES\u00bb","block_context":{"text":"REGIONALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/regionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-05-19-221916.jpg?fit=848%2C441&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-05-19-221916.jpg?fit=848%2C441&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-05-19-221916.jpg?fit=848%2C441&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-05-19-221916.jpg?fit=848%2C441&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":25819,"url":"https:\/\/larevistadigital.com.ar\/blog\/lobo-marino-se-quedo-a-vivir-en-san-bernardo\/","url_meta":{"origin":22614,"position":5},"title":"LOBO MARINO SE QUED\u00d3 A VIVIR EN SAN BERNARDO","author":"Alejandro Sosa Ruda","date":"13 junio, 2022","format":false,"excerpt":"Desde hace una semana, los vecinos y visitantes de San Bernardo reciben a diario una grata visita, que al parecer se ha sentido tan c\u00f3modo en las playas de la zona sur del partido de La Costa que ha decidido quedarse por un tiempo. Seg\u00fan indic\u00f3 Melody De Gennaro, Directora\u2026","rel":"","context":"En \u00abMEDIO AMBIENTE\u00bb","block_context":{"text":"MEDIO AMBIENTE","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/suplementos\/medio-ambiente\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20220611140331_elefante-marino-san-bernanrdo.jpg?fit=880%2C512&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20220611140331_elefante-marino-san-bernanrdo.jpg?fit=880%2C512&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20220611140331_elefante-marino-san-bernanrdo.jpg?fit=880%2C512&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20220611140331_elefante-marino-san-bernanrdo.jpg?fit=880%2C512&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/22614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=22614"}],"version-history":[{"count":1,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/22614\/revisions"}],"predecessor-version":[{"id":22616,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/22614\/revisions\/22616"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media\/22615"}],"wp:attachment":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=22614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=22614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=22614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}