{"id":33094,"date":"2023-08-28T20:27:02","date_gmt":"2023-08-28T23:27:02","guid":{"rendered":"https:\/\/larevistadigital.com.ar\/blog\/?p=33094"},"modified":"2023-08-28T20:27:02","modified_gmt":"2023-08-28T23:27:02","slug":"mar-del-plata-asesinan-a-dos-jovenes-en-un-galpon-ajuste-de-cuentas-narco","status":"publish","type":"post","link":"https:\/\/larevistadigital.com.ar\/blog\/mar-del-plata-asesinan-a-dos-jovenes-en-un-galpon-ajuste-de-cuentas-narco\/","title":{"rendered":"MAR DEL PLATA: ASESINAN A DOS JOVENES EN UN GALPON&#8230;\u00bfAJUSTE DE CUENTAS NARCO?"},"content":{"rendered":"<h2 class=\"fparrafo ctext fz18 lh25\">Las v\u00edctimas, identificadas como Franco David Rodr\u00edguez, de 20 a\u00f1os, y Carlos Lucas Leones, de 21, presentaban cortes en su cuerpo, golpes, disparos de arma de fuego y escoriaciones, producto de haber sido arrastrados.<\/h2>\n<p>28 de agosto de 2023<\/p>\n<p><strong>MAR DEL PLATA &#8211;\u00a0<\/strong> El \u00faltimo domingo, dos j\u00f3venes de 20 y 21 a\u00f1os, fueron hallados muertos en un galp\u00f3n del barrio Parque Hermoso de Mar del Plata. Los cuerpos ten\u00edan disparos, cortes y golpes. Por el doble homicidio detuvieron a una pareja e investigan si se trat\u00f3 de un ajuste de cuentas del narcotr\u00e1fico.<\/p>\n<blockquote>\n<h3>El hecho ocurri\u00f3 en un galp\u00f3n en el oeste de Mar del Plata. La polic\u00eda fue alertada por vecinos del lugar, que vieron un taxi en las proximidades y poco despu\u00e9s escucharon gritos y disparos.<\/h3>\n<\/blockquote>\n<p>Pasadas las 7.30 de la ma\u00f1ana, los agentes interceptaron a Eric Eduardo Ezequiel Lazarte, de 27 a\u00f1os, y a Soledad Yanina Brain, de 33. La pareja estaba a metros del lugar donde simult\u00e1neamente hallaban los cad\u00e1veres. Al momento de ser demorado, Lazarte presentaba manchas de sangre en su ropa. Brain, en tanto, intent\u00f3 huir con una mochila con 170mil pesos.<\/p>\n<blockquote>\n<h3>En la vivienda que compart\u00edan encontraron una escopeta 12.70 con pedido de secuestro activo que estaba enterrada, una balanza de precisi\u00f3n y alrededor de 50 gramos de coca\u00edna. Tambi\u00e9n se hallaron varias vainas calibre 22 y nueve mil\u00edmetros, adem\u00e1s de un destornillador que ser\u00e1 peritado.<\/h3>\n<\/blockquote>\n<p>Las v\u00edctimas, identificadas como Franco David Rodr\u00edguez, de 20 a\u00f1os, y Carlos Lucas Leones, de 21, presentaban cortes en su cuerpo, golpes, disparos de arma de fuego y escoriaciones, producto de haber sido arrastrados. Se cree que las v\u00edctimas pelearon con la pareja por un problema relacionado a la venta de drogas y fueron ultimados.<\/p>\n<p>Los detenidos deber\u00e1n declarar ante la fiscal Andrea G\u00f3mez acerca de lo sucedido. El galp\u00f3n donde aparecieron los cuerpos hab\u00eda sido investigado tiempo atr\u00e1s como punto de venta de drogas. (<b>InfoGEI<\/b>) Mg<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Las v\u00edctimas, identificadas como Franco David Rodr\u00edguez, de 20 a\u00f1os, y Carlos Lucas Leones, de 21, presentaban cortes en su cuerpo, golpes, disparos de arma de fuego y escoriaciones, producto de haber sido arrastrados. 28 <a class=\"mh-excerpt-more\" href=\"https:\/\/larevistadigital.com.ar\/blog\/mar-del-plata-asesinan-a-dos-jovenes-en-un-galpon-ajuste-de-cuentas-narco\/\" title=\"MAR DEL PLATA: ASESINAN A DOS JOVENES EN UN GALPON&#8230;\u00bfAJUSTE DE CUENTAS NARCO?\">[Leer M\u00e1s]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":33095,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[44,51],"tags":[],"class_list":{"0":"post-33094","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policiales","8":"category-regionales"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20230828152631_doble-homicidio-694-192411-600x315-1.jpg?fit=880%2C512&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8qtrQ-8BM","jetpack-related-posts":[{"id":43963,"url":"https:\/\/larevistadigital.com.ar\/blog\/mar-del-plata-un-hombre-efectuo-disparos-en-la-madrugada-y-fue-detenido\/","url_meta":{"origin":33094,"position":0},"title":"Mar del Plata: Un hombre efectu\u00f3 disparos en la madrugada y fue detenido","author":"Alejandro Sosa Ruda","date":"12 febrero, 2026","format":false,"excerpt":"Vecinos alertaron al 911 por detonaciones en la v\u00eda p\u00fablica. La Polic\u00eda secuestr\u00f3 un rev\u00f3lver calibre .38 con la numeraci\u00f3n suprimida y la Fiscal\u00eda inici\u00f3 una causa por tenencia ilegal de arma y encubrimiento. 12 de febrero de 2026 MAR DEL PLATA -\u00a0 Un hombre de 30 a\u00f1os fue aprehendido\u2026","rel":"","context":"En \u00abPOLICIALES\u00bb","block_context":{"text":"POLICIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/policiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-02-12-123904.jpg?fit=769%2C462&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-02-12-123904.jpg?fit=769%2C462&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-02-12-123904.jpg?fit=769%2C462&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-02-12-123904.jpg?fit=769%2C462&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":21093,"url":"https:\/\/larevistadigital.com.ar\/blog\/mar-del-plata-lo-atacaron-en-su-casa-lo-golpearon-y-lo-balearon-en-las-piernas\/","url_meta":{"origin":33094,"position":1},"title":"MAR DEL PLATA: LO ATACARON EN SU CASA, LO GOLPEARON Y LO BALEARON EN LAS PIERNAS","author":"Alejandro Sosa Ruda","date":"12 julio, 2021","format":false,"excerpt":"Sucedi\u00f3 en el barrio 2 de Abril. El herido de 31 a\u00f1os dijo que no pod\u00eda reconocer a los autores y se sospecha que fue un ajuste de cuentas. Un hombre que estaba en su casa fue atacado a golpes por al menos tres sujetos que lo sorprendieron en su\u2026","rel":"","context":"En \u00abPOLICIALES\u00bb","block_context":{"text":"POLICIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/policiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2021-07-12-105832.png?fit=1003%2C502&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2021-07-12-105832.png?fit=1003%2C502&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2021-07-12-105832.png?fit=1003%2C502&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2021-07-12-105832.png?fit=1003%2C502&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":44409,"url":"https:\/\/larevistadigital.com.ar\/blog\/conmocion-en-toma-de-rehenes-una-policia-herida-y-un-delincuente-detenido\/","url_meta":{"origin":33094,"position":2},"title":"Conmoci\u00f3n en toma de rehenes: una polic\u00eda herida y un delincuente detenido","author":"Alejandro Sosa Ruda","date":"9 marzo, 2026","format":false,"excerpt":"El hombre, que ten\u00eda pedido de captura, abri\u00f3 fuego contra los efectivos, tom\u00f3 un reh\u00e9n y termin\u00f3 reducido tras un operativo policial en el sur de Mar del Plata. 09 de marzo de 2026 MAR DEL PLATA -\u00a0 \u00a0Una mujer polic\u00eda result\u00f3 herida de dos disparos este lunes por la\u2026","rel":"","context":"En \u00abPOLICIALES\u00bb","block_context":{"text":"POLICIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/policiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-03-09-191122.jpg?fit=735%2C363&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-03-09-191122.jpg?fit=735%2C363&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-03-09-191122.jpg?fit=735%2C363&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-03-09-191122.jpg?fit=735%2C363&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":17782,"url":"https:\/\/larevistadigital.com.ar\/blog\/arreglaba-el-techo-de-un-galpon-y-cayo-de-6-metros-de-altura-esta-grave\/","url_meta":{"origin":33094,"position":3},"title":"ARREGLABA EL TECHO DE UN GALPON Y CAY\u00d3 DE 6 METROS DE ALTURA&#8230; ESTA GRAVE","author":"Alejandro Sosa Ruda","date":"20 noviembre, 2020","format":false,"excerpt":"Sucedi\u00f3 este mediod\u00eda en el barrio Las Am\u00e9ricas. La v\u00edctima de 45 a\u00f1os est\u00e1 internada con asistencia mec\u00e1nica respiratoria. MAR DEL PLATA - Un hombre de 45 a\u00f1os que cay\u00f3 del techo del galp\u00f3n que estaba arreglando en el barrio Las Am\u00e9ricas qued\u00f3 internado en grave estado en el Hospital\u2026","rel":"","context":"En \u00abINTERES GENERAL\u00bb","block_context":{"text":"INTERES GENERAL","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/interes-general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Screenshot_4-33.jpg?fit=1000%2C560&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Screenshot_4-33.jpg?fit=1000%2C560&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Screenshot_4-33.jpg?fit=1000%2C560&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Screenshot_4-33.jpg?fit=1000%2C560&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":27004,"url":"https:\/\/larevistadigital.com.ar\/blog\/mar-del-plata-tension-por-toma-de-terrenos-en-el-barrio-belisario-roldan\/","url_meta":{"origin":33094,"position":4},"title":"MAR DEL PLATA: TENSI\u00d3N POR TOMA DE TERRENOS EN EL BARRIO BELISARIO ROLD\u00c1N","author":"Alejandro Sosa Ruda","date":"5 agosto, 2022","format":false,"excerpt":"Se trata de personas vinculadas al Movimiento de Trabajadores Excluidos (MTE) que desarrollan actividades laborales informales. \"Necesitamos un galp\u00f3n para log\u00edstica\", dijo uno de los hombres. MAR DEL PLATA -\u00a0 Una veintena de personas, que ante la polic\u00eda se autoproclamaron integrantes del\u00a0Movimiento de Trabajadores Excluidos (MTE),\u00a0tomaron este jueves un terreno\u00a0en\u2026","rel":"","context":"En \u00abPOLICIALES\u00bb","block_context":{"text":"POLICIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/policiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/TOMA-TERRENOS.png?fit=808%2C501&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/TOMA-TERRENOS.png?fit=808%2C501&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/TOMA-TERRENOS.png?fit=808%2C501&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/TOMA-TERRENOS.png?fit=808%2C501&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":23868,"url":"https:\/\/larevistadigital.com.ar\/blog\/mar-del-plata-asesinan-a-joven-que-atendia-un-kiosco-de-un-balazo-en-la-espalda\/","url_meta":{"origin":33094,"position":5},"title":"MAR DEL PLATA: ASESINAN A JOVEN QUE ATEND\u00cdA UN KIOSCO DE UN BALAZO EN LA ESPALDA","author":"Alejandro Sosa Ruda","date":"7 febrero, 2022","format":false,"excerpt":"Una joven de 34 a\u00f1os, Romina Gilardi, muri\u00f3 tras recibir un balazo en la espalda en el kiosco que atend\u00eda en Mar del Plata. La victima lleg\u00f3 por sus propios medios al hospital Interzonal General de Agudos (Higa) Oscar Allende de Mar del Plata, donde falleci\u00f3 por la gravedad de\u2026","rel":"","context":"En \u00abPOLICIALES\u00bb","block_context":{"text":"POLICIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/policiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20220205175701_mar-del-plataa-inseguridad.jpg?fit=880%2C512&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20220205175701_mar-del-plataa-inseguridad.jpg?fit=880%2C512&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20220205175701_mar-del-plataa-inseguridad.jpg?fit=880%2C512&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20220205175701_mar-del-plataa-inseguridad.jpg?fit=880%2C512&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/33094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=33094"}],"version-history":[{"count":1,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/33094\/revisions"}],"predecessor-version":[{"id":33096,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/33094\/revisions\/33096"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media\/33095"}],"wp:attachment":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=33094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=33094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=33094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}