{"id":3350,"date":"2017-09-28T14:41:59","date_gmt":"2017-09-28T14:41:59","guid":{"rendered":"https:\/\/larevistadigital.com.ar\/blog\/?p=3350"},"modified":"2017-09-28T14:41:59","modified_gmt":"2017-09-28T14:41:59","slug":"chascomus-una-buena-para-el-municipio-incorporan-mas-contenedores-para-la-recoleccion-de-residuos","status":"publish","type":"post","link":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-una-buena-para-el-municipio-incorporan-mas-contenedores-para-la-recoleccion-de-residuos\/","title":{"rendered":"CHASCOM\u00daS: UNA BUENA PARA EL MUNICIPIO&#8230; INCORPORAN M\u00c1S CONTENEDORES PARA LA RECOLECCI\u00d3N DE RESIDUOS"},"content":{"rendered":"<p>Se inici\u00f3 la segunda etapa de incorporaci\u00f3n de contenedores, en la Avenida Costanera y en diversos barrios de la ciudad.<br \/>\nEn las \u00faltimas horas, ya fueron colocados los equipos en la avenida Costanera, entre el Parque de la Esperanza y el bulevar Escribano, para dar respuesta a la demanda de turistas y vecinos que utilizan ese sector, especialmente durante los fines de semana.<br \/>\nEn los pr\u00f3ximos d\u00edas, se continuar\u00e1 en los barrios 30 de Mayo, San Luis, Los Sauces, Acceso Norte, El Porte\u00f1o y en diversas plazas. Para garantizar su cuidado, en esta etapa ser\u00e1n situados en lugares que puedan ser monitoreados a trav\u00e9s de c\u00e1maras de seguridad y de inspecciones.<br \/>\nEl Plan de Contenerizaci\u00f3n permite un trabajo m\u00e1s eficiente por parte de los recolectores. Los contenedores s\u00f3lo deben ser utilizados para los residuos domiciliarios en bolsitas, no para otro tipo de desechos.<br \/>\nEn la siguiente etapa se espera llegar al barrio Ipor\u00e1 y a otros sectores de la ciudad, para lo cual se reacondicionar\u00e1 un cami\u00f3n compactador para sumarlo a los dos nuevos equipos que ya funcionan.<\/p>\n<p>FUENTE: DIARIOELFUERTE<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Se inici\u00f3 la segunda etapa de incorporaci\u00f3n de contenedores, en la Avenida Costanera y en diversos barrios de la ciudad. En las \u00faltimas horas, ya fueron colocados los equipos en la avenida Costanera, entre el <a class=\"mh-excerpt-more\" href=\"https:\/\/larevistadigital.com.ar\/blog\/chascomus-una-buena-para-el-municipio-incorporan-mas-contenedores-para-la-recoleccion-de-residuos\/\" title=\"CHASCOM\u00daS: UNA BUENA PARA EL MUNICIPIO&#8230; INCORPORAN M\u00c1S CONTENEDORES PARA LA RECOLECCI\u00d3N DE RESIDUOS\">[Leer M\u00e1s]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":3351,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[6],"tags":[],"class_list":{"0":"post-3350","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-chascomus"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/09\/residuos_27deseptiembrede2017_elfuerte.jpg?fit=737%2C415&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8qtrQ-S2","jetpack-related-posts":[{"id":36725,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-cronograma-de-puntos-limpios-moviles-para-lo-que-resta-del-mes-de-julio\/","url_meta":{"origin":3350,"position":0},"title":"CHASCOM\u00daS: CRONOGRAMA DE PUNTOS LIMPIOS M\u00d3VILES PARA LO QUE RESTA DEL MES DE JULIO","author":"Alejandro Sosa Ruda","date":"17 julio, 2024","format":false,"excerpt":"La separaci\u00f3n de estos residuos es fundamental para su posterior recuperaci\u00f3n y reincorporaci\u00f3n al circuito productivo, evitando as\u00ed el impacto negativo en el ambiente y promoviendo la econom\u00eda circular. 17 de Julio de 2024 CHASCOM\u00daS -\u00a0 Se recuerda el cronograma de Puntos Limpios M\u00f3viles (PML) para los pr\u00f3ximos d\u00edas del\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/66980a7dc4aa9.png?fit=668%2C445&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/66980a7dc4aa9.png?fit=668%2C445&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/66980a7dc4aa9.png?fit=668%2C445&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":43498,"url":"https:\/\/larevistadigital.com.ar\/blog\/cuidar-chascomus-es-tarea-de-todos-como-usar-correctamente-los-contenedores\/","url_meta":{"origin":3350,"position":1},"title":"Cuidar Chascom\u00fas es tarea de todos: c\u00f3mo usar correctamente los contenedores","author":"Alejandro Sosa Ruda","date":"20 enero, 2026","format":false,"excerpt":"Mantener limpia nuestra ciudad es una responsabilidad que debemos asumir entre todos. 20 De enero de 2026 CHASCOM\u00daS -\u00a0 \u00a0En Chascom\u00fas contamos con un sistema de recolecci\u00f3n organizado, con contenedores diferenciados que facilitan el cuidado del ambiente y la convivencia en los barrios. Para que funcione correctamente, es fundamental el\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/696fc6a2d23e1.png?fit=668%2C445&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/696fc6a2d23e1.png?fit=668%2C445&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/696fc6a2d23e1.png?fit=668%2C445&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":5002,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-ricardo-michino-hablo-la-compra-200-nuevos-contenedores\/","url_meta":{"origin":3350,"position":2},"title":"CHASCOM\u00daS: RICARDO MICHINO HABL\u00d3 DE LA COMPRA DE 200 NUEVOS CONTENEDORES","author":"Alejandro Sosa Ruda","date":"23 febrero, 2018","format":false,"excerpt":"Ricardo Michino, director de ambiente sustentable de la Municipalidad de Chascom\u00fas, habl\u00f3 del tema de la basura en la ciudad en la FM 101.5. Manifest\u00f3 que se van a adquirir m\u00e1s contenedores ya que el resultado de los que se han colocado fue muy positivo, con muy buena recepci\u00f3n por\u2026","rel":"","context":"En \u00abPOLITICA\u00bb","block_context":{"text":"POLITICA","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/02\/20785758_1599814140039465_5954032198227884272_o.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/02\/20785758_1599814140039465_5954032198227884272_o.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/02\/20785758_1599814140039465_5954032198227884272_o.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/02\/20785758_1599814140039465_5954032198227884272_o.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/02\/20785758_1599814140039465_5954032198227884272_o.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":44878,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-como-sera-la-recoleccion-de-residuos-durante-el-fin-de-semana-largo\/","url_meta":{"origin":3350,"position":3},"title":"Chascom\u00fas: C\u00f3mo ser\u00e1 la recolecci\u00f3n de residuos durante el fin de semana largo","author":"Alejandro Sosa Ruda","date":"1 abril, 2026","format":false,"excerpt":"Para garantizar la limpieza de la ciudad, el personal municipal trabajar\u00e1 durante los feriados. 01 de abril de 2026 CHASCOM\u00daS -\u00a0 La Municipalidad de Chascom\u00fas da a conocer los horarios del servicio de recolecci\u00f3n de residuos durante los pr\u00f3ximos d\u00edas. El jueves y el viernes, s\u00e1bado, se realizar\u00e1 de manera\u2026","rel":"","context":"En \u00abINTERES GENERAL\u00bb","block_context":{"text":"INTERES GENERAL","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/interes-general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/69cd4c5500238.png?fit=668%2C445&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/69cd4c5500238.png?fit=668%2C445&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/69cd4c5500238.png?fit=668%2C445&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":26089,"url":"https:\/\/larevistadigital.com.ar\/blog\/fotos-chascomus-accidente-en-la-costanera-entre-una-moto-y-dos-autos\/","url_meta":{"origin":3350,"position":4},"title":"[FOTOS] CHASCOM\u00daS: ACCIDENTE EN LA COSTANERA ENTRE UNA MOTO Y DOS AUTOS","author":"Alejandro Sosa Ruda","date":"24 junio, 2022","format":false,"excerpt":"CHASCOM\u00daS -\u00a0 Poco antes de caer la noche, se produjo un accidente en la avenida Costanera, frente al local gastron\u00f3mico \"Mule\". El siniestro fue entre un autom\u00f3vil y una moto, y afortunadamente no hubo heridos graves en el mismo, solo lamentando los da\u00f1os materiales. \u00a0","rel":"","context":"En \u00abINTERES GENERAL\u00bb","block_context":{"text":"INTERES GENERAL","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/interes-general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2022-06-24-at-10.09.28-PM.jpeg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2022-06-24-at-10.09.28-PM.jpeg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2022-06-24-at-10.09.28-PM.jpeg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2022-06-24-at-10.09.28-PM.jpeg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2022-06-24-at-10.09.28-PM.jpeg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":22766,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-malestar-de-vecinos-por-los-contenedores-atestados-de-basura-en-distintos-puntos-de-la-ciudad\/","url_meta":{"origin":3350,"position":5},"title":"CHASCOM\u00daS: MALESTAR DE VECINOS POR LOS CONTENEDORES ATESTADOS DE BASURA EN DISTINTOS PUNTOS DE LA CIUDAD","author":"Alejandro Sosa Ruda","date":"23 noviembre, 2021","format":false,"excerpt":"CHASCOM\u00daS - Luego del fin de semana largo, y la gran afluencia de p\u00fablico que recibi\u00f3 la ciudad de Chascom\u00fas, como era previsible, los contenedores de basura colocados en distintos lugares, colapsaron, sobre todo porque el d\u00eda domingo no hubo servicio de recolecci\u00f3n. Es l\u00f3gico que cada uno tenga derecho\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/dos.jpg?fit=1000%2C1143&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/dos.jpg?fit=1000%2C1143&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/dos.jpg?fit=1000%2C1143&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/dos.jpg?fit=1000%2C1143&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/3350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=3350"}],"version-history":[{"count":1,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/3350\/revisions"}],"predecessor-version":[{"id":3352,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/3350\/revisions\/3352"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media\/3351"}],"wp:attachment":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=3350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=3350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=3350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}