{"id":3380,"date":"2017-10-02T16:20:50","date_gmt":"2017-10-02T16:20:50","guid":{"rendered":"https:\/\/larevistadigital.com.ar\/blog\/?p=3380"},"modified":"2017-10-02T16:20:50","modified_gmt":"2017-10-02T16:20:50","slug":"castelli-un-herido-tras-un-violento-choque-en-el-acceso-a-la-ciudad","status":"publish","type":"post","link":"https:\/\/larevistadigital.com.ar\/blog\/castelli-un-herido-tras-un-violento-choque-en-el-acceso-a-la-ciudad\/","title":{"rendered":"CASTELLI: UN HERIDO, TRAS UN VIOLENTO CHOQUE EN EL ACCESO A LA CIUDAD"},"content":{"rendered":"<p>Una persona result\u00f3 herida tras una colisi\u00f3n que tuvo como protagonistas a una camioneta Chevrolet y un Ford Fiesta. Se\u00a0supo que la camioneta conducida por un vecino de la ciudad habr\u00eda tratado de ingresar a Castelli tomando el retorno de acceso a Castelmar en el Km 180 de la autov\u00eda 2 cuando el veh\u00edculo habr\u00eda impactado dejando da\u00f1os materiales. El siniestro ocurri\u00f3 a las 17 hs y la mujer herida fue asistida en el hospital donde se le practicaron los ex\u00e1menes de rigor. En el lugar trabaj\u00f3 Polic\u00eda vial personal de Emergencias m\u00e9dicas y bomberos.<\/p>\n<p>FUENTE:CASTELLIDIARIO<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Una persona result\u00f3 herida tras una colisi\u00f3n que tuvo como protagonistas a una camioneta Chevrolet y un Ford Fiesta. Se\u00a0supo que la camioneta conducida por un vecino de la ciudad habr\u00eda tratado de ingresar a <a class=\"mh-excerpt-more\" href=\"https:\/\/larevistadigital.com.ar\/blog\/castelli-un-herido-tras-un-violento-choque-en-el-acceso-a-la-ciudad\/\" title=\"CASTELLI: UN HERIDO, TRAS UN VIOLENTO CHOQUE EN EL ACCESO A LA CIUDAD\">[Leer M\u00e1s]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":3381,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[4,12],"tags":[],"class_list":{"0":"post-3380","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-castelli","8":"category-politica"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/10\/22172040_666292913555042_1513752497_o-1.jpg?fit=720%2C571&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8qtrQ-Sw","jetpack-related-posts":[{"id":5829,"url":"https:\/\/larevistadigital.com.ar\/blog\/una-mujer-herida-tras-un-incendio\/","url_meta":{"origin":3380,"position":0},"title":"Una mujer herida tras un incendio","author":"admin","date":"22 junio, 2018","format":false,"excerpt":"Una mujer result\u00f3 con heridas de consideraci\u00f3n luego que una garrafa cobrara fuego. El siniestro ocurri\u00f3 el jueves por la noche, cerca de las 22 30hs, en un sal\u00f3n de fiestas ubicado en la sede social del Club Deportivo. Seg\u00fan supo este portal, la mujer habr\u00eda intentado sacar la garrafa\u2026","rel":"","context":"En \u00abCASTELLI\u00bb","block_context":{"text":"CASTELLI","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/castelli\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/06\/deportivo-700x394.jpg?fit=700%2C394&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/06\/deportivo-700x394.jpg?fit=700%2C394&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/06\/deportivo-700x394.jpg?fit=700%2C394&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/06\/deportivo-700x394.jpg?fit=700%2C394&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":7417,"url":"https:\/\/larevistadigital.com.ar\/blog\/castelli-dos-ciclistas-heridos-por-choque-con-camioneta-en-la-ruta-2\/","url_meta":{"origin":3380,"position":1},"title":"CASTELLI: DOS CICLISTAS HERIDOS POR CHOQUE CON CAMIONETA EN LA RUTA 2","author":"Alejandro Sosa Ruda","date":"28 diciembre, 2018","format":false,"excerpt":"Dos ciclistas de Castelli resultaron con lesiones tras colisionar con una camioneta que estaba parada en la autov\u00eda 2 Seg\u00fan se supo y public\u00f3 en Castelli diario se trata de los pedalistas Carlos Brivio y Hugo Martinez, quienes a\u00a0 bordo de sus bicicletas, impactaron con una camioneta Ford Eco Sport\u2026","rel":"","context":"En \u00abCASTELLI\u00bb","block_context":{"text":"CASTELLI","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/castelli\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/12\/bici-1.jpg?fit=600%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/12\/bici-1.jpg?fit=600%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/12\/bici-1.jpg?fit=600%2C800&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":10413,"url":"https:\/\/larevistadigital.com.ar\/blog\/castelli-encuentran-camioneta-incendiada\/","url_meta":{"origin":3380,"position":2},"title":"CASTELLI: ENCUENTRAN CAMIONETA INCENDIADA","author":"Alejandro Sosa Ruda","date":"3 junio, 2019","format":false,"excerpt":"Una camioneta Ford Ranger, color rojo fue incendiada en la madrugada de este viernes, cerca de las 01.30hs El hecho ocurri\u00f3 en un descampado en el paraje Pueblo Nuevo, lugar a que arribaron bomberos y personal policial quienes finalmente constataron en prima facie la intencionalidad del hecho. Fuentes policiales detallaron\u2026","rel":"","context":"En \u00abCASTELLI\u00bb","block_context":{"text":"CASTELLI","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/castelli\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/camioneta-incendiada-768x1024.jpg?fit=768%2C1024&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/camioneta-incendiada-768x1024.jpg?fit=768%2C1024&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/camioneta-incendiada-768x1024.jpg?fit=768%2C1024&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/camioneta-incendiada-768x1024.jpg?fit=768%2C1024&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":37724,"url":"https:\/\/larevistadigital.com.ar\/blog\/castelli-vuelco-en-la-ruta-2-durante-el-temporal\/","url_meta":{"origin":3380,"position":3},"title":"CASTELLI: VUELCO EN LA RUTA 2 DURANTE EL TEMPORAL","author":"Alejandro Sosa Ruda","date":"5 noviembre, 2024","format":false,"excerpt":"Fue protagonizado por una camioneta que qued\u00f3 tumbada, y su conductor pudo ser rescatado. 5 de Noviembre de 2024 CASTELLI\u00a0 -\u00a0 \u00a0 El siniestro ocurri\u00f3 en la ruta 2, en proximidad a la localidad de Castelli donde una camioneta 4x4 volc\u00f3 y qued\u00f3 con sus ruedas hacia arriba. Afortunadamente quien\u2026","rel":"","context":"En \u00abCASTELLI\u00bb","block_context":{"text":"CASTELLI","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/castelli\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/52e0457cc3dc4033028806b68834304f6b237a49.jpg?fit=1140%2C737&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/52e0457cc3dc4033028806b68834304f6b237a49.jpg?fit=1140%2C737&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/52e0457cc3dc4033028806b68834304f6b237a49.jpg?fit=1140%2C737&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/52e0457cc3dc4033028806b68834304f6b237a49.jpg?fit=1140%2C737&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/52e0457cc3dc4033028806b68834304f6b237a49.jpg?fit=1140%2C737&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":10112,"url":"https:\/\/larevistadigital.com.ar\/blog\/castelli-en-las-redes-hablan-de-una-camioneta-que-persigue-mujeres\/","url_meta":{"origin":3380,"position":4},"title":"CASTELLI: EN LAS REDES HABLAN DE UNA CAMIONETA QUE PERSIGUE MUJERES","author":"Alejandro Sosa Ruda","date":"10 mayo, 2019","format":false,"excerpt":"Pese a las publicaciones que han aparecido en la red social Facebook acerca de un individuo que a bordo de una camioneta Traffic blanca, persigue y acosa a mujeres, aseguran que no existen denuncias al respecto. As\u00ed lo informaron desde la Comisaria local y ayudant\u00eda Fiscal. El titular de la\u2026","rel":"","context":"En \u00abCASTELLI\u00bb","block_context":{"text":"CASTELLI","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/castelli\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2019\/05\/comisaria.jpg?fit=639%2C428&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2019\/05\/comisaria.jpg?fit=639%2C428&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2019\/05\/comisaria.jpg?fit=639%2C428&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":8611,"url":"https:\/\/larevistadigital.com.ar\/blog\/castelli-acceso-sur-renovado-y-con-nueva-iluminacion\/","url_meta":{"origin":3380,"position":5},"title":"CASTELLI: ACCESO SUR: RENOVADO Y CON NUEVA ILUMINACI\u00d3N","author":"Alejandro Sosa Ruda","date":"20 febrero, 2019","format":false,"excerpt":"Ya se encuentra abierto al tr\u00e1nsito el Acceso Sur por Autov\u00eda 2 a Castelli. Anoche se culminaron con las tareas de instalaci\u00f3n de nuevas luminarias de led, que brindan una mejor visibilidad al conductor y adem\u00e1s generan un marco destacado para el ingreso a la ciudad. Por otro lado, se\u2026","rel":"","context":"En \u00abCASTELLI\u00bb","block_context":{"text":"CASTELLI","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/castelli\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2019\/02\/52555104_1119939378175763_6647650862061584384_n.jpg?fit=960%2C691&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2019\/02\/52555104_1119939378175763_6647650862061584384_n.jpg?fit=960%2C691&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2019\/02\/52555104_1119939378175763_6647650862061584384_n.jpg?fit=960%2C691&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2019\/02\/52555104_1119939378175763_6647650862061584384_n.jpg?fit=960%2C691&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/3380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=3380"}],"version-history":[{"count":1,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/3380\/revisions"}],"predecessor-version":[{"id":3382,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/3380\/revisions\/3382"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media\/3381"}],"wp:attachment":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=3380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=3380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=3380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}