{"id":34211,"date":"2023-10-26T11:23:33","date_gmt":"2023-10-26T14:23:33","guid":{"rendered":"https:\/\/larevistadigital.com.ar\/blog\/?p=34211"},"modified":"2023-10-26T11:23:33","modified_gmt":"2023-10-26T14:23:33","slug":"chascomus-roban-un-vehiculo-a-mano-armada-y-la-policia-comunal-con-ayuda-de-monitoreo-logro-detener-a-uno-de-los-responsables-buscan-a-otros-dos-todos-con-frondoso-prontuario","status":"publish","type":"post","link":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-roban-un-vehiculo-a-mano-armada-y-la-policia-comunal-con-ayuda-de-monitoreo-logro-detener-a-uno-de-los-responsables-buscan-a-otros-dos-todos-con-frondoso-prontuario\/","title":{"rendered":"CHASCOM\u00daS: ROBAN UN VEH\u00cdCULO A MANO ARMADA Y LA POLICIA COMUNAL CON AYUDA DE MONITOREO LOGR\u00d3 DETENER A UNO DE LOS RESPONSABLES. BUSCAN A OTROS DOS, TODOS CON FRONDOSO PRONTUARIO."},"content":{"rendered":"<h2>Los delincuentes tienen un frondoso prontuario que incluye \u00abhomicidio en ocasi\u00f3n de robo\u00bb. La polic\u00eda tuvo un r\u00e1pido accionar que se sum\u00f3 al importante trabajo de Monitoreo.<\/h2>\n<p>25 de Octubre de 2023<\/p>\n<p><strong>CHASCOM\u00daS &#8211;<\/strong>\u00a0 El d\u00eda l\u00fanes pasado, se produjo un hecho en horas de la tarde donde 3 sujetos masculinos tras el amedrentamiento con armas de fuego a un vecino de Chascomus lograron robarle un veh\u00edculo marca Ford Ranger y herramientas de mano.<\/p>\n<blockquote>\n<h3>Tras el inmediato y contundente operativo cerrojo realizado por E.P.C. Chascomus 1ra y dem\u00e1s polic\u00edas descentralizadas, los indeseables abandonaron el veh\u00edculo que fue recuperado por personal de EPC Chascomus en el km 93.500 sobre un camino rural.<\/h3>\n<\/blockquote>\n<p>Personal del G.T.O de la ya mencionada dependencia policial, tras diferentes tareas de investigaci\u00f3n y recolecci\u00f3n de grabaciones de camaras de seguridad del Centro de Monitoreo de Chascomus, procedieron a establecer la identidad de uno de los participantes del hecho delictivo, dato que fu\u00e9 muy relevante para identificar al resto de la banda.<\/p>\n<blockquote>\n<h3><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-34214\" src=\"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2023-10-25-at-20.11.04.jpeg?resize=1080%2C1161&#038;ssl=1\" alt=\"\" width=\"1080\" height=\"1161\" srcset=\"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2023-10-25-at-20.11.04.jpeg?w=1080&amp;ssl=1 1080w, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2023-10-25-at-20.11.04.jpeg?resize=279%2C300&amp;ssl=1 279w, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2023-10-25-at-20.11.04.jpeg?resize=953%2C1024&amp;ssl=1 953w, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2023-10-25-at-20.11.04.jpeg?resize=768%2C826&amp;ssl=1 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>En horas de la madrugada, se procedi\u00f3 a realizar un allanamiento en un domicilio de EZPELETA partido de Quilmes, logrando obtener resultados POSITIVOS, ya que en el lugar se logro recuperar elementos sustra\u00eddos a la v\u00edctima y elementos utilizados por los autores al momento de realizar el hecho delictivo.<\/h3>\n<\/blockquote>\n<p>En este momento se contin\u00faan las tareas en la localidad de Quilmes con fines de dar con los tres sujetos para ponerlos a disposici\u00f3n de la justicia. Es dable mencionar que los delincuentes autores del hecho cuentan con frondosos antecedentes delictivos c\u00f3mo Homicidio en ocaci\u00f3n de Robo entre otros delitos graves.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Los delincuentes tienen un frondoso prontuario que incluye \u00abhomicidio en ocasi\u00f3n de robo\u00bb. La polic\u00eda tuvo un r\u00e1pido accionar que se sum\u00f3 al importante trabajo de Monitoreo. 25 de Octubre de 2023 CHASCOM\u00daS &#8211;\u00a0 El <a class=\"mh-excerpt-more\" href=\"https:\/\/larevistadigital.com.ar\/blog\/chascomus-roban-un-vehiculo-a-mano-armada-y-la-policia-comunal-con-ayuda-de-monitoreo-logro-detener-a-uno-de-los-responsables-buscan-a-otros-dos-todos-con-frondoso-prontuario\/\" title=\"CHASCOM\u00daS: ROBAN UN VEH\u00cdCULO A MANO ARMADA Y LA POLICIA COMUNAL CON AYUDA DE MONITOREO LOGR\u00d3 DETENER A UNO DE LOS RESPONSABLES. BUSCAN A OTROS DOS, TODOS CON FRONDOSO PRONTUARIO.\">[Leer M\u00e1s]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":34213,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[41],"tags":[],"class_list":{"0":"post-34211","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destacadas"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2023-10-25-at-20.05.00.jpeg?fit=1600%2C900&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8qtrQ-8TN","jetpack-related-posts":[{"id":32391,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-la-policia-detuvo-a-un-sujeto-con-frondoso-prontuario-cuando-intentaba-robar\/","url_meta":{"origin":34211,"position":0},"title":"CHASCOM\u00daS: LA POLIC\u00cdA DETUVO A UN SUJETO CON FRONDOSO PRONTUARIO, CUANDO INTENTABA ROBAR","author":"Alejandro Sosa Ruda","date":"13 julio, 2023","format":false,"excerpt":"El aprehendido, de 48 a\u00f1os tiene gran cantidad de antecedentes y fue alojado en la comisar\u00eda. 13 de julio de 2023 CHASCOM\u00daS -\u00a0 En las \u00faltimas horas del d\u00eda de ayer 12 de Julio personal policial de EPC Chascom\u00fas Primera lograron proceder a la aprehensi\u00f3n de una persona de 48\u2026","rel":"","context":"En \u00abINTERES GENERAL\u00bb","block_context":{"text":"INTERES GENERAL","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/interes-general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2023-07-13-at-09.49.23-e1689285213996.jpeg?fit=723%2C761&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2023-07-13-at-09.49.23-e1689285213996.jpeg?fit=723%2C761&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2023-07-13-at-09.49.23-e1689285213996.jpeg?fit=723%2C761&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2023-07-13-at-09.49.23-e1689285213996.jpeg?fit=723%2C761&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":34174,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-la-policia-recupero-un-vehiculo-robado-con-arma-de-fuego\/","url_meta":{"origin":34211,"position":1},"title":"CHASCOM\u00daS: LA POLIC\u00cdA RECUPER\u00d3 UN VEH\u00cdCULO ROBADO CON ARMA DE FUEGO","author":"Alejandro Sosa Ruda","date":"23 octubre, 2023","format":false,"excerpt":"La investigaci\u00f3n para dar con los autores est\u00e1 avanzada y en curso 23 de Octubre de 2023 CHASCOM\u00daS -\u00a0 En horas de la tarde, se tom\u00f3 conocimiento de un hecho delictivo en el que autores ignorados tras la utilizaci\u00f3n de arma de fuego lograron sustraer un veh\u00edculo y elementos a\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Polic%C3%ADa-Bonaerense-Patrulleros-3.jpg?fit=772%2C434&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Polic%C3%ADa-Bonaerense-Patrulleros-3.jpg?fit=772%2C434&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Polic%C3%ADa-Bonaerense-Patrulleros-3.jpg?fit=772%2C434&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Polic%C3%ADa-Bonaerense-Patrulleros-3.jpg?fit=772%2C434&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":31666,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-la-policia-comunal-con-ayuda-de-monitoreo-lograron-recuperar-en-unas-horas-una-moto-robada-del-patio-de-una-casa\/","url_meta":{"origin":34211,"position":2},"title":"CHASCOM\u00daS: LA POLIC\u00cdA COMUNAL CON AYUDA DE \u00abMONITOREO\u00bb LOGRARON RECUPERAR EN UNAS HORAS UNA MOTO ROBADA DEL PATIO DE UNA CASA.","author":"Alejandro Sosa Ruda","date":"21 mayo, 2023","format":false,"excerpt":"En pocas horas recuperaron el veh\u00edculo. Esto demuestra la importancia de realizar la correspondiente denuncia policial. 21 de mayo de 2023 CHASCOM\u00daS -\u00a0 \u00a0Aproximadamente al mediod\u00eda de ayer, se tom\u00f3 una denuncia por la sustracci\u00f3n de una motocicleta del patio de un domicili21 o de calle M\u00e9xico. Personal policial,\u00a0 en\u2026","rel":"","context":"En \u00abPOLICIALES\u00bb","block_context":{"text":"POLICIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/policiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2023-05-20-at-19.46.11.jpeg?fit=903%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2023-05-20-at-19.46.11.jpeg?fit=903%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2023-05-20-at-19.46.11.jpeg?fit=903%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2023-05-20-at-19.46.11.jpeg?fit=903%2C1200&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":43905,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-tres-hombres-aprehendidos-tras-una-persecucion-y-el-hallazgo-de-un-arma-de-fuego\/","url_meta":{"origin":34211,"position":3},"title":"Chascom\u00fas: Tres hombres aprehendidos tras una persecuci\u00f3n y el hallazgo de un arma de fuego","author":"Alejandro Sosa Ruda","date":"10 febrero, 2026","format":false,"excerpt":"El hecho se origin\u00f3 tras un alerta por maniobras imprudentes y consumo de alcohol en la v\u00eda p\u00fablica. Los ocupantes del veh\u00edculo huyeron a pie luego de abandonar el auto, donde la Polic\u00eda encontr\u00f3 un rev\u00f3lver con municiones. Clave trabajo conjunto de la Secretar\u00eda de Seguridad, la Patrulla de Prevenci\u00f3n\u2026","rel":"","context":"En \u00abDESTACADAS\u00bb","block_context":{"text":"DESTACADAS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/destacadas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2-22.jpg?fit=900%2C886&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2-22.jpg?fit=900%2C886&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2-22.jpg?fit=900%2C886&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2-22.jpg?fit=900%2C886&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":31083,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-la-policia-comunal-en-conjunto-con-monitoreo-y-la-patrulla-municipal-recuperaron-una-moto-que-se-robo-por-la-manana\/","url_meta":{"origin":34211,"position":4},"title":"CHASCOM\u00daS: LA POLIC\u00cdA COMUNAL EN CONJUNTO CON MONITOREO Y LA PATRULLA MUNICIPAL RECUPERARON UNA MOTO QUE SE ROB\u00d3 POR LA MA\u00d1ANA.","author":"Alejandro Sosa Ruda","date":"17 abril, 2023","format":false,"excerpt":"Trabajaron r\u00e1pidamente y de manera conjunta, consiguiendo recuperar el motoveh\u00edculo sustra\u00eddo a las pocas horas de cometido el hecho. 17 de abril de 2023 CHASCOM\u00daS -\u00a0 Durante la jornada, luego que un vecino inform\u00f3 la sustracci\u00f3n de una moto de su vivienda ubicada en el barrio 30 de Mayo, se\u2026","rel":"","context":"En \u00abDESTACADAS\u00bb","block_context":{"text":"DESTACADAS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/destacadas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2023-04-17-at-18.10.11-e1681770925644.jpeg?fit=899%2C1160&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2023-04-17-at-18.10.11-e1681770925644.jpeg?fit=899%2C1160&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2023-04-17-at-18.10.11-e1681770925644.jpeg?fit=899%2C1160&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2023-04-17-at-18.10.11-e1681770925644.jpeg?fit=899%2C1160&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":39704,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-operativo-conjunto-de-policia-de-seg-vial-comando-de-prevencion-rural-dir-de-invest-en-funcion-judicial-y-epc-lezama-detuvo-luego-de-una-persecucion-a-dos-individuos\/","url_meta":{"origin":34211,"position":5},"title":"Chascom\u00fas: Operativo conjunto de Polic\u00eda de Seg. Vial, Comando de Prevenci\u00f3n Rural, Dir. de Invest. en Funci\u00f3n Judicial, y EPC Lezama, detuvo luego de una persecuci\u00f3n a dos individuos","author":"Alejandro Sosa Ruda","date":"7 mayo, 2025","format":false,"excerpt":"Tras una cinematogr\u00e1fica fuga por varias localidades bonaerenses, la polic\u00eda logr\u00f3 detener a dos hombres en un operativo conjunto que involucr\u00f3 a m\u00faltiples fuerzas de seguridad. 07 de Mayo de 2025 CHASCOM\u00daS -\u00a0 Un operativo coordinado entre distintas fuerzas policiales bonaerenses culmin\u00f3 este martes con la detenci\u00f3n de dos sujetos\u2026","rel":"","context":"En \u00abDESTACADAS\u00bb","block_context":{"text":"DESTACADAS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/destacadas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Policia-Local-Dolores-678x381.jpg?fit=678%2C381&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Policia-Local-Dolores-678x381.jpg?fit=678%2C381&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Policia-Local-Dolores-678x381.jpg?fit=678%2C381&ssl=1&resize=525%2C300 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/34211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=34211"}],"version-history":[{"count":2,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/34211\/revisions"}],"predecessor-version":[{"id":34215,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/34211\/revisions\/34215"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media\/34213"}],"wp:attachment":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=34211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=34211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=34211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}