{"id":3633,"date":"2017-10-30T17:43:23","date_gmt":"2017-10-30T17:43:23","guid":{"rendered":"https:\/\/larevistadigital.com.ar\/blog\/?p=3633"},"modified":"2017-10-30T17:43:23","modified_gmt":"2017-10-30T17:43:23","slug":"macri-los-gremios-queremos-obras-sociales-bien-administradas","status":"publish","type":"post","link":"https:\/\/larevistadigital.com.ar\/blog\/macri-los-gremios-queremos-obras-sociales-bien-administradas\/","title":{"rendered":"MACRI A LOS GREMIOS: \u201cQUEREMOS OBRAS SOCIALES BIEN ADMINISTRADAS\u201d"},"content":{"rendered":"<p>En su exposici\u00f3n ante empresarios, sindicalistas y funcionarios en el CCK, el presidente <strong>Mauricio Macri<\/strong>, dedic\u00f3 un p\u00e1rrafo a los gremios en donde invit\u00f3 a dialogar a la dirigencia sindical.<\/p>\n<blockquote>\n<h3>No solo pidi\u00f3 el dialogo, sino que adem\u00e1s en un tramo de su discurso, dijo que pretend\u00eda <strong><em>\u00abobras sociales bien administradas\u00a0para mejorar la calidad de vida de los trabajadores\u00bb.<\/em><\/strong><\/h3>\n<\/blockquote>\n<p>Tambi\u00e9n se refiri\u00f3 a la CGT, pidiendo que dialoguen porque <strong><em>\u201cen la Argentina hay muchas obras sociales y organizaciones sindicales\u201d<\/em><\/strong>.<\/p>\n<blockquote>\n<h3>Ante el triunvirato de secretarios generales de la CGT\u00a0<strong>Carlos Acu\u00f1a<\/strong>, <strong>Juan Carlos Schmid<\/strong> y <strong>H\u00e9ctor Daer<\/strong>, el jefe de Estado precis\u00f3 que en el pa\u00eds hay 280 obras sociales de las cuales 240 representan el 70% de los trabajadores.<\/h3>\n<\/blockquote>\n<p><strong><em>\u00abQueremos\u00a0obras sociales fuertes y bien administradas\u00a0para mejorar la calidad de vida y la atenci\u00f3n a la salud de los trabajadores y sus familias. Para eso\u00a0invitamos a dialogar\u00a0a nuestra dirigencia sindical\u00bb<\/em><\/strong>, sentenci\u00f3.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>En su exposici\u00f3n ante empresarios, sindicalistas y funcionarios en el CCK, el presidente Mauricio Macri, dedic\u00f3 un p\u00e1rrafo a los gremios en donde invit\u00f3 a dialogar a la dirigencia sindical. No solo pidi\u00f3 el dialogo, <a class=\"mh-excerpt-more\" href=\"https:\/\/larevistadigital.com.ar\/blog\/macri-los-gremios-queremos-obras-sociales-bien-administradas\/\" title=\"MACRI A LOS GREMIOS: \u201cQUEREMOS OBRAS SOCIALES BIEN ADMINISTRADAS\u201d\">[Leer M\u00e1s]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":3634,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[10,12],"tags":[],"class_list":{"0":"post-3633","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-gremiales","8":"category-politica"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/10\/HyEmHaNR-_930x525.jpg?fit=930%2C525&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8qtrQ-WB","jetpack-related-posts":[{"id":3152,"url":"https:\/\/larevistadigital.com.ar\/blog\/marcha-de-la-cgt-macri-echo-a-dos-funcionarios-y-le-quito-a-los-sindicatos-el-manejo-de-la-caja-de-las-obras-sociales\/","url_meta":{"origin":3633,"position":0},"title":"MARCHA DE LA CGT: MACRI ECH\u00d3 A DOS FUNCIONARIOS Y LE QUIT\u00d3 A LOS SINDICATOS EL MANEJO DE LA CAJA DE LAS OBRAS SOCIALES","author":"Alejandro Sosa Ruda","date":"23 agosto, 2017","format":false,"excerpt":"El presidente ech\u00f3 al vice ministro Ezequiel Sabor, y al Superintendente de Servicios de Salud de la Naci\u00f3n, Luis Scervino. R\u00e1pido de reflejos, y para seguramente enviar un mensaje contundente y severo, dejando en claro que es \u00e9l quien tiene \u201cel toro por las astas\u201d, el presidente de la Naci\u00f3n,\u2026","rel":"","context":"En \u00abPOLITICA\u00bb","block_context":{"text":"POLITICA","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/08\/macri-conferencia.jpg?fit=1008%2C566&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/08\/macri-conferencia.jpg?fit=1008%2C566&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/08\/macri-conferencia.jpg?fit=1008%2C566&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/08\/macri-conferencia.jpg?fit=1008%2C566&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":39992,"url":"https:\/\/larevistadigital.com.ar\/blog\/gremios-y-movimientos-sociales-impulsan-un-frente-multisectorial-contra-las-politicas-de-milei\/","url_meta":{"origin":3633,"position":1},"title":"Gremios y movimientos sociales impulsan un frente multisectorial contra las pol\u00edticas de Milei","author":"Alejandro Sosa Ruda","date":"6 junio, 2025","format":false,"excerpt":"Sin participaci\u00f3n formal de la CGT, distintos sindicatos y organizaciones sociales est\u00e1n articulando la creaci\u00f3n de un espacio com\u00fan de lucha contra las medidas adoptadas por el gobierno de Javier Milei. El objetivo es conformar un frente amplio que integre a representantes de m\u00faltiples sectores laborales y sociales bajo el\u2026","rel":"","context":"En \u00abINTERES GENERAL\u00bb","block_context":{"text":"INTERES GENERAL","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/interes-general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20250606083606_gremios-organizaciones-sociales-multisectorial.jpg?fit=880%2C512&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20250606083606_gremios-organizaciones-sociales-multisectorial.jpg?fit=880%2C512&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20250606083606_gremios-organizaciones-sociales-multisectorial.jpg?fit=880%2C512&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20250606083606_gremios-organizaciones-sociales-multisectorial.jpg?fit=880%2C512&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":218,"url":"https:\/\/larevistadigital.com.ar\/blog\/se-sumo-gremio-del-transporte-planes-lucha-movilizacion-la-cgt\/","url_meta":{"origin":3633,"position":2},"title":"SE SUM\u00d3 EL GREMIO DEL TRANSPORTE &#8211; Planes de lucha y movilizaci\u00f3n de la CGT","author":"editor","date":"13 febrero, 2017","format":false,"excerpt":"La central obrera anunci\u00f3 la primera marcha para el 7 de marzo y un paro general para la segunda quincena del mismo mes. Mientras tanto, \u00a0la UTA se sum\u00f3 al reclamo, manifestando que \u201cse perdi\u00f3 la confianza en el gobierno. Parece que la paciencia de los gremios se va agotando,\u2026","rel":"","context":"En \u00abGREMIALES\u00bb","block_context":{"text":"GREMIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/gremiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/02\/paro-7mg2cehfe3k0.jpg?fit=586%2C389&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/02\/paro-7mg2cehfe3k0.jpg?fit=586%2C389&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/02\/paro-7mg2cehfe3k0.jpg?fit=586%2C389&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":5918,"url":"https:\/\/larevistadigital.com.ar\/blog\/la-cgt-encabeza-hoy-el-paro-mas-importante-de-este-siglo\/","url_meta":{"origin":3633,"position":3},"title":"La CGT encabeza hoy el paro m\u00e1s importante de este siglo","author":"admin","date":"25 junio, 2018","format":false,"excerpt":"La huelga, sin movilizaci\u00f3n, decidida por el consejo directivo cegetista el 12 de junio pasado, recibi\u00f3 la adhesi\u00f3n de todo el arco sindical, por lo que se descuenta ser\u00e1 la m\u00e1s importante del siglo. Adem\u00e1s de la CGT se sumaron el MASA, la Corriente Federal, importantes gremios no alineados como\u2026","rel":"","context":"En \u00abGREMIALES\u00bb","block_context":{"text":"GREMIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/gremiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/06\/12-06-2018_buenos_aires_carlos_acunia_hector-5-644x340.jpg?fit=644%2C340&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/06\/12-06-2018_buenos_aires_carlos_acunia_hector-5-644x340.jpg?fit=644%2C340&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/06\/12-06-2018_buenos_aires_carlos_acunia_hector-5-644x340.jpg?fit=644%2C340&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":2163,"url":"https:\/\/larevistadigital.com.ar\/blog\/escueto-acto-de-la-cgt-oficial-con-criticas-a-macri\/","url_meta":{"origin":3633,"position":4},"title":"ESCUETO ACTO DE LA CGT OFICIAL, CON CR\u00cdTICAS A MACRI","author":"Alejandro Sosa Ruda","date":"2 mayo, 2017","format":false,"excerpt":"Durante el d\u00eda de ayer, la CGT se reuni\u00f3 en el estadio de Obras Sanitarias con el objeto de conmemorar el d\u00eda del trabajo y castigar con dureza al gobierno de Mauricio Macri. Juan Carlos Schmid, uno de los integrantes del triunvirato que conduce a la central obrera, fue el\u2026","rel":"","context":"En \u00abDESTACADAS\u00bb","block_context":{"text":"DESTACADAS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/destacadas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/05\/descarga.jpg?fit=650%2C436&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/05\/descarga.jpg?fit=650%2C436&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/05\/descarga.jpg?fit=650%2C436&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":5921,"url":"https:\/\/larevistadigital.com.ar\/blog\/la-lectura-de-roberto-fernandez-nadie-esta-en-contra-del-gobierno-pero-la-situacion-economica-exploto\/","url_meta":{"origin":3633,"position":5},"title":"La lectura de Roberto Fernandez: \u201cnadie est\u00e1 en contra del Gobierno, pero la situaci\u00f3n econ\u00f3mica explot\u00f3\u201d","author":"admin","date":"25 junio, 2018","format":false,"excerpt":"\u201cLa econom\u00eda se dolariz\u00f3, pero el salario es en pesos\u201d, adujo Roberto Fernandez en declaraciones a la radio Mitre. \u201cCada vez el trabajador pierde poder adquisitivo, la econom\u00eda se dolariz\u00f3 y la econom\u00eda es en pesos\u201d, insisti\u00f3 el titular de la UTA y referente de los gremios del transporte. Sostuvo\u2026","rel":"","context":"En \u00abGREMIALES\u00bb","block_context":{"text":"GREMIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/gremiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/06\/25-06-2018_buenos_aires_la_avenida_san-644x340.jpg?fit=644%2C340&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/06\/25-06-2018_buenos_aires_la_avenida_san-644x340.jpg?fit=644%2C340&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/06\/25-06-2018_buenos_aires_la_avenida_san-644x340.jpg?fit=644%2C340&ssl=1&resize=525%2C300 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/3633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=3633"}],"version-history":[{"count":1,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/3633\/revisions"}],"predecessor-version":[{"id":3635,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/3633\/revisions\/3635"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media\/3634"}],"wp:attachment":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=3633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=3633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=3633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}