{"id":4011,"date":"2017-11-26T06:39:03","date_gmt":"2017-11-26T06:39:03","guid":{"rendered":"https:\/\/larevistadigital.com.ar\/blog\/?p=4011"},"modified":"2017-11-27T06:42:21","modified_gmt":"2017-11-27T06:42:21","slug":"encuentran-joven-sin-vida","status":"publish","type":"post","link":"https:\/\/larevistadigital.com.ar\/blog\/encuentran-joven-sin-vida\/","title":{"rendered":"Encuentran a un joven sin vida"},"content":{"rendered":"<p>Un joven de unos 20 a\u00f1os de edad fue encontrado sin vida, esta tarde, cerca de las 17 hs , en una vivienda del sector rural, camino a \u201cLa California\u201d<\/p>\n<p>La informaci\u00f3n fue confirmada por un vocero judicial a castellidiario.com.ar quien adem\u00e1s se\u00f1al\u00f3 que investigan cuales ser\u00edan las causales de la fatal determinaci\u00f3n.<\/p>\n<p>Si bien no trascendieron mayores detalles, el joven habr\u00eda estado solo en la vivienda-<\/p>\n<p>Por estas horas trabaja policia rural Castelli, policia cientifica e interviene la Ayudant\u00eda Fiscal Castelli a cargo de la Dra Bruno Hermosa<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Un joven de unos 20 a\u00f1os de edad fue encontrado sin vida, esta tarde, cerca de las 17 hs , en una vivienda del sector rural, camino a \u201cLa California\u201d La informaci\u00f3n fue confirmada por <a class=\"mh-excerpt-more\" href=\"https:\/\/larevistadigital.com.ar\/blog\/encuentran-joven-sin-vida\/\" title=\"Encuentran a un joven sin vida\">[Leer M\u00e1s]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":4013,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"Encuentran a un joven sin vida","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[4],"tags":[],"class_list":{"0":"post-4011","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-castelli"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/11\/PATRULLERO-POLICIA-CIENTIFICA.jpg?fit=700%2C464&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8qtrQ-12H","jetpack-related-posts":[{"id":37965,"url":"https:\/\/larevistadigital.com.ar\/blog\/muere-en-castelli-un-joven-electrocutado\/","url_meta":{"origin":4011,"position":0},"title":"Muere en Castelli un joven electrocutado.","author":"Alejandro Sosa Ruda","date":"23 noviembre, 2024","format":false,"excerpt":"La v\u00edctima ten\u00eda unos 20 a\u00f1os y resid\u00eda en Castelli. Se habr\u00eda electrocutado con un ventilador. 23 de Noviembre de 2024 CASTELLI -\u00a0 \u00a0Un muchacho que resid\u00eda en Castelli, pero era oriundo de Dolores falleci\u00f3 v\u00edctima de electrocuci\u00f3n en su vivienda. El luctuoso suceso, ocurri\u00f3 en horas del mediod\u00eda, en\u2026","rel":"","context":"En \u00abPOLICIALES\u00bb","block_context":{"text":"POLICIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/policiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2021-12-29-203210.jpg?fit=1013%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2021-12-29-203210.jpg?fit=1013%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2021-12-29-203210.jpg?fit=1013%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2021-12-29-203210.jpg?fit=1013%2C675&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2925,"url":"https:\/\/larevistadigital.com.ar\/blog\/aprehenden-a-un-joven-tras-reyerta-callejera\/","url_meta":{"origin":4011,"position":1},"title":"Aprehenden a un joven tras reyerta callejera","author":"admin","date":"2 agosto, 2017","format":false,"excerpt":"Un joven fue aprehendido, \u00a0este mi\u00e9rcoles por la tarde, en una vivienda del barrio Autoconstrucci\u00f3n. Seg\u00fan se\u00f1al\u00f3 una fuente policial consultada por castellidiario el aprehendido habr\u00eda mantenido una discusi\u00f3n y enfrentamiento con un vecino en el barrio solidaridad, hecho que motivo el llamado de la polic\u00eda. \u201cHubo una discusi\u00f3n y\u2026","rel":"","context":"En \u00abCASTELLI\u00bb","block_context":{"text":"CASTELLI","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/castelli\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/08\/detenido4.jpg?fit=600%2C338&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/08\/detenido4.jpg?fit=600%2C338&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/08\/detenido4.jpg?fit=600%2C338&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":2356,"url":"https:\/\/larevistadigital.com.ar\/blog\/joven-hallado-sin-vida-en-un-taller\/","url_meta":{"origin":4011,"position":2},"title":"JOVEN HALLADO SIN VIDA EN UN TALLER","author":"Alejandro Sosa Ruda","date":"9 junio, 2017","format":false,"excerpt":"Un joven de 22 a\u00f1os fue encontrado sin vida, en un taller de chapa y pintura del automotor, ubicado en calle Buenos Aires al 500 de nuestra ciudad. Se trata de Nahuel Venturo, de profesi\u00f3n chapista, quien habr\u00eda sido encontrado por un familiar, cerca del mediod\u00eda de este viernes, confirm\u00f3\u2026","rel":"","context":"En \u00abCASTELLI\u00bb","block_context":{"text":"CASTELLI","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/castelli\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/06\/am6cntzxqqqpl_gpd5dxehpzyslaurwofwco3rhmeri4.jpg?fit=710%2C350&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/06\/am6cntzxqqqpl_gpd5dxehpzyslaurwofwco3rhmeri4.jpg?fit=710%2C350&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/06\/am6cntzxqqqpl_gpd5dxehpzyslaurwofwco3rhmeri4.jpg?fit=710%2C350&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/06\/am6cntzxqqqpl_gpd5dxehpzyslaurwofwco3rhmeri4.jpg?fit=710%2C350&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":24741,"url":"https:\/\/larevistadigital.com.ar\/blog\/castelli-apunalan-a-policia-en-un-bar\/","url_meta":{"origin":4011,"position":3},"title":"CASTELLI: APU\u00d1ALAN A POLICIA EN UN BAR","author":"Alejandro Sosa Ruda","date":"22 marzo, 2022","format":false,"excerpt":"El agente, que estaba de franco, recibi\u00f3 un puntazo de otro hombre, que todav\u00eda no pudo ser identificado. El efectivo policial est\u00e1 fuera de peligro. CASTELLI -\u00a0 Un joven de aproximadamente 20 a\u00f1os, que se desempe\u00f1a como efectivo policial, recibi\u00f3 un puntazo en una vivienda de Castelli\u00a0que es utilizada como\u2026","rel":"","context":"En \u00abCASTELLI\u00bb","block_context":{"text":"CASTELLI","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/castelli\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/a61246391ccea937704656e6620d20091c74f43e.jpg?fit=1140%2C601&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/a61246391ccea937704656e6620d20091c74f43e.jpg?fit=1140%2C601&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/a61246391ccea937704656e6620d20091c74f43e.jpg?fit=1140%2C601&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/a61246391ccea937704656e6620d20091c74f43e.jpg?fit=1140%2C601&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/a61246391ccea937704656e6620d20091c74f43e.jpg?fit=1140%2C601&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":6615,"url":"https:\/\/larevistadigital.com.ar\/blog\/castelli-detienen-a-joven-por-abuso-sexual-a-una-menor\/","url_meta":{"origin":4011,"position":4},"title":"CASTELLI: DETIENEN A JOVEN POR ABUSO SEXUAL A UNA MENOR","author":"Alejandro Sosa Ruda","date":"23 septiembre, 2018","format":false,"excerpt":"La polic\u00eda aprehendi\u00f3 en la ma\u00f1ana del domingo a un joven se\u00f1alado por ser el autor material de un abuso sexual a una menor en la ciudad de Castelli. Seg\u00fan reportaron a castellidiario el hecho se produjo en la madrugada de este s\u00e1bado, en el predio de un club donde\u2026","rel":"","context":"En \u00abCASTELLI\u00bb","block_context":{"text":"CASTELLI","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/castelli\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/09\/fiscalia-1.jpg?fit=800%2C395&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/09\/fiscalia-1.jpg?fit=800%2C395&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/09\/fiscalia-1.jpg?fit=800%2C395&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/09\/fiscalia-1.jpg?fit=800%2C395&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":39044,"url":"https:\/\/larevistadigital.com.ar\/blog\/conmocion-un-joven-de-castelli-lucha-por-su-vida-tras-un-grave-accidente\/","url_meta":{"origin":4011,"position":5},"title":"Conmoci\u00f3n: Un joven de Castelli lucha por su vida tras un grave accidente","author":"Alejandro Sosa Ruda","date":"16 marzo, 2025","format":false,"excerpt":"Su familia pide una cadena de oraci\u00f3n por su recuperaci\u00f3n. 16 de Marzo de 2025 CASTELLI -\u00a0 \u00a0Un joven de 16 a\u00f1os, identificado como Tom\u00e1s Iriarte, sufri\u00f3 un grave accidente mientras realizaba tareas rurales con su caballo en un establecimiento de la zona de Cerro de La Gloria, en Castelli.\u2026","rel":"","context":"En \u00abCASTELLI\u00bb","block_context":{"text":"CASTELLI","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/castelli\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/4901719641db92185723b4e528ab23c5a3486d02-e1742139651132.jpg?fit=720%2C516&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/4901719641db92185723b4e528ab23c5a3486d02-e1742139651132.jpg?fit=720%2C516&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/4901719641db92185723b4e528ab23c5a3486d02-e1742139651132.jpg?fit=720%2C516&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/4901719641db92185723b4e528ab23c5a3486d02-e1742139651132.jpg?fit=720%2C516&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/4011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=4011"}],"version-history":[{"count":1,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/4011\/revisions"}],"predecessor-version":[{"id":4014,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/4011\/revisions\/4014"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media\/4013"}],"wp:attachment":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=4011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=4011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=4011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}