{"id":40675,"date":"2025-07-31T21:38:16","date_gmt":"2025-08-01T00:38:16","guid":{"rendered":"https:\/\/larevistadigital.com.ar\/blog\/?p=40675"},"modified":"2025-07-31T21:38:16","modified_gmt":"2025-08-01T00:38:16","slug":"detectan-nuevos-brotes-de-triquinosis-en-la-provincia-de-buenos-aires","status":"publish","type":"post","link":"https:\/\/larevistadigital.com.ar\/blog\/detectan-nuevos-brotes-de-triquinosis-en-la-provincia-de-buenos-aires\/","title":{"rendered":"Detectan nuevos brotes de triquinosis en la provincia de Buenos Aires"},"content":{"rendered":"<h3 class=\"fparrafo ctext fz18 lh25\">El Ministerio de Salud bonaerense volvi\u00f3 a emitir una alerta sanitaria tras la confirmaci\u00f3n de dos nuevos brotes de triquinosis en la provincia. Seg\u00fan el \u00faltimo Bolet\u00edn Epidemiol\u00f3gico correspondiente a la semana del 13 al 19 de julio, en lo que va del a\u00f1o se reportaron 81 casos sospechosos de la enfermedad. De estos, 40 fueron confirmados, 3 descartados y 38 a\u00fan contin\u00faan bajo evaluaci\u00f3n m\u00e9dica.<\/h3>\n<p>31 de Julio de 2025<\/p>\n<p><strong>BUENOS AIRES &#8211;\u00a0 <\/strong>Los primeros casos fueron detectados en Tornquist y Bah\u00eda Blanca durante la \u00faltima semana de junio, donde se registraron seis personas afectadas tras consumir carne de cerdo casera. Posteriormente, a mediados de julio, se identific\u00f3 otro brote en la localidad de Azul, que afect\u00f3 a 31 personas, tambi\u00e9n vinculadas al consumo de productos elaborados artesanalmente.<\/p>\n<blockquote>\n<h3 class=\"selectionShareable\">Este martes, el portal InfoGEI dio cuenta de dos adultos, que fueron hospitalizados en el Hospital Municipal de Trenque Lauquen tras haberse confirmado que padecen triquinosis.<\/h3>\n<\/blockquote>\n<p class=\"selectionShareable\">Se trata de un padre y su hijo, quienes ingresaron durante el fin de semana con s\u00edntomas como fiebre, dolor de cabeza, inflamaci\u00f3n en los p\u00e1rpados, enrojecimiento ocular en ambos ojos y dolores musculares generalizados. Ambos evolucionan favorablemente bajo tratamiento m\u00e9dico.<\/p>\n<blockquote>\n<h3 class=\"selectionShareable\">La triquinosis es una enfermedad parasitaria provocada por el Trichinella spiralis, un nem\u00e1todo que infecta principalmente a cerdos y animales silvestres como jabal\u00edes o pumas. La infecci\u00f3n en humanos ocurre tras ingerir carne mal cocida que contiene las larvas del par\u00e1sito.<\/h3>\n<\/blockquote>\n<p class=\"selectionShareable\">Una vez en el cuerpo humano, las larvas se alojan en el intestino y desde all\u00ed migran al torrente sangu\u00edneo, colonizando distintos m\u00fasculos, incluso los del coraz\u00f3n, diafragma y sistema nervioso.<\/p>\n<p class=\"selectionShareable\">El Ministerio de Salud de la Naci\u00f3n subraya que el cerdo dom\u00e9stico es la principal fuente de contagio en Argentina, aunque tambi\u00e9n puede haber infecciones a partir de otros animales salvajes. La enfermedad no se transmite entre personas.<\/p>\n<p class=\"selectionShareable\"><span style=\"color: #ff0000\"><b>S\u00edntomas comunes:<\/b><\/span><\/p>\n<p class=\"selectionShareable\">-Dolor abdominal y espasmos<\/p>\n<p class=\"selectionShareable\">-Diarrea<\/p>\n<p class=\"selectionShareable\">-Fiebre<\/p>\n<p class=\"selectionShareable\">-Hinchaz\u00f3n alrededor de los ojos<\/p>\n<p class=\"selectionShareable\">-Dolores musculares (al respirar, masticar o mover grandes grupos musculares)<\/p>\n<p class=\"selectionShareable\">-Debilidad general<\/p>\n<p class=\"selectionShareable\"><span style=\"color: #ff0000\"><b>Diagn\u00f3stico precoz<\/b><\/span><\/p>\n<p class=\"selectionShareable\">Es clave para iniciar un tratamiento adecuado, un temprano diagn\u00f3stico, sobre todo si la persona consumi\u00f3 embutidos o carne de cerdo casera. Si las larvas alcanzan los m\u00fasculos, no hay cura espec\u00edfica, y los tratamientos se orientan a aliviar los s\u00edntomas, especialmente el dolor.<\/p>\n<p class=\"selectionShareable\">En los brotes m\u00e1s recientes, el Ministerio bonaerense confirm\u00f3 que todas las personas afectadas fueron tratadas con albendazol y mebendazol, medicamentos preparados por el Instituto Biol\u00f3gico Tom\u00e1s Per\u00f3n.<\/p>\n<p class=\"selectionShareable\"><span style=\"color: #ff0000\"><b>Medidas de prevenci\u00f3n<\/b><\/span><\/p>\n<p class=\"selectionShareable\">Se recomienda consumir \u00fanicamente carne bien cocida, asegur\u00e1ndose de que no queden zonas rosadas y que la temperatura interna supere los 71\u00b0C durante al menos un minuto. Tambi\u00e9n se alerta que el curado con sal no elimina el par\u00e1sito.<\/p>\n<p class=\"selectionShareable\">Para evitar riesgos, los expertos aconsejan adquirir productos derivados del cerdo, como chacinados y embutidos, solo en establecimientos habilitados, y revisar siempre las etiquetas para confirmar su procedencia, fecha de elaboraci\u00f3n y vencimiento.\u00a0<b>(InfoGEI)Ac<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>El Ministerio de Salud bonaerense volvi\u00f3 a emitir una alerta sanitaria tras la confirmaci\u00f3n de dos nuevos brotes de triquinosis en la provincia. Seg\u00fan el \u00faltimo Bolet\u00edn Epidemiol\u00f3gico correspondiente a la semana del 13 al <a class=\"mh-excerpt-more\" href=\"https:\/\/larevistadigital.com.ar\/blog\/detectan-nuevos-brotes-de-triquinosis-en-la-provincia-de-buenos-aires\/\" title=\"Detectan nuevos brotes de triquinosis en la provincia de Buenos Aires\">[Leer M\u00e1s]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":40676,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[51],"tags":[],"class_list":{"0":"post-40675","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-regionales"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20250730191617_brotes-triquinosis-provincia-buenos-aires.jpg?fit=880%2C512&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8qtrQ-aA3","jetpack-related-posts":[{"id":33306,"url":"https:\/\/larevistadigital.com.ar\/blog\/a-tener-cuidado-ya-hay-217-casos-confirmados-de-triquinosis-en-20-municipios-bonaerenses\/","url_meta":{"origin":40675,"position":0},"title":"A TENER CUIDADO: YA HAY 217 CASOS CONFIRMADOS DE TRIQUINOSIS EN 20 MUNICIPIOS BONAERENSES.","author":"Alejandro Sosa Ruda","date":"5 septiembre, 2023","format":false,"excerpt":"En tanto, hay otros 239 casos en estudio. Todos los casos evolucionaron favorablemente y se provey\u00f3 el tratamiento correspondiente. En la provincia de Buenos Aires, los brotes de triquinosis se producen en su mayor\u00eda durante la \u00e9poca de bajas temperaturas. 5 de Septiembre de 2023 BUENOS AIRES -\u00a0 La provincia\u2026","rel":"","context":"En \u00abREGIONALES\u00bb","block_context":{"text":"REGIONALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/regionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20230905175519_triquinosis.jpg?fit=880%2C512&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20230905175519_triquinosis.jpg?fit=880%2C512&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20230905175519_triquinosis.jpg?fit=880%2C512&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20230905175519_triquinosis.jpg?fit=880%2C512&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":46518,"url":"https:\/\/larevistadigital.com.ar\/blog\/confirman-seis-casos-de-triquinosis-en-general-madariaga-y-piden-no-consumir-embutidos-sin-rotulo\/","url_meta":{"origin":40675,"position":1},"title":"Confirman seis casos de triquinosis en General Madariaga y piden no consumir embutidos sin r\u00f3tulo","author":"Alejandro Sosa Ruda","date":"12 julio, 2026","format":false,"excerpt":"Las autoridades sanitarias confirmaron seis casos de triquinosis mediante an\u00e1lisis de laboratorio y mantienen bajo observaci\u00f3n a otras 45 personas. Ante el brote, recomendaron no consumir chacinados ni embutidos que no cuenten con identificaci\u00f3n sanitaria. 12 De julio de 2026 GENERAL MADARIAGA -\u00a0 La Municipalidad de General Madariaga confirm\u00f3 la\u2026","rel":"","context":"En \u00abREGIONALES\u00bb","block_context":{"text":"REGIONALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/regionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-07-12-014412.jpg?fit=801%2C434&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-07-12-014412.jpg?fit=801%2C434&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-07-12-014412.jpg?fit=801%2C434&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-07-12-014412.jpg?fit=801%2C434&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":5302,"url":"https:\/\/larevistadigital.com.ar\/blog\/analisis-gratuito-de-triquinosis\/","url_meta":{"origin":40675,"position":2},"title":"AN\u00c1LISIS GRATUITO DE TRIQUINOSIS","author":"admin","date":"27 marzo, 2018","format":false,"excerpt":"\u00a0 El Gobierno Municipal de General Belgrano informa a trav\u00e9s de la Secretar\u00eda de Salud, que se reciben muestras de \u201centra\u00f1as\u201d de\u00a0cerdo para ser analizadas y as\u00ed diagnosticar, fundamentalmente, la presencia o no de triquinosis. Cabe se\u00f1alar que el m\u00e9todo utilizado para determinar existencia de la enfermedad en el animal\u2026","rel":"","context":"En \u00abGENERAL BELGRANO\u00bb","block_context":{"text":"GENERAL BELGRANO","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/general-belgrano\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/03\/29511194_1576716675709231_175917392037441094_n.jpg?fit=710%2C350&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/03\/29511194_1576716675709231_175917392037441094_n.jpg?fit=710%2C350&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/03\/29511194_1576716675709231_175917392037441094_n.jpg?fit=710%2C350&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/03\/29511194_1576716675709231_175917392037441094_n.jpg?fit=710%2C350&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":35636,"url":"https:\/\/larevistadigital.com.ar\/blog\/buenos-aires-un-severo-temporal-fue-dejando-destrozos-a-su-paso\/","url_meta":{"origin":40675,"position":3},"title":"BUENOS AIRES: UN SEVERO TEMPORAL FUE DEJANDO DESTROZOS A SU PASO","author":"Alejandro Sosa Ruda","date":"19 marzo, 2024","format":false,"excerpt":"Una \"supercelda\" de clima severo atraves\u00f3 el centro de la provincia de Buenos Aires, dejando a su paso da\u00f1os en infraestructuras, calles inundadas y \u00e1rboles derribados. 19 de marzo de 2024 BUENOS AIRES -\u00a0 \u00a0Rivadavia, Chivilcoy, Bragado y 9 de Julio fueron algunos de los municipios afectados por este fen\u00f3meno.\u2026","rel":"","context":"En \u00abREGIONALES\u00bb","block_context":{"text":"REGIONALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/regionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/captura-2o.jpg?fit=1200%2C636&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/captura-2o.jpg?fit=1200%2C636&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/captura-2o.jpg?fit=1200%2C636&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/captura-2o.jpg?fit=1200%2C636&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/captura-2o.jpg?fit=1200%2C636&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":25950,"url":"https:\/\/larevistadigital.com.ar\/blog\/alertan-sobre-nuevos-casos-de-fiebre-hemorragica-argentina\/","url_meta":{"origin":40675,"position":4},"title":"ALERTAN SOBRE NUEVOS CASOS DE FIEBRE HEMORR\u00c1GICA ARGENTINA","author":"Alejandro Sosa Ruda","date":"16 junio, 2022","format":false,"excerpt":"La Sociedad Argentina de Infectolog\u00eda alert\u00f3 sobre un aumento de casos de Fiebre Hemorr\u00e1gica Argentina en la zona end\u00e9mica. \u00bfQu\u00e9 es y c\u00f3mo evitarla? Esta semana, la Sociedad Argentina de Infectolog\u00eda alert\u00f3 mediante un informe alert\u00f3 sobre el aumento de casos de Fiebre Hemorr\u00e1gica Argentina. En la provincia de Buenos\u2026","rel":"","context":"En \u00abINTERES GENERAL\u00bb","block_context":{"text":"INTERES GENERAL","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/interes-general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/1da6a380c3b066e95e8d0b4e093904b1e221721a.jpg?fit=1140%2C538&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/1da6a380c3b066e95e8d0b4e093904b1e221721a.jpg?fit=1140%2C538&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/1da6a380c3b066e95e8d0b4e093904b1e221721a.jpg?fit=1140%2C538&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/1da6a380c3b066e95e8d0b4e093904b1e221721a.jpg?fit=1140%2C538&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/1da6a380c3b066e95e8d0b4e093904b1e221721a.jpg?fit=1140%2C538&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":40446,"url":"https:\/\/larevistadigital.com.ar\/blog\/hipomagnesemia-la-enfermedad-silenciosa-que-ya-provoco-la-mortandad-de-miles-de-vacas-en-la-provincia\/","url_meta":{"origin":40675,"position":5},"title":"Hipomagnesemia: La enfermedad silenciosa que ya provoc\u00f3 la mortandad de miles de vacas en la Provincia","author":"Alejandro Sosa Ruda","date":"13 julio, 2025","format":false,"excerpt":"Un reciente informe del INTA Balcarce encendi\u00f3 las alarmas entre los productores ganaderos bonaerenses. Se trata de la hipomagnesemia bovina, conocida tambi\u00e9n como tetania de los pastos, una afecci\u00f3n metab\u00f3lica que afecta a vacas adultas en sistemas pastoriles y puede causar la muerte de forma s\u00fabita, sin se\u00f1ales previas. 13\u2026","rel":"","context":"En \u00abREGIONALES\u00bb","block_context":{"text":"REGIONALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/regionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20250711185803_alerta-hipomagnesemia-enfermedad-silenciosa-inta-balcarce.jpg?fit=880%2C512&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20250711185803_alerta-hipomagnesemia-enfermedad-silenciosa-inta-balcarce.jpg?fit=880%2C512&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20250711185803_alerta-hipomagnesemia-enfermedad-silenciosa-inta-balcarce.jpg?fit=880%2C512&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20250711185803_alerta-hipomagnesemia-enfermedad-silenciosa-inta-balcarce.jpg?fit=880%2C512&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/40675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=40675"}],"version-history":[{"count":1,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/40675\/revisions"}],"predecessor-version":[{"id":40677,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/40675\/revisions\/40677"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media\/40676"}],"wp:attachment":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=40675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=40675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=40675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}