{"id":40937,"date":"2025-08-16T20:38:57","date_gmt":"2025-08-16T23:38:57","guid":{"rendered":"https:\/\/larevistadigital.com.ar\/blog\/?p=40937"},"modified":"2025-08-16T20:38:57","modified_gmt":"2025-08-16T23:38:57","slug":"chascomus-choque-entre-dos-camionetas-sin-heridos","status":"publish","type":"post","link":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-choque-entre-dos-camionetas-sin-heridos\/","title":{"rendered":"Chascom\u00fas: Choque entre dos camionetas sin heridos"},"content":{"rendered":"<h2>El accidente gener\u00f3 demoras en el tr\u00e1nsito durante el mediod\u00eda del s\u00e1bado.<\/h2>\n<p>16 de Agosto de 2025<\/p>\n<p><strong>CHASCOM\u00daS\u00a0 &#8211;\u00a0 <\/strong>Un choque entre dos camionetas,\u00a0 m\u00e1s precisamente dos\u00a0 Toyota Hilux, en la intersecci\u00f3n de las calles Alte. Brown y Mendiola provoc\u00f3 demoras en el tr\u00e1nsito durante la tarde de este s\u00e1bado. El hecho ocurri\u00f3 cerca de las 14 horas y oblig\u00f3 a la intervenci\u00f3n de personal policial y de inspector\u00eda municipal.<\/p>\n<p data-start=\"497\" data-end=\"759\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-40939 alignright\" src=\"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/CHOQUE-1.jpg?resize=300%2C132&#038;ssl=1\" alt=\"\" width=\"300\" height=\"132\" srcset=\"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/CHOQUE-1.jpg?resize=300%2C132&amp;ssl=1 300w, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/CHOQUE-1.jpg?resize=1024%2C450&amp;ssl=1 1024w, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/CHOQUE-1.jpg?resize=768%2C338&amp;ssl=1 768w, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/CHOQUE-1.jpg?w=1272&amp;ssl=1 1272w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Si bien uno de los veh\u00edculos qued\u00f3 detenido en medio de la calle, lo que gener\u00f3 complicaciones para circular, no se registraron heridos. Inspector\u00eda permaneci\u00f3 en el lugar hasta la llegada de una gr\u00faa para retirar el rodado y normalizar el tr\u00e1nsito en la zona.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>El accidente gener\u00f3 demoras en el tr\u00e1nsito durante el mediod\u00eda del s\u00e1bado. 16 de Agosto de 2025 CHASCOM\u00daS\u00a0 &#8211;\u00a0 Un choque entre dos camionetas,\u00a0 m\u00e1s precisamente dos\u00a0 Toyota Hilux, en la intersecci\u00f3n de las calles <a class=\"mh-excerpt-more\" href=\"https:\/\/larevistadigital.com.ar\/blog\/chascomus-choque-entre-dos-camionetas-sin-heridos\/\" title=\"Chascom\u00fas: Choque entre dos camionetas sin heridos\">[Leer M\u00e1s]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":40938,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[41,44],"tags":[],"class_list":{"0":"post-40937","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destacadas","8":"category-policiales"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/CHOQUE-2.jpg?fit=1280%2C573&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8qtrQ-aEh","jetpack-related-posts":[{"id":43052,"url":"https:\/\/larevistadigital.com.ar\/blog\/choque-entre-dos-autos-en-ruta-2-provoco-demoras-y-desvios-en-plena-tarde\/","url_meta":{"origin":40937,"position":0},"title":"Choque entre dos autos en Ruta 2 provoc\u00f3 demoras y desv\u00edos en plena tarde","author":"Alejandro Sosa Ruda","date":"29 diciembre, 2025","format":false,"excerpt":"El accidente ocurri\u00f3 en el kil\u00f3metro 82,5 en sentido a Mar del Plata. No hubo heridos, pero la calzada qued\u00f3 obstruida durante varios minutos. 29 de diciembre de 2025 Un fuerte choque entre dos autom\u00f3viles gener\u00f3 importantes complicaciones en el tr\u00e1nsito durante la tarde de este lunes en la Ruta\u2026","rel":"","context":"En \u00abINTERES GENERAL\u00bb","block_context":{"text":"INTERES GENERAL","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/interes-general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2025-12-29-204512.jpg?fit=892%2C365&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2025-12-29-204512.jpg?fit=892%2C365&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2025-12-29-204512.jpg?fit=892%2C365&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2025-12-29-204512.jpg?fit=892%2C365&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":40865,"url":"https:\/\/larevistadigital.com.ar\/blog\/tragedia-y-caos-en-ruta-11-choque-multiple-por-perros-sueltos-dejo-cinco-heridos\/","url_meta":{"origin":40937,"position":1},"title":"Tragedia y caos en Ruta 11: choque m\u00faltiple por perros sueltos dej\u00f3 cinco heridos","author":"Alejandro Sosa Ruda","date":"13 agosto, 2025","format":false,"excerpt":"Un ins\u00f3lito accidente involucr\u00f3 a tres veh\u00edculos y provoc\u00f3 horas de demoras. Dos animales murieron en el acto. 13 de Agosto de 2025 BUENOS AIRES\u00a0 -\u00a0 \u00a0 La calma de la costa atl\u00e1ntica se vio interrumpida este martes por la tarde, cuando la Ruta Provincial N\u00b011, a la altura del\u2026","rel":"","context":"En \u00abPOLICIALES\u00bb","block_context":{"text":"POLICIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/policiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/ACCIDENTE-MULTIPLE.jpg?fit=481%2C351&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":13892,"url":"https:\/\/larevistadigital.com.ar\/blog\/choque-en-la-ruta-11-un-herido-con-heridas-de-consideracion\/","url_meta":{"origin":40937,"position":2},"title":"CHOQUE EN LA RUTA 11. UN HERIDO CON HERIDAS DE CONSIDERACI\u00d3N","author":"Alejandro Sosa Ruda","date":"29 diciembre, 2019","format":false,"excerpt":"Otro choque en cadena se produjo durante la tarde de ayer, en este caso fue en el kil\u00f3metro 288 de la Ruta 11, en jurisdicci\u00f3n de General Lavalle. Fueron cuatro los veh\u00edculos involucrados y once las personas que debieron ser atendidas en el lugar, de las cuales una fue trasladada\u2026","rel":"","context":"En \u00abREGIONALES\u00bb","block_context":{"text":"REGIONALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/regionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/e4266c8485676aa195db623388a9406742cec28b.jpg?fit=1140%2C855&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/e4266c8485676aa195db623388a9406742cec28b.jpg?fit=1140%2C855&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/e4266c8485676aa195db623388a9406742cec28b.jpg?fit=1140%2C855&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/e4266c8485676aa195db623388a9406742cec28b.jpg?fit=1140%2C855&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/e4266c8485676aa195db623388a9406742cec28b.jpg?fit=1140%2C855&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":40629,"url":"https:\/\/larevistadigital.com.ar\/blog\/tragedia-en-ruta-29-una-mujer-fallecida-y-varios-heridos-tras-un-violento-choque-frontal-cerca-de-villanueva\/","url_meta":{"origin":40937,"position":3},"title":"Tragedia en Ruta 29: una mujer fallecida y varios heridos tras un violento choque frontal cerca de Villanueva","author":"Alejandro Sosa Ruda","date":"26 julio, 2025","format":false,"excerpt":"El accidente ocurri\u00f3 pasadas las 20 en un tramo cercano al acceso a Villanueva. La v\u00edctima fatal falleci\u00f3 en el acto y entre los heridos hay dos menores. Todos fueron trasladados al Hospital de Ranchos. 26 de Julio de 225 VILLANUEVA -\u00a0 \u00a0Un tr\u00e1gico accidente de tr\u00e1nsito se produjo en\u2026","rel":"","context":"En \u00abPOLICIALES\u00bb","block_context":{"text":"POLICIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/policiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/istockphoto-1446474143-612x612-1.jpg?fit=612%2C344&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/istockphoto-1446474143-612x612-1.jpg?fit=612%2C344&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/istockphoto-1446474143-612x612-1.jpg?fit=612%2C344&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":44741,"url":"https:\/\/larevistadigital.com.ar\/blog\/choque-en-cadena-y-caos-total-en-la-ruta-11-transito-colapsado-a-la-salida-de-mar-del-plata\/","url_meta":{"origin":40937,"position":4},"title":"Choque en cadena y caos total en la Ruta 11: tr\u00e1nsito colapsado a la salida de Mar del Plata","author":"Alejandro Sosa Ruda","date":"26 marzo, 2026","format":false,"excerpt":"Un siniestro con al menos cinco veh\u00edculos gener\u00f3 demoras, desv\u00edos y una postal de alto impacto en plena hora pico. 26 de marzo de 2026 Una escena de tensi\u00f3n y largas filas de autos marc\u00f3 la tarde de este jueves en la Ruta 11, a la altura del ingreso al\u2026","rel":"","context":"En \u00abPOLICIALES\u00bb","block_context":{"text":"POLICIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/policiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-03-26-235541.jpg?fit=808%2C240&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-03-26-235541.jpg?fit=808%2C240&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-03-26-235541.jpg?fit=808%2C240&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-03-26-235541.jpg?fit=808%2C240&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":8287,"url":"https:\/\/larevistadigital.com.ar\/blog\/choque-en-cadena-en-ruta-11-al-menos-diez-heridos\/","url_meta":{"origin":40937,"position":5},"title":"CHOQUE EN CADENA EN RUTA 11. AL MENOS DIEZ HERIDOS","author":"Alejandro Sosa Ruda","date":"10 febrero, 2019","format":false,"excerpt":"Se habr\u00eda producido por el humo y la neblina que imped\u00edan la visibilidad. Los motivos y detalles. Al menos diez heridos en un choque en cadena en la Ruta 11 a la altura del kil\u00f3metro 404. Ocurri\u00f3 por la ma\u00f1ana, entre el humo y la neblina imped\u00edan la visibilidad. Un\u2026","rel":"","context":"En \u00abPOLICIALES\u00bb","block_context":{"text":"POLICIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/policiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2019\/02\/0e758ef5e97a969bd6b7f5d1fa7454f27ca0224c.jpg?fit=1140%2C760&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2019\/02\/0e758ef5e97a969bd6b7f5d1fa7454f27ca0224c.jpg?fit=1140%2C760&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2019\/02\/0e758ef5e97a969bd6b7f5d1fa7454f27ca0224c.jpg?fit=1140%2C760&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2019\/02\/0e758ef5e97a969bd6b7f5d1fa7454f27ca0224c.jpg?fit=1140%2C760&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2019\/02\/0e758ef5e97a969bd6b7f5d1fa7454f27ca0224c.jpg?fit=1140%2C760&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/40937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=40937"}],"version-history":[{"count":1,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/40937\/revisions"}],"predecessor-version":[{"id":40940,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/40937\/revisions\/40940"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media\/40938"}],"wp:attachment":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=40937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=40937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=40937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}