{"id":41073,"date":"2025-08-24T17:04:13","date_gmt":"2025-08-24T20:04:13","guid":{"rendered":"https:\/\/larevistadigital.com.ar\/blog\/?p=41073"},"modified":"2025-08-24T17:10:34","modified_gmt":"2025-08-24T20:10:34","slug":"allanamientos-en-tres-ciudades-bonaerenses-por-un-caso-de-mala-praxis-y-ejercicio-ilegal-de-la-medicina","status":"publish","type":"post","link":"https:\/\/larevistadigital.com.ar\/blog\/allanamientos-en-tres-ciudades-bonaerenses-por-un-caso-de-mala-praxis-y-ejercicio-ilegal-de-la-medicina\/","title":{"rendered":"Allanamientos en tres ciudades bonaerenses por un caso de mala praxis y ejercicio ilegal de la medicina"},"content":{"rendered":"<h3 data-start=\"428\" data-end=\"694\"><em data-start=\"428\" data-end=\"692\">La investigaci\u00f3n se origin\u00f3 tras la muerte de una mujer que recibi\u00f3 un diagn\u00f3stico equivocado en su domicilio por un servicio privado de ambulancias. Tres personas quedaron imputadas por delitos vinculados al ejercicio ilegal de la medicina y asociaci\u00f3n il\u00edcita.<\/em><\/h3>\n<p>24 de agosto de 2025<\/p>\n<p data-start=\"696\" data-end=\"1161\"><strong>BUENOS AIRES\u00a0 &#8211;<\/strong>\u00a0 \u00a0Tres allanamientos en simult\u00e1neo se llevaron adelante en los partidos bonaerenses de Presidente Per\u00f3n, La Plata y Magdalena, en el marco de una causa por <strong data-start=\"850\" data-end=\"958\">asociaci\u00f3n il\u00edcita, estafa, abandono de persona, usurpaci\u00f3n de t\u00edtulos y ejercicio ilegal de la medicina<\/strong>. El caso se inici\u00f3 luego de la muerte de una mujer que fue atendida en su domicilio por un servicio privado de emergencias que le brind\u00f3 un diagn\u00f3stico equivocado y se retir\u00f3 sin prestarle asistencia.<\/p>\n<blockquote>\n<p data-start=\"1163\" data-end=\"1492\">Los procedimientos estuvieron encabezados por el <strong data-start=\"1212\" data-end=\"1252\">Cuerpo de Investigaciones Judiciales<\/strong> y la <strong data-start=\"1258\" data-end=\"1324\">Divisi\u00f3n Investigaciones Especiales de la Polic\u00eda de la Ciudad<\/strong>, quienes incautaron <strong data-start=\"1345\" data-end=\"1489\">computadoras, certificados presuntamente ap\u00f3crifos, credenciales, talonarios, gran cantidad de documentaci\u00f3n y sellos de m\u00e9dicos habilitados<\/strong>.<\/p>\n<\/blockquote>\n<p data-start=\"1494\" data-end=\"1808\">Seg\u00fan la investigaci\u00f3n, la atenci\u00f3n fue realizada por una persona que usaba el sello de un profesional matriculado, lo que configura <strong data-start=\"1627\" data-end=\"1662\">ejercicio ilegal de la medicina<\/strong>. En los tres operativos se identific\u00f3 e imput\u00f3 a tres personas, bajo infracci\u00f3n a los art\u00edculos 29 y 30 del C\u00f3digo Procesal Penal de la Ciudad.<\/p>\n<blockquote>\n<h3 data-start=\"1810\" data-end=\"2001\">La causa es investigada por la <strong data-start=\"1841\" data-end=\"1893\">Fiscal\u00eda Penal, Contravencional y de Faltas N\u00b025<\/strong>, con intervenci\u00f3n del <strong data-start=\"1916\" data-end=\"1966\">Juzgado Penal, Contravencional y de Faltas N\u00b02<\/strong>, que autoriz\u00f3 los allanamientos.<\/h3>\n<\/blockquote>\n<p data-start=\"2003\" data-end=\"2255\">El caso vuelve a poner en debate la <strong data-start=\"2042\" data-end=\"2112\">vulnerabilidad de pacientes frente a servicios m\u00e9dicos irregulares<\/strong>, y la necesidad de controles m\u00e1s estrictos para evitar que la salud de las personas quede en manos de profesionales falsos o inescrupulosos.<\/p>\n<p data-start=\"2003\" data-end=\"2255\">FUENTE E IMAGEN: 0223.com<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>La investigaci\u00f3n se origin\u00f3 tras la muerte de una mujer que recibi\u00f3 un diagn\u00f3stico equivocado en su domicilio por un servicio privado de ambulancias. Tres personas quedaron imputadas por delitos vinculados al ejercicio ilegal de <a class=\"mh-excerpt-more\" href=\"https:\/\/larevistadigital.com.ar\/blog\/allanamientos-en-tres-ciudades-bonaerenses-por-un-caso-de-mala-praxis-y-ejercicio-ilegal-de-la-medicina\/\" title=\"Allanamientos en tres ciudades bonaerenses por un caso de mala praxis y ejercicio ilegal de la medicina\">[Leer M\u00e1s]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":41074,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[44,51],"tags":[],"class_list":{"0":"post-41073","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policiales","8":"category-regionales"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2025-08-24-170141.jpg?fit=811%2C426&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8qtrQ-aGt","jetpack-related-posts":[{"id":41504,"url":"https:\/\/larevistadigital.com.ar\/blog\/trata-de-personas-y-ejercicio-ilegal-de-la-medicina-procesan-a-una-pastora-evangelista-en-miramar\/","url_meta":{"origin":41073,"position":0},"title":"Trata de personas y ejercicio ilegal de la medicina: procesan a una pastora evangelista en Miramar","author":"Alejandro Sosa Ruda","date":"18 septiembre, 2025","format":false,"excerpt":"La Justicia Federal prohibi\u00f3 salir del pa\u00eds a Claudia Peyrano, l\u00edder de la congregaci\u00f3n Escuderos de Cristo, a su pareja y a una hija, en el marco de una investigaci\u00f3n por explotaci\u00f3n laboral y pr\u00e1cticas m\u00e9dicas ilegales. 18 de Septiembre de 2025 MIRAMAR -\u00a0 \u00a0El juez federal Santiago Inchausti orden\u00f3\u2026","rel":"","context":"En \u00abPOLICIALES\u00bb","block_context":{"text":"POLICIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/policiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/69d8926f620f3bd6ed2bffc1bef27f5b346bc796.png?fit=1140%2C698&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/69d8926f620f3bd6ed2bffc1bef27f5b346bc796.png?fit=1140%2C698&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/69d8926f620f3bd6ed2bffc1bef27f5b346bc796.png?fit=1140%2C698&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/69d8926f620f3bd6ed2bffc1bef27f5b346bc796.png?fit=1140%2C698&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/69d8926f620f3bd6ed2bffc1bef27f5b346bc796.png?fit=1140%2C698&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":12372,"url":"https:\/\/larevistadigital.com.ar\/blog\/detuvieron-en-monte-a-rodolfo-robatto-ex-fiscal-de-canuelas-y-abogado-de-la-causa-mia\/","url_meta":{"origin":41073,"position":1},"title":"DETUVIERON EN MONTE A RODOLFO ROBATTO, EX FISCAL DE CA\u00d1UELAS Y ABOGADO DE LA CAUSA \u00abMIA\u00bb","author":"Alejandro Sosa Ruda","date":"30 septiembre, 2019","format":false,"excerpt":"El ex fiscal de Ca\u00f1uelas,\u00a0 Rodolfo C\u00e9sar Robatto, fue detenido en el mediod\u00eda de este domingo 29 de septiembre por personal de la DDI Brandsen en su domicilio de calles Pinazo y Rivadavia de la ciudad de Monte, a trav\u00e9s de una orden dictada por el fiscal Lisandro Damonte, titular\u2026","rel":"","context":"En \u00abPOLICIALES\u00bb","block_context":{"text":"POLICIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/policiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20190929_224226.jpg?fit=1080%2C601&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20190929_224226.jpg?fit=1080%2C601&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20190929_224226.jpg?fit=1080%2C601&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20190929_224226.jpg?fit=1080%2C601&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20190929_224226.jpg?fit=1080%2C601&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":42529,"url":"https:\/\/larevistadigital.com.ar\/blog\/allanamientos-por-un-caso-de-abigeato-en-chascomus-un-joven-fue-aprehendido-y-recupero-la-libertad-horas-despues\/","url_meta":{"origin":41073,"position":2},"title":"Allanamientos por un caso de abigeato en Chascom\u00fas: un joven fue aprehendido y recuper\u00f3 la libertad horas despu\u00e9s","author":"Alejandro Sosa Ruda","date":"19 noviembre, 2025","format":false,"excerpt":"\u00a0Todo comienza con una denuncia por la faena de un animal en un campo. 19 de Noviembre de 2025 CHASCOM\u00daS -\u00a0 \u00a0La Polic\u00eda Rural de Chascom\u00fas llev\u00f3 a cabo tres allanamientos en el marco de una causa por abigeato, iniciada luego de que un productor local denunciara la faena ilegal\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/ABIGEATO-CHASCOMUS.jpg?fit=850%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/ABIGEATO-CHASCOMUS.jpg?fit=850%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/ABIGEATO-CHASCOMUS.jpg?fit=850%2C500&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/ABIGEATO-CHASCOMUS.jpg?fit=850%2C500&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":13402,"url":"https:\/\/larevistadigital.com.ar\/blog\/detienen-a-una-famila-de-brandsen-que-comercializaba-crema-y-aceite-de-cannabis\/","url_meta":{"origin":41073,"position":3},"title":"DETIENEN A UNA FAMILA DE BRANDSEN QUE COMERCIALIZABA CREMA Y ACEITE DE CANNABIS","author":"Alejandro Sosa Ruda","date":"1 diciembre, 2019","format":false,"excerpt":"La detenci\u00f3n se produjo luego de que alertaran a la polic\u00eda, que en inmediaciones a la laguna, varios sujetos estar\u00edan comercializando cremas y aceite de cannabis. Esta tarde les allanaron la casa. En las \u00faltimas horas efectivos de la polic\u00eda comunal de Ranchos identificaron en inmediaciones a la laguna \"a\u2026","rel":"","context":"En \u00abRANCHOS\u00bb","block_context":{"text":"RANCHOS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/ranchos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/1575152284586_wm-1.jpg?fit=1200%2C674&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/1575152284586_wm-1.jpg?fit=1200%2C674&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/1575152284586_wm-1.jpg?fit=1200%2C674&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/1575152284586_wm-1.jpg?fit=1200%2C674&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/1575152284586_wm-1.jpg?fit=1200%2C674&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":43097,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-los-caps-barriales-mantienen-su-atencion-habitual-durante-el-verano\/","url_meta":{"origin":41073,"position":4},"title":"Chascom\u00fas: Los CAPS barriales mantienen su atenci\u00f3n habitual durante el verano","author":"Alejandro Sosa Ruda","date":"2 enero, 2026","format":false,"excerpt":"Desde los centros barriales se promueve una atenci\u00f3n cercana, accesible y continua, orientada no solo a la atenci\u00f3n de la enfermedad, sino principalmente a la prevenci\u00f3n y al cuidado integral de la salud. 2 de enero de 2026 CHASCOM\u00daS -\u00a0 \u00a0Los Centros de Atenci\u00f3n Primaria de la Salud (CAPS) continuar\u00e1n\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/695800be06976.png?fit=668%2C445&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/695800be06976.png?fit=668%2C445&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/695800be06976.png?fit=668%2C445&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":30425,"url":"https:\/\/larevistadigital.com.ar\/blog\/megabanda-criminal-condenaron-al-ex-juez-platense-cesar-melazo-por-coautor-de-asociacion-ilicita\/","url_meta":{"origin":41073,"position":5},"title":"\u00abMEGABANDA CRIMINAL\u00bb CONDENARON AL EX JUEZ PLATENSE C\u00c9SAR MELAZO POR \u00abCOAUTOR\u00bb DE ASOCIACI\u00d3N IL\u00cdCITA","author":"Alejandro Sosa Ruda","date":"6 marzo, 2023","format":false,"excerpt":"La justicia dict\u00f3 por mayor\u00eda una pena de 7 a\u00f1os y diez meses de prisi\u00f3n. Lleva cuatro a\u00f1os y medio detenido con prisi\u00f3n preventiva y seguir\u00e1 tras las rejas 06 de marzo de 2023 Una\u00a0condena de siete a\u00f1os y diez meses de prisi\u00f3n recay\u00f3 sobre el exjuez de Garant\u00edas de\u2026","rel":"","context":"En \u00abPOLICIALES\u00bb","block_context":{"text":"POLICIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/policiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/1670418230917.jpg?fit=1200%2C594&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/1670418230917.jpg?fit=1200%2C594&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/1670418230917.jpg?fit=1200%2C594&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/1670418230917.jpg?fit=1200%2C594&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/1670418230917.jpg?fit=1200%2C594&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/41073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=41073"}],"version-history":[{"count":2,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/41073\/revisions"}],"predecessor-version":[{"id":41076,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/41073\/revisions\/41076"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media\/41074"}],"wp:attachment":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=41073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=41073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=41073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}