{"id":4115,"date":"2017-12-03T17:20:47","date_gmt":"2017-12-03T17:20:47","guid":{"rendered":"https:\/\/larevistadigital.com.ar\/blog\/?p=4115"},"modified":"2017-12-03T17:20:47","modified_gmt":"2017-12-03T17:20:47","slug":"dolores-detienen-sujeto-estafas-reiteradas","status":"publish","type":"post","link":"https:\/\/larevistadigital.com.ar\/blog\/dolores-detienen-sujeto-estafas-reiteradas\/","title":{"rendered":"DOLORES: DETIENEN A SUJETO POR \u00abESTAFAS REITERADAS\u00bb"},"content":{"rendered":"<p>En el transcurso del mi\u00e9rcoles, personal policial fue alertado que en un comercio raz\u00f3n social \u201cvida libre\u201d, sito en calle Vucetich al 200, se encontraba un masculino, el cual hab\u00eda querido realizar una compra utilizando una tarjeta de cr\u00e9dito de la cual no era titular.<\/p>\n<p>Al arribar los efectivos al lugar, el sujeto se torn\u00f3 agresivo, por lo que fue reducido y\u00a0 trasladado a la dependencia local, donde se hicieron presentes dos personas m\u00e1s para denunciar el mismo proceder en sus comercios. El imputado fue notificado del inicio de las actuaciones legales caratuladas Posible Estafas Reiteradas.<\/p>\n<p>FUENTE: DIARIO COMPROMISO<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>En el transcurso del mi\u00e9rcoles, personal policial fue alertado que en un comercio raz\u00f3n social \u201cvida libre\u201d, sito en calle Vucetich al 200, se encontraba un masculino, el cual hab\u00eda querido realizar una compra utilizando <a class=\"mh-excerpt-more\" href=\"https:\/\/larevistadigital.com.ar\/blog\/dolores-detienen-sujeto-estafas-reiteradas\/\" title=\"DOLORES: DETIENEN A SUJETO POR \u00abESTAFAS REITERADAS\u00bb\">[Leer M\u00e1s]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":4116,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[43,12],"tags":[],"class_list":{"0":"post-4115","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-dolores","8":"category-politica"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/12\/poli-chasco.jpg?fit=760%2C452&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8qtrQ-14n","jetpack-related-posts":[{"id":29139,"url":"https:\/\/larevistadigital.com.ar\/blog\/dolores-utilizan-el-domicilio-de-una-vecina-para-cometer-estafas\/","url_meta":{"origin":4115,"position":0},"title":"DOLORES: UTILIZAN EL DOMICILIO DE UNA VECINA PARA COMETER ESTAFAS","author":"Alejandro Sosa Ruda","date":"28 noviembre, 2022","format":false,"excerpt":"Lo hacen a trav\u00e9s de una cuenta de Facebook, y ofrecen distintos art\u00edculos. 27 de noviembre de DOLORES -\u00a0\u00a0El portal \"Criterio On line\" dio a conocer que una vecina realiz\u00f3 una denuncia, porque su domicilio es utilizado por un perfil de la red social Facebook, ofreciendo diferentes art\u00edculos entre los\u2026","rel":"","context":"En \u00abDOLORES\u00bb","block_context":{"text":"DOLORES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/dolores\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/estafa-1.jpg?fit=624%2C521&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/estafa-1.jpg?fit=624%2C521&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/estafa-1.jpg?fit=624%2C521&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":6286,"url":"https:\/\/larevistadigital.com.ar\/blog\/lezama-la-policia-federal-detuvo-un-individuo-con-pedido-de-captura\/","url_meta":{"origin":4115,"position":1},"title":"LEZAMA: LA POLIC\u00cdA FEDERAL DETUVO UN INDIVIDUO CON PEDIDO DE CAPTURA","author":"Alejandro Sosa Ruda","date":"19 agosto, 2018","format":false,"excerpt":"El \u00faltimo s\u00e1bado, personal de la Brigada de la Polic\u00eda Federal Argentina, Subdelegaci\u00f3n Chascom\u00fas, logr\u00f3 la detenci\u00f3n de un ciudadano mayor de edad, domiciliado en la Ciudad de Lezama, el cual ten\u00eda pedido de captura por Asociaci\u00f3n Il\u00edcita y Estafas Reiteradas. Dicha detenci\u00f3n cont\u00f3 con el aporte y colaboraci\u00f3n de\u2026","rel":"","context":"En \u00abPOLICIALES\u00bb","block_context":{"text":"POLICIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/policiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/08\/DETENIDO-LEZAMA.jpg?fit=960%2C692&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/08\/DETENIDO-LEZAMA.jpg?fit=960%2C692&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/08\/DETENIDO-LEZAMA.jpg?fit=960%2C692&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/08\/DETENIDO-LEZAMA.jpg?fit=960%2C692&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":39325,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-sujeto-fue-aprehendido-por-desobediencia\/","url_meta":{"origin":4115,"position":2},"title":"Chascom\u00fas: Sujeto fue aprehendido por \u00abdesobediencia\u00bb","author":"Alejandro Sosa Ruda","date":"7 abril, 2025","format":false,"excerpt":"CHASCOM\u00daS -\u00a0 \u00a0Ocurri\u00f3 ayer, 6 de abril cuando a raiz de un llamado, personal policial acudi\u00f3 a la calle Grito de Dolores, entre I. Arabes y Per\u00fa, ya que una persona de sexo masculino se encontraba en un domicilio sobre el cual ten\u00eda una restricci\u00f3n perimetral para con la moradora\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/una-mujer-fue-rescatada-la-policia-la-plata.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/una-mujer-fue-rescatada-la-policia-la-plata.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/una-mujer-fue-rescatada-la-policia-la-plata.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/una-mujer-fue-rescatada-la-policia-la-plata.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/una-mujer-fue-rescatada-la-policia-la-plata.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":23501,"url":"https:\/\/larevistadigital.com.ar\/blog\/continua-la-ola-de-estafas-en-la-region-ahora-le-robaron-1700-dolares-a-una-mujer-en-dolores\/","url_meta":{"origin":4115,"position":3},"title":"CONTIN\u00daA LA OLA DE ESTAFAS EN LA REGI\u00d3N. AHORA LE ROBARON 1700 D\u00d3LARES A UNA MUJER EN DOLORES","author":"Alejandro Sosa Ruda","date":"22 enero, 2022","format":false,"excerpt":"Una persona se hizo pasar por su sobrina y le dijo que deb\u00eda cambiar el dinero. Dos hombres fueron los c\u00f3mplices. Luego, la mujer habl\u00f3 con otro familiar y advirti\u00f3 que hab\u00eda sido enga\u00f1ada y v\u00edctima de un robo. DOLORES -\u00a0Una docente jubilada de Dolores fue v\u00edctima de un enga\u00f1o\u2026","rel":"","context":"En \u00abDOLORES\u00bb","block_context":{"text":"DOLORES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/dolores\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20220121184129_cuentodeltiojpg.jpg?fit=880%2C512&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20220121184129_cuentodeltiojpg.jpg?fit=880%2C512&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20220121184129_cuentodeltiojpg.jpg?fit=880%2C512&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20220121184129_cuentodeltiojpg.jpg?fit=880%2C512&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":18035,"url":"https:\/\/larevistadigital.com.ar\/blog\/algo-que-viene-pasando-en-la-region-dolorense-denuncia-estafas-a-partir-del-robo-de-identidad\/","url_meta":{"origin":4115,"position":4},"title":"ALGO QUE VIENE PASANDO EN LA REGI\u00d3N: DOLORENSE DENUNCIA ESTAFAS A PARTIR DEL ROBO DE IDENTIDAD.","author":"Alejandro Sosa Ruda","date":"10 diciembre, 2020","format":false,"excerpt":"Sacaron a su nombre prestamos y cr\u00e9ditos en financieras. Algo que nos puede pasar... Un dolorense denunci\u00f3 que le robaron la identidad\u00a0y a partir de all\u00ed\u00a0sacaron cr\u00e9ditos, tarjetas, pr\u00e9stamos en financieras.\u201cEstoy en el Veraz, no puedo hacer tr\u00e1mites, no puedo usar tarjetas, desde hace dos a\u00f1os vivo una pesadilla\u201d,\u00a0dijo a\u2026","rel":"","context":"En \u00abDOLORES\u00bb","block_context":{"text":"DOLORES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/dolores\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/afa12c03c6a15e7b98b92f161440d3963fa692f8.jpg?fit=1140%2C759&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/afa12c03c6a15e7b98b92f161440d3963fa692f8.jpg?fit=1140%2C759&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/afa12c03c6a15e7b98b92f161440d3963fa692f8.jpg?fit=1140%2C759&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/afa12c03c6a15e7b98b92f161440d3963fa692f8.jpg?fit=1140%2C759&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/afa12c03c6a15e7b98b92f161440d3963fa692f8.jpg?fit=1140%2C759&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":21856,"url":"https:\/\/larevistadigital.com.ar\/blog\/habrian-encontrado-en-sevigne-al-peligroso-sujeto-que-se-dio-a-la-fuga-de-la-dependencia-federal-de-dolores\/","url_meta":{"origin":4115,"position":5},"title":"HABR\u00cdAN ENCONTRADO EN SEVIGNE AL PELIGROSO SUJETO QUE SE DIO A LA FUGA DE LA DEPENDENCIA FEDERAL DE DOLORES","author":"Alejandro Sosa Ruda","date":"4 septiembre, 2021","format":false,"excerpt":"SEVIGNE - El periodista chascomunense y conductor del programa televisivo \"Somos Noticias\",\u00a0 Sergio \"Tony\" Peralta nos hizo saber que Personal policial del Destacamento de Sevign\u00e9 habr\u00eda logrado dar con el paradero del sujeto que en la ma\u00f1ana de hoy, se fug\u00f3 de la Dependencia Federal de Dolores. El malviviente fue\u2026","rel":"","context":"En \u00abDESTACADAS\u00bb","block_context":{"text":"DESTACADAS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/destacadas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/240653205_4938346472846507_7438336681077109817_n.jpg?fit=700%2C400&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/240653205_4938346472846507_7438336681077109817_n.jpg?fit=700%2C400&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/240653205_4938346472846507_7438336681077109817_n.jpg?fit=700%2C400&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/240653205_4938346472846507_7438336681077109817_n.jpg?fit=700%2C400&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/4115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=4115"}],"version-history":[{"count":1,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/4115\/revisions"}],"predecessor-version":[{"id":4117,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/4115\/revisions\/4117"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media\/4116"}],"wp:attachment":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=4115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=4115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=4115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}