{"id":43722,"date":"2026-02-02T16:00:47","date_gmt":"2026-02-02T19:00:47","guid":{"rendered":"https:\/\/larevistadigital.com.ar\/blog\/?p=43722"},"modified":"2026-02-02T16:00:47","modified_gmt":"2026-02-02T19:00:47","slug":"chascomus-el-equipo-municipal-de-guardavidas-intervino-en-un-rescate-durante-el-fin-de-semana-en-la-laguna","status":"publish","type":"post","link":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-el-equipo-municipal-de-guardavidas-intervino-en-un-rescate-durante-el-fin-de-semana-en-la-laguna\/","title":{"rendered":"Chascom\u00fas: El equipo municipal de guardavidas intervino en un rescate durante el fin de semana en la laguna"},"content":{"rendered":"<h3 class=\"excerpt\">La situaci\u00f3n ocurri\u00f3 el s\u00e1bado por la ma\u00f1ana, antes del inicio del horario del servicio. Adem\u00e1s, se registraron m\u00faltiples intervenciones preventivas por actividades n\u00e1uticas no autorizadas.<\/h3>\n<p>02 de febrero de 2026<\/p>\n<div id=\"miDiv1\" class=\"text\">\n<p><strong>CHASCOM\u00daS &#8211;\u00a0<\/strong> \u00a0El equipo municipal de Guardavidas y Seguridad Lacustre desarroll\u00f3 una intensa actividad durante el \u00faltimo fin de semana en la laguna de Chascom\u00fas, con intervenciones vinculadas tanto a emergencias como a tareas preventivas.<\/p>\n<p>Durante la ma\u00f1ana del s\u00e1bado, el personal debi\u00f3 intervenir para asistir a una persona que se hab\u00eda arrojado al agua antes del inicio del horario de cobertura del servicio de guardavidas. Al advertir el pedido de auxilio, el equipo actu\u00f3 de inmediato y logr\u00f3 poner a salvo tanto al involucrado como a otro acompa\u00f1ante que hab\u00eda ingresado al agua para ayudar. Los asistidos eran oriundos de la localidad de Luis Guill\u00f3n.<\/p>\n<blockquote>\n<h3>El \u00e1rea de Seguridad Lacustre realiz\u00f3 adem\u00e1s numerosas intervenciones por el descenso de lanchas y motos de agua en sectores no autorizados, reforzando las tareas de control y prevenci\u00f3n en distintos puntos del espejo de agua.<\/h3>\n<\/blockquote>\n<p>Como cierre del domingo, el personal municipal acompa\u00f1\u00f3 a una gran cantidad de participantes de la tradicional actividad recreativa que se realiza en la laguna durante la luna llena, brindando asistencia a quienes presentaron inconvenientes y garantizando su regreso a zonas seguras.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>La situaci\u00f3n ocurri\u00f3 el s\u00e1bado por la ma\u00f1ana, antes del inicio del horario del servicio. Adem\u00e1s, se registraron m\u00faltiples intervenciones preventivas por actividades n\u00e1uticas no autorizadas. 02 de febrero de 2026 CHASCOM\u00daS &#8211;\u00a0 \u00a0El equipo <a class=\"mh-excerpt-more\" href=\"https:\/\/larevistadigital.com.ar\/blog\/chascomus-el-equipo-municipal-de-guardavidas-intervino-en-un-rescate-durante-el-fin-de-semana-en-la-laguna\/\" title=\"Chascom\u00fas: El equipo municipal de guardavidas intervino en un rescate durante el fin de semana en la laguna\">[Leer M\u00e1s]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":43723,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[41],"tags":[],"class_list":{"0":"post-43722","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destacadas"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/6980d5de60be7.png?fit=668%2C445&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8qtrQ-bnc","jetpack-related-posts":[{"id":38250,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-este-fin-de-semana-comienza-el-servicio-de-guardavidas\/","url_meta":{"origin":43722,"position":0},"title":"Chascom\u00fas: Este fin de semana, comienza el servicio de Guardavidas.","author":"Alejandro Sosa Ruda","date":"14 diciembre, 2024","format":false,"excerpt":"Este important\u00edsimo equipo de prevenci\u00f3n y rescate, permite a los ba\u00f1istas disfrutar de la laguna en forma segura. 14 de Diciembre de 2024 CHASCOM\u00daS -\u00a0 Con la apertura de la temporada de verano 2024\/2025, comienza a funcionar el servicio de guardavidas de la Municipalidad de Chascom\u00fas, el cual depende de\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/675c709af1adf.png?fit=668%2C445&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/675c709af1adf.png?fit=668%2C445&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/675c709af1adf.png?fit=668%2C445&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":44962,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-finalizo-la-temporada-del-servicio-municipal-de-guardavidas-en-la-laguna\/","url_meta":{"origin":43722,"position":1},"title":"Chascom\u00fas: Finaliz\u00f3 la temporada del servicio municipal de guardavidas en la laguna","author":"Alejandro Sosa Ruda","date":"6 abril, 2026","format":false,"excerpt":"El operativo que se realiz\u00f3 durante toda la temporada de verano fue evaluado de manera positiva. 06 de abril de 2026 CHASCOM\u00daS -\u00a0 \u00a0El servicio municipal de guardavidas concluy\u00f3 este fin de semana tras su labor a lo largo de la temporada en distintos sectores de la costanera. Este dispositivo\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/69d3e7d908f81.png?fit=668%2C445&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/69d3e7d908f81.png?fit=668%2C445&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/69d3e7d908f81.png?fit=668%2C445&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":42782,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-el-servicio-de-guardavidas-brinda-seguridad-para-vecinos-y-turistas\/","url_meta":{"origin":43722,"position":2},"title":"Chascom\u00fas: El servicio de guardavidas brinda seguridad para vecinos y turistas","author":"Alejandro Sosa Ruda","date":"5 diciembre, 2025","format":false,"excerpt":"La Municipalidad cuenta con puestos en diferentes sectores de la costanera, para brindar protecci\u00f3n y asistencia a quienes ingresan a las aguas de la laguna. 05 de Diciembre de 2025 CHASCOM\u00daS -\u00a0 \u00a0El equipo de rescatistas, dependiente de la Secretar\u00eda de Seguridad Ciudadana, resguarda la seguridad en la laguna local\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/693319e390c69.png?fit=668%2C445&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/693319e390c69.png?fit=668%2C445&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/693319e390c69.png?fit=668%2C445&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":43290,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-dias-y-horarios-del-equipo-de-guardavidas-y-seguridad-lacustre\/","url_meta":{"origin":43722,"position":3},"title":"Chascom\u00fas: d\u00edas y horarios del equipo de Guardavidas y Seguridad Lacustre","author":"Alejandro Sosa Ruda","date":"12 enero, 2026","format":false,"excerpt":"El Operativo de Seguridad Acu\u00e1tica es una inversi\u00f3n municipal clave para la prevenci\u00f3n, el cuidado y la r\u00e1pida respuesta ante emergencias. 12 de enero de 2026 CHASCOM\u00daS -\u00a0 \u00a0La Municipalidad de Chascom\u00fas se encuentra prestando servicios el cuerpo de guardavidas municipal como as\u00ed tambi\u00e9n el equipo de seguridad lacustre. Ambos\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/6965337ce57f7.png?fit=668%2C445&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/6965337ce57f7.png?fit=668%2C445&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/6965337ce57f7.png?fit=668%2C445&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":44116,"url":"https:\/\/larevistadigital.com.ar\/blog\/galeria-de-fotos-insolito-accidente-en-la-laguna-de-chascomus-cayo-una-lancha-voladora-y-debieron-rescatar-al-conductor\/","url_meta":{"origin":43722,"position":4},"title":"[Galer\u00eda de Fotos] Ins\u00f3lito accidente en la laguna de Chascom\u00fas: cay\u00f3 una \u201clancha voladora\u201d y debieron rescatar al conductor","author":"Alejandro Sosa Ruda","date":"22 febrero, 2026","format":false,"excerpt":"El hecho ocurri\u00f3 pasado el mediod\u00eda en el sector de Parque Girado. El veh\u00edculo qued\u00f3 con el casco partido y las alas destrozadas. El conductor, un turista de CABA, fue rescatado sin lesiones. 22 de febrero de 2026 CHASCOM\u00daS\u00a0 -\u00a0 \u00a0 Este 22 de febrero, alrededor de las 13:10, desde\u2026","rel":"","context":"En \u00abDESTACADAS\u00bb","block_context":{"text":"DESTACADAS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/destacadas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/rescate-0.jpg?fit=961%2C650&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/rescate-0.jpg?fit=961%2C650&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/rescate-0.jpg?fit=961%2C650&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/rescate-0.jpg?fit=961%2C650&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":4530,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-adolescente-muere-ahogada-la-laguna\/","url_meta":{"origin":43722,"position":5},"title":"CHASCOM\u00daS: ADOLESCENTE MUERE AHOGADA EN LA LAGUNA","author":"Alejandro Sosa Ruda","date":"15 enero, 2018","format":false,"excerpt":"Una muy triste noticia conmocion\u00f3 la ciudad de Chascom\u00fas, ya que en un lamentable hecho una adolescente oriunda de Guernica falleci\u00f3 ahogada en aguas de la laguna. Los hechos aparentemente se desencadenaron a ra\u00edz de que la muchacha padec\u00eda de epilepsia, lo que provoc\u00f3 la p\u00e9rdida del conocimiento de la\u2026","rel":"","context":"En \u00abDESTACADAS\u00bb","block_context":{"text":"DESTACADAS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/destacadas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/01\/chascomus01-marita-1024x707.jpg?fit=1024%2C707&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/01\/chascomus01-marita-1024x707.jpg?fit=1024%2C707&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/01\/chascomus01-marita-1024x707.jpg?fit=1024%2C707&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/01\/chascomus01-marita-1024x707.jpg?fit=1024%2C707&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/43722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=43722"}],"version-history":[{"count":1,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/43722\/revisions"}],"predecessor-version":[{"id":43724,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/43722\/revisions\/43724"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media\/43723"}],"wp:attachment":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=43722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=43722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=43722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}