{"id":43725,"date":"2026-02-03T17:18:29","date_gmt":"2026-02-03T20:18:29","guid":{"rendered":"https:\/\/larevistadigital.com.ar\/blog\/?p=43725"},"modified":"2026-02-03T17:18:29","modified_gmt":"2026-02-03T20:18:29","slug":"43725-2","status":"publish","type":"post","link":"https:\/\/larevistadigital.com.ar\/blog\/43725-2\/","title":{"rendered":""},"content":{"rendered":"<p data-start=\"226\" data-end=\"517\"><strong data-start=\"226\" data-end=\"517\">Con el inicio del a\u00f1o judicial, en los tribunales de Dolores se esperan juicios por causas resonantes que generaron un fuerte impacto p\u00fablico en los \u00faltimos a\u00f1os. Entre ellas, se encuentra el triple crimen ocurrido en un campo de Chascom\u00fas, cuyo juicio comenzar\u00e1 el pr\u00f3ximo 10 de agosto.<\/strong><\/p>\n<p data-start=\"226\" data-end=\"517\">03 de febrero de 2026<\/p>\n<p data-start=\"226\" data-end=\"517\"><strong>DOLORES &#8211;<\/strong>\u00a0 El caso conmovi\u00f3 profundamente a la regi\u00f3n por tratarse de una familia con fuertes v\u00ednculos locales. El acusado es <strong data-start=\"634\" data-end=\"662\">Francisco Waldemar Reddy<\/strong>, de 20 a\u00f1os, quien llega a juicio imputado por haber asesinado a su padre, <strong data-start=\"738\" data-end=\"753\">Diego Reddy<\/strong>, a la pareja de \u00e9ste, <strong data-start=\"776\" data-end=\"800\">Mar\u00eda Eugenia Su\u00e1rez<\/strong>, y a su hermano <strong data-start=\"817\" data-end=\"834\">Ignacio Reddy<\/strong>, de 12 a\u00f1os.<\/p>\n<blockquote>\n<h3 data-start=\"849\" data-end=\"1144\">El triple homicidio ocurri\u00f3 el <strong data-start=\"880\" data-end=\"907\">29 de diciembre de 2023<\/strong> en el establecimiento rural \u201cLos Pinos\u201d, ubicado a la vera de la Autov\u00eda 2, en jurisdicci\u00f3n de Chascom\u00fas. Seg\u00fan la investigaci\u00f3n, ese d\u00eda el acusado \u2014quien resid\u00eda en la ciudad de Dolores\u2014 se present\u00f3 en el campo portando un arma larga.<\/h3>\n<\/blockquote>\n<p data-start=\"1146\" data-end=\"1402\">De acuerdo al expediente, primero asesin\u00f3 a la mujer, que se encontraba en la cocina de la vivienda, y luego al menor, a quien hall\u00f3 en un galp\u00f3n. Posteriormente mat\u00f3 a su padre, que se encontraba a cierta distancia del casco del campo, y se dio a la fuga.<\/p>\n<p data-start=\"1404\" data-end=\"1826\">El hecho sali\u00f3 a la luz cuando un vecino encontr\u00f3 los cuerpos de la mujer y del ni\u00f1o. Al no hallarse inicialmente el cuerpo del padre, en un primer momento se especul\u00f3 con que pudiera haber sido el autor del crimen. Sin embargo, con el avance de la investigaci\u00f3n, la hip\u00f3tesis fue descartada y las sospechas se concentraron en el joven, quien incluso habr\u00eda intentado organizar una coartada con otros efectivos policiales.<\/p>\n<blockquote>\n<h3 data-start=\"1828\" data-end=\"1969\">Finalmente, <strong data-start=\"1840\" data-end=\"1894\">Francisco Reddy fue detenido el 1 de enero de 2024<\/strong> y desde entonces permanece alojado en la <strong data-start=\"1936\" data-end=\"1968\">Unidad Penal N\u00b0 6 de Dolores<\/strong>.<\/h3>\n<\/blockquote>\n<p data-start=\"1971\" data-end=\"2142\">El debate oral estar\u00e1 a cargo del <strong data-start=\"2005\" data-end=\"2053\">Tribunal Oral en lo Criminal N\u00b0 1 de Dolores<\/strong>, integrado por los jueces <strong data-start=\"2080\" data-end=\"2141\">Mar\u00eda Claudia Castro, Christian Rabaia y Emiliano Lazzari<\/strong>.<\/p>\n<p data-start=\"1971\" data-end=\"2142\">fuente e imagen: entrel\u00edneas.info\/Gabriela Urrutibehety<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Con el inicio del a\u00f1o judicial, en los tribunales de Dolores se esperan juicios por causas resonantes que generaron un fuerte impacto p\u00fablico en los \u00faltimos a\u00f1os. Entre ellas, se encuentra el triple crimen ocurrido <a class=\"mh-excerpt-more\" href=\"https:\/\/larevistadigital.com.ar\/blog\/43725-2\/\" title=\"\">[Leer M\u00e1s]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":43727,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[50],"tags":[],"class_list":{"0":"post-43725","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-interes-general"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/3d5424295590292ae579637ba7f3e1ac6ccbab41.jpg?fit=1140%2C699&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8qtrQ-bnf","jetpack-related-posts":[{"id":43795,"url":"https:\/\/larevistadigital.com.ar\/blog\/crimen-de-nicolas-riccardi-en-septiembre-juzgaran-al-acusado-en-dolores\/","url_meta":{"origin":43725,"position":0},"title":"Crimen de Nicol\u00e1s Riccardi: en septiembre juzgar\u00e1n al acusado en Dolores","author":"Alejandro Sosa Ruda","date":"5 febrero, 2026","format":false,"excerpt":"El adolescente de 16 a\u00f1os fue asesinado cerca de la laguna de Chascom\u00fas. El caso conmovi\u00f3 a toda la ciudad. 05 de febrero de 2026 En septiembre de 2026 se realizar\u00e1 en la ciudad de Dolores el juicio por el asesinato de Nicol\u00e1s Riccardi, el adolescente de 16 a\u00f1os que\u2026","rel":"","context":"En \u00abDESTACADAS\u00bb","block_context":{"text":"DESTACADAS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/destacadas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Nico-Riccardi.jpg?fit=1140%2C738&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Nico-Riccardi.jpg?fit=1140%2C738&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Nico-Riccardi.jpg?fit=1140%2C738&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Nico-Riccardi.jpg?fit=1140%2C738&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Nico-Riccardi.jpg?fit=1140%2C738&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":29320,"url":"https:\/\/larevistadigital.com.ar\/blog\/dolores-la-justicia-confirmo-la-condena-a-el-pepo-por-la-muerte-de-dos-integrantes-de-su-banda\/","url_meta":{"origin":43725,"position":1},"title":"DOLORES: LA JUSTICIA CONFIRM\u00d3 LA CONDENA A \u00abEL PEPO\u00bb POR LA MUERTE DE DOS INTEGRANTES DE SU BANDA.","author":"Alejandro Sosa Ruda","date":"8 diciembre, 2022","format":false,"excerpt":"La sentencia lo obliga a seguir con un tratamiento psiqui\u00e1trico y psicol\u00f3gico y le proh\u00edbe conducir por diez a\u00f1os. 8 de diciembre de 2022 La Justicia confirm\u00f3 la condena al cantante Rub\u00e9n Dar\u00edo Casti\u00f1eiras, conocido como\u00a0\u201cEl Pepo\u201d, a\u00a04 a\u00f1os y siete meses de c\u00e1rcel\u00a0por la muerte de dos integrantes de\u2026","rel":"","context":"En \u00abPOLICIALES\u00bb","block_context":{"text":"POLICIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/policiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/0108b3aaaa8a74f17140f615a2bf186053e74cfd-1.jpg?fit=1140%2C759&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/0108b3aaaa8a74f17140f615a2bf186053e74cfd-1.jpg?fit=1140%2C759&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/0108b3aaaa8a74f17140f615a2bf186053e74cfd-1.jpg?fit=1140%2C759&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/0108b3aaaa8a74f17140f615a2bf186053e74cfd-1.jpg?fit=1140%2C759&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/0108b3aaaa8a74f17140f615a2bf186053e74cfd-1.jpg?fit=1140%2C759&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":34873,"url":"https:\/\/larevistadigital.com.ar\/blog\/pinamar-condenan-a-ex-concejal-por-abuso-agravado-contra-una-menor-a-16-anos-de-carcel\/","url_meta":{"origin":43725,"position":2},"title":"PINAMAR: CONDENAN A EX CONCEJAL POR ABUSO AGRAVADO CONTRA UNA MENOR A 16 A\u00d1OS DE CARCEL","author":"Alejandro Sosa Ruda","date":"18 diciembre, 2023","format":false,"excerpt":"Claudio Galarza estaba detenido desde 2018. Roc\u00edo Ayel\u00e9n Salazar, su pareja, fue sentenciada a 10 a\u00f1os de prisi\u00f3n por facilitar el abuso. 18 de diciembre de 2023 PINAMAR -\u00a0\u00a0Claudio Marcelo Galarza, ex concejal de Pinamar, fue condenado a 16 a\u00f1os de prisi\u00f3n por abuso sexual agravado en perjuicio de una\u2026","rel":"","context":"En \u00abPOLICIALES\u00bb","block_context":{"text":"POLICIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/policiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20231215150651_whatsapp-image-2023-12-15-at-15-04-30.jpg?fit=880%2C512&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20231215150651_whatsapp-image-2023-12-15-at-15-04-30.jpg?fit=880%2C512&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20231215150651_whatsapp-image-2023-12-15-at-15-04-30.jpg?fit=880%2C512&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20231215150651_whatsapp-image-2023-12-15-at-15-04-30.jpg?fit=880%2C512&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":14820,"url":"https:\/\/larevistadigital.com.ar\/blog\/dolores-condenan-a-vecino-por-tenencia-ilegal-de-arma-de-fuego\/","url_meta":{"origin":43725,"position":3},"title":"DOLORES: CONDENAN A VECINO POR TENENCIA ILEGAL DE ARMA DE FUEGO","author":"Alejandro Sosa Ruda","date":"14 febrero, 2020","format":false,"excerpt":"Fue aprehendido junto a otra persona, no sometida este juicio, en junio del a\u00f1o pasado en el camino a Libres del Sur, Partido de Chascom\u00fas. La sentencia fue dictada por el Juez de Feria, encontr\u00e1ndose a cargo del Juzgado Correccional n\u00ba 2 Departamental. En los primeros d\u00edas del mes de\u2026","rel":"","context":"En \u00abDOLORES\u00bb","block_context":{"text":"DOLORES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/dolores\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Edificio-Tribunales-1.jpg?fit=759%2C379&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Edificio-Tribunales-1.jpg?fit=759%2C379&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Edificio-Tribunales-1.jpg?fit=759%2C379&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Edificio-Tribunales-1.jpg?fit=759%2C379&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":40339,"url":"https:\/\/larevistadigital.com.ar\/blog\/mar-de-ajo-durante-9-anos-abuso-de-sus-hijos-e-hijastra-le-dieron-11-anos\/","url_meta":{"origin":43725,"position":4},"title":"Mar de Aj\u00f3: Durante 9 a\u00f1os, abus\u00f3 de sus hijos e hijastra. Le dieron 11 a\u00f1os.","author":"Alejandro Sosa Ruda","date":"5 julio, 2025","format":false,"excerpt":"El fallo fu\u00e9 un\u00e1nime y conden\u00f3 al acusado. \u00bfEs justo? 05 de Julio de 2025 MAR DE AJ\u00d3 -\u00a0 Un sujeto abus\u00f3 sexualmente de sus dos hijos, y una hijastra entre los a\u00f1os 2010 y 2019 en distintas viviendas de la ciudad de Mar de Aj\u00f3 en el Partido de\u2026","rel":"","context":"En \u00abPOLICIALES\u00bb","block_context":{"text":"POLICIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/policiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Abusador-de-Mar-de-Ajo.jpg?fit=1140%2C721&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Abusador-de-Mar-de-Ajo.jpg?fit=1140%2C721&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Abusador-de-Mar-de-Ajo.jpg?fit=1140%2C721&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Abusador-de-Mar-de-Ajo.jpg?fit=1140%2C721&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Abusador-de-Mar-de-Ajo.jpg?fit=1140%2C721&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":24738,"url":"https:\/\/larevistadigital.com.ar\/blog\/dolores-condenaron-a-un-gomero-que-estafo-a-una-famiia-en-la-ruta-2-y-le-saco-14-mil-pesos\/","url_meta":{"origin":43725,"position":5},"title":"DOLORES: CONDENARON A UN GOMERO QUE ESTAF\u00d3 A UNA FAMILIA EN LA RUTA 2 Y LE SAC\u00d3 14 MIL PESOS","author":"Alejandro Sosa Ruda","date":"22 marzo, 2022","format":false,"excerpt":"El episodio hab\u00eda ocurrido hace un a\u00f1o cuando el sujeto los enga\u00f1\u00f3 diciendo que sal\u00eda humo de una rueda. Los hizo entrar a una gomer\u00eda, supuestamente cambi\u00f3 un repuesto y les cobr\u00f3 una importante suma de dinero. DOLORES -\u00a0 En un juicio abreviado, el\u00a0Tribunal Correccional N\u00ba 3 de Dolores, conden\u00f3\u2026","rel":"","context":"En \u00abDOLORES\u00bb","block_context":{"text":"DOLORES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/dolores\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/377dbe75f7689127a592f0c74f43d3e5559c1a3a.jpeg?fit=1140%2C836&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/377dbe75f7689127a592f0c74f43d3e5559c1a3a.jpeg?fit=1140%2C836&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/377dbe75f7689127a592f0c74f43d3e5559c1a3a.jpeg?fit=1140%2C836&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/377dbe75f7689127a592f0c74f43d3e5559c1a3a.jpeg?fit=1140%2C836&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/377dbe75f7689127a592f0c74f43d3e5559c1a3a.jpeg?fit=1140%2C836&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/43725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=43725"}],"version-history":[{"count":1,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/43725\/revisions"}],"predecessor-version":[{"id":43728,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/43725\/revisions\/43728"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media\/43727"}],"wp:attachment":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=43725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=43725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=43725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}