{"id":43744,"date":"2026-02-03T18:49:30","date_gmt":"2026-02-03T21:49:30","guid":{"rendered":"https:\/\/larevistadigital.com.ar\/blog\/?p=43744"},"modified":"2026-02-03T18:49:30","modified_gmt":"2026-02-03T21:49:30","slug":"nuevos-subsidios-a-apicultores-de-chascomus","status":"publish","type":"post","link":"https:\/\/larevistadigital.com.ar\/blog\/nuevos-subsidios-a-apicultores-de-chascomus\/","title":{"rendered":"Nuevos subsidios a apicultores de Chascom\u00fas"},"content":{"rendered":"<h3 class=\"excerpt\">El acto de entrega se realiz\u00f3 en la Estaci\u00f3n Hidrobiol\u00f3gica y se suma a una l\u00ednea de financiamiento productivo que ya alcanza los 78 millones de pesos.<\/h3>\n<p>03 de febrero de 2026<\/p>\n<div id=\"miDiv1\" class=\"text\">\n<p><strong>CHASCOM\u00daS &#8211;<\/strong>\u00a0 \u00a0El intendente Javier Gast\u00f3n encabez\u00f3 el pasado viernes la entrega de subsidios a tres apicultores locales.<\/p>\n<p>De la actividad, realizada en la Estaci\u00f3n Hidrobiol\u00f3gica, participaron tambi\u00e9n el secretario de Hacienda y Producci\u00f3n, Marcelo Teileche; la directora de Producci\u00f3n, Mar\u00eda Eugenia Pietrantuono; y el director de la estaci\u00f3n, Alfredo Astesuain.<\/p>\n<p>Si bien en esta oportunidad se otorgaron tres subsidios, desde el \u00e1rea de Producci\u00f3n se destac\u00f3 que estas entregas forman parte de un proceso iniciado en instancias anteriores, cuando se financiaron proyectos productivos con apoyo del Ministerio de Desarrollo Agrario de la provincia de Buenos Aires.<\/p>\n<p>Al sumar los aportes otorgados anteriores con los entregados recientemente, el monto total de financiamiento destinado a productores locales asciende a una cifra cercana a los 78 millones de pesos, con proyectos vinculados principalmente a las actividades ap\u00edcola y ganadera.<\/p>\n<p>La continuidad de estas pol\u00edticas apunta a acompa\u00f1ar a los productores del distrito, fortaleciendo el entramado productivo local y promoviendo el desarrollo de actividades con arraigo en la comunidad.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>El acto de entrega se realiz\u00f3 en la Estaci\u00f3n Hidrobiol\u00f3gica y se suma a una l\u00ednea de financiamiento productivo que ya alcanza los 78 millones de pesos. 03 de febrero de 2026 CHASCOM\u00daS &#8211;\u00a0 \u00a0El <a class=\"mh-excerpt-more\" href=\"https:\/\/larevistadigital.com.ar\/blog\/nuevos-subsidios-a-apicultores-de-chascomus\/\" title=\"Nuevos subsidios a apicultores de Chascom\u00fas\">[Leer M\u00e1s]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":43745,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[6],"tags":[],"class_list":{"0":"post-43744","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-chascomus"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/6982252e5faa5.png?fit=668%2C445&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8qtrQ-bny","jetpack-related-posts":[{"id":18804,"url":"https:\/\/larevistadigital.com.ar\/blog\/dolores-el-ministro-de-produccion-entrego-subsidios-para-la-reactivacion-del-turismo-y-la-cultura\/","url_meta":{"origin":43744,"position":0},"title":"DOLORES: EL MINISTRO DE PRODUCCI\u00d3N ENTREG\u00d3 SUBSIDIOS PARA LA REACTIVACI\u00d3N DEL TURISMO Y LA CULTURA","author":"Alejandro Sosa Ruda","date":"9 febrero, 2021","format":false,"excerpt":"El titular de la cartera bonaerense, Augusto Costa, estuvo en Castelli y Dolores donde encabez\u00f3 la entrega de fondos a instituciones vinculadas con estas dos actividades. DOLORES - El ministro de la Producci\u00f3n, Ciencia e Innovaci\u00f3n Tecnol\u00f3gica de la provincia, Augusto Costa, recorri\u00f3 varias localidades de la regi\u00f3n, entregando subsidios\u2026","rel":"","context":"En \u00abDOLORES\u00bb","block_context":{"text":"DOLORES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/dolores\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/fe0db3655b97085b503c335ff79a3e574a6166b5.jpg?fit=1140%2C763&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/fe0db3655b97085b503c335ff79a3e574a6166b5.jpg?fit=1140%2C763&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/fe0db3655b97085b503c335ff79a3e574a6166b5.jpg?fit=1140%2C763&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/fe0db3655b97085b503c335ff79a3e574a6166b5.jpg?fit=1140%2C763&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/fe0db3655b97085b503c335ff79a3e574a6166b5.jpg?fit=1140%2C763&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":42786,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-cuna-del-pejerrey-como-trabaja-piscicultura-para-abastecer-a-la-provincia-y-al-mundo\/","url_meta":{"origin":43744,"position":1},"title":"Chascom\u00fas, cuna del pejerrey: c\u00f3mo trabaja Piscicultura para abastecer a la Provincia y al mundo","author":"Alejandro Sosa Ruda","date":"6 diciembre, 2025","format":false,"excerpt":"Alfredo \u201cCacho\u201d Astessuain explic\u00f3 en Ataque de Radio el detr\u00e1s de escena de la cr\u00eda de pejerreyes y el rol estrat\u00e9gico del centro local. 06de Diciembre de 2025 CHASCOM\u00daS -\u00a0 \u00a0En una entrevista en\u00a0 Ataque de Radio-Home office-, desde el vivo de Facebook de la Revista Digital,\u00a0 Alfredo \u201cCacho\u201d Astessuain,\u2026","rel":"","context":"En \u00abATAQUE DE RADIO\u00bb","block_context":{"text":"ATAQUE DE RADIO","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/ataque-de-radio\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2025-12-06-183756.jpg?fit=664%2C377&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2025-12-06-183756.jpg?fit=664%2C377&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2025-12-06-183756.jpg?fit=664%2C377&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":37042,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-en-el-barrio-ipora-se-inscribira-en-el-registro-de-acceso-a-los-subsidios-de-energia\/","url_meta":{"origin":43744,"position":2},"title":"CHASCOM\u00daS: EN EL BARRIO IPOR\u00c1 SE INSCRIBIR\u00c1 EN EL REGISTRO DE ACCESO A LOS SUBSIDIOS DE ENERG\u00cdA","author":"Alejandro Sosa Ruda","date":"23 agosto, 2024","format":false,"excerpt":"Este s\u00e1bado de 9 a 12 horas, el equipo de Pol\u00edticas Comunitarias municipal realizar\u00e1 un operativo especial en el SUM barrial, ubicado en Sargento Cabral y Per\u00fa. 23 de Agosto de 2024 CHASCOM\u00daS -\u00a0 Este s\u00e1bado de 9 a 12 horas, el equipo de Pol\u00edticas Comunitarias municipal realizar\u00e1 un operativo\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/66c8c102be257.png?fit=668%2C445&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/66c8c102be257.png?fit=668%2C445&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/66c8c102be257.png?fit=668%2C445&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":33427,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-el-ministerio-de-desarrollo-agrario-organiza-el-proximo-sabado-la-feria-de-sabores-bonaerenses\/","url_meta":{"origin":43744,"position":3},"title":"CHASCOM\u00daS: EL MINISTERIO DE DESARROLLO AGRARIO ORGANIZA EL PR\u00d3XIMO S\u00c1BADO LA FERIA DE SABORES BONAERENSES.","author":"Alejandro Sosa Ruda","date":"11 septiembre, 2023","format":false,"excerpt":"El evento, que se llevar\u00e1 a cabo el s\u00e1bado 16 de septiembre de 11 a 19 horas en la Estaci\u00f3n Hidrobiol\u00f3gica de Chascom\u00fas, ofrece la oportunidad de disfrutar y adquirir productos aut\u00e9nticos de la regi\u00f3n. 11 De Septiembre de 2023 CHASCOM\u00daS -\u00a0 El gobierno de la Provincia de Buenos aires,\u2026","rel":"","context":"En \u00abINTERES GENERAL\u00bb","block_context":{"text":"INTERES GENERAL","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/interes-general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/03528deb90b1a477092d1b20a096cb5e9a9a43ce.jpeg?fit=1140%2C642&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/03528deb90b1a477092d1b20a096cb5e9a9a43ce.jpeg?fit=1140%2C642&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/03528deb90b1a477092d1b20a096cb5e9a9a43ce.jpeg?fit=1140%2C642&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/03528deb90b1a477092d1b20a096cb5e9a9a43ce.jpeg?fit=1140%2C642&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/03528deb90b1a477092d1b20a096cb5e9a9a43ce.jpeg?fit=1140%2C642&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":10293,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-pago-de-becas-universitarias-y-subsidios-para-bibliotecas\/","url_meta":{"origin":43744,"position":4},"title":"CHASCOM\u00daS: PAGO DE BECAS UNIVERSITARIAS Y SUBSIDIOS PARA BIBLIOTECAS","author":"Alejandro Sosa Ruda","date":"23 mayo, 2019","format":false,"excerpt":"Desde la Secretar\u00eda de Hacienda se hace saber que desde este jueves 23, se har\u00e1 efectivo el cobro de las contribuciones correspondientes al mes de mayo a sus respectivos beneficiarios en la oficina de Tesorer\u00eda, ubicada en la planta baja del Palacio Municipal (Cr\u00e1mer 270), de lunes a viernes, a\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2019\/05\/municipio-copia.jpg?fit=1200%2C795&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2019\/05\/municipio-copia.jpg?fit=1200%2C795&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2019\/05\/municipio-copia.jpg?fit=1200%2C795&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2019\/05\/municipio-copia.jpg?fit=1200%2C795&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2019\/05\/municipio-copia.jpg?fit=1200%2C795&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":40740,"url":"https:\/\/larevistadigital.com.ar\/blog\/se-viene-sabores-bonaerenses-a-chascomus\/","url_meta":{"origin":43744,"position":5},"title":"Se viene Sabores Bonaerenses a Chascom\u00fas","author":"Alejandro Sosa Ruda","date":"4 agosto, 2025","format":false,"excerpt":"Se trata de la feria de alimentos m\u00e1s importante de la provincia de Buenos Aires, donde productores y productoras comercializan directamente sus creaciones. 04 de Agosto de 2025 CHASCOM\u00daS -\u00a0 \u00a0La Municipalidad de Chascom\u00fas en conjunto con el Ministerio Desarrollo Agrario invitan a la comunidad a participar de una nueva\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/6890f15d68be0.png?fit=668%2C445&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/6890f15d68be0.png?fit=668%2C445&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/6890f15d68be0.png?fit=668%2C445&ssl=1&resize=525%2C300 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/43744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=43744"}],"version-history":[{"count":1,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/43744\/revisions"}],"predecessor-version":[{"id":43746,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/43744\/revisions\/43746"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media\/43745"}],"wp:attachment":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=43744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=43744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=43744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}