{"id":44803,"date":"2026-03-30T19:04:10","date_gmt":"2026-03-30T22:04:10","guid":{"rendered":"https:\/\/larevistadigital.com.ar\/blog\/?p=44803"},"modified":"2026-03-30T19:04:10","modified_gmt":"2026-03-30T22:04:10","slug":"la-gran-logia-de-masones-se-suma-al-programa-chascomus-km-0-de-la-democracia","status":"publish","type":"post","link":"https:\/\/larevistadigital.com.ar\/blog\/la-gran-logia-de-masones-se-suma-al-programa-chascomus-km-0-de-la-democracia\/","title":{"rendered":"La Gran Logia de Masones se suma al programa \u201cChascom\u00fas Km 0 de la Democracia\u201d"},"content":{"rendered":"<h3 class=\"excerpt\">El intendente Javier Gast\u00f3n fue invitado especialmente a exponer sobre la iniciativa local en un homenaje a Ra\u00fal Alfons\u00edn realizado en la ciudad de Buenos Aires.<\/h3>\n<p>30 De Marzo de 2026<\/p>\n<div id=\"miDiv1\" class=\"text\">\n<p><strong>CHASCOM\u00daS &#8211;\u00a0<\/strong> \u00a0La Municipalidad de Chascom\u00fas firm\u00f3 un convenio de adhesi\u00f3n con la Gran Logia de la Argentina de Libres y Aceptados Masones para incorporar a la instituci\u00f3n al programa \u201cChascom\u00fas Km 0 de la Democracia\u201d.<\/p>\n<blockquote>\n<h3>El acuerdo fue suscripto por el intendente Javier Gast\u00f3n y el Gran Maestre de la entidad, Pablo L\u00e1zaro, en el marco de una jornada de reflexi\u00f3n y homenaje al expresidente Ra\u00fal Alfons\u00edn, realizada el pasado 28 de marzo en la sede central de la organizaci\u00f3n, en la ciudad de Buenos Aires.<\/h3>\n<\/blockquote>\n<p>La participaci\u00f3n del jefe comunal se dio a partir de una invitaci\u00f3n formal de la Gran Logia, en una actividad que reuni\u00f3 a referentes del \u00e1mbito institucional, educativo y pol\u00edtico con el objetivo de poner en valor el legado democr\u00e1tico de Alfons\u00edn desde diversas miradas.<\/p>\n<blockquote>\n<h3>En ese contexto, Javier Gast\u00f3n fue uno de los expositores de la jornada, donde present\u00f3 el programa \u201cChascom\u00fas Km 0 de la Democracia\u201d, en un bloque espec\u00edfico dedicado a esta pol\u00edtica p\u00fablica local.<\/h3>\n<\/blockquote>\n<p>Durante su intervenci\u00f3n, el intendente comparti\u00f3 los objetivos y alcances de la iniciativa, que busca poner en valor la figura de Ra\u00fal Alfons\u00edn, fortalecer la memoria colectiva y consolidar a la ciudad como un punto de referencia en la historia democr\u00e1tica argentina.<\/p>\n<p>La inclusi\u00f3n del programa dentro de la agenda del encuentro constituye un reconocimiento al trabajo que se viene desarrollando desde el Municipio en materia de promoci\u00f3n de valores democr\u00e1ticos y construcci\u00f3n de memoria.<\/p>\n<p><span style=\"color: #ff0000\"><strong>Un espacio de reflexi\u00f3n con referentes de distintos \u00e1mbitos<\/strong><\/span><\/p>\n<p>La jornada cont\u00f3 con la participaci\u00f3n de distintos expositores que abordaron la figura de <strong>Ra\u00fal Alfons\u00edn<\/strong> desde m\u00faltiples perspectivas.<\/p>\n<p>Entre ellos, se destacaron: Eduardo L\u00e1zara, quien desde su conocimiento y cercan\u00eda, desarroll\u00f3 una mirada hist\u00f3rica sobre el expresidente; Jorge Ferronato, que expuso sobre los valores de integridad, valent\u00eda y compromiso de Alfons\u00edn, y Pablo L\u00e1zaro, Gran Maestre de la instituci\u00f3n, quien abord\u00f3 su v\u00ednculo con la masoner\u00eda.<\/p>\n<blockquote>\n<h3>Tambi\u00e9n particip\u00f3 de la jornada, el secretario de Gesti\u00f3n P\u00fablica y Modernizaci\u00f3n municipal, Pablo N\u00e1poli.<\/h3>\n<\/blockquote>\n<p>Asimismo, se puso en valor su trayectoria como vecino de Chascom\u00fas, donde inici\u00f3 su carrera pol\u00edtica, y su legado proyectado en el presente.<\/p>\n<p>A lo largo del encuentro, los participantes coincidieron en la vigencia de los ideales democr\u00e1ticos que Alfons\u00edn represent\u00f3 y en la importancia de seguir promoviendo esos valores en la actualidad.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>El intendente Javier Gast\u00f3n fue invitado especialmente a exponer sobre la iniciativa local en un homenaje a Ra\u00fal Alfons\u00edn realizado en la ciudad de Buenos Aires. 30 De Marzo de 2026 CHASCOM\u00daS &#8211;\u00a0 \u00a0La Municipalidad <a class=\"mh-excerpt-more\" href=\"https:\/\/larevistadigital.com.ar\/blog\/la-gran-logia-de-masones-se-suma-al-programa-chascomus-km-0-de-la-democracia\/\" title=\"La Gran Logia de Masones se suma al programa \u201cChascom\u00fas Km 0 de la Democracia\u201d\">[Leer M\u00e1s]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":44804,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[6],"tags":[],"class_list":{"0":"post-44803","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-chascomus"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/69cab642ab9e7.png?fit=668%2C445&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8qtrQ-bED","jetpack-related-posts":[{"id":37849,"url":"https:\/\/larevistadigital.com.ar\/blog\/el-intendente-de-chascomus-firmo-un-convenio-de-cooperacion-con-la-organizacion-de-estados-iberoamericanos\/","url_meta":{"origin":44803,"position":0},"title":"El intendente de Chascom\u00fas, firm\u00f3 un convenio de cooperaci\u00f3n con la Organizaci\u00f3n de Estados Iberoamericanos","author":"Alejandro Sosa Ruda","date":"12 noviembre, 2024","format":false,"excerpt":"Ser\u00e1 una gran posibilidad para nuestra ciudad de promover proyectos de distintos \u00edndole, poniendo el acento en el \u201cChascom\u00fas, Km 0 de la Democracia\u201d 12 de Noviembre de CHASCOM\u00daS -\u00a0 El intendente Javier Gast\u00f3n firm\u00f3 el convenio marco de cooperaci\u00f3n con la Organizaci\u00f3n de Estados Iberoamericanos (OEI), el organismo internacional\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/67337f68c8772.png?fit=668%2C445&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/67337f68c8772.png?fit=668%2C445&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/67337f68c8772.png?fit=668%2C445&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":38188,"url":"https:\/\/larevistadigital.com.ar\/blog\/javier-gaston-presento-en-lalin-el-proyecto-chascomus-km0-de-la-democracia\/","url_meta":{"origin":44803,"position":1},"title":"Javier Gast\u00f3n present\u00f3 en Lal\u00edn el proyecto \u201cChascom\u00fas KM0 de la Democracia\u201d","author":"Alejandro Sosa Ruda","date":"9 diciembre, 2024","format":false,"excerpt":"En el Concejo de la ciudad gallega, brind\u00f3 detalles de la iniciativa que busca destacar el legado de Ra\u00fal Alfons\u00edn y fortalecer los valores democr\u00e1ticos. 09 de diciembre de 2024 CHASCOM\u00daS -\u00a0 \u00a0El intendente Javier Gast\u00f3n inici\u00f3 su viaje oficial a Europa con una agenda enfocada en promover los valores\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/67572cf2a6226.png?fit=668%2C445&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/67572cf2a6226.png?fit=668%2C445&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/67572cf2a6226.png?fit=668%2C445&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":40276,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-pablo-napoli-visito-el-centro-de-lalin-agolada-y-silleda-de-buenos-aires\/","url_meta":{"origin":44803,"position":2},"title":"Chascom\u00fas: Pablo N\u00e1poli visit\u00f3 el Centro de Lal\u00edn, Agolada y Silleda de Buenos Aires","author":"Alejandro Sosa Ruda","date":"2 julio, 2025","format":false,"excerpt":"Particip\u00f3 del tradicional evento del cocido que re\u00fane cada a\u00f1o a numerosos descendientes gallegos El \u00faltimo domingo, tuvo lugar la fiesta gastron\u00f3mica que se celebra anualmente en el Centro de Lal\u00edn, Agolada y Silleda de Buenos Aires, para honrar el cocido, un plato tradicional gallego, de la cual particip\u00f3 el\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/68656928b5052.png?fit=668%2C445&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/68656928b5052.png?fit=668%2C445&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/68656928b5052.png?fit=668%2C445&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":44738,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-javier-gaston-y-directivos-de-aubasa-recorrieron-comercios-y-empresas-locales\/","url_meta":{"origin":44803,"position":3},"title":"Chascom\u00fas: Javier Gast\u00f3n y directivos de AUBASA recorrieron comercios y empresas locales","author":"Alejandro Sosa Ruda","date":"26 marzo, 2026","format":false,"excerpt":"El presidente de la concesionaria, Jos\u00e9 Arteaga, visit\u00f3 la ciudad en el marco de una recorrida por la Autov\u00eda 2. 26 de marzo de 2026 CHASCOM\u00daS -\u00a0 \u00a0El intendente Javier Gast\u00f3n recibi\u00f3 al presidente de Autopistas de Buenos Aires S.A. (AUBASA), Jos\u00e9 Arteaga, quien visit\u00f3 la ciudad como parte de\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/69c572d65ed99.png?fit=668%2C445&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/69c572d65ed99.png?fit=668%2C445&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/69c572d65ed99.png?fit=668%2C445&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":9476,"url":"https:\/\/larevistadigital.com.ar\/blog\/el-pj-de-la-provincia-de-buenos-aires-homenajeo-a-raul-alfonsin\/","url_meta":{"origin":44803,"position":4},"title":"EL PJ DE LA PROVINCIA DE BUENOS AIRES HOMENAJE\u00d3 A RA\u00daL ALFONS\u00cdN","author":"Alejandro Sosa Ruda","date":"1 abril, 2019","format":false,"excerpt":"El presidente del Pj de Chascom\u00fas, y jefe del Bloque de PJ Unidad Ciudadana, Gabriel Macchi, hizo una publicaci\u00f3n en su cuenta personal de Facebook en donde se refiri\u00f3 al homenaje que el Peronismo bonaerense hizo hoy a la tarde al ex presidente nativo de Chascom\u00fas, Don Ra\u00fal Alfons\u00edn, al\u2026","rel":"","context":"En \u00abPOLITICA\u00bb","block_context":{"text":"POLITICA","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2019\/03\/56328656_2438342616190203_7169636753148477440_n.jpg?fit=960%2C720&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2019\/03\/56328656_2438342616190203_7169636753148477440_n.jpg?fit=960%2C720&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2019\/03\/56328656_2438342616190203_7169636753148477440_n.jpg?fit=960%2C720&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2019\/03\/56328656_2438342616190203_7169636753148477440_n.jpg?fit=960%2C720&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":39648,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-km-0-de-la-democracia-el-embajador-de-suecia-visito-la-ciudad\/","url_meta":{"origin":44803,"position":5},"title":"Chascom\u00fas Km 0 de la Democracia: El embajador de Suecia visit\u00f3 la ciudad","author":"Alejandro Sosa Ruda","date":"5 mayo, 2025","format":false,"excerpt":"El intendente Javier Gast\u00f3n encabez\u00f3 el encuentro junto a representantes de la Asociaci\u00f3n Sueca de Municipios y autoridades nacionales y provinciales. 05 De Mayo de 2025 CHASCOM\u00daS -\u00a0 \u00a0En el marco del programa \u201cChascom\u00fas Km 0 de la Democracia\u201d, el intendente Javier Gast\u00f3n recibi\u00f3 al embajador de Suecia en Argentina,\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/6818ef0122185.png?fit=668%2C445&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/6818ef0122185.png?fit=668%2C445&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/6818ef0122185.png?fit=668%2C445&ssl=1&resize=525%2C300 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/44803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=44803"}],"version-history":[{"count":1,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/44803\/revisions"}],"predecessor-version":[{"id":44805,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/44803\/revisions\/44805"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media\/44804"}],"wp:attachment":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=44803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=44803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=44803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}