{"id":44984,"date":"2026-04-07T16:27:12","date_gmt":"2026-04-07T19:27:12","guid":{"rendered":"https:\/\/larevistadigital.com.ar\/blog\/?p=44984"},"modified":"2026-04-07T16:27:12","modified_gmt":"2026-04-07T19:27:12","slug":"video-el-duende-que-trabaja-en-un-diario-y-desata-fenomenos-inexplicables","status":"publish","type":"post","link":"https:\/\/larevistadigital.com.ar\/blog\/video-el-duende-que-trabaja-en-un-diario-y-desata-fenomenos-inexplicables\/","title":{"rendered":"[VIDEO] El duende que \u201ctrabaja\u201d en un diario y desata fen\u00f3menos inexplicables"},"content":{"rendered":"<h3 data-start=\"75\" data-end=\"204\">En Oruro, Bolivia, periodistas aseguran convivir con una entidad que mueve objetos, hace ruidos y protege un misterioso \u201ctesoro\u201d.<\/h3>\n<p>07 de abril de 2026<\/p>\n<p data-start=\"206\" data-end=\"541\"><strong>Oruro, BOLIVIA &#8211;\u00a0<\/strong> \u00a0Lo que parece una historia salida de la ficci\u00f3n ocurre \u2014seg\u00fan relatan sus propios protagonistas\u2014 dentro de un peri\u00f3dico de la ciudad de Oruro. All\u00ed, trabajadores y periodistas afirman haberse convertido en \u201cguardianes\u201d de un duende al que incluso le atribuyen travesuras, manifestaciones f\u00edsicas y hasta la capacidad de cumplir deseos.<\/p>\n<blockquote>\n<h3 data-start=\"543\" data-end=\"816\">Todo gira en torno a una imagen hecha en papel por una extrabajadora del medio, Marcela Vald\u00e9z. Desde entonces, aseguran, comenzaron a registrarse hechos extra\u00f1os: objetos que cambian de lugar, herramientas que desaparecen y ruidos sin explicaci\u00f3n en medio de la redacci\u00f3n.<\/h3>\n<\/blockquote>\n<p data-start=\"818\" data-end=\"1122\"><em><strong>\u201cTodo lo que la gente le deja est\u00e1 resguardado, es de \u00e9l. Nadie puede tocar\u201d<\/strong><\/em>, advierten quienes trabajan en el lugar, en referencia a una especie de \u201colla\u201d donde se acumulan monedas y ofrendas. La creencia es clara: <strong>quien se atreva a tomar algo podr\u00eda convertirse en v\u00edctima de las travesuras del duende<\/strong>.<\/p>\n<blockquote>\n<h3 data-start=\"1124\" data-end=\"1411\">El origen del fen\u00f3meno, seg\u00fan reconstruyen, se remonta a casi 80 a\u00f1os atr\u00e1s, cuando el terreno donde hoy funciona el diario era bosque y zona minera. En ese entonces, un \u00e1rbol ubicado en el patio central era se\u00f1alado como el hogar de la criatura. Durante a\u00f1os evitaron talarlo por temor.<\/h3>\n<\/blockquote>\n<p data-start=\"1413\" data-end=\"1473\"><strong>\u201cAlgunos dicen que de ah\u00ed ve\u00edan bajar al duende\u201d, recuerdan.<\/strong><\/p>\n<div style=\"width: 1280px;\" class=\"wp-video\"><!--[if lt IE 9]><script>document.createElement('video');<\/script><![endif]-->\n<video class=\"wp-video-shortcode\" id=\"video-44984-1\" width=\"1280\" height=\"720\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Periodistas-aseguran-que-un-duende-hace-travesuras-en-su-redaccion-en-Bolivia.mp4?_=1\" \/><a href=\"https:\/\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Periodistas-aseguran-que-un-duende-hace-travesuras-en-su-redaccion-en-Bolivia.mp4\">https:\/\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Periodistas-aseguran-que-un-duende-hace-travesuras-en-su-redaccion-en-Bolivia.mp4<\/a><\/video><\/div>\n<p data-start=\"1475\" data-end=\"1853\">Con el paso del tiempo, las historias no hicieron m\u00e1s que multiplicarse. Trabajadores aseguran haber escuchado ruidos de m\u00e1quinas en funcionamiento sin que hubiera nadie presente, o incluso haber visto c\u00f3mo objetos se mov\u00edan solos. Uno de los relatos m\u00e1s impactantes describe c\u00f3mo una cucharita comenz\u00f3 a vibrar dentro de una taza: \u201cEmpez\u00f3 a sonar tin, tin\u2026 y despu\u00e9s se calm\u00f3\u201d.<\/p>\n<blockquote>\n<h3 data-start=\"1855\" data-end=\"2124\">La situaci\u00f3n lleg\u00f3 a tal punto que incluso un investigador paranormal realiz\u00f3 una psicofon\u00eda en el edificio, especialmente en la zona donde estaba el antiguo \u00e1rbol. All\u00ed, seg\u00fan el testimonio, un trabajador sinti\u00f3 que \u201cle tocaron la espalda\u201d sin que hubiera nadie cerca.<\/h3>\n<\/blockquote>\n<p data-start=\"2126\" data-end=\"2333\">Lejos de generar miedo, en el diario aseguran que aprendieron a convivir con la supuesta entidad. \u201cSon actitudes muchas veces juguetonas. Lo importante es aprender a convivir con estas entidades\u201d, sostienen.<\/p>\n<blockquote>\n<h3 data-start=\"2335\" data-end=\"2594\">El v\u00ednculo es tal que el duende ya forma parte de la identidad del lugar. Los trabajadores cuidan sus pertenencias, respetan su \u201cespacio\u201d y hasta preparan una presentaci\u00f3n p\u00fablica para que pueda ser conocido por la comunidad en la pr\u00f3xima Noche de los Museos.<\/h3>\n<\/blockquote>\n<p data-start=\"2596\" data-end=\"2824\" data-is-last-node=\"\" data-is-only-node=\"\">Entre la creencia, la sugesti\u00f3n y lo inexplicable, la historia del \u201cduende del diario\u201d crece y suma adeptos. Y aunque no haya pruebas concluyentes, hay algo que en esa redacci\u00f3n nadie discute: mejor no tocar lo que le pertenece.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>En Oruro, Bolivia, periodistas aseguran convivir con una entidad que mueve objetos, hace ruidos y protege un misterioso \u201ctesoro\u201d. 07 de abril de 2026 Oruro, BOLIVIA &#8211;\u00a0 \u00a0Lo que parece una historia salida de la <a class=\"mh-excerpt-more\" href=\"https:\/\/larevistadigital.com.ar\/blog\/video-el-duende-que-trabaja-en-un-diario-y-desata-fenomenos-inexplicables\/\" title=\"[VIDEO] El duende que \u201ctrabaja\u201d en un diario y desata fen\u00f3menos inexplicables\">[Leer M\u00e1s]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":44986,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11,50,45],"tags":[],"class_list":{"0":"post-44984","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-curiosas","8":"category-interes-general","9":"category-lo-vi-en-internet"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-04-07-161900.jpg?fit=809%2C418&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8qtrQ-bHy","jetpack-related-posts":[{"id":22354,"url":"https:\/\/larevistadigital.com.ar\/blog\/furioso-por-los-ruidos-por-refacciones-en-la-casa-del-vecino-le-baleo-la-puerta\/","url_meta":{"origin":44984,"position":0},"title":"FURIOSO POR LOS RUIDOS POR REFACCIONES EN LA CASA DEL VECINO, LE BALE\u00d3 LA PUERTA","author":"Alejandro Sosa Ruda","date":"12 octubre, 2021","format":false,"excerpt":"El hecho ocurri\u00f3 el pasado s\u00e1bado en el barrio La Perla. En las \u00faltimas horas, se orden\u00f3 un allanamiento en la casa del acusado, donde se secuestr\u00f3 el arma de fuego utilizada. El hombre tiene 71 a\u00f1os y qued\u00f3 detenido. MAR DEL PLATA -\u00a0 Un hombre de 71 a\u00f1os fue\u2026","rel":"","context":"En \u00abPOLICIALES\u00bb","block_context":{"text":"POLICIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/policiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2021-10-11-222526.jpg?fit=1007%2C492&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2021-10-11-222526.jpg?fit=1007%2C492&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2021-10-11-222526.jpg?fit=1007%2C492&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2021-10-11-222526.jpg?fit=1007%2C492&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":14443,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-vecinos-alertan-a-la-policia-por-ruidos-en-los-techos-y-detienen-a-dos-personas\/","url_meta":{"origin":44984,"position":1},"title":"CHASCOM\u00daS: VECINOS ALERTAN A LA POLIC\u00cdA POR \u00abRUIDOS EN LOS TECHOS\u00bb Y DETIENEN A DOS PERSONAS","author":"Alejandro Sosa Ruda","date":"29 enero, 2020","format":false,"excerpt":"Personal E.P.C. Chascomus (Cria. Chascomus) juntamente con DDI CHASCOMUS concurrieron a llamado de vecinos en calle Garay e Hipolito Irigoyen de este medio en raz\u00f3n que escuchaban pasos sobre los techos de una carnicer\u00eda (LA BARRERA) y veterinaria (HUELLAS) existente en el lugar, donde lograron la aprehensi\u00f3n de dos masculinos\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2019\/01\/bbx_755050019_comisaria_chasco_01.jpg?fit=800%2C579&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2019\/01\/bbx_755050019_comisaria_chasco_01.jpg?fit=800%2C579&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2019\/01\/bbx_755050019_comisaria_chasco_01.jpg?fit=800%2C579&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2019\/01\/bbx_755050019_comisaria_chasco_01.jpg?fit=800%2C579&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":6929,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-roban-vivienda-haciendo-un-boquete\/","url_meta":{"origin":44984,"position":2},"title":"CHASCOM\u00daS: ROBAN VIVIENDA HACIENDO UN \u00abBOQUETE\u00bb","author":"Alejandro Sosa Ruda","date":"19 octubre, 2018","format":false,"excerpt":"Otro robo sucedi\u00f3 el d\u00eda de ayer en la ciudad de Chascom\u00fas, seg\u00fan inform\u00f3 el m\u00f3vil de FM Por Siempre 97.3 mhtz. Durante el programa \u201cBuenos Muchachos\u201d. En esta oportunidad, Juan Pablo cont\u00f3 que, en el fondo de un galponcito, los malhechores rompieron unos ladrillos de vidrio e ingresaron al\u2026","rel":"","context":"En \u00abPOLICIALES\u00bb","block_context":{"text":"POLICIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/policiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/10\/Screenshot_1-1.jpg?fit=650%2C667&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/10\/Screenshot_1-1.jpg?fit=650%2C667&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/10\/Screenshot_1-1.jpg?fit=650%2C667&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":14153,"url":"https:\/\/larevistadigital.com.ar\/blog\/mochilero-desaparecido-madre-pide-compartir-en-redes-sociales\/","url_meta":{"origin":44984,"position":3},"title":"MOCHILERO DESAPARECIDO: MADRE PIDE COMPARTIR EN REDES SOCIALES","author":"Alejandro Sosa Ruda","date":"13 enero, 2020","format":false,"excerpt":"La familia del joven mochilero oriundo de Pig\u00fc\u00e9, provincia de Buenos Aires,\u00a0Francisco Ciarlantini Cristoforone\u00a0impulsa una b\u00fasqueda a trav\u00e9s de las redes sociales para ubicarlo luego que no se tienen m\u00e1s novedades sobre \u00e9l\u00a0desde el 23 de diciembre\u00a0\u00faltimo cuando se encontraba en la zona entre Per\u00fa y Bolivia. La mam\u00e1 Fabiana\u2026","rel":"","context":"En \u00abINTERES GENERAL\u00bb","block_context":{"text":"INTERES GENERAL","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/interes-general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/desap.jpg?fit=600%2C375&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/desap.jpg?fit=600%2C375&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/desap.jpg?fit=600%2C375&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":21600,"url":"https:\/\/larevistadigital.com.ar\/blog\/padre-e-hijo-escucharon-ruidos-en-el-patio-terminaron-atrapando-a-un-ladron\/","url_meta":{"origin":44984,"position":4},"title":"PADRE E HIJO ESCUCHARON RUIDOS EN EL PATIO. TERMINARON ATRAPANDO A UN LADR\u00d3N","author":"Alejandro Sosa Ruda","date":"17 agosto, 2021","format":false,"excerpt":"El hecho ocurri\u00f3 ayer por la noche. El detenido tiene 22 a\u00f1os, mientras que otros dos delincuentes lograron escapar. MAR DEL PLATA -\u00a0 Padre e hijo\u00a0atraparon ayer a la noche a un ladr\u00f3n\u00a0que hab\u00eda ingresado al patio de su casa del barrio\u00a0Peralta Ramos Oeste\u00a0y lo retuvieron hasta la llegada de\u2026","rel":"","context":"En \u00abPOLICIALES\u00bb","block_context":{"text":"POLICIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/policiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/CACO-MDQ-e1629211250256.png?fit=786%2C283&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/CACO-MDQ-e1629211250256.png?fit=786%2C283&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/CACO-MDQ-e1629211250256.png?fit=786%2C283&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/CACO-MDQ-e1629211250256.png?fit=786%2C283&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":13180,"url":"https:\/\/larevistadigital.com.ar\/blog\/jeanine-anez-se-autoproclamo-presidenta-de-bolivia\/","url_meta":{"origin":44984,"position":5},"title":"JEANINE \u00c1\u00d1EZ SE AUTOPROCLAM\u00d3 PRESIDENTA DE BOLIVIA","author":"Alejandro Sosa Ruda","date":"12 noviembre, 2019","format":false,"excerpt":"La senadora Jeanine \u00c1\u00f1ez asumi\u00f3 la Presidencia de Bolivia tras la interrupci\u00f3n del mandato de Evo Morales al autoproclamarse ante una diezmada Asamblea Legislativa. \u201cAsumo de inmediato la presidencia\u201d dijo A\u00f1ez, quien luego dijo estar \u201ccon el compromiso de llevar adelante este proceso que no va a ser f\u00e1cil, pero\u2026","rel":"","context":"En \u00abDESTACADAS\u00bb","block_context":{"text":"DESTACADAS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/destacadas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Screenshot_1-65.jpg?fit=934%2C622&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Screenshot_1-65.jpg?fit=934%2C622&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Screenshot_1-65.jpg?fit=934%2C622&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Screenshot_1-65.jpg?fit=934%2C622&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/44984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=44984"}],"version-history":[{"count":1,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/44984\/revisions"}],"predecessor-version":[{"id":44988,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/44984\/revisions\/44988"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media\/44986"}],"wp:attachment":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=44984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=44984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=44984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}