{"id":45636,"date":"2026-05-13T17:16:23","date_gmt":"2026-05-13T20:16:23","guid":{"rendered":"https:\/\/larevistadigital.com.ar\/blog\/?p=45636"},"modified":"2026-05-13T17:16:23","modified_gmt":"2026-05-13T20:16:23","slug":"impactante-choque-entre-un-auto-y-un-tren-en-castelli-el-conductor-sobrevivio-de-milagro","status":"publish","type":"post","link":"https:\/\/larevistadigital.com.ar\/blog\/impactante-choque-entre-un-auto-y-un-tren-en-castelli-el-conductor-sobrevivio-de-milagro\/","title":{"rendered":"Impactante choque entre un auto y un tren en Castelli: el conductor sobrevivi\u00f3 de milagro"},"content":{"rendered":"<h3 data-section-id=\"15xmek\" data-start=\"94\" data-end=\"310\">El accidente ocurri\u00f3 en un paso a nivel sin barreras ubicado sobre la Ruta Provincial N\u00ba 2. El autom\u00f3vil fue embestido por una formaci\u00f3n de la L\u00ednea Roca que viajaba hacia Mar del Plata con 258 pasajeros a bordo.<\/h3>\n<p>13 de Mayo de 2026<\/p>\n<p data-start=\"312\" data-end=\"563\"><strong>CASTELLI &#8211;\u00a0<\/strong> \u00a0Un impresionante accidente ferroviario se registr\u00f3 este martes en el partido de <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Castelli<\/span><\/span>, donde un autom\u00f3vil fue embestido por un tren en un paso a nivel sin barreras ubicado en el kil\u00f3metro 170 de la Ruta Provincial N\u00ba 2.<\/p>\n<blockquote>\n<h3 data-start=\"565\" data-end=\"805\">El siniestro involucr\u00f3 a un <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Renault M\u00e9gane II<\/span><\/span> conducido por un hombre de 52 a\u00f1os oriundo de Castelli y una formaci\u00f3n de la <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">L\u00ednea Roca<\/span><\/span> que se dirig\u00eda hacia <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Mar del Plata<\/span><\/span>.<\/h3>\n<\/blockquote>\n<p data-start=\"807\" data-end=\"974\">Seg\u00fan inform\u00f3 Canal 4 de Castelli, por causas que a\u00fan son materia de investigaci\u00f3n el veh\u00edculo intent\u00f3 cruzar las v\u00edas y fue impactado en la parte trasera por el tren.<\/p>\n<p data-start=\"976\" data-end=\"1254\">Pese a la violencia del choque y a las impactantes im\u00e1genes que dej\u00f3 el hecho, el conductor sufri\u00f3 \u00fanicamente heridas leves y fue trasladado al Hospital Municipal \u201cDr. Ram\u00f3n Carrillo\u201d para recibir atenci\u00f3n m\u00e9dica. El episodio fue informado oficialmente sin lesiones de gravedad.<\/p>\n<blockquote>\n<h3 data-start=\"1256\" data-end=\"1427\">En tanto, ninguno de los 258 pasajeros que viajaban en la formaci\u00f3n ferroviaria result\u00f3 herido, aunque el tren permaneci\u00f3 detenido sobre las v\u00edas durante m\u00e1s de dos horas.<\/h3>\n<\/blockquote>\n<p data-start=\"1429\" data-end=\"1653\" data-is-last-node=\"\" data-is-only-node=\"\">En el lugar trabajaron Bomberos Voluntarios de Castelli, efectivos policiales, personal m\u00e9dico y operarios de <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">AUBASA<\/span><\/span>, quienes llevaron adelante las tareas de asistencia y prevenci\u00f3n en la zona.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>El accidente ocurri\u00f3 en un paso a nivel sin barreras ubicado sobre la Ruta Provincial N\u00ba 2. El autom\u00f3vil fue embestido por una formaci\u00f3n de la L\u00ednea Roca que viajaba hacia Mar del Plata con <a class=\"mh-excerpt-more\" href=\"https:\/\/larevistadigital.com.ar\/blog\/impactante-choque-entre-un-auto-y-un-tren-en-castelli-el-conductor-sobrevivio-de-milagro\/\" title=\"Impactante choque entre un auto y un tren en Castelli: el conductor sobrevivi\u00f3 de milagro\">[Leer M\u00e1s]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":45637,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[4,44,51],"tags":[],"class_list":{"0":"post-45636","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-castelli","8":"category-policiales","9":"category-regionales"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-05-13-171156.jpg?fit=605%2C461&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8qtrQ-bS4","jetpack-related-posts":[{"id":24836,"url":"https:\/\/larevistadigital.com.ar\/blog\/castelli-fuerte-accidente-en-la-ruta-11-hay-dos-heridos\/","url_meta":{"origin":45636,"position":0},"title":"CASTELLI: FUERTE ACCIDENTE EN LA RUTA 11. HAY DOS HERIDOS","author":"Alejandro Sosa Ruda","date":"27 marzo, 2022","format":false,"excerpt":"El autom\u00f3vil en el que viajaban protagoniz\u00f3 un impactante vuelco. Los detalles. CASTELLI-\u00a0 Dos personas resultaron heridas tras despistar un autom\u00f3vil Citro\u00ebn C3 y terminar volcando en la Ruta N\u00b0 11, en el kil\u00f3metro 193 en jurisdicci\u00f3n del partido de Castelli. Como consecuencia del accidente, las dos personas que viajaban\u2026","rel":"","context":"En \u00abCASTELLI\u00bb","block_context":{"text":"CASTELLI","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/castelli\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/e9fa25361b0aa097e59246ab31e24d38d3c6580d.jpg?fit=1140%2C855&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/e9fa25361b0aa097e59246ab31e24d38d3c6580d.jpg?fit=1140%2C855&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/e9fa25361b0aa097e59246ab31e24d38d3c6580d.jpg?fit=1140%2C855&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/e9fa25361b0aa097e59246ab31e24d38d3c6580d.jpg?fit=1140%2C855&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/e9fa25361b0aa097e59246ab31e24d38d3c6580d.jpg?fit=1140%2C855&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":36888,"url":"https:\/\/larevistadigital.com.ar\/blog\/ruta-2-accidente-a-la-altura-de-castelli\/","url_meta":{"origin":45636,"position":1},"title":"RUTA 2: ACCIDENTE A LA ALTURA DE CASTELLI","author":"Alejandro Sosa Ruda","date":"3 agosto, 2024","format":false,"excerpt":"Afortunadamente no hubo que lamentar v\u00edctimas. 03 de Agosto de 2024 CASTELLI -\u00a0 \u00a0Un autom\u00f3vil, ocupado por tres jovenes mujeres impact\u00f3 contra el guardrail a la altura del km. 172 de la Autovia 2 en jurisdicci\u00f3n de Castelli. La conductora del veh\u00edculo, relat\u00f3 que el fuerte imp\u00e1cto se debi\u00f3 a\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2024-08-03-151728.png?fit=1125%2C523&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2024-08-03-151728.png?fit=1125%2C523&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2024-08-03-151728.png?fit=1125%2C523&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2024-08-03-151728.png?fit=1125%2C523&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2024-08-03-151728.png?fit=1125%2C523&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":34802,"url":"https:\/\/larevistadigital.com.ar\/blog\/lezama-en-fatal-accidente-el-tren-arrollo-un-auto-y-fallece-una-mujer-chascomunense\/","url_meta":{"origin":45636,"position":2},"title":"LEZAMA: EN FATAL ACCIDENTE EL TREN ARROLL\u00d3 UN AUTO Y FALLECE UNA MUJER CHASCOMUNENSE","author":"Alejandro Sosa Ruda","date":"6 diciembre, 2023","format":false,"excerpt":"La v\u00edctima es una mujer nativa de Chascom\u00fas, quien hace a\u00f1os viv\u00eda en Lezama junto a su marido e hijas. 6 de diciembre de 2023 LEZAMA -\u00a0 En un fatal accidente, un autom\u00f3vil cruz\u00f3 las v\u00edas del tren, sin advertir que se acercaba la formaci\u00f3n y fue embestido provocando la\u2026","rel":"","context":"En \u00abDESTACADAS\u00bb","block_context":{"text":"DESTACADAS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/destacadas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2023-12-06-151357.png?fit=815%2C338&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2023-12-06-151357.png?fit=815%2C338&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2023-12-06-151357.png?fit=815%2C338&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2023-12-06-151357.png?fit=815%2C338&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":33761,"url":"https:\/\/larevistadigital.com.ar\/blog\/ruta-2-fuerte-choque-con-cinco-heridos-a-la-altura-de-castelli\/","url_meta":{"origin":45636,"position":3},"title":"RUTA 2: FUERTE CHOQUE CON CINCO HERIDOS A LA ALTURA DE CASTELLI","author":"Alejandro Sosa Ruda","date":"4 octubre, 2023","format":false,"excerpt":"Ocurri\u00f3 en la intersecci\u00f3n de las Ruta 2 y 41. Los detalles. 4 de Octubre de 2023 CASTELLI -\u00a0 Cinco personas resultaron heridas tras protagonizar un fuerte\u00a0accidente en la Ruta 2 en jurisdicci\u00f3n de Castelli, donde el autom\u00f3vil volc\u00f3. El accidente se registr\u00f3 esta ma\u00f1ana, m\u00e1s precisamente en\u00a0el cruce de\u2026","rel":"","context":"En \u00abREGIONALES\u00bb","block_context":{"text":"REGIONALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/regionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/927fa38fb060cc0b78bd858ed2d4aeb29da05ad9.jpg?fit=1140%2C855&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/927fa38fb060cc0b78bd858ed2d4aeb29da05ad9.jpg?fit=1140%2C855&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/927fa38fb060cc0b78bd858ed2d4aeb29da05ad9.jpg?fit=1140%2C855&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/927fa38fb060cc0b78bd858ed2d4aeb29da05ad9.jpg?fit=1140%2C855&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/927fa38fb060cc0b78bd858ed2d4aeb29da05ad9.jpg?fit=1140%2C855&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":4738,"url":"https:\/\/larevistadigital.com.ar\/blog\/tragico-accidente-la-ruta-muerto-herido-grave\/","url_meta":{"origin":45636,"position":4},"title":"TR\u00c1GICO ACCIDENTE EN LA RUTA: UN MUERTO Y UN HERIDO GRAVE","author":"Alejandro Sosa Ruda","date":"5 febrero, 2018","format":false,"excerpt":"Un \u00a0fatal accidente ocurri\u00f3 en la madrugada de este domingo, aproximadamente a las 05.hs, \u00a0en la ruta provincial 11 a unos 10 km al norte de Cerro de La Gloria. El siniestro se produjo precisamente en el km 171 de la mencionada v\u00eda, cuando un autom\u00f3vil Renault Clio color Blanco\u2026","rel":"","context":"En \u00abCASTELLI\u00bb","block_context":{"text":"CASTELLI","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/castelli\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/02\/2-1.jpg?fit=800%2C450&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/02\/2-1.jpg?fit=800%2C450&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/02\/2-1.jpg?fit=800%2C450&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/02\/2-1.jpg?fit=800%2C450&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":31775,"url":"https:\/\/larevistadigital.com.ar\/blog\/accidente-con-un-herido-chascomunense-en-la-ruta-2\/","url_meta":{"origin":45636,"position":5},"title":"ACCIDENTE CON UN HERIDO CHASCOMUNENSE EN LA RUTA 2","author":"Alejandro Sosa Ruda","date":"27 mayo, 2023","format":false,"excerpt":"Ocurri\u00f3 por la ma\u00f1ana, a la altura de la localidad de Castelli, y el conductor del veh\u00edculo debi\u00f3 ser trasladado para ser atendido. 27 de mayo de 2023 CASTELLI -\u00a0 Durante la ma\u00f1ana del d\u00eda de hoy se produjo un accidente de tr\u00e1nsito a la altura del kil\u00f3metro 169 de\u2026","rel":"","context":"En \u00abINTERES GENERAL\u00bb","block_context":{"text":"INTERES GENERAL","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/interes-general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/399b8f4106c11ed3852306f121d8dd6bc9282d7a.jpg?fit=924%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/399b8f4106c11ed3852306f121d8dd6bc9282d7a.jpg?fit=924%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/399b8f4106c11ed3852306f121d8dd6bc9282d7a.jpg?fit=924%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/399b8f4106c11ed3852306f121d8dd6bc9282d7a.jpg?fit=924%2C900&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/45636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=45636"}],"version-history":[{"count":1,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/45636\/revisions"}],"predecessor-version":[{"id":45638,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/45636\/revisions\/45638"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media\/45637"}],"wp:attachment":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=45636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=45636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=45636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}