{"id":530,"date":"2017-03-04T09:22:58","date_gmt":"2017-03-04T09:22:58","guid":{"rendered":"https:\/\/larevistadigital.com.ar\/blog\/?p=530"},"modified":"2017-03-04T09:29:51","modified_gmt":"2017-03-04T09:29:51","slug":"los-tres-gremios-pidieron-distintos-aumentos-coincidieron-la-necesidad-una-clausula-gatillo-la-inflacion","status":"publish","type":"post","link":"https:\/\/larevistadigital.com.ar\/blog\/los-tres-gremios-pidieron-distintos-aumentos-coincidieron-la-necesidad-una-clausula-gatillo-la-inflacion\/","title":{"rendered":"Los tres gremios pidieron distintos aumentos pero coincidieron en la necesidad de una cl\u00e1usula gatillo por la inflaci\u00f3n"},"content":{"rendered":"<p>Reuni\u00f3n de la Mesa Salarial Municipal<\/p>\n<p>En la ma\u00f1ana del jueves pasado, el Secretario de Gobierno, Cipriano P\u00e9rez del Cerro, junto al Director de Recursos Humanos, Jos\u00e9 Yezza Ross, recibieron a los representantes gremiales. Durante la reuni\u00f3n se aprob\u00f3 el listado de recategorizaciones correspondientes al sector de la Secretar\u00eda de Obras y Servicios. A su vez, iniciaron las negociaciones respecto al aumento salarial solicitado por los gremios.<\/p>\n<p>En tal sentido, desde ATE se pidi\u00f3 un aumento de 25% en 2 cuotas y el Sindicato de Trabajadores Municipales solicit\u00f3 un 20% sumado a un incremento en el Presentismo, debiendo ser el primer aumento a partir del mes de marzo; mientras que desde UPCN, se plante\u00f3 la suma de 9.500 pesos para la Categor\u00eda Ingresante. Coincidiendo todos los representantes sindicales en incorporar la cl\u00e1usula de ajuste por inflaci\u00f3n. Por su parte, desde el Departamento Ejecutivo plantearon la falta de herramientas elementales de gobernabilidad, al no contar con la aprobaci\u00f3n del Presupuesto 2017, adem\u00e1s de la falta de actualizaci\u00f3n en las tasas municipales debido al no tratamiento de las Ordenanzas Fiscal e Impositiva; sumado esto a la situaci\u00f3n de crisis econ\u00f3mica que atraviesa el pa\u00eds. Estuvieron presentes, Mercedes Rold\u00e1n por el Sindicato de Trabajadores Municipales, Mar\u00eda Alicia Barletta por ATE y Francisco Balzano por UPCN, junto a colaboradores.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Reuni\u00f3n de la Mesa Salarial Municipal En la ma\u00f1ana del jueves pasado, el Secretario de Gobierno, Cipriano P\u00e9rez del Cerro, junto al Director de Recursos Humanos, Jos\u00e9 Yezza Ross, recibieron a los representantes gremiales. Durante <a class=\"mh-excerpt-more\" href=\"https:\/\/larevistadigital.com.ar\/blog\/los-tres-gremios-pidieron-distintos-aumentos-coincidieron-la-necesidad-una-clausula-gatillo-la-inflacion\/\" title=\"Los tres gremios pidieron distintos aumentos pero coincidieron en la necesidad de una cl\u00e1usula gatillo por la inflaci\u00f3n\">[Leer M\u00e1s]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":531,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[10,26,12,23],"tags":[],"class_list":{"0":"post-530","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-gremiales","8":"category-local-y-de-la-zona","9":"category-politica","10":"category-politica-local"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/gremios_elfuerte_040317.jpg?fit=946%2C641&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8qtrQ-8y","jetpack-related-posts":[{"id":953,"url":"https:\/\/larevistadigital.com.ar\/blog\/primicia-de-lrd-los-gremios-municipales-llegaron-a-un-acuerdo-por-el-aumento-salarial\/","url_meta":{"origin":530,"position":0},"title":"PRIMICIA DE LRD: LOS GREMIOS MUNICIPALES LLEGARON A UN ACUERDO POR EL AUMENTO SALARIAL","author":"Alejandro Sosa Ruda","date":"10 marzo, 2017","format":false,"excerpt":"LRD dialog\u00f3 en exclusiva con la Secretaria general de ATE, Mar\u00eda Alicia Barletta, qui\u00e9n confirm\u00f3 que luego de una larga reuni\u00f3n pudieron llegar a un acuerdo sobre el monto del aumento salarial con el ejecutivo municipal. En el d\u00eda de hoy, se produjo la reuni\u00f3n pactada entre funcionarios del ejecutivo\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/barleta_Alicia-Copy.jpg?fit=1024%2C768&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/barleta_Alicia-Copy.jpg?fit=1024%2C768&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/barleta_Alicia-Copy.jpg?fit=1024%2C768&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/barleta_Alicia-Copy.jpg?fit=1024%2C768&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":5195,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-municipio-saber-hubo-acuerdo-los-gremios-19-aumento\/","url_meta":{"origin":530,"position":1},"title":"CHASCOM\u00daS: EL MUNICIPIO HIZO SABER QUE HUBO ACUERDO CON LOS GREMIOS POR UN 19% DE AUMENTO","author":"Alejandro Sosa Ruda","date":"7 marzo, 2018","format":false,"excerpt":"La Municipalidad de Chascom\u00fas, desde su p\u00e1gina de facebook\u00a0 hizo conocer que tras realizarse el segundo encuentro de la Mesa Paritaria, el Departamento Ejecutivo logr\u00f3 un\u00a0 acuerdo con todos los gremios, sobre un incremento salarial para los empleados municipales del 19,1 %, en tres tramos que incluye la cl\u00e1usula gatillo.\u2026","rel":"","context":"En \u00abGREMIALES\u00bb","block_context":{"text":"GREMIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/gremiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/03\/28783319_1801448603209350_666381720539938954_n.jpg?fit=883%2C589&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/03\/28783319_1801448603209350_666381720539938954_n.jpg?fit=883%2C589&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/03\/28783319_1801448603209350_666381720539938954_n.jpg?fit=883%2C589&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/03\/28783319_1801448603209350_666381720539938954_n.jpg?fit=883%2C589&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":43237,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-aumento-salarial-del-13-para-trabajadores-municipales\/","url_meta":{"origin":530,"position":2},"title":"Chascom\u00fas: Aumento salarial del 13% para trabajadores municipales","author":"Alejandro Sosa Ruda","date":"10 enero, 2026","format":false,"excerpt":"Las autoridades del Departamento Ejecutivo y representantes de los sindicatos municipales alcanzaron un acuerdo un\u00e1nime que establece aumentos salariales en dos tramos y mantiene el di\u00e1logo permanente con los gremios. 10 de enero de 2026 CHASCOM\u00daS -\u00a0 \u00a0El encuentro de la Mesa Salarial tuvo lugar en el Palacio Municipal, donde\u2026","rel":"","context":"En \u00abINTERES GENERAL\u00bb","block_context":{"text":"INTERES GENERAL","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/interes-general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/69615a06816dc.png?fit=668%2C445&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/69615a06816dc.png?fit=668%2C445&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/69615a06816dc.png?fit=668%2C445&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":43450,"url":"https:\/\/larevistadigital.com.ar\/blog\/buenos-aires-la-provincia-acordo-con-los-gremios-bonaerenses-un-nuevo-aumento-salarial-en-enero\/","url_meta":{"origin":530,"position":3},"title":"Buenos Aires: La Provincia acord\u00f3 con los gremios bonaerenses un nuevo aumento salarial en enero","author":"Alejandro Sosa Ruda","date":"19 enero, 2026","format":false,"excerpt":"La oferta incluye un retroactivo a diciembre con el proporcional del aguinaldo; y un 3% en enero, respecto de los haberes vigentes al mes de octubre. 19 de enero de 2026 El Gobierno de la provincia de Buenos Aires, en un marco de emergencia econ\u00f3mica provocada por las pol\u00edticas del\u2026","rel":"","context":"En \u00abGREMIALES\u00bb","block_context":{"text":"GREMIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/gremiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-01-19-132851.jpg?fit=699%2C439&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-01-19-132851.jpg?fit=699%2C439&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-01-19-132851.jpg?fit=699%2C439&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":9718,"url":"https:\/\/larevistadigital.com.ar\/blog\/lezama-harispe-recibio-a-los-gremios-y-les-comunico-la-propuesta-de-aumento-salarial-para-municipales\/","url_meta":{"origin":530,"position":4},"title":"LEZAMA: HARISPE RECIBI\u00d3 A LOS GREMIOS Y LES COMUNIC\u00d3 LA PROPUESTA DE AUMENTO SALARIAL PARA MUNICIPALES","author":"Alejandro Sosa Ruda","date":"15 abril, 2019","format":false,"excerpt":"El Ejecutivo local convoc\u00f3 a los gremios a reuni\u00f3n paritaria y realiz\u00f3 una propuesta de aumento en el salario municipal seg\u00fan el siguiente detalle: - 11 % en abril, a liquidarse en los pr\u00f3ximos 20 d\u00edas; 11 % en julio y 11% en septiembre.\u00a0 - El acumulado arroja un incremento\u2026","rel":"","context":"En \u00abLEZAMA\u00bb","block_context":{"text":"LEZAMA","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/lezama\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2019\/04\/57154197_1440083409517689_5208683122496897024_n.jpg?fit=960%2C720&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2019\/04\/57154197_1440083409517689_5208683122496897024_n.jpg?fit=960%2C720&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2019\/04\/57154197_1440083409517689_5208683122496897024_n.jpg?fit=960%2C720&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2019\/04\/57154197_1440083409517689_5208683122496897024_n.jpg?fit=960%2C720&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":6797,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-se-reunio-la-mesa-salarial-y-acordaron-un-nuevo-encuentro-para-el-proximo-martes\/","url_meta":{"origin":530,"position":5},"title":"CHASCOM\u00daS: SE REUNI\u00d3 LA MESA SALARIAL Y ACORDARON UN NUEVO ENCUENTRO PARA EL PR\u00d3XIMO MARTES","author":"Alejandro Sosa Ruda","date":"11 octubre, 2018","format":false,"excerpt":"Finalmente se llev\u00f3 a cabo el d\u00eda de ayer la reuni\u00f3n pactada entre el ejecutivo local y los distintos gremios que conforman la \"mesa salarial\", tal como lo ped\u00eda la ordenanza aprobada por mayor\u00eda en el Concejo Deliberante. La misma se desarroll\u00f3 en el municipio, y fueron de la partida,\u2026","rel":"","context":"En \u00abGREMIALES\u00bb","block_context":{"text":"GREMIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/gremiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/10\/mesasalarial_11deoctubrede2018_elfuerte.jpg?fit=737%2C415&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/10\/mesasalarial_11deoctubrede2018_elfuerte.jpg?fit=737%2C415&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/10\/mesasalarial_11deoctubrede2018_elfuerte.jpg?fit=737%2C415&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/10\/mesasalarial_11deoctubrede2018_elfuerte.jpg?fit=737%2C415&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=530"}],"version-history":[{"count":1,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/530\/revisions"}],"predecessor-version":[{"id":532,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/530\/revisions\/532"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media\/531"}],"wp:attachment":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}