{"id":5640,"date":"2018-05-26T17:27:38","date_gmt":"2018-05-26T17:27:38","guid":{"rendered":"https:\/\/larevistadigital.com.ar\/blog\/?p=5640"},"modified":"2018-05-26T17:27:38","modified_gmt":"2018-05-26T17:27:38","slug":"chascomus-el-doctor-martin-larralde-hablo-de-su-desplazamiento-del-registro-civil","status":"publish","type":"post","link":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-el-doctor-martin-larralde-hablo-de-su-desplazamiento-del-registro-civil\/","title":{"rendered":"CHASCOM\u00daS: EL DOCTOR MART\u00cdN LARRALDE HABL\u00d3 DE SU DESPLAZAMIENTO DEL REGISTRO CIVIL"},"content":{"rendered":"<h2>El abogado <strong>Mart\u00edn Larralde<\/strong> hizo menci\u00f3n a su alejamiento de la jefatura del Registro Civil de Chascom\u00fas, durante una nota en la FM 101.5 realizada por el periodista <strong>Alfredo Perona<\/strong>.<\/h2>\n<p>Lo primero que manifest\u00f3, fue que su gesti\u00f3n se bas\u00f3 especialmente en un fuerte trabajo en equipo, lo que redund\u00f3 en un notable mejoramiento de la oficina.<\/p>\n<p>Esto, fue muy valorado por la sociedad, como puede observarse en las redes sociales, y distintas manifestaciones de apoyo de casi todo el arco pol\u00edtico local, reconociendo que lo trabajado por el abogado en esa direcci\u00f3n ha sido realmente notable y con muy buenos resultados.<\/p>\n<blockquote>\n<h3>Manifest\u00f3 sentirse agradecido por la oportunidad que tuvo de comandar esa oficina, a la que le tom\u00f3 un gran cari\u00f1o, aunque tambi\u00e9n dijo que esta decisi\u00f3n lo tom\u00f3 por sorpresa, ya que no tuvo ni un solo problema, denuncia u otro inconveniente durante su gesti\u00f3n.<\/h3>\n<\/blockquote>\n<p>Otra cosa es que se lo quit\u00f3 de su lugar, pero a\u00fan no se ha nombrado a nadie para cubrir el puesto, por lo que la situaci\u00f3n es a\u00fan m\u00e1s irregular.<\/p>\n<p><strong><em>\u201cMe molest\u00f3 y enoj\u00f3 un poco las formas que se manejaron para comunicarme esta decisi\u00f3n. Yo tuve que averiguar, informarme por las m\u00edas. Me dijeron que la orden viene de arriba, por pedido de Chascom\u00fas. Si alguien ten\u00eda alg\u00fan problema conmigo, debi\u00f3 haberme llamado\u201d<\/em><\/strong>, asegur\u00f3.<\/p>\n<p>Termin\u00f3 diciendo que <strong><em>\u201cme voy con la consciencia tranquila de no haber tenido ning\u00fan problema, y haber dejado las cosas en orden. Por ahora seguir\u00e9 trabajando como un empleado m\u00e1s, o hasta que me designen nuevas funciones\u201d<\/em><\/strong>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>El abogado Mart\u00edn Larralde hizo menci\u00f3n a su alejamiento de la jefatura del Registro Civil de Chascom\u00fas, durante una nota en la FM 101.5 realizada por el periodista Alfredo Perona. Lo primero que manifest\u00f3, fue <a class=\"mh-excerpt-more\" href=\"https:\/\/larevistadigital.com.ar\/blog\/chascomus-el-doctor-martin-larralde-hablo-de-su-desplazamiento-del-registro-civil\/\" title=\"CHASCOM\u00daS: EL DOCTOR MART\u00cdN LARRALDE HABL\u00d3 DE SU DESPLAZAMIENTO DEL REGISTRO CIVIL\">[Leer M\u00e1s]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":5641,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[12],"tags":[],"class_list":{"0":"post-5640","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/05\/DSC_0161.jpg?fit=3720%2C2776&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8qtrQ-1sY","jetpack-related-posts":[{"id":5595,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-de-manera-inesperada-y-sin-motivo-martin-larralde-fue-relevado-de-la-jefatura-del-registro-civil\/","url_meta":{"origin":5640,"position":0},"title":"CHASCOM\u00daS: DE MANERA INESPERADA Y SIN MOTIVO, MART\u00cdN LARRALDE FUE RELEVADO DE LA JEFATURA DEL REGISTRO CIVIL","author":"Alejandro Sosa Ruda","date":"21 mayo, 2018","format":false,"excerpt":"De manera sorpresiva, y verdaderamente bastante desprolija, el abogado Mart\u00edn Larralde fue desplazado de su cargo como Jefe de la Oficina del registro Civil de Chascom\u00fas, sin previo aviso, y enter\u00e1ndose de casualidad. Larralde hab\u00eda entrado en funciones en agosto de 2015 y desde ese entonces, llev\u00f3 adelante una muy\u2026","rel":"","context":"En \u00abPOLITICA\u00bb","block_context":{"text":"POLITICA","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/05\/22528252_826566037514249_6032541600636590143_n.jpg?fit=960%2C720&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/05\/22528252_826566037514249_6032541600636590143_n.jpg?fit=960%2C720&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/05\/22528252_826566037514249_6032541600636590143_n.jpg?fit=960%2C720&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/05\/22528252_826566037514249_6032541600636590143_n.jpg?fit=960%2C720&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":26108,"url":"https:\/\/larevistadigital.com.ar\/blog\/concurrido-e-importante-marco-para-el-lanzamiento-de-martin-larralde-como-el-referente-del-partido-fe-en-chascomus\/","url_meta":{"origin":5640,"position":1},"title":"CONCURRIDO E IMPORTANTE MARCO PARA EL LANZAMIENTO DE MART\u00cdN LARRALDE COMO EL REFERENTE DEL PARTIDO FE EN CHASCOM\u00daS","author":"Alejandro Sosa Ruda","date":"26 junio, 2022","format":false,"excerpt":"Diputados, el presidente del partido en provincia, dirigentes de la quinta con asistencia perfecta y figuras invitadas de otras secciones fueron parte del marco que en un plenario presentaron al dirigente peronista Mart\u00edn Larralde, como el referente del Partido Fe en la quinta secci\u00f3n electoral. CHASCOM\u00daS -\u00a0 El d\u00eda s\u00e1bado,\u2026","rel":"","context":"En \u00abDESTACADAS\u00bb","block_context":{"text":"DESTACADAS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/destacadas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20220626130251_sanchez-jauregui-2.jpg?fit=730%2C487&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20220626130251_sanchez-jauregui-2.jpg?fit=730%2C487&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20220626130251_sanchez-jauregui-2.jpg?fit=730%2C487&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20220626130251_sanchez-jauregui-2.jpg?fit=730%2C487&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":26081,"url":"https:\/\/larevistadigital.com.ar\/blog\/manana-se-hace-la-presentacion-de-martin-larralde-como-referente-local-del-partido-fe\/","url_meta":{"origin":5640,"position":2},"title":"MA\u00d1ANA SE HACE LA PRESENTACI\u00d3N DE MART\u00cdN LARRALDE COMO REFERENTE LOCAL DEL PARTIDO FE","author":"Alejandro Sosa Ruda","date":"24 junio, 2022","format":false,"excerpt":"El joven y respetado dirigente peronista, Mart\u00edn Larralde ser\u00e1 ma\u00f1ana presentado en sociedad como el referente del partido Fe en Chascom\u00fas. se destaca la presencia de la diputada provincial Natalia S\u00e1nchez Jauregui. CHASCOM\u00daS -\u00a0\u00a0Ma\u00f1ana s\u00e1bado 25\/6 se llevar\u00e1 a cabo en la ciudad de Chascom\u00fas, un plenario del Partido Fe\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2022-06-24-at-8.45.46-PM.jpeg?fit=860%2C1024&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2022-06-24-at-8.45.46-PM.jpeg?fit=860%2C1024&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2022-06-24-at-8.45.46-PM.jpeg?fit=860%2C1024&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2022-06-24-at-8.45.46-PM.jpeg?fit=860%2C1024&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":19705,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-joven-tomo-la-tragica-decision-de-quitarse-la-vida\/","url_meta":{"origin":5640,"position":3},"title":"CHASCOM\u00daS : JOVEN TOM\u00d3 LA TR\u00c1GICA DECISI\u00d3N DE QUITARSE LA VIDA","author":"Alejandro Sosa Ruda","date":"18 abril, 2021","format":false,"excerpt":"CHASCOM\u00daS - Trascendi\u00f3 la noticia de que un joven chascomunense de 30 a\u00f1os de edad, habr\u00eda tomado la triste decisi\u00f3n de quitarse la vida. Seg\u00fan indican fuentes policiales, se tom\u00f3 conocimiento del hecho a trav\u00e9s de un llamado al 911 del padre del muchacho, que lo habr\u00eda encontrado ahorcado en\u2026","rel":"","context":"En \u00abDESTACADAS\u00bb","block_context":{"text":"DESTACADAS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/destacadas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/10\/CRESP%C3%93N-NEGRO.jpg?fit=900%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/10\/CRESP%C3%93N-NEGRO.jpg?fit=900%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/10\/CRESP%C3%93N-NEGRO.jpg?fit=900%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/10\/CRESP%C3%93N-NEGRO.jpg?fit=900%2C900&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":10252,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-el-intendente-removio-del-cargo-de-director-del-hospital-municipal-al-doctor-martin-pezoa\/","url_meta":{"origin":5640,"position":4},"title":"CHASCOM\u00daS: EL INTENDENTE REMOVI\u00d3 DEL CARGO DE DIRECTOR DEL HOSPITAL MUNICIPAL AL DOCTOR MART\u00cdN PEZOA","author":"Alejandro Sosa Ruda","date":"21 mayo, 2019","format":false,"excerpt":"Luego de la informaci\u00f3n que publicamos en primicia de las irregularidades detectadas por Femeba, respecto del cobro de prestaciones por el doctor Mart\u00edn Pesoa a pacientes que no hab\u00edan sido atendidos, el Secretario de gobierno, Cipriano P\u00e9rez del Cerro, respondi\u00f3 el requerimiento de los concejales por el proyecto de comunicaci\u00f3n\u2026","rel":"","context":"En \u00abDESTACADAS\u00bb","block_context":{"text":"DESTACADAS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/destacadas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/11\/hospi1-1024x767-111-700x524.jpg?fit=700%2C524&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/11\/hospi1-1024x767-111-700x524.jpg?fit=700%2C524&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/11\/hospi1-1024x767-111-700x524.jpg?fit=700%2C524&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/11\/hospi1-1024x767-111-700x524.jpg?fit=700%2C524&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":1318,"url":"https:\/\/larevistadigital.com.ar\/blog\/estamos-trabajando-en-la-construccion-de-un-nuevo-partido-vecinalista\/","url_meta":{"origin":5640,"position":5},"title":"\u00abEstamos trabajando en la construcci\u00f3n de un nuevo partido vecinalista\u00bb","author":"editor","date":"18 marzo, 2017","format":false,"excerpt":"Jose Ochoa: El Abogado local y dirigente pol\u00edtico del Frente Renovador, Dr. Jos\u00e9 Ochoa, fue entrevistado en el programa \"Dos por M\u00e1s\" que conducen Alberto Morel y Mart\u00edn Palmero por FM La Radio 101.5, donde se refiri\u00f3 al panorama pol\u00edtico. En lo que respecta a la unidad entre Sergio Massa\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/descarga-7.jpg?fit=238%2C212&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/5640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=5640"}],"version-history":[{"count":2,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/5640\/revisions"}],"predecessor-version":[{"id":5643,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/5640\/revisions\/5643"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media\/5641"}],"wp:attachment":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=5640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=5640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=5640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}