{"id":5685,"date":"2018-05-28T00:12:05","date_gmt":"2018-05-28T00:12:05","guid":{"rendered":"https:\/\/larevistadigital.com.ar\/blog\/?p=5685"},"modified":"2018-05-28T00:12:05","modified_gmt":"2018-05-28T00:12:05","slug":"quien-esta-detras-de-emepa-un-poco-de-historia","status":"publish","type":"post","link":"https:\/\/larevistadigital.com.ar\/blog\/quien-esta-detras-de-emepa-un-poco-de-historia\/","title":{"rendered":"QUIEN EST\u00c1 DETR\u00c1S DE EMEPA&#8230; UN POCO DE HISTORIA"},"content":{"rendered":"<p>El \u00abGrupo EMEPA\u00bb, seg\u00fan lo publica \u00abEl liberal\u00bb, est\u00e1 conformado de la siguiente manera:<strong><em> \u00abLa empresa Ferrov\u00edas, que realiza el trayecto Retiro-Villa Rosa tiene la concesi\u00f3n de Belgrano Norte desde 1 de abril de 1994. Pertenece al grupo Emepa que mantiene Gabriel Benjam\u00edn Romero. Fue constituida en la d\u00e9cada del \u201950. Creci\u00f3 como contratista y concesionario de servicios p\u00fablicos durante las presidencias de Alfons\u00edn, Carlos Menem, Fernando de la R\u00faa y Eduardo Duhalde.\u00a0<\/em><\/strong><br \/>\n<strong><em>En 1986, Romero adquiri\u00f3 los talleres de Emepa en Chascom\u00fas, dedicados a la reparaci\u00f3n de vagones ferroviarios. El grupo Emepa est\u00e1 constituido por las siguientes empresas: Ferrov\u00edas SAC, Ferrocentral (concesionarias de la red de cargas del Ferrocarril General Mitre y del servicio metropolitano de pasajeros del Ferrocarril General Belgrano de la red ferroviaria argentina).\u00a0<\/em><\/strong><br \/>\n<strong><em>En 2005 comenz\u00f3 a brindar trenes de pasajeros en v\u00edas del ferrocarril Mitre con destino a C\u00f3rdoba, partiendo de Retiro y previo paso por Rosario, en Santa Fe. En 2006 se iniciaron servicios a Tucum\u00e1n, pasando por Rosario y La Banda, en Santiago del Estero\u00bb<\/em><\/strong>. (sic)<\/p>\n<p>En 2007 le sacaron a Metropolitano SA la concesi\u00f3n de la Roca y Belgrano Sur. A Ugofe la conforman Ferrov\u00edas (Romero), Metrov\u00edas (Roggio) y TBA (Cirigliano) y recibi\u00f3 s\u00f3lo en enero la suma de 108.045.414 pesos de subsidio del Estado nacional, asegura el diario El Liberal.<\/p>\n<blockquote>\n<h3>Hace un tiempo, el diario El Liberal publicaba acerca del due\u00f1o del Grupo EMEPA. ( https:\/\/www.elliberal.com.ar\/noticia\/93677\/mix-economico\/romero-dueno-emporio-ferroviario-campos-obras-santiago-recibe-subsidios-mas-400-millones-al-ano.html )<\/h3>\n<\/blockquote>\n<p>Ah\u00ed se narraba que el empresario, due\u00f1o de un grupo ferraviario recib\u00eda subsidios por m\u00e1s de 400 millones de pesos. transcribimos el art\u00edculo publicado entonces:<\/p>\n<p><strong>Un empresario que es uno de los socios mayoritarios de la estrat\u00e9gica Unidad de Gesti\u00f3n Operativa Ferroviaria de Emergencia (Ugofe) y ahora tambi\u00e9n de la Ugoms (Mitre y Sarmiento), realiza una millonaria obra de refacci\u00f3n de rieles en Santiago del Estero y, adem\u00e1s, cuenta con un establecimiento agro ganadero en el departamento Alberdi (MDN) que es uno de los m\u00e1s importantes de la regi\u00f3n.<\/strong><br \/>\n<strong>Gabriel Benjam\u00edn Romero tiene 57 a\u00f1os de edad y es un empresario poderoso. Es propietario de Emepa, que tiene la concesi\u00f3n de Ferrov\u00edas \u2013entre otras l\u00edneas, la que une Retiro con Tucum\u00e1n y pasa por Santiago del Estero- y de Ferrocentral. Tambi\u00e9n es due\u00f1o en Santiago del Estero del establecimiento Madera Dura del Norte, de 120.000 hect\u00e1reas, una extensi\u00f3n 20 veces m\u00e1s grande que toda la capital santiague\u00f1a y casi 2 veces la superficie del lago de R\u00edo Hondo.\u00a0<\/strong><br \/>\n<strong>El campo de Romero es de tal magnitud, que representa el 10% de la superficie del departamento Alberdi. Seg\u00fan algunas estimaciones, posee unas 50.000 hect\u00e1reas en producci\u00f3n, adem\u00e1s de poseer alrededor de 20.000 cabezas de ganado bovino, de las cuales por la \u00faltima sequ\u00eda tuvo que vender o trasladar m\u00e1s de 25% de ese total. Tambi\u00e9n tiene pista de aterrizaje propia y al menos 20 perforaciones que la abastecen de agua, en una zona caracterizada por ser una de las de menor promedio de lluvias de la provincia. Este a\u00f1o, precisamente, sufri\u00f3 las consecuencias de ello.\u00a0<\/strong><br \/>\n<strong>A trav\u00e9s del negocio ferroviario, Romero hizo una industria que trabaja en, por y para el sector ferroviario. Opera con su empresa Ferrov\u00edas el servicio de transporte de pasajeros Belgrano Norte. En todo el 2012, seg\u00fan el ministerio de Transporte, esta l\u00ednea recibi\u00f3 subsidios del Estado nacional por un monto de $401.458.825,58. Pero este a\u00f1o, ser\u00e1n muchos millones m\u00e1s.\u00a0<\/strong><br \/>\n<strong>En el per\u00edodo enero-mayo, el mismo organismo oficial, inform\u00f3 que al Belgrano Norte se le giraron subsidios por $185,9 millones. La cifra exacta es $185.966.187,45 en los primeros 5 meses del a\u00f1o. A un promedio de $37,1 millones por mes. Con los datos de estos primeros 5 meses, se puede inferir y proyectar que a un promedio de $37,1 millones por mes, al cierre de 2013, el Estado nacional subsidiar\u00e1 a esta l\u00ednea con un monto de $446.318.849,8 o sea, casi $43 millones m\u00e1s que en 2012.\u00a0<\/strong><br \/>\n<strong>Casi sin dudas, el negocio ferroviario le permiti\u00f3 a Romero crecer econ\u00f3micamente, en donde los subsidios vuelven a ser parte de un complejo entramado.<\/strong><\/p>\n<p><strong>Pero adem\u00e1s, Gabriel Benjam\u00edn Romero, es socio en la Ugofe a trav\u00e9s de Ferrov\u00edas, de las empresas Metrov\u00edas y hasta el a\u00f1o pasado tambi\u00e9n lo era TBA, hasta que tras el accidente ferroviario de Once en el que murieron m\u00e1s de 50 personas, fue separada de la Ugofe. Con la separaci\u00f3n de TBA, se conform\u00f3 una unidad operativa para operar esos ramales, el Mitre y el Sarmiento. As\u00ed naci\u00f3 la Ugoms. All\u00ed est\u00e1n tanto Romero como Roggio, adem\u00e1s del Estado nacional.<\/strong><br \/>\n<strong>Entre la Ugofe y la Ugoms, en 2012 administaron el destino de $4.708.354.994,67 en subsidios. Este a\u00f1o, en los primeros 5 meses, el Estado nacional les remiti\u00f3 fondos por un monto de $2.116.128.484,15, seg\u00fan la secretar\u00eda de Transporte de la Nacion. Seg\u00fan el promedio de subsidios mensuales que se entreg\u00f3 a ambas unidades operativas en lo que va de 2013, la proyecci\u00f3n se\u00f1ala que se cerrar\u00e1 este a\u00f1o con subsidos por encima de los $5.078,7 millones.<\/strong><\/p>\n<p>fuente:ELLIBERAL.COM<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>El \u00abGrupo EMEPA\u00bb, seg\u00fan lo publica \u00abEl liberal\u00bb, est\u00e1 conformado de la siguiente manera: \u00abLa empresa Ferrov\u00edas, que realiza el trayecto Retiro-Villa Rosa tiene la concesi\u00f3n de Belgrano Norte desde 1 de abril de 1994. <a class=\"mh-excerpt-more\" href=\"https:\/\/larevistadigital.com.ar\/blog\/quien-esta-detras-de-emepa-un-poco-de-historia\/\" title=\"QUIEN EST\u00c1 DETR\u00c1S DE EMEPA&#8230; UN POCO DE HISTORIA\">[Leer M\u00e1s]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":5687,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[6,12],"tags":[],"class_list":{"0":"post-5685","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-chascomus","8":"category-politica"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/05\/descarga.jpg?fit=600%2C336&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8qtrQ-1tH","jetpack-related-posts":[{"id":5681,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-vecinos-se-manifestaron-en-la-ruta-contra-los-despidos-en-emepa\/","url_meta":{"origin":5685,"position":0},"title":"CHASCOM\u00daS: VECINOS SE MANIFESTARON  EN LA RUTA CONTRA LOS DESPIDOS EN EMEPA","author":"Alejandro Sosa Ruda","date":"27 mayo, 2018","format":false,"excerpt":"Tal y como se ven\u00eda convocando a trav\u00e9s de las redes sociales, numerosos vecinos de la ciudad de Chascom\u00fas se hicieron presentes a la vera de la ruta 2, para manifestarse en contra de los recientes despidos en la f\u00e1brica EMEPA. Luego de una semana complicada, muchos vecinos se acercaron\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/05\/33651442_2060614824260785_6045352351009603584_n.jpg?fit=960%2C720&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/05\/33651442_2060614824260785_6045352351009603584_n.jpg?fit=960%2C720&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/05\/33651442_2060614824260785_6045352351009603584_n.jpg?fit=960%2C720&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/05\/33651442_2060614824260785_6045352351009603584_n.jpg?fit=960%2C720&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":5627,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-el-triste-momento-en-el-que-algunos-trabajadores-de-emepa-se-enteran-que-fueron-despedidos\/","url_meta":{"origin":5685,"position":1},"title":"CHASCOMUS: EL TRISTE MOMENTO EN EL QUE ALGUNOS TRABAJADORES DE EMEPA SE ENTERAN QUE FUERON DESPEDIDOS","author":"Alejandro Sosa Ruda","date":"25 mayo, 2018","format":false,"excerpt":"Hoy por la ma\u00f1ana, se film\u00f3 un video que subi\u00f3 el sitio \"Noticia registrada\", cuando en la empresa EMEPA Chascom\u00fas se dio lectura a la nomina de empleados que \"en este momento, se van a tener que retirar\", seg\u00fan se dijo. Sucedi\u00f3 en el mismo interior de la f\u00e1brica, ante\u2026","rel":"","context":"En \u00abDESTACADAS\u00bb","block_context":{"text":"DESTACADAS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/destacadas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/05\/emepa_05deOctubrede2017_elfuerte.jpg?fit=737%2C415&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/05\/emepa_05deOctubrede2017_elfuerte.jpg?fit=737%2C415&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/05\/emepa_05deOctubrede2017_elfuerte.jpg?fit=737%2C415&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/05\/emepa_05deOctubrede2017_elfuerte.jpg?fit=737%2C415&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":36116,"url":"https:\/\/larevistadigital.com.ar\/blog\/robaba-en-los-vagones-de-emepa-y-fue-aprehendido\/","url_meta":{"origin":5685,"position":2},"title":"ROBABA EN LOS VAGONES DE EMEPA Y FUE APREHENDIDO","author":"Alejandro Sosa Ruda","date":"22 mayo, 2024","format":false,"excerpt":"Se encontraba robando instalaciones el\u00e9ctricas cuando fue aprehendido. 22 de Mayo de 2024 CHASCOM\u00daS .\u00a0 En horas de la ma\u00f1ana del dia de la fecha, personal policial procedi\u00f3 a la aprehension de una persona mayor de edad, en momentos en que se encontraba sustrayendo instalaci\u00f3nes electricas de vagones en reparacion\u2026","rel":"","context":"En \u00abINTERES GENERAL\u00bb","block_context":{"text":"INTERES GENERAL","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/interes-general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/05\/emepa_05deOctubrede2017_elfuerte.jpg?fit=737%2C415&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/05\/emepa_05deOctubrede2017_elfuerte.jpg?fit=737%2C415&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/05\/emepa_05deOctubrede2017_elfuerte.jpg?fit=737%2C415&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/05\/emepa_05deOctubrede2017_elfuerte.jpg?fit=737%2C415&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":5644,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-conciliacion-obligatoria-por-quince-dias-en-emepa-que-brinda-una-luz-de-esperanza\/","url_meta":{"origin":5685,"position":3},"title":"CHASCOM\u00daS: CONCILIACI\u00d3N OBLIGATORIA POR QUINCE D\u00cdAS EN EMEPA QUE BRINDA UNA LUZ DE ESPERANZA","author":"Alejandro Sosa Ruda","date":"27 mayo, 2018","format":false,"excerpt":"El dirigente gremial de la UOM, Mario Batista, habl\u00f3 con el periodista Alfredo Perona durante el programa \u201cTardes El Tr\u00e9bol\u201d que se emite por la FM 101.5 de Chascom\u00fas, en relaci\u00f3n a los despidos producidos en la f\u00e1brica EMEPA de esa localidad. Coment\u00f3 que esta es una de las situaciones\u2026","rel":"","context":"En \u00abGREMIALES\u00bb","block_context":{"text":"GREMIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/gremiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/05\/IMG-20180406-WA0006.jpg?fit=1040%2C780&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/05\/IMG-20180406-WA0006.jpg?fit=1040%2C780&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/05\/IMG-20180406-WA0006.jpg?fit=1040%2C780&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/05\/IMG-20180406-WA0006.jpg?fit=1040%2C780&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":1014,"url":"https:\/\/larevistadigital.com.ar\/blog\/material-rodante-de-emepa-circulara-en-el-ramal-guemes-salta-capital\/","url_meta":{"origin":5685,"position":4},"title":"Material rodante de EMEPA circular\u00e1 en el ramal G\u00fcemes- Salta Capital","author":"editor","date":"12 marzo, 2017","format":false,"excerpt":"Se trata de un tren \"Alerce\" fabricado en nuestra ciudad, que tiene capacidad para 120 pasajeros sentados - Se estima que en 45 d\u00edas entrar\u00e1 en funcionamiento. Dio a conocer el portal InformateSalta, que se incorpor\u00f3 en los \u00faltimos d\u00edass una nueva formaci\u00f3n cero kil\u00f3metros que, a priori, trasladar\u00e1 pasajeros\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/tren_elfuerte_110317.jpg?fit=918%2C525&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/tren_elfuerte_110317.jpg?fit=918%2C525&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/tren_elfuerte_110317.jpg?fit=918%2C525&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/tren_elfuerte_110317.jpg?fit=918%2C525&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":4051,"url":"https:\/\/larevistadigital.com.ar\/blog\/emepa-consiguio-contrato-no-adelanto-vacaciones\/","url_meta":{"origin":5685,"position":5},"title":"Emepa consigui\u00f3 un contrato y no adelant\u00f3 vacaciones","author":"admin","date":"27 noviembre, 2017","format":false,"excerpt":"Una buena entre tantas malas La empresa Emepa finalmente pudo evitar el otorgar vacaciones anticipadas a la totalidad de su personal durante los meses de noviembre y diciembre, al haber logrado un contrato que refiere al reacondicionamiento de vagones ferroviarios. La noticia no puede ser considerada menos que auspiciosa, teniendo\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/11\/emepa_27denoviembrede2017_elfuerte.jpg?fit=737%2C415&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/11\/emepa_27denoviembrede2017_elfuerte.jpg?fit=737%2C415&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/11\/emepa_27denoviembrede2017_elfuerte.jpg?fit=737%2C415&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/11\/emepa_27denoviembrede2017_elfuerte.jpg?fit=737%2C415&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/5685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=5685"}],"version-history":[{"count":1,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/5685\/revisions"}],"predecessor-version":[{"id":5688,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/5685\/revisions\/5688"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media\/5687"}],"wp:attachment":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=5685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=5685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=5685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}