{"id":609,"date":"2017-03-06T21:19:07","date_gmt":"2017-03-06T21:19:07","guid":{"rendered":"https:\/\/larevistadigital.com.ar\/blog\/?p=609"},"modified":"2017-03-06T21:19:07","modified_gmt":"2017-03-06T21:19:07","slug":"temor-los-vecinos-ante-la-aparicion-viboras-barrio","status":"publish","type":"post","link":"https:\/\/larevistadigital.com.ar\/blog\/temor-los-vecinos-ante-la-aparicion-viboras-barrio\/","title":{"rendered":"Temor de los vecinos ante la aparici\u00f3n de v\u00edboras en un barrio"},"content":{"rendered":"<p>\u201cEl vecino Fernando Celio public\u00f3 un video donde se ve a una v\u00edbora atac\u00e1ndolo mientras la filmaba, y con bastante agresividad\u201d; as\u00ed lo se\u00f1ala el sitio period\u00edstico www.laciudad.info, a cargo del periodista Leandro Solferino. \u201cLa obra en construcci\u00f3n donde encontr\u00f3 este animal est\u00e1 ubicada en el barrio que est\u00e1 entre la Avenida Juan Manuel de Rosas y el 30 de Mayo, donde se construyen casas de la Cooperativa Por un techo propio\u201d, precisa el sitio.<\/p>\n<p>Agrega que \u201c&#8230; m\u00e1s all\u00e1 de que el vecino se lo toma con cierta gracia al escribir \u201cme parece que no me mudo nada\u201d, lo cierto es que se nota una gran predisposici\u00f3n de la v\u00edbora para atacar y defender su lugar. Ser\u00eda importante que autoridades competentes se acerquen al lugar y puedan examinar el animal para ver si es venenoso, teniendo en cuenta que viven y vivir\u00e1n varios chicos en ese lugar\u201d. El video (que puede verse en el sitio period\u00edstico mencionado l\u00edneas arriba)\u2008uestra una v\u00edbora de importantes dimensiones, y ser\u00e1 seguramente tarea -urgente por cierto- de las autoridades del \u00e1rea de bromatolog\u00eda comunal, llevar tranquilidad a quienes viven en esa zona. Como se sabe, son varias ya las viviendas que est\u00e1n all\u00ed en plena etapa de construcci\u00f3n.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.facebook.com\/plugins\/video.php?href=https%3A%2F%2Fwww.facebook.com%2Ffernando.celio%2Fvideos%2F10208907624303355%2F&#038;show_text=0&#038;width=560\" width=\"560\" height=\"315\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowTransparency=\"true\" allowFullScreen=\"true\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>\u201cEl vecino Fernando Celio public\u00f3 un video donde se ve a una v\u00edbora atac\u00e1ndolo mientras la filmaba, y con bastante agresividad\u201d; as\u00ed lo se\u00f1ala el sitio period\u00edstico www.laciudad.info, a cargo del periodista Leandro Solferino. \u201cLa <a class=\"mh-excerpt-more\" href=\"https:\/\/larevistadigital.com.ar\/blog\/temor-los-vecinos-ante-la-aparicion-viboras-barrio\/\" title=\"Temor de los vecinos ante la aparici\u00f3n de v\u00edboras en un barrio\">[Leer M\u00e1s]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":610,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[6],"tags":[],"class_list":{"0":"post-609","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-chascomus"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/vivora_elfuerte_050317.jpg?fit=869%2C601&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8qtrQ-9P","jetpack-related-posts":[{"id":22162,"url":"https:\/\/larevistadigital.com.ar\/blog\/preocupacion-por-vibora-de-cascabel-que-mordio-a-tres-perros\/","url_meta":{"origin":609,"position":0},"title":"PREOCUPACI\u00d3N POR V\u00cdBORA DE CASCABEL QUE MORDI\u00d3 A TRES PERROS","author":"Alejandro Sosa Ruda","date":"29 septiembre, 2021","format":false,"excerpt":"CLAROMEC\u00d3 - En las \u00faltimas horas una v\u00edbora de cascabel apareci\u00f3 en un domicilio ubicado en la zona de las cortaderas de la localidad de Claromec\u00f3. La serpiente caus\u00f3 un enorme susto, ya que adem\u00e1s mordi\u00f3 a tres perros. El guardafauna de Claromec\u00f3 Juan \u201cTito\u201d Gasverde, acudi\u00f3 al lugar para\u2026","rel":"","context":"En \u00abINTERES GENERAL\u00bb","block_context":{"text":"INTERES GENERAL","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/interes-general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/fotonoticia_20200217170857_1200.jpg?fit=1200%2C792&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/fotonoticia_20200217170857_1200.jpg?fit=1200%2C792&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/fotonoticia_20200217170857_1200.jpg?fit=1200%2C792&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/fotonoticia_20200217170857_1200.jpg?fit=1200%2C792&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/fotonoticia_20200217170857_1200.jpg?fit=1200%2C792&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":17943,"url":"https:\/\/larevistadigital.com.ar\/blog\/vecino-del-barrio-san-luis-evito-un-robo\/","url_meta":{"origin":609,"position":1},"title":"VECINO DEL BARRIO SAN LUIS, EVIT\u00d3 UN ROBO","author":"Alejandro Sosa Ruda","date":"3 diciembre, 2020","format":false,"excerpt":"El testigo del robo ocurrido en calle Escribano E\/Ju\u00e1rez y Dorrego fue entrevistado en la ma\u00f1ana de FM por siempre 97.3\u00a0 donde contaba que el episodio tuvo lugar entre la 1:45 y 2:00 am. de la noche del martes. El vecino escuch\u00f3 ruidos y al acercarse a ver por una\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/03\/Policia-allanamiento-noche.jpg?fit=777%2C498&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/03\/Policia-allanamiento-noche.jpg?fit=777%2C498&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/03\/Policia-allanamiento-noche.jpg?fit=777%2C498&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/03\/Policia-allanamiento-noche.jpg?fit=777%2C498&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":22364,"url":"https:\/\/larevistadigital.com.ar\/blog\/lo-que-faltaba-en-chascomus-ahora-en-una-violenta-entradera-le-robaron-a-un-vecino-del-barrio-esteban-echeverria\/","url_meta":{"origin":609,"position":2},"title":"LO QUE FALTABA EN CHASCOM\u00daS: AHORA EN UNA VIOLENTA ENTRADERA LE ROBARON A UN VECINO DEL BARRIO ESTEBAN ECHEVERR\u00cdA","author":"Alejandro Sosa Ruda","date":"13 octubre, 2021","format":false,"excerpt":"CHASCOM\u00daS - Como lo indica el t\u00edtulo, ocurri\u00f3 un hecho que marca una nueva forma de robar, que hasta ahora no ocurr\u00eda en la ciudad de Chascom\u00fas, y se suma a la creciente ola de inseguridad que parece no tener fin. Los hechos, ocurrieron en horas del mediod\u00eda, cuando el\u2026","rel":"","context":"En \u00abDESTACADAS\u00bb","block_context":{"text":"DESTACADAS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/destacadas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/resize_1550333539.jpg?fit=810%2C410&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/resize_1550333539.jpg?fit=810%2C410&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/resize_1550333539.jpg?fit=810%2C410&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/resize_1550333539.jpg?fit=810%2C410&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":14048,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-vecino-encuentra-un-cangrejo-en-el-inodoro-de-su-bano\/","url_meta":{"origin":609,"position":3},"title":"CHASCOM\u00daS: VECINO ENCUENTRA UN CANGREJO EN EL INODORO DE SU BA\u00d1O","author":"Alejandro Sosa Ruda","date":"7 enero, 2020","format":false,"excerpt":"Ayer nos esteramos que un vecino de la ciudad de Chascom\u00fas, m\u00e1s concretamente el periodista Omar Carrizo contaba en su p\u00e1gina de Facebook el desagradable encuentro con un peque\u00f1o cangrejo, que lleg\u00f3 por las ca\u00f1er\u00edas al inodoro del ba\u00f1o de su casa. Charlamos con Omar, y nos relat\u00f3 que en\u2026","rel":"","context":"En \u00abCURIOSAS\u00bb","block_context":{"text":"CURIOSAS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/curiosas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2020-01-06-at-22.35.271.jpeg?fit=675%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2020-01-06-at-22.35.271.jpeg?fit=675%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2020-01-06-at-22.35.271.jpeg?fit=675%2C1200&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":12433,"url":"https:\/\/larevistadigital.com.ar\/blog\/camioneta-choca-y-se-incendia-hace-quince-dias-la-conductora-esta-internada-pero-nadie-hace-nada-para-quitar-el-vehiculo-que-contamina-el-lugar\/","url_meta":{"origin":609,"position":4},"title":"CAMIONETA CHOCA Y SE INCENDIA HACE QUINCE D\u00cdAS. LA CONDUCTORA EST\u00c1 INTERNADA, PERO NADIE HACE NADA PARA QUITAR EL VEH\u00cdCULO QUE CONTAMINA EL  LUGAR","author":"Alejandro Sosa Ruda","date":"2 octubre, 2019","format":false,"excerpt":"Un vecino del Barrio Lomas Altas, nos hace llegar una inquietud de los vecinos , propietarios y gente de la ciudad, ante una lamentable situaci\u00f3n que atenta contra la salud y contra el medio ambiente. Hace aproximadamente unos 15 d\u00edas, hubo un accidente en el camino de circunvalaci\u00f3n a la\u2026","rel":"","context":"En \u00abDESTACADAS\u00bb","block_context":{"text":"DESTACADAS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/destacadas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2019-10-02-at-14.12.53.jpeg?fit=1032%2C774&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2019-10-02-at-14.12.53.jpeg?fit=1032%2C774&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2019-10-02-at-14.12.53.jpeg?fit=1032%2C774&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2019-10-02-at-14.12.53.jpeg?fit=1032%2C774&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":24591,"url":"https:\/\/larevistadigital.com.ar\/blog\/su-vecino-lo-amenazo-y-aprovecho-que-lo-detuvieron-para-incendiarle-la-casa\/","url_meta":{"origin":609,"position":5},"title":"SU VECINO LO AMENAZ\u00d3 Y APROVECH\u00d3 QUE LO DETUVIERON PARA INCENDIARLE LA CASA","author":"Alejandro Sosa Ruda","date":"15 marzo, 2022","format":false,"excerpt":"Ocurri\u00f3 en el barrio Aeroparque. El conflicto se hab\u00eda originado porque uno de los hombres acusaba al otro de ladr\u00f3n. Ahora la v\u00edctima se volvi\u00f3 victimario y tambi\u00e9n fue aprehendido. Ambos se encuentran alojados en la Unidad Penal 44 de Bat\u00e1n. MAR DEL PLATA -\u00a0 Un hombre de 33 a\u00f1os\u00a0que\u2026","rel":"","context":"En \u00abPOLICIALES\u00bb","block_context":{"text":"POLICIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/policiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2022-03-15-194954.jpg?fit=1012%2C488&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2022-03-15-194954.jpg?fit=1012%2C488&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2022-03-15-194954.jpg?fit=1012%2C488&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2022-03-15-194954.jpg?fit=1012%2C488&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=609"}],"version-history":[{"count":1,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/609\/revisions"}],"predecessor-version":[{"id":611,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/609\/revisions\/611"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media\/610"}],"wp:attachment":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}