{"id":6609,"date":"2018-09-23T15:52:56","date_gmt":"2018-09-23T15:52:56","guid":{"rendered":"https:\/\/larevistadigital.com.ar\/blog\/?p=6609"},"modified":"2018-09-23T15:54:57","modified_gmt":"2018-09-23T15:54:57","slug":"6609-2","status":"publish","type":"post","link":"https:\/\/larevistadigital.com.ar\/blog\/6609-2\/","title":{"rendered":"CHASCOMUS: SUSANA BEDACARRATZ HABL\u00d3 DE IMPORTANTES PROYECTOS"},"content":{"rendered":"<p>La Secretaria General del CEC de Chascom\u00fas. <strong>Susana Bedacarratz<\/strong> dialog\u00f3 con el periodista <strong>Alfredo Perona<\/strong> en la FM \u201cRadio UNO\u201d acerca de varios temas de importancia para el sector.<\/p>\n<p>La dirigente se refiri\u00f3 al festejo que se prepara por conmemorarse el d\u00eda del Empleado de Comercio, aclarando que luego de un acuerdo entre las C\u00e1maras empresarias y la Federaci\u00f3n de Comercio, el d\u00eda que es el 26 de septiembre, por caer mi\u00e9rcoles se traslada ahora al lunes 24.<\/p>\n<blockquote>\n<h3>Aclar\u00f3 tambi\u00e9n, que por ley 26.541 se le da a ese d\u00eda el car\u00e1cter de feriado nacional, por lo que no es laborable teniendo el trabajador el derecho de tomarse ese d\u00eda.<\/h3>\n<\/blockquote>\n<p>Resalt\u00f3 que los comerciantes, colaboran con esto y cierran sus negocios, pero que en el caso que el trabajador decida trabajarlo, las horas se cobran al 100%.<\/p>\n<blockquote>\n<h3>Luego, refiri\u00f3 que este a\u00f1o, est\u00e1n abocados al proyecto de construcci\u00f3n de un Centro de Salud y actividades sociales, han optado por hacer un festejo a fin de a\u00f1o, pero el mi\u00e9rcoles en su sede de calle Caseros van a sortear 50 viajes a Mar del Plata para dos personas, como agasajo a los afiliados en su d\u00eda.<\/h3>\n<\/blockquote>\n<p>Es destacable que todo lo que est\u00e1 generando se ha afrontado con fondos propios del sindicato, y que va a ser algo realmente muy importante para el beneficio de todos los afiliados, no solo brindando un gran c\u00famulo de servicios, sino tambi\u00e9n capitalizando el sindicato.<\/p>\n<p>A\u00fan el logro es m\u00e1s loable porque la filial de Chascom\u00fas no es precisamente de las \u201cm\u00e1s grandes\u201d, lo que resalta m\u00e1s la excelente administraci\u00f3n que lleva a cabo <strong>Bedacarratz<\/strong> y su gente.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>La Secretaria General del CEC de Chascom\u00fas. Susana Bedacarratz dialog\u00f3 con el periodista Alfredo Perona en la FM \u201cRadio UNO\u201d acerca de varios temas de importancia para el sector. La dirigente se refiri\u00f3 al festejo <a class=\"mh-excerpt-more\" href=\"https:\/\/larevistadigital.com.ar\/blog\/6609-2\/\" title=\"CHASCOMUS: SUSANA BEDACARRATZ HABL\u00d3 DE IMPORTANTES PROYECTOS\">[Leer M\u00e1s]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":6611,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[10,12],"tags":[],"class_list":{"0":"post-6609","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-gremiales","8":"category-politica"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/09\/bedacarrazt_05deseptiembrede2017_elfuerte.jpg?fit=737%2C415&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8qtrQ-1IB","jetpack-related-posts":[{"id":5650,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-susana-bedacarratz-llevo-tranquilidad-a-los-empleados-de-un-importante-comercio-local\/","url_meta":{"origin":6609,"position":0},"title":"CHASCOM\u00daS: SUSANA BEDACARRATZ LLEV\u00d3 TRANQUILIDAD A LOS EMPLEADOS DE UN IMPORTANTE COMERCIO LOCAL","author":"Alejandro Sosa Ruda","date":"27 mayo, 2018","format":false,"excerpt":"La Secretaria General del Sindicato de Empleados de Comercio de Chascom\u00fas, Susana Bedacarratz, mantuvo un di\u00e1logo con el periodista Alfredo Perona durante el programa \u201cTardes El Tr\u00e9bol, que se emite por la FM 101.5 de esa ciudad. En primer lugar, cuando se la consult\u00f3 acerca de que hay un reconocido\u2026","rel":"","context":"En \u00abDESTACADAS\u00bb","block_context":{"text":"DESTACADAS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/destacadas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/05\/402096_3040372428895_685130830_n.jpg?fit=960%2C720&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/05\/402096_3040372428895_685130830_n.jpg?fit=960%2C720&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/05\/402096_3040372428895_685130830_n.jpg?fit=960%2C720&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/05\/402096_3040372428895_685130830_n.jpg?fit=960%2C720&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":4950,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-susana-bedacarratz-hablo-actualidad-osecac\/","url_meta":{"origin":6609,"position":1},"title":"CHASCOM\u00daS: SUSANA BEDACARRATZ HABL\u00d3 DE ACTUALIDAD DE OSECAC","author":"Alejandro Sosa Ruda","date":"20 febrero, 2018","format":false,"excerpt":"Susana Bedacarratz, es la secretaria general de OSECAC, y sin dudas una de las m\u00e1s apreciadas y destacadas personalidades del sindicalismo de Chascom\u00fas. Est\u00e1 pasando por un excelente momento laboral, y adem\u00e1s de ser reconocida por la dirigencia del sector, para muchos vecinos de su ciudad, sobre todo los de\u2026","rel":"","context":"En \u00abGREMIALES\u00bb","block_context":{"text":"GREMIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/gremiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/02\/24852345_10208778422498488_7599745894853488987_n.jpg?fit=960%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/02\/24852345_10208778422498488_7599745894853488987_n.jpg?fit=960%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/02\/24852345_10208778422498488_7599745894853488987_n.jpg?fit=960%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/02\/24852345_10208778422498488_7599745894853488987_n.jpg?fit=960%2C638&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":816,"url":"https:\/\/larevistadigital.com.ar\/blog\/la-camara-comercio-industria-produccion-servicios-chascomus-publico-reconocimiento-dia-la-mujer\/","url_meta":{"origin":6609,"position":2},"title":"La C\u00e1mara de Comercio, Industria, Producci\u00f3n y Servicios de Chascom\u00fas hace p\u00fablico su reconocimiento en el D\u00eda de la Mujer","author":"Alejandro Sosa Ruda","date":"8 marzo, 2017","format":false,"excerpt":"Como lo viene haciendo los \u00faltimos a\u00f1os,\u00a0reconocer\u00e1 en el presente mes,\u00a0a mujeres que han contribuido al desarrollo comercial y emprendedor de nuestro distrito, como tambi\u00e9n aquellas que han logrado por su trabajo en equipo un lugar\u00a0 destacado en nuestra sociedad. Los reconocimientos ser\u00e1n los siguientes: Reconocimiento a la mujer y\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/maxresdefault-1.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/maxresdefault-1.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/maxresdefault-1.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/maxresdefault-1.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/maxresdefault-1.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1309,"url":"https:\/\/larevistadigital.com.ar\/blog\/la-asociacion-rural-de-chascomus-participo-del-dia-de-la-produccion\/","url_meta":{"origin":6609,"position":3},"title":"La Asociaci\u00f3n Rural de Chascom\u00fas particip\u00f3 del D\u00eda de la Producci\u00f3n","author":"editor","date":"18 marzo, 2017","format":false,"excerpt":"El Presidente de la Asociaci\u00f3n Rural de Chascom\u00fas, Ra\u00fal Naufel particip\u00f3 de la jornada D\u00eda de la Producci\u00f3n organizada por el Ministerio de Producci\u00f3n de la Naci\u00f3n, junto al de Provincia, la Municipalidad y entidades locales. El encuentro, comenz\u00f3 con una mesa de intercambio entre autoridades ejecutivas, secretarios de Producci\u00f3n\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/thumbnail_DSC_0077.jpg?fit=1200%2C794&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/thumbnail_DSC_0077.jpg?fit=1200%2C794&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/thumbnail_DSC_0077.jpg?fit=1200%2C794&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/thumbnail_DSC_0077.jpg?fit=1200%2C794&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/thumbnail_DSC_0077.jpg?fit=1200%2C794&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":10775,"url":"https:\/\/larevistadigital.com.ar\/blog\/la-camara-de-comercio-invita-a-sus-socios-a-una-reunion-el-dia-de-hoy\/","url_meta":{"origin":6609,"position":4},"title":"LA C\u00c1MARA DE COMERCIO INVITA A SUS SOCIOS A UNA REUNI\u00d3N EL D\u00cdA DE HOY","author":"Alejandro Sosa Ruda","date":"25 junio, 2019","format":false,"excerpt":"La C\u00e1mara de Comercio invita a sus socios para participar de una reuni\u00f3n que se realizar\u00e1 hoy, martes 25 de junio a las 14 horas, en su sede social de Alvear 101, esquina Soler, donde asistir\u00e1 el gerente de la sucursal Chascom\u00fas del Banco de la Provincia de Buenos Aires,\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/CAMARA.jpg?fit=737%2C415&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/CAMARA.jpg?fit=737%2C415&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/CAMARA.jpg?fit=737%2C415&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/CAMARA.jpg?fit=737%2C415&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":4147,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-comenzaron-circular-tres-servicios-diarios-trenes-desde-alejandro-korn\/","url_meta":{"origin":6609,"position":5},"title":"CHASCOM\u00daS: COMENZARON A CIRCULAR TRES SERVICIOS DIARIOS DE TRENES DESDE ALEJANDRO KORN","author":"Alejandro Sosa Ruda","date":"7 diciembre, 2017","format":false,"excerpt":"Durante el programa AM Show, que se emite por la FM 101,5 de Chascom\u00fas, el jefe de estaci\u00f3n Lucas Ferreyra se refiri\u00f3 a los servicios que han comenzado a circular entre la localidad de Alejandro Korn y la ciudad de Chascom\u00fas. Ferreyra coment\u00f3 que \u201cestos servicios comenzaron a circular el\u2026","rel":"","context":"En \u00abDESTACADAS\u00bb","block_context":{"text":"DESTACADAS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/destacadas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/12\/estacion-chascomusnva.jpg?fit=960%2C539&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/12\/estacion-chascomusnva.jpg?fit=960%2C539&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/12\/estacion-chascomusnva.jpg?fit=960%2C539&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/12\/estacion-chascomusnva.jpg?fit=960%2C539&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/6609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=6609"}],"version-history":[{"count":3,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/6609\/revisions"}],"predecessor-version":[{"id":6614,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/6609\/revisions\/6614"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media\/6611"}],"wp:attachment":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=6609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=6609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=6609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}