{"id":6817,"date":"2018-10-13T19:46:16","date_gmt":"2018-10-13T19:46:16","guid":{"rendered":"https:\/\/larevistadigital.com.ar\/blog\/?p=6817"},"modified":"2018-10-13T19:46:16","modified_gmt":"2018-10-13T19:46:16","slug":"propician-ley-para-auditar-la-obra-publica","status":"publish","type":"post","link":"https:\/\/larevistadigital.com.ar\/blog\/propician-ley-para-auditar-la-obra-publica\/","title":{"rendered":"PROPICIAN LEY PARA AUDITAR LA OBRA P\u00daBLICA"},"content":{"rendered":"<p>El diputado provincial del Frente Renovador por la sexta secci\u00f3n, <strong>Pablo Garate<\/strong>, coment\u00f3 los alcances de un proyecto de su autor\u00eda en el que se crear\u00eda una ley para auditar la obra p\u00fablica, en el programa conducido por el periodista <strong>Alfredo Perona<\/strong> en la FM de Chascom\u00fas Radio UNO 102,1 mhtz.<\/p>\n<p>El proyecto en cuesti\u00f3n, estar\u00eda abordando un tema que hist\u00f3ricamente trajo sospechas y hechos de supuesta corrupci\u00f3n a lo largo de los a\u00f1os.<\/p>\n<p><strong>Garate<\/strong> sostuvo que el gobierno actual comete el error de continuar con las Obras P\u00fablicas iniciadas durante el gobierno anterior y que est\u00e1n sospechadas de hechos vinculados a distintos tipos de corrupci\u00f3n.<\/p>\n<blockquote>\n<h3>Luego, se refiri\u00f3 a distintos tipos de corrupci\u00f3n vinculados a la Obra P\u00fablica. En primer lugar, lo que refiere a la calidad de la Obra P\u00fablica, es decir si se hizo o se usaron los materiales adecuados y en la cantidad necesaria, y en segunda instancia, el tema de los sobreprecios o pagos de coimas en la Obra P\u00fablica, es decir el costo que insume la misma.<\/h3>\n<\/blockquote>\n<p>Por eso, explic\u00f3 que lo que proponen es ampliar o generar una auditor\u00eda que sea dependiente del Tribunal de Cuentas de la Provincia de Buenos Aires, para ejercer el control de la Obra P\u00fablica de manera independiente y sin necesidad de generar nuevos organismos.<\/p>\n<p>El diputado, hizo tambi\u00e9n el planteo de la aplicaci\u00f3n de la ley 113.981 que establece que las empresas que se hayan quedado con uno obra p\u00fablica a partir del pago de una coima o cualquier irregularidad pierdan autom\u00e1ticamente la concesi\u00f3n de la misma, por lo que evitar\u00edamos que quienes han sido beneficiados por otros gobiernos sigan adelante en los gobiernos siguientes.<\/p>\n<blockquote>\n<h3>Garate mencion\u00f3 que en la legislatura se ir\u00e1 discutiendo, pero que <strong><em>\u201cel gobierno nacional que prometi\u00f3 transparencia, no est\u00e1 haciendo lo que prometi\u00f3 durante la campa\u00f1a\u201d<\/em><\/strong>, afirm\u00f3.<\/h3>\n<\/blockquote>\n<p>Dijo que el gobierno parece que no quisiera hacer los controles necesarios, y que se deber\u00eda estar trabajando sobre distintas licitaciones que se ganaron a trav\u00e9s de coimas. <strong><em>\u201cPero si vemos que la justicia solo va a investigar hasta cierto a\u00f1o, la obra p\u00fablica anterior para no afectar empresarios o funcionarios o familiares de funcionarios incluso de este gobierno, estamos en un problema porque nunca vamos a conocer la verdad, porque la verdad parcial, no es bueno. La empresa que gan\u00f3 una obra p\u00fablica con una coima y el empresario se arrepiente, \u00bfqu\u00e9 hacemos con eso? Las ganancias generadas son ilegales\u201d<\/em><\/strong>, sentenci\u00f3.<\/p>\n<p>Culmin\u00f3 afirmando que <strong><em>\u201ccuando uno se arrepiente, la justicia no tiene que corroborar nada, porque eso es una confesi\u00f3n. Como dice el dicho: a confesi\u00f3n de parte, relevo de prueba, es decir el que confiesa se acoge a una ley que no lo libera de culpa, sino que se le reemplaza la pena por su confesi\u00f3n, pero no deber\u00eda tener ning\u00fan requisito para que se le quite esa obra p\u00fablica\u201d<\/em><\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>El diputado provincial del Frente Renovador por la sexta secci\u00f3n, Pablo Garate, coment\u00f3 los alcances de un proyecto de su autor\u00eda en el que se crear\u00eda una ley para auditar la obra p\u00fablica, en el <a class=\"mh-excerpt-more\" href=\"https:\/\/larevistadigital.com.ar\/blog\/propician-ley-para-auditar-la-obra-publica\/\" title=\"PROPICIAN LEY PARA AUDITAR LA OBRA P\u00daBLICA\">[Leer M\u00e1s]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":6818,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[12],"tags":[],"class_list":{"0":"post-6817","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/10\/unnamed-3-116.jpg?fit=1387%2C925&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8qtrQ-1LX","jetpack-related-posts":[{"id":40973,"url":"https:\/\/larevistadigital.com.ar\/blog\/axel-kicillof-anuncio-un-proyecto-para-reactivar-la-obra-publica-nacional-en-la-provincia\/","url_meta":{"origin":6817,"position":0},"title":"Axel Kicillof anunci\u00f3 un proyecto para reactivar la obra p\u00fablica nacional en la Provincia","author":"Alejandro Sosa Ruda","date":"18 agosto, 2025","format":false,"excerpt":"\"Nunca en la historia pas\u00f3 que, por dos a\u00f1os, est\u00e9 absolutamente parada la obra p\u00fablica a nivel nacional\", expres\u00f3 el mandatario bonaerense. 18 de agosto de 2025 El gobernador de la provincia de Buenos Aires,\u00a0Axel Kicillof, anunci\u00f3 que enviar\u00e1 un proyecto de ley para reactivar la\u00a0obra p\u00fablica, paralizada a nivel\u2026","rel":"","context":"En \u00abINTERES GENERAL\u00bb","block_context":{"text":"INTERES GENERAL","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/interes-general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2025-08-18-232936.jpg?fit=603%2C400&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2025-08-18-232936.jpg?fit=603%2C400&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2025-08-18-232936.jpg?fit=603%2C400&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":1555,"url":"https:\/\/larevistadigital.com.ar\/blog\/julio-piumato-luchar-contra-el-traspaso-es-luchar-contra-la-corrupcion\/","url_meta":{"origin":6817,"position":1},"title":"JULIO PIUMATO: LUCHAR CONTRA EL TRASPASO ES LUCHAR CONTRA LA CORRUPCI\u00d3N","author":"Alejandro Sosa Ruda","date":"23 marzo, 2017","format":false,"excerpt":"La Uni\u00f3n de Empleados de la Justicia de la Naci\u00f3n (UEJN) que conduce\u00a0Julio Piumato\u00a0moviliz\u00f3 este martes al Congreso Nacional para repudiar el traspaso de un sector de la Justicia nacional a la \u00f3rbita de la Ciudad de Buenos Aires, en el marco de un paro de 36 horas. Para Piumato,\u00a0el\u2026","rel":"","context":"En \u00abDESTACADAS\u00bb","block_context":{"text":"DESTACADAS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/destacadas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/0000023315.jpg?fit=690%2C405&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/0000023315.jpg?fit=690%2C405&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/0000023315.jpg?fit=690%2C405&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":26429,"url":"https:\/\/larevistadigital.com.ar\/blog\/denuncian-a-julio-conte-grand-funcionario-de-vidal-por-corrupcion\/","url_meta":{"origin":6817,"position":2},"title":"DENUNCIAN A JULIO CONTE GRAND (FUNCIONARIO DE VIDAL) POR CORRUPCI\u00d3N","author":"Alejandro Sosa Ruda","date":"7 julio, 2022","format":false,"excerpt":"La presidenta de la comisi\u00f3n de Asuntos Constitucionales y Justicia de la C\u00e1mara de Diputados bonaerense, Susana Gonz\u00e1lez, denunci\u00f3 penalmente al Procurador General provincial, Julio Conte Grand, acus\u00e1ndolo de \u201cencubrir\u201d a funcionarios del gobierno de Juntos por el Cambio de la provincia de Buenos Aires que habr\u00edan cometido hechos de\u2026","rel":"","context":"En \u00abINTERES GENERAL\u00bb","block_context":{"text":"INTERES GENERAL","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/interes-general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20220706172405_denuncian-al-procurador-general-provincial-julio-conte-grand-funcionario-de-maria-eugenia-vidal.jpg?fit=880%2C512&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20220706172405_denuncian-al-procurador-general-provincial-julio-conte-grand-funcionario-de-maria-eugenia-vidal.jpg?fit=880%2C512&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20220706172405_denuncian-al-procurador-general-provincial-julio-conte-grand-funcionario-de-maria-eugenia-vidal.jpg?fit=880%2C512&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20220706172405_denuncian-al-procurador-general-provincial-julio-conte-grand-funcionario-de-maria-eugenia-vidal.jpg?fit=880%2C512&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":20891,"url":"https:\/\/larevistadigital.com.ar\/blog\/nueva-iniciativa-presentada-por-jose-ochoa-en-el-concejo-deliberante-cuando-se-quiere-se-puede\/","url_meta":{"origin":6817,"position":3},"title":"NUEVA INICIATIVA PRESENTADA POR JOS\u00c9 OCHOA EN EL CONCEJO DELIBERANTE. CUANDO SE QUIERE, SE PUEDE&#8230;","author":"Alejandro Sosa Ruda","date":"24 junio, 2021","format":false,"excerpt":"El Dirigente Jos\u00e9 Ochoa presento una iniciativa ante el Concejo Deliberante para la implementaci\u00f3n del Sistema de Transparencia de la Obra P\u00fablica \u2013STOP- CHASCOM\u00daS - En la ma\u00f1ana del viernes el Presidente de Juntos Por Chascom\u00fas Jos\u00e9 Ochoa present\u00f3 ante el Honorable Consejo Deliberante un Proyecto de Ordenanza para la\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/banca-abierta-Ochoa_FOTO-EL-CRONISTA-1-1-1392x1044-1.jpg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/banca-abierta-Ochoa_FOTO-EL-CRONISTA-1-1-1392x1044-1.jpg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/banca-abierta-Ochoa_FOTO-EL-CRONISTA-1-1-1392x1044-1.jpg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/banca-abierta-Ochoa_FOTO-EL-CRONISTA-1-1-1392x1044-1.jpg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/banca-abierta-Ochoa_FOTO-EL-CRONISTA-1-1-1392x1044-1.jpg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":36947,"url":"https:\/\/larevistadigital.com.ar\/blog\/kicillof-y-sileoni-encabezaron-la-apertura-del-encuentro-provincial-de-educacion\/","url_meta":{"origin":6817,"position":4},"title":"KICILLOF Y SILEONI ENCABEZARON LA APERTURA DEL ENCUENTRO PROVINCIAL DE EDUCACI\u00d3N","author":"Alejandro Sosa Ruda","date":"11 agosto, 2024","format":false,"excerpt":"Fue en el Teatro Argentino con la participaci\u00f3n de m\u00e1s de 800 representantes del \u00e1mbito educativo y de gremios docentes. 11 de Agosto de 2024 BUENOS AIRES -\u00a0 \u00a0El gobernador Axel Kicillof encabez\u00f3 este jueves la apertura del Encuentro Provincial de Educaci\u00f3n celebrado en el marco de los 140 a\u00f1os\u2026","rel":"","context":"En \u00abPOLITICA PROVINCIAL\u00bb","block_context":{"text":"POLITICA PROVINCIAL","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/politica\/politica-provincial\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20240808120441__77A55602.jpg?fit=743%2C530&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20240808120441__77A55602.jpg?fit=743%2C530&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20240808120441__77A55602.jpg?fit=743%2C530&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/20240808120441__77A55602.jpg?fit=743%2C530&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2980,"url":"https:\/\/larevistadigital.com.ar\/blog\/salvador-no-hay-municipio-que-no-haya-recibido-obra-publica\/","url_meta":{"origin":6817,"position":5},"title":"Salvador: \u201cNo hay municipio que no haya recibido obra p\u00fablica\u201d","author":"admin","date":"4 agosto, 2017","format":false,"excerpt":"El vicegobernador bonaerense, Daniel Salvador, asegur\u00f3 que \u201cno hay municipio que no haya recibido obra p\u00fablica\u201d durante la gesti\u00f3n de Cambiemos, aunque acept\u00f3 que \u201ca\u00fan falta mucho por hacer\u201d. \u201cNo hay un municipio de los 135 de la provincia de Buenos Aires que no haya recibido obra p\u00fablica de agua,\u2026","rel":"","context":"En \u00abPOLITICA\u00bb","block_context":{"text":"POLITICA","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/08\/salvador_01deagostode2017_elfuerte.jpg?fit=737%2C415&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/08\/salvador_01deagostode2017_elfuerte.jpg?fit=737%2C415&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/08\/salvador_01deagostode2017_elfuerte.jpg?fit=737%2C415&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/08\/salvador_01deagostode2017_elfuerte.jpg?fit=737%2C415&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/6817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=6817"}],"version-history":[{"count":1,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/6817\/revisions"}],"predecessor-version":[{"id":6819,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/6817\/revisions\/6819"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media\/6818"}],"wp:attachment":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=6817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=6817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=6817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}