{"id":6875,"date":"2018-10-16T16:34:01","date_gmt":"2018-10-16T16:34:01","guid":{"rendered":"https:\/\/larevistadigital.com.ar\/blog\/?p=6875"},"modified":"2018-10-16T16:34:01","modified_gmt":"2018-10-16T16:34:01","slug":"chascomus-los-medicos-de-la-cicop-vuelven-a-denunciar-maltratos-y-persecuciones-del-municipio","status":"publish","type":"post","link":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-los-medicos-de-la-cicop-vuelven-a-denunciar-maltratos-y-persecuciones-del-municipio\/","title":{"rendered":"CHASCOM\u00daS: LOS M\u00c9DICOS DE LA CICOP VUELVEN A DENUNCIAR MALTRATOS Y PERSECUCIONES DEL MUNICIPIO"},"content":{"rendered":"<p>En\u00a0<em><strong>Radio UNO 102.1\u00a0<\/strong><\/em>la referente de CICOP <strong>Rebeca Biggi<\/strong> apunt\u00f3 al Ejecutivo municipal y calific\u00f3 como una provocaci\u00f3n la decisi\u00f3n de aplicar descuentos sin comunicarlo previamente al gremio.<br \/>\nSe\u00f1al\u00f3 al respecto que un gran malestar caus\u00f3 en el seno de los trabajadores del \u00e1mbito de la salud municipal observar en sus recibos de haberes descuentos establecidos por el Municipio.<\/p>\n<blockquote>\n<h3><strong>Biggi<\/strong> dijo que\u00a0<strong><em>\u00a0\u201ccuando se recibi\u00f3 el dep\u00f3sito de nuestro salario nos sorprendi\u00f3 la medida que tom\u00f3 el Ejecutivo de retener un monto con una conducta arbitraria que la denominan como un error contable, pero creemos que es una clara provocaci\u00f3n donde no interesa el perjuicio que se le genera al trabajador\u201d<\/em><\/strong>agregando que los descuentos <strong><em>\u201chan sido montos importantes que van desde los $2 mil hasta $7 mil, de una manera abrupta, no de la misma manera para pagar los retrasos\u201d<\/em><\/strong>.<\/h3>\n<\/blockquote>\n<p>La dirigente gremial, dej\u00f3 en claro el malestar que esto caus\u00f3 en los trabajadores, manifestando que <strong><em>\u201cdescontar descuentan r\u00e1pido pero cuando deben dinero se toman 6 cuotas para pagarlo\u201d<\/em><\/strong>, afirmando a su vez que desde el Ejecutivo <strong><em>\u201clo descontaron sin siquiera tener una charla con el gremio\u201d<\/em><\/strong>.<\/p>\n<p>Por otra parte,\u00a0 consider\u00f3 que <strong><em>\u201ccreo que esto se da por el di\u00e1logo que ha interrumpido el Ejecutivo con el gremio y los profesionales de la salud\u201d<\/em><\/strong>, asegurado en ese sentido que <em><strong>\u201cno costaba nada un llamado\u201d.<\/strong><\/em><\/p>\n<p>Por otra parte, la m\u00e1xima autoridad local de CICOP resalt\u00f3 que actualmente <em><strong>\u201chay una clara falta al cumplimiento de los acuerdos preexistentes, porque acordamos en diciembre la adecuaci\u00f3n a la escala salarial de Provincia\u201d<\/strong><\/em>, agregando en ese sentido que <em><strong>\u201cel Ejecutivo aplic\u00f3 una bonificaci\u00f3n a cuenta de futuros aumentos para evitar que se generen retroactivos de un monto del 7%\u201d<\/strong><\/em>, explicando que <em><strong>\u201ccuando se estableci\u00f3 el aumento de la escala salarial provincial que ya estaba previsto desde inicio de a\u00f1o el Ejecutivo sigui\u00f3 pagando la bonificaci\u00f3n del 7%, y al darse cuenta al mes siguiente no solo no la pag\u00f3 sino que adem\u00e1s descont\u00f3 tambi\u00e9n la que hab\u00eda pagado en agosto, generando un montos de descuento muy alto\u201d<\/strong><\/em>.<br \/>\nA su vez,<strong> Biggi<\/strong> se\u00f1al\u00f3 que el accionar administrativo tampoco fue prolijo, al indicar que<em><strong> \u201csi hablamos de correcto tampoco es tan correcto porque no hubo acuerdo con el gremio de aplicar esto a futuros aumentos, no hubo consenso\u201d<\/strong><\/em>, a\u00f1adiendo que <strong><em>\u201ccuando toman esta conducta arbitraria de aplicar esta bonificaci\u00f3n y se equivocan se podr\u00eda haber hablado y decir que fue un error\u201d<\/em><\/strong>, considerando adem\u00e1s que la decisi\u00f3n del Ejecutivo <strong><em>\u201cse podr\u00eda haber descontado en cuotas de la misma manera que nos pagan los retroactivos\u201d<\/em><\/strong>.<br \/>\nFinalmente,<strong> Biggi<\/strong> remarc\u00f3 el cuadro de situaci\u00f3n del v\u00ednculo entre el gremio y la administraci\u00f3n municipal, afirmando que <strong><em>\u201cno se nos inform\u00f3, no se notific\u00f3, y est\u00e1 suspendido el di\u00e1logo por parte del Ejecutivo, y en una de las cartas que nos env\u00eda el intendente en respuesta a una solicitud de la reuni\u00f3n nos puso como condici\u00f3n que cuando entreg\u00e1ramos la oficina el Director nos iba a comunicar la fecha y ya hace un mes que no tenemos respuesta\u201d<\/em><\/strong>. Agreg\u00f3 adem\u00e1s que <strong><em>\u201cha habido muchos incumplimientos, como el pago del SAMO o el pase a planta permanentes del mes de abril\u201d, motivo por el cual inform\u00f3 que \u201cen la asamblea se decidi\u00f3 hacer un comunicado y esperamos que estas conductas no se vuelvan a repetir porque si no tomar otro tipo de medidas\u201d<\/em><\/strong>, concluyendo en cuanto a esto que <strong><em>\u201cse est\u00e1 profundizando la grieta, el destrato se est\u00e1 convirtiendo en maltrato y en persecuci\u00f3n permanente\u201d<\/em><\/strong>.<\/p>\n<p>PUBLICADO EN EL FUERTE<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>En\u00a0Radio UNO 102.1\u00a0la referente de CICOP Rebeca Biggi apunt\u00f3 al Ejecutivo municipal y calific\u00f3 como una provocaci\u00f3n la decisi\u00f3n de aplicar descuentos sin comunicarlo previamente al gremio. Se\u00f1al\u00f3 al respecto que un gran malestar caus\u00f3 <a class=\"mh-excerpt-more\" href=\"https:\/\/larevistadigital.com.ar\/blog\/chascomus-los-medicos-de-la-cicop-vuelven-a-denunciar-maltratos-y-persecuciones-del-municipio\/\" title=\"CHASCOM\u00daS: LOS M\u00c9DICOS DE LA CICOP VUELVEN A DENUNCIAR MALTRATOS Y PERSECUCIONES DEL MUNICIPIO\">[Leer M\u00e1s]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":6877,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[10,12],"tags":[],"class_list":{"0":"post-6875","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-gremiales","8":"category-politica"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/10\/21688068_122427838479090_680493666080812121_o.jpg?fit=1280%2C719&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8qtrQ-1MT","jetpack-related-posts":[{"id":4412,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-la-cicop-advierte-maniobras-del-municipio-sacar-ventaja\/","url_meta":{"origin":6875,"position":0},"title":"CHASCOM\u00daS: LA CICOP ADVIERTE MANIOBRAS DEL MUNICIPIO PARA \u00abSACAR VENTAJA\u00bb","author":"Alejandro Sosa Ruda","date":"6 enero, 2018","format":false,"excerpt":"Los profesionales de la salud, nucleados por la CICOP, nuevamente han percibido una sutil maniobra (o no tanto)\u00a0por parte de las autoridades del Municipio de Chascom\u00fas, en la que tratar\u00edan de sacar alguna ventaja en la convocatoria a asamblea para elegir representantes de la organizaci\u00f3n gremial, en la mesa que\u2026","rel":"","context":"En \u00abDESTACADAS\u00bb","block_context":{"text":"DESTACADAS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/destacadas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/01\/CICOP-MESA-CALLE.jpg?fit=650%2C488&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/01\/CICOP-MESA-CALLE.jpg?fit=650%2C488&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/01\/CICOP-MESA-CALLE.jpg?fit=650%2C488&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":3515,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-la-cicop-asegura-ejecutivo-no-intencion-dialogar\/","url_meta":{"origin":6875,"position":1},"title":"CHASCOM\u00daS: LA CICOP ASEGURA QUE EL EJECUTIVO NO TIENE INTENCI\u00d3N DE DIALOGAR.","author":"Alejandro Sosa Ruda","date":"18 octubre, 2017","format":false,"excerpt":"La presidenta de la CICOP de Chascom\u00fas Rebeca Biggi se refiri\u00f3 a la situaci\u00f3n que se est\u00e1 viviendo con los destratos del ejecutivo local. Como primera medida, Biggi agradeci\u00f3 la gran adhesi\u00f3n y muestras de cari\u00f1o de la poblaci\u00f3n en general, que no solo acompa\u00f1aron, sino que inclusive mostraban su\u2026","rel":"","context":"En \u00abGREMIALES\u00bb","block_context":{"text":"GREMIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/gremiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/10\/21768357_135123350566961_2481987643994153920_n.jpg?fit=953%2C627&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/10\/21768357_135123350566961_2481987643994153920_n.jpg?fit=953%2C627&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/10\/21768357_135123350566961_2481987643994153920_n.jpg?fit=953%2C627&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/10\/21768357_135123350566961_2481987643994153920_n.jpg?fit=953%2C627&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":6072,"url":"https:\/\/larevistadigital.com.ar\/blog\/se-desarrollo-ayer-la-audiencia-entre-cicop-y-la-comuna\/","url_meta":{"origin":6875,"position":2},"title":"Se desarroll\u00f3 ayer la audiencia entre CICOP y la Comuna","author":"admin","date":"21 julio, 2018","format":false,"excerpt":"Desalojo de la oficina del gremio en el Hospital Tal como se anunciara, ayer se llev\u00f3 adelante una nueva audiencia entre el Gobierno Municipal y el gremio CICOP, esta vez, enmarcada en el conflicto que acarrean por el espacio que posee el gremio en el Hospital Municipal San Vicente de\u2026","rel":"","context":"En \u00abDESTACADAS\u00bb","block_context":{"text":"DESTACADAS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/destacadas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/07\/cicpo_21dejuliode2108_elfuerte.jpg?fit=737%2C415&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/07\/cicpo_21dejuliode2108_elfuerte.jpg?fit=737%2C415&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/07\/cicpo_21dejuliode2108_elfuerte.jpg?fit=737%2C415&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/07\/cicpo_21dejuliode2108_elfuerte.jpg?fit=737%2C415&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":3338,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-gran-acatamiento-en-el-paro-de-24-hs-de-los-profesionales-de-la-salud\/","url_meta":{"origin":6875,"position":3},"title":"CHASCOM\u00daS: GRAN ACATAMIENTO EN EL PARO DE 24 HS. DE LOS PROFESIONALES DE LA SALUD","author":"Alejandro Sosa Ruda","date":"28 septiembre, 2017","format":false,"excerpt":"Como estaba previsto, en el d\u00eda de ayer se llev\u00f3 a cabo la jornada de paro de profesionales de la salud, en el Hospital Municipal San Vicente de Paul, por 24 horas. Esto sucede en el marco del conflicto que mantienen con el Ejecutivo Municipal por la ordenanza de salud\u2026","rel":"","context":"En \u00abDESTACADAS\u00bb","block_context":{"text":"DESTACADAS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/destacadas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/09\/CICOP.jpg?fit=960%2C720&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/09\/CICOP.jpg?fit=960%2C720&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/09\/CICOP.jpg?fit=960%2C720&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/09\/CICOP.jpg?fit=960%2C720&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":3642,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-rebecca-biggi-confirmo-todos-los-jefes-area-del-hospital-podrian-presentar-renuncia-ademas-contar-los-siguen-grabando\/","url_meta":{"origin":6875,"position":4},"title":"CHASCOM\u00daS: REBECCA BIGGI CONFIRM\u00d3 QUE TODOS LOS JEFES DE \u00c1REA DEL HOSPITAL PODR\u00cdAN PRESENTAR SU RENUNCIA, ADEM\u00c1S DE CONTAR QUE LOS SIGUEN GRABANDO","author":"Alejandro Sosa Ruda","date":"30 octubre, 2017","format":false,"excerpt":"ASEGUR\u00d3 TAMBI\u00c9N QUE LA SECRETARIA DE SALUD, LLEV\u00d3 A SU HERMANO, EL SECRETARIO DE OBRAS A UNA REUNI\u00d3N EL D\u00cdA JUEVES EN LA DIRECCI\u00d3N DEL HOSPITAL, EN LA QUE GRAB\u00d3 DESCARADAMENTE LA DISCUSI\u00d3N. En di\u00e1logo con el programa radial \u201cAtaque de Radio\u201d que se emite los s\u00e1bados de 10 a\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/10\/21768357_135123350566961_2481987643994153920_n.jpg?fit=953%2C627&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/10\/21768357_135123350566961_2481987643994153920_n.jpg?fit=953%2C627&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/10\/21768357_135123350566961_2481987643994153920_n.jpg?fit=953%2C627&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/10\/21768357_135123350566961_2481987643994153920_n.jpg?fit=953%2C627&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":19966,"url":"https:\/\/larevistadigital.com.ar\/blog\/cicop-los-trabajadores-de-la-salud-acamparon-frente-a-la-municipalidad-de-pinamar\/","url_meta":{"origin":6875,"position":5},"title":"CICOP: LOS TRABAJADORES DE LA SALUD ACAMPARON FRENTE A LA MUNICIPALIDAD DE PINAMAR","author":"Alejandro Sosa Ruda","date":"30 abril, 2021","format":false,"excerpt":"Fue para rechazar la oferta salarial del ejecutivo local. Desde CICOP Seccional Pinamar advirtieron que\u00a0\u201cestamos dando la pelea en el peor momento de la pandemia y el intendente Yeza se nos r\u00ede en la cara con una magra propuesta de aumento de apenas 17,5% para el primer trimestre del 2021\u201d.\u2026","rel":"","context":"En \u00abGREMIALES\u00bb","block_context":{"text":"GREMIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/gremiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/CICOP.png?fit=1200%2C797&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/CICOP.png?fit=1200%2C797&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/CICOP.png?fit=1200%2C797&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/CICOP.png?fit=1200%2C797&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/CICOP.png?fit=1200%2C797&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/6875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=6875"}],"version-history":[{"count":2,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/6875\/revisions"}],"predecessor-version":[{"id":6878,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/6875\/revisions\/6878"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media\/6877"}],"wp:attachment":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=6875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=6875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=6875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}