{"id":6949,"date":"2018-10-25T03:18:16","date_gmt":"2018-10-25T03:18:16","guid":{"rendered":"https:\/\/larevistadigital.com.ar\/blog\/?p=6949"},"modified":"2018-10-25T03:24:11","modified_gmt":"2018-10-25T03:24:11","slug":"congreso-imagenes-de-la-barbarie-que-dan-verguenza","status":"publish","type":"post","link":"https:\/\/larevistadigital.com.ar\/blog\/congreso-imagenes-de-la-barbarie-que-dan-verguenza\/","title":{"rendered":"CONGRESO: IM\u00c1GENES DE LA BARBARIE QUE DAN VERG\u00dcENZA&#8230;"},"content":{"rendered":"<p>El \u00bfHonorable? Congreso de la Naci\u00f3n, se reuni\u00f3 para tratar la ley de presupuesto, y nuevamente la pol\u00edtica nacional volvi\u00f3 a mostrar lo peor de sus pr\u00e1cticas: la violencia, dentro y fuera del recinto.<\/p>\n<blockquote>\n<h3>En esta nota, no pretendemos juzgar lo bueno o no del presupuesto que se pretend\u00eda votar desde el oficialismo, y que desde la vereda de enfrente se intent\u00f3 boicotear, mediante actos de violencia que ya se est\u00e1n tornando una lamentable costumbre.<\/h3>\n<\/blockquote>\n<p>Es l\u00edcito manifestarse. Es l\u00edcito protestar y hacer sentir el descontento por las pol\u00edticas que lleva a cabo un gobierno de turno.\u00a0 Pero lo que se ha hecho es directamente delictivo, b\u00e1rbaro y desprovisto de representaci\u00f3n hacia nadie.<\/p>\n<p>En nombre de alguna ideolog\u00eda, mentirosa y ego\u00edsta, se han cometido todo tipo de tropel\u00edas y delitos, destruyendo la plaza, con el \u00fanico objeto de provocar el caos, y conseguir \u00abmuniciones\u00bb para seguir atacando a la polic\u00eda y las fuerzas de seguridad.<\/p>\n<blockquote>\n<h3>\u00bfVa a manifestarse democr\u00e1ticamente quien llega provisto de gomeras, bombas molotov, piedras, palos Y MORTEROS? La respuesta es muy sencilla: NO.<\/h3>\n<\/blockquote>\n<p>Quienes se preparan y se arman para estas acciones, cometen delitos que pueden terminar con la muerte de cualquier persona que por ah\u00ed circule, o que realmente haya ido a manifestarse de manera democr\u00e1tica, pac\u00edfica y coherente, o inclusive de alg\u00fan polic\u00eda, o integrante de las fuerzas de seguridad, que dicho sea de paso, tambi\u00e9n son trabajadores y seres humanos, o hasta inclusive de alg\u00fan manifestante de sus propias l\u00edneas.<\/p>\n<blockquote>\n<h3>\u00bfNo est\u00e1n de acuerdo con el presupuesto?, que lo manifiesten en paz, o a trav\u00e9s de sus propios representantes. Para eso, y de esa manera debe trabajar la democracia. Pronto habr\u00e1 una nueva elecci\u00f3n y se podr\u00e1 definir y expresar cada ciudadano en las urnas, que es el lugar adecuado.<\/h3>\n<\/blockquote>\n<p>Lo de hoy por la tarde, fue realmente lamentable y mostr\u00f3 las miserias del ser humano, y de algunos pol\u00edticos que dejaron en claro que con tal de sacar provecho, son capaces de cualquier cosa, cueste a quien cueste, y caiga quien caiga.<\/p>\n<p>Una forma de comenzar a cambiar estas cosas, es que los responsables\u00a0 paguen por estos hechos, que paguen por los arreglos de todo lo que han destru\u00eddo, y que vayan presos quienes cometieron delitos y abusos. Y que los extranjeros que participaron si tienen sus papeles en regla, tendr\u00e1n que pagar e ir presos como cualquier argentino, y si no los tienen, deber\u00edan ser deportados inmediatamente.<\/p>\n<p>Para terminar, les avisamos a los que fomentaron el caos y la destrucci\u00f3n, que si su intenci\u00f3n es conseguir debilitar al gobierno de <strong>Macri<\/strong>, est\u00e1n consiguiendo de esta manera absolutamente lo contrario. As\u00ed nadie puede estar de acuerdo con ellos, y victimizan al oficialismo. Realmente est\u00e1n haciendo la mejor campa\u00f1a para que el hoy presidente sea reelecto.<\/p>\n<p style=\"text-align: center\"><strong>ALGUNAS IM\u00c1GENES DE INFOBAE DE LOS LAMENTABLES INCIDENTES:<\/strong><\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_6950\" aria-describedby=\"caption-attachment-6950\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/10\/Congreso-7.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6950\" src=\"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/10\/Congreso-7.jpg?resize=600%2C338&#038;ssl=1\" alt=\"\" width=\"600\" height=\"338\" srcset=\"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/10\/Congreso-7.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/10\/Congreso-7.jpg?resize=300%2C169&amp;ssl=1 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><figcaption id=\"caption-attachment-6950\" class=\"wp-caption-text\"><strong>BANCOS ROTOS PARA CONSEGUIR PIEDRAS PARA TIRAR<\/strong><\/figcaption><\/figure>\n<figure id=\"attachment_6951\" aria-describedby=\"caption-attachment-6951\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/10\/Marcha-protestas-incidentes-Presupuesto-2019-Congreso-811.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-6951 size-full\" src=\"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/10\/Marcha-protestas-incidentes-Presupuesto-2019-Congreso-811.jpg?resize=600%2C433&#038;ssl=1\" alt=\"\" width=\"600\" height=\"433\" \/><\/a><figcaption id=\"caption-attachment-6951\" class=\"wp-caption-text\"><strong>MANIFESTANTES ARROJAN PIEDRAS CON GOMERAS<\/strong><\/figcaption><\/figure>\n<figure id=\"attachment_6952\" aria-describedby=\"caption-attachment-6952\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/10\/Incidentes-Congreso-Presupuesto-4.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-6952 size-full\" src=\"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/10\/Incidentes-Congreso-Presupuesto-4.jpg?resize=600%2C338&#038;ssl=1\" alt=\"\" width=\"600\" height=\"338\" srcset=\"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/10\/Incidentes-Congreso-Presupuesto-4.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/10\/Incidentes-Congreso-Presupuesto-4.jpg?resize=300%2C169&amp;ssl=1 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><figcaption id=\"caption-attachment-6952\" class=\"wp-caption-text\"><strong>PAREDES ROTAS<\/strong><\/figcaption><\/figure>\n<p><a href=\"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/10\/Asi-quedo-la-plaza-despues-de-los-incidentes-en-el-Congreso-Presupuesto-2019-11.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"size-full wp-image-6954 aligncenter\" src=\"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/10\/Asi-quedo-la-plaza-despues-de-los-incidentes-en-el-Congreso-Presupuesto-2019-11.jpg?ssl=1\" alt=\"\" \/><\/a><\/p>\n<figure id=\"attachment_6955\" aria-describedby=\"caption-attachment-6955\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/10\/Incidentes-Congreso-Presupuesto-2.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-6955 size-full\" src=\"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/10\/Incidentes-Congreso-Presupuesto-2.jpg?resize=600%2C338&#038;ssl=1\" alt=\"\" width=\"600\" height=\"338\" srcset=\"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/10\/Incidentes-Congreso-Presupuesto-2.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/10\/Incidentes-Congreso-Presupuesto-2.jpg?resize=300%2C169&amp;ssl=1 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><figcaption id=\"caption-attachment-6955\" class=\"wp-caption-text\"><strong>VEREDAS ROTAS<\/strong><\/figcaption><\/figure>\n<figure id=\"attachment_6953\" aria-describedby=\"caption-attachment-6953\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/10\/Incidentes-Congreso-Presupuesto-5.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-6953 size-full\" src=\"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/10\/Incidentes-Congreso-Presupuesto-5.jpg?resize=600%2C800&#038;ssl=1\" alt=\"\" width=\"600\" height=\"800\" \/><\/a><figcaption id=\"caption-attachment-6953\" class=\"wp-caption-text\"><strong>M\u00c1S PAREDES ROTAS<\/strong><\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>El \u00bfHonorable? Congreso de la Naci\u00f3n, se reuni\u00f3 para tratar la ley de presupuesto, y nuevamente la pol\u00edtica nacional volvi\u00f3 a mostrar lo peor de sus pr\u00e1cticas: la violencia, dentro y fuera del recinto. En <a class=\"mh-excerpt-more\" href=\"https:\/\/larevistadigital.com.ar\/blog\/congreso-imagenes-de-la-barbarie-que-dan-verguenza\/\" title=\"CONGRESO: IM\u00c1GENES DE LA BARBARIE QUE DAN VERG\u00dcENZA&#8230;\">[Leer M\u00e1s]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":6961,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[41],"tags":[],"class_list":{"0":"post-6949","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destacadas"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/10\/congreso-buitres.jpg?fit=765%2C498&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8qtrQ-1O5","jetpack-related-posts":[{"id":1050,"url":"https:\/\/larevistadigital.com.ar\/blog\/se-licito-las-mejoras-en-el-camino-desde-la-ruta-29-a-el-limite-con-san-miguel\/","url_meta":{"origin":6949,"position":0},"title":"Se licit\u00f3 las mejoras en el camino desde la Ruta 29 a el limite con San Miguel","author":"editor","date":"12 marzo, 2017","format":false,"excerpt":"En respuesta a gestiones iniciadas por el Intendente Municipal del partido de General Paz, Juan Manuel Alvarez, ante las autoridades provinciales pertinentes, a\u00a0fines del pasado a\u00f1o, el mi\u00e9rcoles 8 del corriente, en la sede de la Direcci\u00f3n Provincial de Vialidad, zona III de la ciudad de Ensenada, se llev\u00f3 a\u2026","rel":"","context":"En \u00abRANCHOS\u00bb","block_context":{"text":"RANCHOS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/ranchos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/LICITACION-RANCHOS1.jpg?fit=995%2C560&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/LICITACION-RANCHOS1.jpg?fit=995%2C560&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/LICITACION-RANCHOS1.jpg?fit=995%2C560&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/LICITACION-RANCHOS1.jpg?fit=995%2C560&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":45460,"url":"https:\/\/larevistadigital.com.ar\/blog\/provincia-licito-el-recambio-de-canerias-de-agua-potable-para-tres-arroyos\/","url_meta":{"origin":6949,"position":1},"title":"Provincia licit\u00f3 el recambio de ca\u00f1er\u00edas de agua potable para Tres Arroyos","author":"Alejandro Sosa Ruda","date":"4 mayo, 2026","format":false,"excerpt":"Se reemplazar\u00e1n aproximadamente 27.000 metros de la red existente beneficiando a unos 10 mil habitantes del oeste de la localidad. 04 de Mayo de 2026 La Subsecretar\u00eda de Recursos H\u00eddricos del Ministerio de Infraestructura y Servicios P\u00fablicos de la provincia de Buenos Aires realiz\u00f3 la licitaci\u00f3n de la obra \u201cRecambio\u2026","rel":"","context":"En \u00abINTERES GENERAL\u00bb","block_context":{"text":"INTERES GENERAL","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/interes-general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-05-04-173739.jpg?fit=686%2C391&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-05-04-173739.jpg?fit=686%2C391&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2026-05-04-173739.jpg?fit=686%2C391&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":36286,"url":"https:\/\/larevistadigital.com.ar\/blog\/sufrimiento-de-un-periodista-al-que-le-quemaron-el-auto-no-quiero-este-pais-para-mis-hijos\/","url_meta":{"origin":6949,"position":2},"title":"SUFRIMIENTO DE UN PERIOD\u00cdSTA AL QUE LE QUEMARON EL AUTO: \u00abNO QUIERO ESTE PA\u00cdS PARA MIS HIJOS\u00bb","author":"Alejandro Sosa Ruda","date":"12 junio, 2024","format":false,"excerpt":"Mientras se discut\u00eda la Ley Bases en el recinto, las inmediaciones del Congreso eran un caos: violencia policial y el relato de un hombre al cual los manifestantes le incendiaron el veh\u00edculo. 12 de Junio de 2024 BUENOS AIRES-\u00a0 Con la violencia como protagonista, fueron reprimidos cientos de manifestantes\u00a0que se\u2026","rel":"","context":"En \u00abINTERES GENERAL\u00bb","block_context":{"text":"INTERES GENERAL","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/interes-general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Periodista-CADENA-3.png?fit=603%2C422&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Periodista-CADENA-3.png?fit=603%2C422&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Periodista-CADENA-3.png?fit=603%2C422&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":7188,"url":"https:\/\/larevistadigital.com.ar\/blog\/una-empleada-del-congreso-denuncio-al-senador-radical-marino-por-abuso-sexual\/","url_meta":{"origin":6949,"position":3},"title":"UNA EMPLEADA DEL CONGRESO DENUNCI\u00d3 AL SENADOR RADICAL MARINO POR ABUSO SEXUAL","author":"Alejandro Sosa Ruda","date":"14 diciembre, 2018","format":false,"excerpt":"Asegur\u00f3 que \"Me toc\u00f3 los pechos y me pregunt\u00f3 cu\u00e1ndo \u00edbamos a tomar un caf\u00e9\". Y cont\u00f3 que un asesor le \"introdujo\" la lengua en su boca \"con violencia\". La declaraci\u00f3n completa. Una empleada del Congreso denunci\u00f3 haber sido v\u00edctima de un abuso sexual del senador radical Juan Carlos Marino,\u00a0\u2026","rel":"","context":"En \u00abDESTACADAS\u00bb","block_context":{"text":"DESTACADAS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/destacadas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/12\/untitled-1_crop1544749135359.jpg_1734428432.jpg?fit=970%2C546&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/12\/untitled-1_crop1544749135359.jpg_1734428432.jpg?fit=970%2C546&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/12\/untitled-1_crop1544749135359.jpg_1734428432.jpg?fit=970%2C546&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/12\/untitled-1_crop1544749135359.jpg_1734428432.jpg?fit=970%2C546&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":25603,"url":"https:\/\/larevistadigital.com.ar\/blog\/acerca-de-la-marcha-de-ni-una-menos-dialogamos-con-carolina-gonzalez-de-leon-referente-de-mumala\/","url_meta":{"origin":6949,"position":4},"title":"ACERCA DE LA \u00abMARCHA DE NI UNA MENOS\u00bb: DIALOGAMOS CON CAROLINA GONZALEZ DE LEON, REFERENTE DE MUMALA","author":"Alejandro Sosa Ruda","date":"4 junio, 2022","format":false,"excerpt":"CHASCOM\u00daS - Carolina, o \"Carito\" para los amigos, es la referente chascomunense de \"Mumala\" (Mujeres de la matria latinoamericana) y una ferviente militante del espacio, y luchadora por los derechos de las mujeres y las personas. Mantuvo una charla con La Revista Digital, donde nos cont\u00f3 acerca de la Marcha\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2022-06-03-at-10.18.12-PM.jpeg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2022-06-03-at-10.18.12-PM.jpeg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2022-06-03-at-10.18.12-PM.jpeg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2022-06-03-at-10.18.12-PM.jpeg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2022-06-03-at-10.18.12-PM.jpeg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1431,"url":"https:\/\/larevistadigital.com.ar\/blog\/sola-con-el-blanqueo-de-familiares-macri-demostro-que-no-le-importa-lo-que-el-congreso-dictamina\/","url_meta":{"origin":6949,"position":5},"title":"Sol\u00e1: \u201cCon el blanqueo de familiares Macri demostr\u00f3 que no le importa lo que el Congreso dictamina\u201d","author":"editor","date":"18 marzo, 2017","format":false,"excerpt":"El diputado nacional Felipe Sol\u00e1 se refiri\u00f3 al fallo en primera instancia que permite a los familiares de funcionarios puedan ingresar al blanqueo de capitales. \u201c\u00bfD\u00f3nde est\u00e1n los defensores de la Rep\u00fablica? Es una verg\u00fcenza que se adjudiquen la condici\u00f3n de jueces morales y avalen este decreto\u201d, indic\u00f3. Felipe Sol\u00e1\u2026","rel":"","context":"En \u00abPOLITICA\u00bb","block_context":{"text":"POLITICA","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/Felipe-Sola.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/Felipe-Sola.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/Felipe-Sola.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/Felipe-Sola.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/Felipe-Sola.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/6949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=6949"}],"version-history":[{"count":1,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/6949\/revisions"}],"predecessor-version":[{"id":6956,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/6949\/revisions\/6956"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media\/6961"}],"wp:attachment":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=6949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=6949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=6949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}