{"id":6962,"date":"2018-10-25T18:36:26","date_gmt":"2018-10-25T18:36:26","guid":{"rendered":"https:\/\/larevistadigital.com.ar\/blog\/?p=6962"},"modified":"2018-10-25T18:36:26","modified_gmt":"2018-10-25T18:36:26","slug":"chascomus-otra-baja-en-el-frente-renovador-ahora-el-salto-lo-dio-cecilia-machado","status":"publish","type":"post","link":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-otra-baja-en-el-frente-renovador-ahora-el-salto-lo-dio-cecilia-machado\/","title":{"rendered":"CHASCOM\u00daS: OTRA BAJA EN EL FRENTE RENOVADOR. AHORA EL SALTO LO DI\u00d3 CECILIA MACHADO"},"content":{"rendered":"<p>La concejal <strong>Cecila Machado<\/strong>, mantuvo un di\u00e1logo con el periodista <strong>Alfredo Perona<\/strong> en Radio Uno (fm 102.1) con respecto a su salida del Frente Renovador, para ingresar en el frente denominado Red Por Argentina, que integra el ex ministro <strong>Arroyo<\/strong> y lidera el ex gobernador <strong>Felipe Sol\u00e1<\/strong>.<\/p>\n<p>Mencion\u00f3 que han tenido algunas diferencias con el Frente Renovador en los caminos que debe tomar la oposici\u00f3n, tanto a nivel nacional, como en la ciudad de Chascom\u00fas, lo que la llev\u00f3 a tomar la decisi\u00f3n de abandonar el grupo que lidera <strong>Javier Gast\u00f3n<\/strong> como intendente de la ciudad.<\/p>\n<p><strong>Machado<\/strong> dijo que es un espacio en el que ven\u00edan trabajando varios diputados, siendo un desprendimiento del Frente Renovador, y se cre\u00f3 este espacio para agruparse y trabajar juntos.<\/p>\n<blockquote>\n<h3>Tambi\u00e9n dijo que a nivel local, <strong><em>\u201cconformar\u00e1 un \u201cmonobloque\u201d en el Concejo Deliberante, para desde ah\u00ed seguir luchando por el peronismo\u201d<\/em><\/strong>.<\/h3>\n<\/blockquote>\n<p><strong>Perona<\/strong>, hizo menci\u00f3n a que todas las consultoras coinciden que la gente le baj\u00f3 el pulgar al kirchner\u00edsmo, por lo que no es muy viable hablar de \u201cunidad del peronismo\u201d, a lo que la concejal respondi\u00f3 que <strong><em>\u201ccreo que s\u00ed, que si no hay unidad no se puede ganarle a este gobierno. No conozco las mediciones, pero la gente est\u00e1 muy mal y no llega con la plata porque todo aumenta, en la Argentina y en Chascom\u00fas\u201d<\/em><\/strong>.<\/p>\n<blockquote>\n<h3>El periodista insisti\u00f3 con la pregunta de si la unidad pod\u00eda darse sin <strong>Cristina<\/strong>, ya que la gente manifiesta un fuerte rechazo a su figura, pero <strong>Machado<\/strong> se puso nerviosa, y esquiv\u00f3 la respuesta, diciendo que <strong><em>\u201cyo no s\u00e9 lo que piensa la gente del kirchner\u00edsmo, o no, lo que s\u00ed s\u00e9 es lo que piensa la gente de lo que est\u00e1 pasando. Todav\u00eda no sabemos qui\u00e9n va a ser el candidato, si va a ser Felipe o Cristina o quien va a ser\u201d.<\/em><\/strong><\/h3>\n<\/blockquote>\n<p>Respecto de la posibilidad de conformar un interbloque con Unidad Ciudadana, machado dijo que por ahora no est\u00e1 hablado, aunque tienen muchas ideas que van a trabajar juntos en lo social.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>La concejal Cecila Machado, mantuvo un di\u00e1logo con el periodista Alfredo Perona en Radio Uno (fm 102.1) con respecto a su salida del Frente Renovador, para ingresar en el frente denominado Red Por Argentina, que <a class=\"mh-excerpt-more\" href=\"https:\/\/larevistadigital.com.ar\/blog\/chascomus-otra-baja-en-el-frente-renovador-ahora-el-salto-lo-dio-cecilia-machado\/\" title=\"CHASCOM\u00daS: OTRA BAJA EN EL FRENTE RENOVADOR. AHORA EL SALTO LO DI\u00d3 CECILIA MACHADO\">[Leer M\u00e1s]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":6963,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[12],"tags":[],"class_list":{"0":"post-6962","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/10\/machado_24deoctubrede2018_elfuerte.jpg?fit=737%2C415&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8qtrQ-1Oi","jetpack-related-posts":[{"id":1318,"url":"https:\/\/larevistadigital.com.ar\/blog\/estamos-trabajando-en-la-construccion-de-un-nuevo-partido-vecinalista\/","url_meta":{"origin":6962,"position":0},"title":"\u00abEstamos trabajando en la construcci\u00f3n de un nuevo partido vecinalista\u00bb","author":"editor","date":"18 marzo, 2017","format":false,"excerpt":"Jose Ochoa: El Abogado local y dirigente pol\u00edtico del Frente Renovador, Dr. Jos\u00e9 Ochoa, fue entrevistado en el programa \"Dos por M\u00e1s\" que conducen Alberto Morel y Mart\u00edn Palmero por FM La Radio 101.5, donde se refiri\u00f3 al panorama pol\u00edtico. En lo que respecta a la unidad entre Sergio Massa\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/descarga-7.jpg?fit=238%2C212&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6699,"url":"https:\/\/larevistadigital.com.ar\/blog\/el-diputado-facundo-moyano-visitara-chascomus\/","url_meta":{"origin":6962,"position":1},"title":"EL DIPUTADO FACUNDO MOYANO VISITAR\u00c1 CHASCOM\u00daS","author":"Alejandro Sosa Ruda","date":"1 octubre, 2018","format":false,"excerpt":"Tal como adelant\u00f3 como primicia el diario El Fuerte en su edici\u00f3n de ayer, el pr\u00f3ximo mi\u00e9rcoles visitar\u00e1 Chascom\u00fas el diputado nacional por el Frente Renovador, Facundo Moyano. El legislador, titular del gremio de los trabajadores de los peajes, ser\u00e1 recibido en nuestro medio por la concejal Cecilia Machado, quien\u2026","rel":"","context":"En \u00abPOLITICA\u00bb","block_context":{"text":"POLITICA","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/10\/Facundo_Moyano_en_la_C%C3%A1mara_de_Diputados_de_la_Rep%C3%BAblica_Argentina.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/10\/Facundo_Moyano_en_la_C%C3%A1mara_de_Diputados_de_la_Rep%C3%BAblica_Argentina.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/10\/Facundo_Moyano_en_la_C%C3%A1mara_de_Diputados_de_la_Rep%C3%BAblica_Argentina.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/10\/Facundo_Moyano_en_la_C%C3%A1mara_de_Diputados_de_la_Rep%C3%BAblica_Argentina.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/10\/Facundo_Moyano_en_la_C%C3%A1mara_de_Diputados_de_la_Rep%C3%BAblica_Argentina.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":10621,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-perez-del-cerro-hablo-de-la-candidatura-de-gaston-que-dejaria-afuera-a-gabriel-macchi\/","url_meta":{"origin":6962,"position":2},"title":"CHASCOM\u00daS: PEREZ DEL CERRO HABL\u00d3 DE LA CANDIDATURA DE GAST\u00d3N QUE DEJAR\u00cdA AFUERA A GABRIEL MACCHI","author":"Alejandro Sosa Ruda","date":"14 junio, 2019","format":false,"excerpt":"De pronto, record\u00f3 su pertenencia al Frente Renovador, luego de haberlo negado en m\u00e1s de una oportunidad el \u00faltimo mes. Inclusive hab\u00eda dicho que \"podemos volver a la lista corta\" Seg\u00fan se informa en la p\u00e1gina de facebook de Unidad por Chascom\u00fas, el secretario de gobierno Cipriano P\u00e9rez del Cerro,\u2026","rel":"","context":"En \u00abPOLITICA\u00bb","block_context":{"text":"POLITICA","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/cipriano_15defebrerode2017_elfuerte.jpg?fit=703%2C618&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/cipriano_15defebrerode2017_elfuerte.jpg?fit=703%2C618&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/cipriano_15defebrerode2017_elfuerte.jpg?fit=703%2C618&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/cipriano_15defebrerode2017_elfuerte.jpg?fit=703%2C618&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":10441,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-unidad-por-chascomus-entre-estar-con-cualquiera-o-con-nadie\/","url_meta":{"origin":6962,"position":3},"title":"CHASCOM\u00daS: UNIDAD POR CHASCOM\u00daS ENTRE ESTAR CON CUALQUIERA, O CON NADIE&#8230;","author":"Alejandro Sosa Ruda","date":"5 junio, 2019","format":false,"excerpt":"El Secretario de Gobierno de Chascom\u00fas, Cipriano P\u00e9rez del Cerro, volvi\u00f3 a hablar, en el t\u00e9rmino de quince d\u00edas de la posibilidad de que Unidad Por Chascom\u00fas, vaya a la pr\u00f3xima elecci\u00f3n con \u201cboleta corta\u201d, como lo hizo hist\u00f3ricamente hasta su arreglo con el Frente Renovador y Sergio Massa, que\u2026","rel":"","context":"En \u00abDESTACADAS\u00bb","block_context":{"text":"DESTACADAS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/destacadas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Chapa-indeciso.jpg?fit=1200%2C799&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Chapa-indeciso.jpg?fit=1200%2C799&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Chapa-indeciso.jpg?fit=1200%2C799&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Chapa-indeciso.jpg?fit=1200%2C799&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Chapa-indeciso.jpg?fit=1200%2C799&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":2566,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-por-que-jose-ochoa-rompio-con-el-frente-renovador-y-armo-un-nuevo-vecinalismo\/","url_meta":{"origin":6962,"position":4},"title":"CHASCOM\u00daS: \u00bfPOR QU\u00c9 JOS\u00c9 OCHOA ROMPI\u00d3 CON EL FRENTE RENOVADOR Y ARM\u00d3 UN NUEVO VECINALISMO?","author":"Alejandro Sosa Ruda","date":"28 junio, 2017","format":false,"excerpt":"En una entrevista exclusiva con LRD, el candidato a concejal y Presidente del partido vecinalista \u201cJuntos por Chascom\u00fas\u201d, Jos\u00e9 Ochoa abord\u00f3 distintos temas que tienen que ver con la pr\u00f3xima elecci\u00f3n y con las razones que lo llevaron a crear un nuevo espacio pol\u00edtico local. Comenz\u00f3 diciendo que \u201cEste fue\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/06\/19400334_111872562760790_7570310030625522465_o.jpg?fit=800%2C565&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/06\/19400334_111872562760790_7570310030625522465_o.jpg?fit=800%2C565&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/06\/19400334_111872562760790_7570310030625522465_o.jpg?fit=800%2C565&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/06\/19400334_111872562760790_7570310030625522465_o.jpg?fit=800%2C565&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":40175,"url":"https:\/\/larevistadigital.com.ar\/blog\/peronismo-el-nombre-del-frente-que-conduciran-massa-y-maximo\/","url_meta":{"origin":6962,"position":5},"title":"\u00abPeronismo\u00bb: El nombre del frente que conducir\u00e1n Massa y M\u00e1ximo","author":"Alejandro Sosa Ruda","date":"24 junio, 2025","format":false,"excerpt":"De cara al calendario electoral bonaerense, los l\u00edderes del Frente Renovador y La C\u00e1mpora comenzaron a delinear un nuevo espacio pol\u00edtico, mientras el sector de Axel Kicillof observa con recelo desde la vereda de enfrente. 24 de Junio de 2025 Un nuevo reacomodamiento pol\u00edtico sacude al peronismo en la provincia\u2026","rel":"","context":"En \u00abINTERES GENERAL\u00bb","block_context":{"text":"INTERES GENERAL","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/interes-general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2025-06-24-145554.jpg?fit=800%2C452&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2025-06-24-145554.jpg?fit=800%2C452&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2025-06-24-145554.jpg?fit=800%2C452&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/Captura-de-pantalla-2025-06-24-145554.jpg?fit=800%2C452&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/6962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=6962"}],"version-history":[{"count":1,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/6962\/revisions"}],"predecessor-version":[{"id":6964,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/6962\/revisions\/6964"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media\/6963"}],"wp:attachment":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=6962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=6962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=6962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}