{"id":6988,"date":"2018-10-30T04:30:28","date_gmt":"2018-10-30T04:30:28","guid":{"rendered":"https:\/\/larevistadigital.com.ar\/blog\/?p=6988"},"modified":"2018-10-30T04:30:28","modified_gmt":"2018-10-30T04:30:28","slug":"chascomus-vecinos-prenden-fuego-a-una-casilla-supuestamente-ocupada-por-delincuentes-que-asolaban-al-barrio","status":"publish","type":"post","link":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-vecinos-prenden-fuego-a-una-casilla-supuestamente-ocupada-por-delincuentes-que-asolaban-al-barrio\/","title":{"rendered":"CHASCOM\u00daS: VECINOS PRENDEN FUEGO A UNA CASILLA SUPUESTAMENTE OCUPADA POR DELINCUENTES QUE ASOLABAN AL BARRIO"},"content":{"rendered":"<p>En la vida todo tiene un l\u00edmite, y ese l\u00edmite lleg\u00f3 a los vecinos de Barrio Parque, que cansados por verse acechados por robos y diversos delitos, tomaron la dr\u00e1stica decisi\u00f3n de quemar una casilla de quienes seg\u00fan aseguran ser\u00edan los responsables de los hechos en el barrio.<\/p>\n<blockquote>\n<h3>Seg\u00fan nos comentan, la situaci\u00f3n que los hac\u00edan vivir estos individuos se habr\u00eda tornado insoportable, y dicen no haber encontrado respuesta en las autoridades.<\/h3>\n<\/blockquote>\n<p>Obviamente no estamos de acuerdo con este tipo de actitudes, pero si, podemos entender la desesperaci\u00f3n de quienes ven c\u00f3mo los amigos de lo ajeno, se apropian de las cosas que tanto trabajo y sacrificio cuesta adquirir.<\/p>\n<p>Por el momento, no tenemos datos de la filiaci\u00f3n de los damnificados, ni se sabe qui\u00e9nes ser\u00edan los que habr\u00edan participado del acto de \u201cjusticia por mano propia\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>En la vida todo tiene un l\u00edmite, y ese l\u00edmite lleg\u00f3 a los vecinos de Barrio Parque, que cansados por verse acechados por robos y diversos delitos, tomaron la dr\u00e1stica decisi\u00f3n de quemar una casilla <a class=\"mh-excerpt-more\" href=\"https:\/\/larevistadigital.com.ar\/blog\/chascomus-vecinos-prenden-fuego-a-una-casilla-supuestamente-ocupada-por-delincuentes-que-asolaban-al-barrio\/\" title=\"CHASCOM\u00daS: VECINOS PRENDEN FUEGO A UNA CASILLA SUPUESTAMENTE OCUPADA POR DELINCUENTES QUE ASOLABAN AL BARRIO\">[Leer M\u00e1s]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":6991,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[44,12],"tags":[],"class_list":{"0":"post-6988","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policiales","8":"category-politica"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2018\/10\/WhatsApp-Image-2018-10-30-at-00.06.jpg?fit=1280%2C633&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8qtrQ-1OI","jetpack-related-posts":[{"id":18786,"url":"https:\/\/larevistadigital.com.ar\/blog\/la-plata-vecinos-se-movilizan-preocupados-por-las-usurpaciones\/","url_meta":{"origin":6988,"position":0},"title":"LA PLATA: VECINOS SE MOVILIZAN PREOCUPADOS POR LAS USURPACIONES","author":"Alejandro Sosa Ruda","date":"8 febrero, 2021","format":false,"excerpt":"Temen que sigan las usurpaciones de lotes. Reclaman acci\u00f3n de la Justicia despu\u00e9s de dos denuncias penales. Vecinos del barrio de 11 y 610 mantuvieron una reuni\u00f3n con los due\u00f1os de los terrenos usurpados frente al Aeropuerto de La Plata\u00a0para pedir intervenci\u00f3n policial. Como resultado de este encuentro, en la\u2026","rel":"","context":"En \u00abPOLICIALES\u00bb","block_context":{"text":"POLICIALES","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/policiales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/1612809076923.jpeg?fit=720%2C1103&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/1612809076923.jpeg?fit=720%2C1103&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/1612809076923.jpeg?fit=720%2C1103&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/1612809076923.jpeg?fit=720%2C1103&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":11462,"url":"https:\/\/larevistadigital.com.ar\/blog\/ola-de-robos-en-barrio-parque-girado-que-atormenta-a-los-vecinos\/","url_meta":{"origin":6988,"position":1},"title":"OLA DE ROBOS EN BARRIO PARQUE GIRADO QUE ATORMENTA A LOS VECINOS.","author":"Alejandro Sosa Ruda","date":"24 julio, 2019","format":false,"excerpt":"Los vecinos de Barrio Parque Girado se encuentran movilizados y en estado de alerta por una serie de robos que vienen sufriendo las \u00faltimas semanas, que ya han afectado cerca de diez casas de la zona. As\u00ed nos lo han hecho saber, manifestando su preocupaci\u00f3n, porque lo que era muy\u2026","rel":"","context":"En \u00abINTERES GENERAL\u00bb","block_context":{"text":"INTERES GENERAL","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/interes-general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/img_73348_Escuela8rejadoblada.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/img_73348_Escuela8rejadoblada.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/img_73348_Escuela8rejadoblada.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/img_73348_Escuela8rejadoblada.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/img_73348_Escuela8rejadoblada.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":777,"url":"https:\/\/larevistadigital.com.ar\/blog\/foro-vecinal-seguridad-se-reune-los-vecinos-del-barrio-obispado-donde-siguen-los-robos\/","url_meta":{"origin":6988,"position":2},"title":"El Foro Vecinal de Seguridad se re\u00fane con los vecinos del barrio Obispado, donde siguen los robos","author":"editor","date":"8 marzo, 2017","format":false,"excerpt":"El Foro Vecinal de Seguridad, presidido por Sonia Cabrera, mantuvo una reuni\u00f3n con vecinos del barrio \u201cObispado\u201d. Como se sabe, en dicho sector de la ciudad proliferaron los robos en los \u00faltimos d\u00edas, en particular ocurri\u00f3 en las noches de corsos. Ayer tambi\u00e9n se conocieron nuevos hechos delictivos en un\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/nota-925756-martin-larralde-tengo-dudas-ganamos-paso-agosto-130805072335.jpg?fit=800%2C751&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/nota-925756-martin-larralde-tengo-dudas-ganamos-paso-agosto-130805072335.jpg?fit=800%2C751&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/nota-925756-martin-larralde-tengo-dudas-ganamos-paso-agosto-130805072335.jpg?fit=800%2C751&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/nota-925756-martin-larralde-tengo-dudas-ganamos-paso-agosto-130805072335.jpg?fit=800%2C751&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":3718,"url":"https:\/\/larevistadigital.com.ar\/blog\/chascomus-los-vecinos-lomas-altas-se-sienten-olvidados\/","url_meta":{"origin":6988,"position":3},"title":"CHASCOM\u00daS: LOS VECINOS DE \u00abLOMAS ALTAS\u00bb SE SIENTEN OLVIDADOS","author":"Alejandro Sosa Ruda","date":"6 noviembre, 2017","format":false,"excerpt":"La sociedad de fomento del Barrio Lomas Altas, emiti\u00f3 un comunicado que manifiesta su pesar por el estado de abandono en el que se sienten sumidos. No es la primera vez que quienes viven en ese barrio, dan a conocer la realidad que les toca vivir, y la actitud del\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/11\/1569871393.jpg?fit=650%2C394&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/11\/1569871393.jpg?fit=650%2C394&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/11\/1569871393.jpg?fit=650%2C394&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":582,"url":"https:\/\/larevistadigital.com.ar\/blog\/foro-vecinal-seguridad-local-se-reunio-vecinos-del-barrio-obispado\/","url_meta":{"origin":6988,"position":4},"title":"El Foro Vecinal de Seguridad local se reuni\u00f3 con vecinos del barrio Obispado","author":"editor","date":"5 marzo, 2017","format":false,"excerpt":"Ante la ola de robos El Foro Vecinal de Seguridad, presidido por Sonia Cabrera, mantuvo una reuni\u00f3n en la ma\u00f1ana de ayer con vecinos del barrio \u201cObispado\u201d. Como se sabe, en dicho sector de la ciudad proliferaron los robos en los \u00faltimos d\u00edas, en particular en las noches de los\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/soniacabrera_elfuerte_050317.jpg?fit=641%2C907&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/soniacabrera_elfuerte_050317.jpg?fit=641%2C907&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/2017\/03\/soniacabrera_elfuerte_050317.jpg?fit=641%2C907&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":13019,"url":"https:\/\/larevistadigital.com.ar\/blog\/13019-2\/","url_meta":{"origin":6988,"position":5},"title":"DETIENEN AUTORES DE ROBOS EN PARQUE GIRADO","author":"Alejandro Sosa Ruda","date":"4 noviembre, 2019","format":false,"excerpt":"Durante el fin de semana, y en horas de la tarde noche fueron detenidos tres sujetos identificados como Lucas Haedo de 21 a\u00f1os, Lucas Irigoyen de 21 a\u00f1os y Alejandro Velazquez de 24 a\u00f1os quienes hab\u00edan cometido un Robo en una casilla del camping 6 de septiembre en el km\u2026","rel":"","context":"En \u00abCHASCOM\u00daS\u00bb","block_context":{"text":"CHASCOM\u00daS","link":"https:\/\/larevistadigital.com.ar\/blog\/category\/chascomus\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2019-11-02-at-23.08.04.jpeg?fit=648%2C1152&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2019-11-02-at-23.08.04.jpeg?fit=648%2C1152&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/larevistadigital.com.ar\/blog\/wp-content\/uploads\/WhatsApp-Image-2019-11-02-at-23.08.04.jpeg?fit=648%2C1152&ssl=1&resize=525%2C300 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/6988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=6988"}],"version-history":[{"count":1,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/6988\/revisions"}],"predecessor-version":[{"id":6989,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/posts\/6988\/revisions\/6989"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media\/6991"}],"wp:attachment":[{"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=6988"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=6988"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larevistadigital.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=6988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}